{"id":81934,"date":"2020-04-22T23:35:29","date_gmt":"2020-04-22T21:35:29","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/?page_id=81934"},"modified":"2026-04-15T15:38:47","modified_gmt":"2026-04-15T13:38:47","slug":"conditions-generales-de-vente","status":"publish","type":"page","link":"https:\/\/www.vetorino.com\/boutique\/conditions-generales-de-vente\/","title":{"rendered":"Conditions g\u00e9n\u00e9rales de vente"},"content":{"rendered":" <p class=\"wp-block-paragraph\"><strong>SOMMAIRE<\/strong><\/p>   <ol class=\"wp-block-list\"> <li>Objet et dispositions g\u00e9n\u00e9rales<\/li>   <li>Les produits<\/li>   <li>Disponibilit\u00e9 des produits<\/li>   <li>Prix<\/li>   <li>Commande<\/li>   <li>Paiement<\/li>   <li>Actions r\u00e9alis\u00e9es par la Soci\u00e9t\u00e9 pour le compte de l\u2019Utilisateur dans le cadre des services de paiement<\/li>   <li>Livraison<\/li>   <li>D\u00e9lai de r\u00e9tractation \/ Satisfait ou Rembours\u00e9<\/li>   <li>Service Apr\u00e8s Vente \/ R\u00e9clamations<\/li>   <li>Responsabilit\u00e9<\/li>   <li>Droits de propri\u00e9t\u00e9 intellectuelle<\/li>   <li>Force majeure<\/li>   <li>Droit applicable<\/li>   <li>Protection des donn\u00e9es personnelles<\/li>   <li>Garantie l\u00e9gale de conformit\u00e9<\/li>   <li>Garantie des vices cach\u00e9s<\/li>   <li>Dispositions diverses<\/li> <\/ol>   <p class=\"wp-block-paragraph\">CGV \u2013 Conditions G\u00e9n\u00e9rales de Vente Entre,<\/p>   <p class=\"wp-block-paragraph\">la SAS Woofie, 47 route du Ch\u00eane Rogneux, 78490 Grosrouvre, au Capital de 16 000\u20ac, SIRET 85171272900033, ci-apr\u00e8s la \u00ab Soci\u00e9t\u00e9 \u00bb d\u2019une part ;<\/p>   <p class=\"wp-block-paragraph\">Et,<\/p>   <p class=\"wp-block-paragraph\">la personne physique ou morale proc\u00e9dant \u00e0 l\u2019achat de produits de la Soci\u00e9t\u00e9, ci-apr\u00e8s, \u00ab l\u2019Acheteur \u00bb, ou \u00ab le Client \u00bb d\u2019autre part ;<\/p>   <p class=\"wp-block-paragraph\">Et,<\/p>   <p class=\"wp-block-paragraph\">la personne physique ou morale ayant la qualit\u00e9 de V\u00e9t\u00e9rinaire, ci-apr\u00e8s, \u00ab le V\u00e9t\u00e9rinaire \u00bb ou \u00ab le Vendeur \u00bb d\u2019autre part ;<\/p>   <p class=\"wp-block-paragraph\">Il a \u00e9t\u00e9 expos\u00e9 et convenu ce qui suit :<\/p>   <p class=\"wp-block-paragraph\"><strong>D\u00e9finitions<\/strong> <\/p>   <p class=\"wp-block-paragraph\">La Boutique : la partie du site internet vetorino.com li\u00e9e \u00e0 la vente de produits, accessoires ou services \u00e0 destination du Client.<\/p>   <p class=\"wp-block-paragraph\"><strong>Pr\u00e9ambule<\/strong> <\/p>   <p class=\"wp-block-paragraph\">Les pr\u00e9sentes Conditions G\u00e9n\u00e9rales de Vente r\u00e9gissent les relations contractuelles entre la Soci\u00e9t\u00e9, le Client et le V\u00e9t\u00e9rinaire existant du fait de l\u2019utilisation du site internet de la Soci\u00e9t\u00e9 : vetorino.com. En acceptant ces conditions g\u00e9n\u00e9rales, le Client accepte \u00e9galement les conditions g\u00e9n\u00e9rales de notre moyen de paiement Mangopay.<\/p>   <p class=\"wp-block-paragraph\"><strong>Article 1 : Objet et dispositions g\u00e9n\u00e9rales <\/strong><\/p>   <p class=\"wp-block-paragraph\">Les pr\u00e9sentes Conditions G\u00e9n\u00e9rales de Vente d\u00e9terminent les droits et obligations des parties dans le cadre de la vente en ligne de Produits propos\u00e9s par le Vendeur. Les pr\u00e9sentes Conditions G\u00e9n\u00e9rales de Vente (CGV) s\u2019appliquent \u00e0 toutes les ventes de Produits, effectu\u00e9es au travers du site Internet de la Soci\u00e9t\u00e9 qui est partie int\u00e9grante du Contrat entre l\u2019Acheteur, le Vendeur et la Soci\u00e9t\u00e9. La soci\u00e9t\u00e9 se r\u00e9serve la possibilit\u00e9 de modifier les pr\u00e9sentes, \u00e0 tout moment par la publication d\u2019une nouvelle version sur son site Internet. Les CGV applicables alors sont celles \u00e9tant en vigueur \u00e0 la date du paiement de la commande. Ces CGV sont consultables sur le site Internet de la Soci\u00e9t\u00e9 \u00e0 l\u2019adresse suivante : <a href=\"https:\/\/www.vetorino.com\/boutique\/conditions-generales-de-vente\/\">https:\/\/www.vetorino.com\/boutique\/conditions-generales-de-vente\/<\/a>. La Soci\u00e9t\u00e9 s\u2019assure \u00e9galement que leur acceptation soit claire et sans r\u00e9serve en mettant en place une case \u00e0 cocher et un clic de validation. Le Client d\u00e9clare avoir pris connaissance de l\u2019ensemble des pr\u00e9sentes Conditions G\u00e9n\u00e9rales de Vente, et le cas \u00e9ch\u00e9ant des Conditions Particuli\u00e8res de Vente li\u00e9es \u00e0 un produit ou \u00e0 un service, et les accepter sans restriction ni r\u00e9serve. Le Client reconna\u00eet qu\u2019il a b\u00e9n\u00e9fici\u00e9 des conseils et informations n\u00e9cessaires afin de s\u2019assurer de l\u2019ad\u00e9quation de l\u2019offre \u00e0 ses besoins. Le Client d\u00e9clare \u00eatre en mesure de contracter l\u00e9galement en vertu des lois fran\u00e7aises ou valablement repr\u00e9senter la personne physique ou morale pour laquelle il s\u2019engage. Sauf preuve contraire les informations enregistr\u00e9es par la Soci\u00e9t\u00e9 constituent la preuve de l\u2019ensemble des transactions.<\/p>   <p class=\"wp-block-paragraph\"><strong>Article 2 : Les produits <\/strong><\/p>   <p class=\"wp-block-paragraph\">La Soci\u00e9t\u00e9 et son site internet ne repr\u00e9sentent aucun fabricant de produits pour animaux de compagnie et disposent donc d\u2019une totale ind\u00e9pendance dans la s\u00e9lection des produits propos\u00e9s dans la Boutique. Les produits propos\u00e9s sur la Boutique sont la propri\u00e9t\u00e9 des V\u00e9t\u00e9rinaires, la Soci\u00e9t\u00e9 n\u2019est en aucun cas propri\u00e9taire desdits produits. Les fabricants s\u00e9lectionn\u00e9s proposent des produits conformes \u00e0 la l\u00e9gislation et aux normes applicables en France. Les photographies des produits sont r\u00e9guli\u00e8rement tenues \u00e0 jour, mais un changement de pr\u00e9sentation peut nous avoir \u00e9chapper. Si vous constatez une diff\u00e9rence entre la photographie et le produit re\u00e7u, merci de nous informer. De ce fait, ces photos sont pr\u00e9sentes \u00e0 titre indicatif et n\u2019ont aucun caract\u00e8re contractuel. La Soci\u00e9t\u00e9 se r\u00e9serve le droit \u00e0 tout moment et sans pr\u00e9avis d\u2019ajouter ou de supprimer des produits \u00e0 son catalogue.<\/p>   <p class=\"wp-block-paragraph\"><strong>Article 3 : Disponibilit\u00e9 des produits <\/strong><\/p>   <p class=\"wp-block-paragraph\">La Soci\u00e9t\u00e9 s\u2019efforce de communiquer les informations de disponibilit\u00e9 les plus justes possibles. Le site de la soci\u00e9t\u00e9 communique avec les fournisseurs des V\u00e9t\u00e9rinaires tous les jours ouvr\u00e9s, entre 8h et 9h, pour mettre \u00e0 jour les stocks affich\u00e9s sur les fiches produits. En fonction de votre localisation, les stocks peuvent diff\u00e9rer. La commande du Client sera satisfaite dans la limite des stocks disponibles aupr\u00e8s des fournisseurs des V\u00e9t\u00e9rinaires pour le site vetorino.com au moment de la transmission de la commande. Dans le cadre d\u2019une commande d\u2019un seul ou de plusieurs articles, une indisponibilit\u00e9 d\u2019un ou de plusieurs articles entra\u00eene l\u2019envoi d\u2019un e-mail avertissant le client de la rupture de stock et du d\u00e9lai \u00e9ventuel de r\u00e9approvisionnement. Le Client fait part au service apr\u00e8s-vente de vetorino.com de sa d\u00e9cision quant au maintien ou \u00e0 l\u2019annulation du ou des articles manquants. La Soci\u00e9t\u00e9 et le V\u00e9t\u00e9rinaire se r\u00e9serve \u00e9galement le droit d\u2019annuler la commande (ou partie de commande) et de proc\u00e9der au remboursement total (ou partiel) de celle\u2013ci.<\/p>   <p class=\"wp-block-paragraph\"><strong>Article 4 : Prix <\/strong><\/p>   <p class=\"wp-block-paragraph\">Les prix des produits vendus au travers du site vetorino.com sont indiqu\u00e9s en Euros. Le prix total indiqu\u00e9 en euros toutes taxes comprises (TVA + autres taxes \u00e9ventuelles) dans le r\u00e9capitulatif de votre commande est le prix d\u00e9finitif. Ce prix comprend le prix du total de la commande avec le d\u00e9tail de chaque produit et les frais de port. Pour tous les produits factur\u00e9s hors Union europ\u00e9enne, le prix est calcul\u00e9 hors taxes automatiquement sur la facture. Des droits de douane ou autres taxes locales ou droits d\u2019importation ou taxes d\u2019\u00e9tat sont susceptibles d\u2019\u00eatre exigibles dans certains cas. Ces droits et sommes ne rel\u00e8vent pas du ressort du Vendeur. Ils seront \u00e0 la charge du Client et rel\u00e8vent de sa responsabilit\u00e9 (d\u00e9clarations, paiement aux autorit\u00e9s comp\u00e9tentes, etc.). Le Vendeur invite l\u2019Acheteur \u00e0 se renseigner sur ces aspects aupr\u00e8s des autorit\u00e9s locales correspondantes. La Soci\u00e9t\u00e9 et les V\u00e9t\u00e9rinaires se r\u00e9servent la possibilit\u00e9 de modifier les prix \u00e0 tout moment pour l\u2019avenir. Les frais de t\u00e9l\u00e9communication n\u00e9cessaires \u00e0 l\u2019acc\u00e8s au site internet du Vendeur sont \u00e0 la charge du Client. Le cas \u00e9ch\u00e9ant \u00e9galement, les frais de livraison. Les produits demeurent la propri\u00e9t\u00e9 des V\u00e9t\u00e9rinaires jusqu\u2019au complet encaissement du prix par le Vendeur. Le prix des Abonnements indiqu\u00e9 sur le site correspond au prix r\u00e9duit lors de la premi\u00e8re commande. Les commandes r\u00e9currentes sont au prix normal non r\u00e9duit sauf stipulation explicite contraire. Le prix de certains articles peut varier en fonction de la politique de prix des V\u00e9t\u00e9rinaires ou des variations des prix fournisseurs. La mise en place d\u2019Abonnement ne garantie donc pas le maintien futur du prix de vente d\u2019un produit.<\/p>   <p class=\"wp-block-paragraph\"><strong>Article 5 : Commande <\/strong><\/p>   <p class=\"wp-block-paragraph\">Un Client s\u2019\u00e9tant enregistr\u00e9 sur le site de la Soci\u00e9t\u00e9 est en mesure d\u2019enregistrer une commande. L\u2019enregistrement d\u2019une commande par le Client intervient au moment o\u00f9 le paiement est valid\u00e9 par la banque. Outre l\u2019acceptation du contenu de la commande, cet enregistrement implique l\u2019acceptation de l\u2019int\u00e9gralit\u00e9 des pr\u00e9sentes Conditions G\u00e9n\u00e9rales de Vente et constitue une preuve de la date de passation. Le Vendeur par le biais de la Soci\u00e9t\u00e9 confirme au Client l\u2019acceptation de sa commande par e-mail \u00e0 l\u2019adresse indiqu\u00e9e par le client. Le Vendeur et la Soci\u00e9t\u00e9 se r\u00e9servent le droit de refuser ou d\u2019annuler toute nouvelle commande venant d\u2019un Client avec lequel un litige existe. Le traitement des commandes se fait du lundi au vendredi. Sous r\u00e9serve de la disponibilit\u00e9 des produits, toute commande pass\u00e9e avant 12H sera trait\u00e9e le jour m\u00eame. Une commande pass\u00e9e apr\u00e8s 12H sera trait\u00e9e le lendemain (samedi, dimanche et jours f\u00e9ri\u00e9s exclus). Aux fins de bonne r\u00e9alisation de la commande, et conform\u00e9ment \u00e0 l\u2019article 1316-1 du Code civil, le Client s\u2019engage \u00e0 fournir ses \u00e9l\u00e9ments d\u2019identification v\u00e9ridiques. Le Vendeur et la Soci\u00e9t\u00e9 se r\u00e9servent la possibilit\u00e9 de refuser la commande, par exemple pour toute demande anormale, r\u00e9alis\u00e9e de mauvaise foi ou pour tout motif l\u00e9gitime. Lors d\u2019une passation de commande, le client fournit sous son enti\u00e8re et unique responsabilit\u00e9 les informations suivantes :<\/p>   <ul class=\"wp-block-list\"> <li>Adresse e-mail <\/li>   <li>Nom et Pr\u00e9nom <\/li>   <li>Adresse de facturation <\/li>   <li>T\u00e9l\u00e9phone <\/li>   <li>Lieu de livraison <\/li> <\/ul>   <p class=\"wp-block-paragraph\">En cas d\u2019erreur dans le libell\u00e9 des coordonn\u00e9es du Client, ni le Vendeur ni la Soci\u00e9t\u00e9 ne saurait \u00eatre tenu pour responsable de l\u2019impossibilit\u00e9 de livraison.<\/p>   <p class=\"wp-block-paragraph\">Les commandes avec Abonnement sont associ\u00e9es \u00e0 une p\u00e9riode d\u2019engagement d\u2019au moins deux commandes. Les abonnements ne peuvent \u00eatre interrompus ou modifi\u00e9s qu\u2019apr\u00e8s la validation de la remise de la deuxi\u00e8me commande au Client par le V\u00e9t\u00e9rinaire. Le v\u00e9t\u00e9rinaire peut \u00e0 tout moment modifier ou supprimer un abonnement s\u2019il le souhaite. Les abonnements sont soumis \u00e0 la disponibilit\u00e9 des produits, en cas de rupture de stock l\u2019abonnement pourra \u00eatre annul\u00e9 sans p\u00e9nalit\u00e9.<\/p>   <p class=\"wp-block-paragraph\"><strong>Article 6 : Paiement <\/strong><\/p>   <p class=\"wp-block-paragraph\">L\u2019int\u00e9gralit\u00e9 du montant de la commande est payable au comptant au moment de la passation de la commande. Ce prix est indiqu\u00e9 :<\/p>   <p class=\"wp-block-paragraph\">sur le panier valid\u00e9 par le client lors de sa commande, sur l\u2019interface de paiement par carte bancaire au moment de la saisie des donn\u00e9es de paiement si celle-ci diff\u00e8re de l\u2019interface panier, sur la confirmation de commande adress\u00e9e par email au client en fin de processus d\u2019achat. Le Client peut effectuer le r\u00e8glement par carte de paiement. Le paiement s\u00e9curis\u00e9 en ligne par carte bancaire est r\u00e9alis\u00e9 par notre prestataire de paiement MANGOPAY SA. Les informations transmises sont chiffr\u00e9es dans les r\u00e8gles de l\u2019art et ne peuvent \u00eatre lues au cours du transport sur le r\u00e9seau. Le Vendeur et la Soci\u00e9t\u00e9 ne conna\u00eetront \u00e0 aucun moment les informations relatives \u00e0 la carte bancaire du client. La commande d\u2019un client ne sera consid\u00e9r\u00e9e comme effective qu\u2019\u00e0 partir du moment o\u00f9 le centre de paiement aura donn\u00e9 son accord. En cas de refus de la part de MANGOPAY SA, le Client est imm\u00e9diatement inform\u00e9 dans l\u2019interface de paiement. Dans ce cas, la commande ne sera pas prise en compte par le Vendeur. Le Client confirme qu\u2019il est bien le titulaire l\u00e9gal de la carte \u00e0 d\u00e9biter et qu\u2019il est l\u00e9galement en droit d\u2019en faire usage. En cas d\u2019erreur, ou d\u2019impossibilit\u00e9 de d\u00e9biter la carte, la Vente est imm\u00e9diatement r\u00e9solue de plein droit et la commande annul\u00e9e. La facture de la commande est disponible apr\u00e8s retrait ou livraison de la commande. Elle est disponible sur la partie Mon compte accessible au Client une fois connect\u00e9 sur le site vetorino.com. Le Client peut choisir d\u2019enregistrer sa carte bancaire, et celle-ci sera toujours enregistr\u00e9e si un abonnement est mis en place par le client. Le Client peut d\u00e9senregistrer sa carte bancaire depuis son espace Mon compte s\u2019il ne dispose d\u2019aucun abonnement actif. Les donn\u00e9es enregistr\u00e9es par le syst\u00e8me informatique de la Soci\u00e9t\u00e9 constituent la preuve de l\u2019ensemble des transactions pass\u00e9es entre le V\u00e9t\u00e9rinaire et le Client.<\/p>   <p class=\"wp-block-paragraph\"><strong>Article 6 bis : Actions r\u00e9alis\u00e9es par la Soci\u00e9t\u00e9 pour le compte de l\u2019Utilisateur dans le cadre des services de paiement <\/strong><\/p>   <p class=\"wp-block-paragraph\">Dans le cadre de l\u2019utilisation des services de paiement fournis par MANGOPAY, le Client et, le cas \u00e9ch\u00e9ant, le V\u00e9t\u00e9rinaire, autorisent express\u00e9ment la Soci\u00e9t\u00e9 \u00e0 agir en leur nom et pour leur compte, par voie de proxy, aupr\u00e8s de MANGOPAY, lorsque cela est n\u00e9cessaire au fonctionnement du site vetorino.com et \u00e0 l\u2019ex\u00e9cution des op\u00e9rations de paiement li\u00e9es aux services propos\u00e9s.<\/p>   <p class=\"wp-block-paragraph\">\u00c0 ce titre, l\u2019Utilisateur autorise notamment la Soci\u00e9t\u00e9 \u00e0 effectuer, en son nom et pour son compte, selon les fonctionnalit\u00e9s effectivement propos\u00e9es sur le site, les actions suivantes aupr\u00e8s de MANGOPAY : la cr\u00e9ation et la mise \u00e0 jour de son profil utilisateur MANGOPAY, la cr\u00e9ation et la gestion de son portefeuille \u00e9lectronique (wallet), l\u2019initiation, la gestion et le suivi des op\u00e9rations de paiement, de remboursement, de transfert ou de versement li\u00e9es aux transactions r\u00e9alis\u00e9es sur le site, l\u2019enregistrement, la transmission ou la mise \u00e0 jour des informations n\u00e9cessaires \u00e0 l\u2019ex\u00e9cution des op\u00e9rations de paiement ou de reversement ainsi que, plus g\u00e9n\u00e9ralement, toute action technique ou administrative strictement n\u00e9cessaire \u00e0 l\u2019ex\u00e9cution, \u00e0 la s\u00e9curisation ou \u00e0 la r\u00e9gularisation d\u2019une op\u00e9ration de paiement effectu\u00e9e via le site.<\/p>   <p class=\"wp-block-paragraph\">L\u2019Utilisateur reconna\u00eet que certaines de ces actions peuvent n\u00e9cessiter, conform\u00e9ment aux exigences r\u00e9glementaires applicables et aux proc\u00e9dures de MANGOPAY, une authentification forte ou un recueil de consentement sp\u00e9cifique directement aupr\u00e8s de MANGOPAY. L\u2019Utilisateur accepte que la Soci\u00e9t\u00e9 puisse initier ces d\u00e9marches en son nom, \u00e9tant pr\u00e9cis\u00e9 que lorsque la r\u00e9glementation ou MANGOPAY l\u2019exigent, l\u2019action concern\u00e9e ne pourra \u00eatre r\u00e9alis\u00e9e qu\u2019apr\u00e8s validation ou consentement expr\u00e8s de l\u2019Utilisateur via les interfaces ou parcours s\u00e9curis\u00e9s mis \u00e0 disposition par MANGOPAY.<\/p>   <p class=\"wp-block-paragraph\">L\u2019Utilisateur reconna\u00eet enfin avoir \u00e9t\u00e9 inform\u00e9 que les services de paiement sont fournis par MANGOPAY, prestataire de services de paiement distinct de la Soci\u00e9t\u00e9, et d\u00e9clare accepter les conditions g\u00e9n\u00e9rales de MANGOPAY applicables \u00e0 ces services.<\/p>   <p class=\"wp-block-paragraph\"><strong>Article 7 : Livraison Zone de livraison<\/strong><\/p>   <p class=\"wp-block-paragraph\">La zone de livraison comprend uniquement la France M\u00e9tropolitaine et la Corse. Sont exclus de la zone de livraison \u00e0 domicile : les DOM-TOM et les pays \u00e9trangers.<\/p>   <ul class=\"wp-block-list\"> <li>Mode de livraison et D\u00e9lais<\/li> <\/ul>   <p class=\"wp-block-paragraph\">Un mode de livraison est actuellement disponible:<\/p>   <p class=\"wp-block-paragraph\">Livraison en Point Relais chez le V\u00e9t\u00e9rinaire du Client en 2 \u00e0 4 jours ouvr\u00e9s en France m\u00e9tropolitaine; 2 \u00e0 10 jours ouvr\u00e9s pour l\u2019acheminement en Corse. Retard de livraison<\/p>   <p class=\"wp-block-paragraph\">Conform\u00e9ment au Code de la consommation, le Vendeur s\u2019engage \u00e0 livrer les biens sans retard injustifi\u00e9 et au plus tard trente jours apr\u00e8s la conclusion du contrat. Si le Client subit un retard de livraison de plus de 5 jours ouvr\u00e9s par rapport au d\u00e9lai annonc\u00e9 dans les conditions g\u00e9n\u00e9rales de vente, il est invit\u00e9 \u00e0 contacter le SAV. Le service apr\u00e8s-vente du Vendeur mettra tout en oeuvre pour acheminer le Client dans les meilleurs d\u00e9lais. En cas de manquement du Vendeur de plus de trente jours apr\u00e8s la conclusion du contrat, le Client dispose de la possibilit\u00e9 de r\u00e9soudre le contrat dans les conditions et modalit\u00e9s d\u00e9finies \u00e0 l\u2019Article L 138-2 du Code de la consommation. Le Vendeur pourra alors proc\u00e9der \u00e0 une \u00e9ventuelle r\u00e9exp\u00e9dition ou un remboursement suivant le choix du Client. Le remboursement sera limit\u00e9 au montant de la commande et ne donne pas droit \u00e0 des dommages et int\u00e9r\u00eats de la part du Vendeur.<\/p>   <ul class=\"wp-block-list\"> <li>Tarifs de livraison<\/li> <\/ul>   <p class=\"wp-block-paragraph\">La livraison en point relais chez les v\u00e9t\u00e9rinaires du client est gratuite.<\/p>   <ul class=\"wp-block-list\"> <li>R\u00e9ception de la commande<\/li> <\/ul>   <p class=\"wp-block-paragraph\">En cas de livraison en Point Relais (chez le V\u00e9t\u00e9rinaire), le colis sera disponible aux heures d\u2019ouverture de la structure v\u00e9t\u00e9rinaire r\u00e9f\u00e9rente. La commande y restera disponible pendant 15 jours. Le client doit s\u2019assurer \u00e0 la livraison de l\u2019absence de d\u00e9t\u00e9rioration du colis. En cas de probl\u00e8me la livraison doit \u00eatre refus\u00e9e et un mail doit \u00eatre envoy\u00e9e au Vendeur. Limite de responsabilit\u00e9 :<\/p>   <p class=\"wp-block-paragraph\">En cas d\u2019acceptation d\u2019un colis d\u00e9t\u00e9rior\u00e9, le Vendeur se d\u00e9gage de toute responsabilit\u00e9 La Soci\u00e9t\u00e9 ne saurait \u00eatre tenu pour responsable en cas de perturbation, gr\u00e8ve totale ou partielle des transporteurs Le Client a la responsabilit\u00e9 de s\u2019assurer de la conformit\u00e9 de la livraison selon les instructions re\u00e7ues dans le mail d\u2019information d\u2019exp\u00e9dition par la Soci\u00e9t\u00e9<\/p>   <p class=\"wp-block-paragraph\"><strong>Article 8 : D\u00e9lai de r\u00e9tractation \/ Satisfait ou Rembours\u00e9 <\/strong><\/p>   <p class=\"wp-block-paragraph\">Conform\u00e9ment \u00e0 l\u2019article L. 121-20 du Code de la consommation, \u00ab le consommateur dispose d\u2019un d\u00e9lai de quatorze jours francs pour exercer son droit de r\u00e9tractation sans avoir \u00e0 justifier de motifs ni \u00e0 payer de p\u00e9nalit\u00e9s, \u00e0 l\u2019exception, le cas \u00e9ch\u00e9ant, des frais de retour \u00bb. Le d\u00e9lai court \u00e0 compter de la r\u00e9ception de la commande chez le V\u00e9t\u00e9rinaire. Le droit de r\u00e9tractation peut \u00eatre exerc\u00e9 en contactant le V\u00e9t\u00e9rinaire r\u00e9f\u00e9rent ou la Soci\u00e9t\u00e9. En cas d\u2019exercice du droit de r\u00e9tractation dans le d\u00e9lai susmentionn\u00e9, seul le prix du ou des produits achet\u00e9s et les frais d\u2019envoi seront rembours\u00e9s, les frais de retour restent \u00e0 la charge du Client.<\/p>   <p class=\"wp-block-paragraph\">La Soci\u00e9t\u00e9 s\u2019engage \u00e0 conc\u00e9der un remboursement de l\u2019article sous r\u00e9serve que celui-ci soit retourn\u00e9 intact dans son emballage d\u2019origine, sans trace d\u2019utilisation.<\/p>   <p class=\"wp-block-paragraph\"><strong>Article 9 : Service Apr\u00e8s Vente \/ R\u00e9clamations <\/strong><\/p>   <p class=\"wp-block-paragraph\">Le Service Apr\u00e8s Vente est assur\u00e9 par le V\u00e9t\u00e9rinaire. La structure V\u00e9t\u00e9rinaire reste votre interlocutrice principale dans les conseils en nutrition de vos animaux. Elle vous accompagne au quotidien dans vos d\u00e9marches sur le site vetorino.com pour vos achats, \u00e9changes et retours. L\u2019Acheteur peut aussi pr\u00e9senter toute r\u00e9clamation en contactant directement la Soci\u00e9t\u00e9. Notre service client est ouvert du Lundi au Vendredi de 10h \u00e0 18h. Les demandes effectu\u00e9es le week-end, nuits et jours f\u00e9ri\u00e9s seront trait\u00e9es en priorit\u00e9 d\u00e8s l\u2019ouverture du service client. Les retours pour cause de r\u00e9tractation ou d\u2019erreur sur la commande sont \u00e0 effectuer par d\u00e9p\u00f4t chez le V\u00e9t\u00e9rinaire du client aupr\u00e8s de qui il a r\u00e9cup\u00e9r\u00e9 sa commande ou par colis \u00e0 celui-ci \u00e0 la charge du Client.<\/p>   <p class=\"wp-block-paragraph\"><strong>Article 10 : Responsabilit\u00e9 <\/strong><\/p>   <p class=\"wp-block-paragraph\">Le Vendeur ne peut \u00eatre tenu pour responsable des dommages de toute nature qui pourraient r\u00e9sulter d\u2019une mauvaise utilisation des articles livr\u00e9s au Client. Le Vendeur ne peut \u00eatre tenu pour responsable des \u00e9ventuelles modifications apport\u00e9es par les fabricants et\/ou les fournisseurs dans la composition des articles vendus sur le site vetorino.com. En tout \u00e9tat de cause, la responsabilit\u00e9 du Vendeur sera limit\u00e9e au montant de la commande. La Soci\u00e9t\u00e9 n\u2019\u00e9tant pas propri\u00e9taire du ou des Produits et op\u00e9rant comme une place de march\u00e9 sa responsabilit\u00e9 ne pourra pas \u00eatre retenue dans le cadre de ce contrat. Le Client d\u00e9clare \u00eatre client de la clinique V\u00e9t\u00e9rinaire aupr\u00e8s de laquelle il a pass\u00e9 commande et suivre les conseils du v\u00e9t\u00e9rinaire d\u00e9sign\u00e9 pour cette commande. Le v\u00e9t\u00e9rinaire d\u00e9sign\u00e9 se r\u00e9serve le droit, apr\u00e8s v\u00e9rification, de refuser la d\u00e9livrance de la commande du Client en cas d\u2019inexactitude de cette d\u00e9claration.<\/p>   <p class=\"wp-block-paragraph\"><strong>Article 11 : Droits de propri\u00e9t\u00e9 intellectuelle <\/strong><\/p>   <p class=\"wp-block-paragraph\">Les marques, noms de domaines, produits, logiciels, images, vid\u00e9os, textes ou plus g\u00e9n\u00e9ralement toute information objet de droits de propri\u00e9t\u00e9 intellectuelle sont et restent la propri\u00e9t\u00e9 exclusive de la Soci\u00e9t\u00e9. Aucune cession de droits de propri\u00e9t\u00e9 intellectuelle n\u2019est r\u00e9alis\u00e9e au travers des pr\u00e9sentes CGV. Toute reproduction totale ou partielle, modification ou utilisation de ces biens pour quelque motif que ce soit est strictement interdite.<\/p>   <p class=\"wp-block-paragraph\"><strong>Article 12 : Force majeure <\/strong><\/p>   <p class=\"wp-block-paragraph\">L\u2019ex\u00e9cution des obligations du Vendeur au terme des pr\u00e9sentes est suspendue en cas de survenance d\u2019un cas fortuit ou de force majeure qui en emp\u00eacherait l\u2019ex\u00e9cution. Le Vendeur avisera le client de la survenance d\u2019un tel \u00e9v\u00e8nement d\u00e8s que possible.<\/p>   <p class=\"wp-block-paragraph\"><strong>Article 13 : Droit applicable <\/strong><\/p>   <p class=\"wp-block-paragraph\">Les pr\u00e9sentes Conditions G\u00e9n\u00e9rales de Vente sont soumises \u00e0 la Loi Fran\u00e7aise. Le Client, le V\u00e9t\u00e9rinaire et la Soci\u00e9t\u00e9 privil\u00e9gieront toujours une solution amiable avant toute action en justice. En cas de litige, seul le tribunal de Paris sera comp\u00e9tent.<\/p>   <p class=\"wp-block-paragraph\"><strong>Article 14 : Protection des donn\u00e9es personnelles <\/strong><\/p>   <p class=\"wp-block-paragraph\">Conform\u00e9ment au R\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es (RGPD applicable au 25 mai 2018), le Client dispose d\u2019un droit d\u2019acc\u00e8s, de modification, de rectification des donn\u00e9es qui le concernent. Ce droit peut \u00eatre exerc\u00e9 en contactant la Soci\u00e9t\u00e9:<\/p>   <p class=\"wp-block-paragraph\">par e-mail : <a href=\"mailto:contact@vetorino.com\">contact@vetorino.com<\/a> le client peut \u00e9galement modifier ses coordonn\u00e9es sur le site vetorino.com via la rubrique \u00ab Mon Compte \u00bb La politique de confidentialit\u00e9 d\u00e9taill\u00e9e du site vetorino.com peut \u00eatre consult\u00e9e \u00e0 l\u2019adresse suivante: <a href=\"https:\/\/www.vetorino.com\/boutique\/politique-de-confidentialite\/\">https:\/\/www.vetorino.com\/boutique\/politique-de-confidentialite\/<\/a><\/p>   <p class=\"wp-block-paragraph\">Pour les donn\u00e9es de paiement, vous pouvez exercer vos droits li\u00e9s \u00e0 vos donn\u00e9es personnelles directement aupr\u00e8s de Mangopay notre prestataire de paiement \u00e0 l&#8217;adresse suivante : <a href=\"mailto:dpo.mangopay@mangopay.com\" target=\"_blank\" rel=\"noreferrer noopener\">dpo.mangopay@mangopay.com<\/a>.<\/p>   <p class=\"wp-block-paragraph\"><strong>Article 15 : Garantie l\u00e9gale de conformit\u00e9 <\/strong><\/p>   <p class=\"wp-block-paragraph\">Conform\u00e9ment aux dispositions l\u00e9gales en vigueur, le Vendeur garantit au Client, dans les conditions pr\u00e9vues par les articles L. 217-4 et suivants du Code de la consommation, que le Produit livr\u00e9 est conforme au descriptif figurant sur le site internet de la Soci\u00e9t\u00e9.<\/p>   <p class=\"wp-block-paragraph\"><strong>Article 16 : Garantie des vices cach\u00e9s <\/strong><\/p>   <p class=\"wp-block-paragraph\">Conform\u00e9ment aux dispositions l\u00e9gales en vigueur, le Vendeur garantit au Client, dans les conditions pr\u00e9vues par les articles 1641 et suivants du Code civil, que le Produit livr\u00e9 est exempt de vices cach\u00e9s.<\/p>   <p class=\"wp-block-paragraph\"><strong>Article 17 : Dispositions diverses <\/strong><\/p>   <p class=\"wp-block-paragraph\">Les pr\u00e9sentes Conditions G\u00e9n\u00e9rales de Vente expriment l\u2019int\u00e9gralit\u00e9 des obligations des parties. Aucune addition, modification, compl\u00e9ment, ni stipulation contraire n\u2019aura cours entre les parties. Toute clause des pr\u00e9sentes Conditions G\u00e9n\u00e9rales de Vente jug\u00e9e nulle ou non \u00e9crite par une d\u00e9cision de justice sera r\u00e9put\u00e9e non \u00e9crite, mais n\u2019entra\u00eenera pas la nullit\u00e9 des autres clauses. Les parties conviennent que les pr\u00e9sentes Conditions G\u00e9n\u00e9rales de Vente sont r\u00e9dig\u00e9es en langue fran\u00e7aise. Dans le cas o\u00f9 elles seraient traduites en une ou plusieurs langues \u00e9trang\u00e8res, seul le texte fran\u00e7ais ferait foi en cas de litige. Les pr\u00e9sentes Conditions G\u00e9n\u00e9rales de Vente sont accessibles sur le site internet de la Soci\u00e9t\u00e9 \u00e0 l\u2019adresse suivante : <a href=\"https:\/\/www.vetorino.com\/boutique\/conditions-generales-de-vente\/\">https:\/\/www.vetorino.com\/boutique\/conditions-generales-de-vente\/<\/a>. Les parties conviennent que leurs relations ne sauraient \u00eatre r\u00e9gies par les usages de la commande.<\/p>   <p class=\"wp-block-paragraph\">En cas de difficult\u00e9s dans l\u2019interpr\u00e9tation des pr\u00e9sentes Conditions G\u00e9n\u00e9rales de Vente, les parties se rapprocheront pour trouver une solution amiable.<\/p> ","protected":false},"excerpt":{"rendered":"<p>SOMMAIRE CGV \u2013 Conditions G\u00e9n\u00e9rales de Vente Entre, la SAS Woofie, 47 route du Ch\u00eane Rogneux, 78490 Grosrouvre, au Capital de 16 000\u20ac, SIRET 85171272900033, ci-apr\u00e8s la \u00ab Soci\u00e9t\u00e9 \u00bb d\u2019une part ; Et, la personne physique ou morale proc\u00e9dant \u00e0 l\u2019achat de produits de la Soci\u00e9t\u00e9, ci-apr\u00e8s, \u00ab l\u2019Acheteur \u00bb, ou \u00ab le Client [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-81934","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Conditions g\u00e9n\u00e9rales de vente - V\u00e9torino<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.vetorino.com\/boutique\/conditions-generales-de-vente\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conditions g\u00e9n\u00e9rales de vente - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"SOMMAIRE CGV \u2013 Conditions G\u00e9n\u00e9rales de Vente Entre, la SAS Woofie, 47 route du Ch\u00eane Rogneux, 78490 Grosrouvre, au Capital de 16 000\u20ac, SIRET 85171272900033, ci-apr\u00e8s la \u00ab Soci\u00e9t\u00e9 \u00bb d\u2019une part ; Et, la personne physique ou morale proc\u00e9dant \u00e0 l\u2019achat de produits de la Soci\u00e9t\u00e9, ci-apr\u00e8s, \u00ab l\u2019Acheteur \u00bb, ou \u00ab le Client [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/boutique\/conditions-generales-de-vente\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-15T13:38:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/09\/logo-vetorino-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"539\" \/>\n\t<meta property=\"og:image:height\" content=\"224\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/conditions-generales-de-vente\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/conditions-generales-de-vente\\\/\",\"name\":\"Conditions g\u00e9n\u00e9rales de vente - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"datePublished\":\"2020-04-22T21:35:29+00:00\",\"dateModified\":\"2026-04-15T13:38:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/conditions-generales-de-vente\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/conditions-generales-de-vente\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/conditions-generales-de-vente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conditions g\u00e9n\u00e9rales de vente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conditions g\u00e9n\u00e9rales de vente - V\u00e9torino","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.vetorino.com\/boutique\/conditions-generales-de-vente\/","og_locale":"fr_FR","og_type":"article","og_title":"Conditions g\u00e9n\u00e9rales de vente - V\u00e9torino","og_description":"SOMMAIRE CGV \u2013 Conditions G\u00e9n\u00e9rales de Vente Entre, la SAS Woofie, 47 route du Ch\u00eane Rogneux, 78490 Grosrouvre, au Capital de 16 000\u20ac, SIRET 85171272900033, ci-apr\u00e8s la \u00ab Soci\u00e9t\u00e9 \u00bb d\u2019une part ; Et, la personne physique ou morale proc\u00e9dant \u00e0 l\u2019achat de produits de la Soci\u00e9t\u00e9, ci-apr\u00e8s, \u00ab l\u2019Acheteur \u00bb, ou \u00ab le Client [&hellip;]","og_url":"https:\/\/www.vetorino.com\/boutique\/conditions-generales-de-vente\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-04-15T13:38:47+00:00","og_image":[{"width":539,"height":224,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/09\/logo-vetorino-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/conditions-generales-de-vente\/","url":"https:\/\/www.vetorino.com\/boutique\/conditions-generales-de-vente\/","name":"Conditions g\u00e9n\u00e9rales de vente - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"datePublished":"2020-04-22T21:35:29+00:00","dateModified":"2026-04-15T13:38:47+00:00","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/conditions-generales-de-vente\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/conditions-generales-de-vente\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/conditions-generales-de-vente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Conditions g\u00e9n\u00e9rales de vente"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/boutique\/wp-json\/wp\/v2\/pages\/81934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/boutique\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.vetorino.com\/boutique\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/boutique\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/boutique\/wp-json\/wp\/v2\/comments?post=81934"}],"version-history":[{"count":11,"href":"https:\/\/www.vetorino.com\/boutique\/wp-json\/wp\/v2\/pages\/81934\/revisions"}],"predecessor-version":[{"id":1664606,"href":"https:\/\/www.vetorino.com\/boutique\/wp-json\/wp\/v2\/pages\/81934\/revisions\/1664606"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/boutique\/wp-json\/wp\/v2\/media?parent=81934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}