{"id":1359858,"date":"2025-07-02T12:00:00","date_gmt":"2025-07-02T10:00:00","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/?p=1359858"},"modified":"2025-08-05T15:32:08","modified_gmt":"2025-08-05T13:32:08","slug":"chien-selles-molles","status":"publish","type":"post","link":"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/2025\/07\/02\/chien-selles-molles\/","title":{"rendered":"Mon chien a des selles molles : et si \u00e7a venait de son alimentation ?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1359858\" class=\"elementor elementor-1359858\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4747b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4747b9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e24be0c\" data-id=\"e24be0c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bf12388 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bf12388\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-540852e\" data-id=\"540852e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31aaa21 elementor-widget elementor-widget-text-editor\" data-id=\"31aaa21\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<section data-id=\"8j8qvkr\" data-element_type=\"section\"><div data-id=\"tcv8rwn\" data-element_type=\"heading.default\">Mon chien a des selles molles : et si \u00e7a venait de son alimentation ?<br \/><!-- notionvc: 3b4d4ca9-e767-4365-9375-bf8f4630222f --><\/div><\/section>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86b51a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86b51a2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca49f12\" data-id=\"ca49f12\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d92d7f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2d92d7f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il arrive que les selles de votre chien deviennent molles ou irr\u00e9guli\u00e8res sans raison \u00e9vidente. Pourtant, dans de nombreux cas, l\u2019alimentation est en cause. Un changement de croquettes mal g\u00e9r\u00e9, une formule inadapt\u00e9e, ou encore des ingr\u00e9dients peu digestes peuvent perturber son transit.<\/p><p>Avant de s\u2019inqui\u00e9ter, il est utile de se pencher sur sa gamelle.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37f3744 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37f3744\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5abeb12\" data-id=\"5abeb12\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48e3ba0 elementor-widget elementor-widget-heading\" data-id=\"48e3ba0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Les principales causes alimentaires des troubles digestifs<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-448f199 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"448f199\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Parmi les erreurs fr\u00e9quentes :<\/p><p>&#8211; Un <strong>changement de croquettes trop rapide<\/strong>, sans transition<br \/>&#8211; Des restes de table ou des <strong>aliments trop gras<\/strong><br \/>&#8211; Un <strong>exc\u00e8s de friandises<\/strong> mal adapt\u00e9es<br \/>&#8211; Ingestion de <strong>d\u00e9chets ou<\/strong> <strong>nourriture suspecte<\/strong> en balade<br \/>&#8211; Une alimentation mal dig\u00e9r\u00e9e ou contenant des <strong>allerg\u00e8nes<\/strong> (gluten, certaines prot\u00e9ines, etc.)<\/p><p>Un chien sensible peut r\u00e9agir fortement \u00e0 ces variations, avec des selles molles, des gaz ou m\u00eame des diarrh\u00e9es l\u00e9g\u00e8res. Ces signes doivent vous alerter.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e442a3b elementor-widget elementor-widget-image\" data-id=\"e442a3b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1536\" height=\"864\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/selles-molles-alimentation-chien-1536x864.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-1359878\" alt=\"selles molles alimentation chien\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/selles-molles-alimentation-chien-1536x864.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/selles-molles-alimentation-chien-300x169.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/selles-molles-alimentation-chien-1024x576.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/selles-molles-alimentation-chien-768x432.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/selles-molles-alimentation-chien-2048x1152.jpg 2048w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/selles-molles-alimentation-chien-555x312.jpg 555w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5b291e elementor-widget elementor-widget-heading\" data-id=\"c5b291e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comment am\u00e9liorer son confort digestif ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5245d3d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"5245d3d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pour r\u00e9tablir un bon \u00e9quilibre, il est souvent conseill\u00e9 de \u00a0revenir \u00e0 une alimentation plus simple, riche en fibres et en ingr\u00e9dients digestes. Vous pouvez \u00e9galement privil\u00e9gier des croquettes v\u00e9t\u00e9rinaires formul\u00e9es pour les chiens sensibles. Dans tous les cas, respectez une transition alimentaire sur plusieurs jours.<\/p><p>Vous trouverez une s\u00e9lection de croquettes et p\u00e2t\u00e9es recommand\u00e9es par les v\u00e9t\u00e9rinaires pour les chiens \u00e0 digestion fragile sur Vetorino. Qualit\u00e9, s\u00e9curit\u00e9 et livraison rapide garanties chez votre v\u00e9t\u00e9rinaire.<\/p><p>Si les troubles persistent (diarrh\u00e9es, fatigue, perte d\u2019app\u00e9tit), consultez votre v\u00e9t\u00e9rinaire pour exclure une cause m\u00e9dicale sous-jacente.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1570360 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1570360\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/pierrebenite-69310\/boutique\/product-category\/chien\/?s&#038;maladie=troubles-digestifs&#038;swcfpc=1\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir tous les produits pour le confort digestif<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Mon chien a des selles molles : et si \u00e7a venait de son alimentation ? Il arrive que les selles de votre chien deviennent molles ou irr\u00e9guli\u00e8res sans raison \u00e9vidente. Pourtant, dans de nombreux cas, l\u2019alimentation est en cause. Un changement de croquettes mal g\u00e9r\u00e9, une formule inadapt\u00e9e, ou encore des ingr\u00e9dients peu digestes peuvent [&hellip;]<\/p>\n","protected":false},"author":68707,"featured_media":1359864,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[14088,14087,14094],"tags":[],"class_list":["post-1359858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentation-chien","category-chien","category-sante-chien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Chien selles molles : et si \u00e7a venait de son alimentation ?<\/title>\n<meta name=\"description\" content=\"Il arrive que les selles de votre chien deviennent molles sans raison \u00e9vidente. Pourtant, l\u2019alimentation est souvent en cause.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chien selles molles : et si \u00e7a venait de son alimentation ?\" \/>\n<meta property=\"og:description\" content=\"Il arrive que les selles de votre chien deviennent molles sans raison \u00e9vidente. Pourtant, l\u2019alimentation est souvent en cause.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/2025\/07\/02\/chien-selles-molles\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-02T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-05T13:32:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/chien-selles-molles.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1905\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Clemence Sully\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Clemence Sully\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/07\\\/02\\\/chien-selles-molles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/07\\\/02\\\/chien-selles-molles\\\/\"},\"author\":{\"name\":\"Clemence Sully\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/9bd231449b5dab066d32dab7d241eb4a\"},\"headline\":\"Mon chien a des selles molles : et si \u00e7a venait de son alimentation ?\",\"datePublished\":\"2025-07-02T10:00:00+00:00\",\"dateModified\":\"2025-08-05T13:32:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/07\\\/02\\\/chien-selles-molles\\\/\"},\"wordCount\":307,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/07\\\/02\\\/chien-selles-molles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/chien-selles-molles.jpg\",\"articleSection\":[\"Alimentation pour chien\",\"Chien\",\"Sant\u00e9 pour chien\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/07\\\/02\\\/chien-selles-molles\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/07\\\/02\\\/chien-selles-molles\\\/\",\"name\":\"Chien selles molles : et si \u00e7a venait de son alimentation ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/07\\\/02\\\/chien-selles-molles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/07\\\/02\\\/chien-selles-molles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/chien-selles-molles.jpg\",\"datePublished\":\"2025-07-02T10:00:00+00:00\",\"dateModified\":\"2025-08-05T13:32:08+00:00\",\"description\":\"Il arrive que les selles de votre chien deviennent molles sans raison \u00e9vidente. Pourtant, l\u2019alimentation est souvent en cause.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/07\\\/02\\\/chien-selles-molles\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/07\\\/02\\\/chien-selles-molles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/07\\\/02\\\/chien-selles-molles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/chien-selles-molles.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/chien-selles-molles.jpg\",\"width\":1905,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/07\\\/02\\\/chien-selles-molles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chien\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/champs-sur-marne-77420\\\/boutique\\\/category\\\/chien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mon chien a des selles molles : et si \u00e7a venait de son alimentation ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/9bd231449b5dab066d32dab7d241eb4a\",\"name\":\"Clemence Sully\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g\",\"caption\":\"Clemence Sully\"},\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/athismons-91200\\\/boutique\\\/author\\\/clemence-sully\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chien selles molles : et si \u00e7a venait de son alimentation ?","description":"Il arrive que les selles de votre chien deviennent molles sans raison \u00e9vidente. Pourtant, l\u2019alimentation est souvent en cause.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Chien selles molles : et si \u00e7a venait de son alimentation ?","og_description":"Il arrive que les selles de votre chien deviennent molles sans raison \u00e9vidente. Pourtant, l\u2019alimentation est souvent en cause.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/2025\/07\/02\/chien-selles-molles\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_published_time":"2025-07-02T10:00:00+00:00","article_modified_time":"2025-08-05T13:32:08+00:00","og_image":[{"width":1905,"height":450,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/chien-selles-molles.jpg","type":"image\/jpeg"}],"author":"Clemence Sully","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Clemence Sully","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vetorino.com\/boutique\/2025\/07\/02\/chien-selles-molles\/#article","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/07\/02\/chien-selles-molles\/"},"author":{"name":"Clemence Sully","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/9bd231449b5dab066d32dab7d241eb4a"},"headline":"Mon chien a des selles molles : et si \u00e7a venait de son alimentation ?","datePublished":"2025-07-02T10:00:00+00:00","dateModified":"2025-08-05T13:32:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/07\/02\/chien-selles-molles\/"},"wordCount":307,"publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/07\/02\/chien-selles-molles\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/chien-selles-molles.jpg","articleSection":["Alimentation pour chien","Chien","Sant\u00e9 pour chien"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/2025\/07\/02\/chien-selles-molles\/","url":"https:\/\/www.vetorino.com\/boutique\/2025\/07\/02\/chien-selles-molles\/","name":"Chien selles molles : et si \u00e7a venait de son alimentation ?","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/07\/02\/chien-selles-molles\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/07\/02\/chien-selles-molles\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/chien-selles-molles.jpg","datePublished":"2025-07-02T10:00:00+00:00","dateModified":"2025-08-05T13:32:08+00:00","description":"Il arrive que les selles de votre chien deviennent molles sans raison \u00e9vidente. Pourtant, l\u2019alimentation est souvent en cause.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/07\/02\/chien-selles-molles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/2025\/07\/02\/chien-selles-molles\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/2025\/07\/02\/chien-selles-molles\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/chien-selles-molles.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/06\/chien-selles-molles.jpg","width":1905,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/2025\/07\/02\/chien-selles-molles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Chien","item":"https:\/\/www.vetorino.com\/veterinaire\/champs-sur-marne-77420\/boutique\/category\/chien\/"},{"@type":"ListItem","position":3,"name":"Mon chien a des selles molles : et si \u00e7a venait de son alimentation ?"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]},{"@type":"Person","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/9bd231449b5dab066d32dab7d241eb4a","name":"Clemence Sully","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g","caption":"Clemence Sully"},"url":"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/author\/clemence-sully\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/wp-json\/wp\/v2\/posts\/1359858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/wp-json\/wp\/v2\/users\/68707"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/wp-json\/wp\/v2\/comments?post=1359858"}],"version-history":[{"count":8,"href":"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/wp-json\/wp\/v2\/posts\/1359858\/revisions"}],"predecessor-version":[{"id":1441255,"href":"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/wp-json\/wp\/v2\/posts\/1359858\/revisions\/1441255"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/wp-json\/wp\/v2\/media\/1359864"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/wp-json\/wp\/v2\/media?parent=1359858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/wp-json\/wp\/v2\/categories?post=1359858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/wp-json\/wp\/v2\/tags?post=1359858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}