{"id":119174,"date":"2020-10-05T19:00:50","date_gmt":"2020-10-05T17:00:50","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/specific-cgw-senior-all-breeds-2\/"},"modified":"2025-11-04T16:21:00","modified_gmt":"2025-11-04T15:21:00","slug":"specific-cgw-senior-all-breeds-2","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/product\/specific-cgw-senior-all-breeds-2\/","title":{"rendered":"CGW Senior All Breeds \u2013 chien"},"content":{"rendered":"<p><strong>Chien CGW Senior est un aliment complet et \u00e9quilibr\u00e9 pour le chien senior de toute race. Il couvre tous les besoins nutritionnels du chien senior.<br \/>\n<\/strong><\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Alimentation quotidienne du chien senior de toute race (\u00e0 partir de 8 ans pour les petites races, \u00e0 partir de 7 ans pour les races moyennes, \u00e0 partir de 6 ans pour les grandes races et \u00e0 partir de 5 ans pour les races g\u00e9antes), st\u00e9rilis\u00e9 ou non.<\/li>\n<li>SPECIFIC\u00ae CGW Senior All Breeds est un soutien nutritionnel \u00e0 la sant\u00e9 du chien senior.<\/li>\n<\/ul>\n<p><strong>Bienfaits essentiels :<\/strong><\/p>\n<ul>\n<li>Les teneurs mod\u00e9r\u00e9ment r\u00e9duites en prot\u00e9ines et en phosphore et la teneur contr\u00f4l\u00e9e en sodium\u00a0<strong>soutiennent la fonction r\u00e9nale<\/strong>\u00a0des chiens seniors. La valeur biologique \u00e9lev\u00e9e des prot\u00e9ines\u00a0<strong>assure un apport suffisant d\u2019acides amin\u00e9s essentiels.<\/strong><\/li>\n<li>Les acides gras Om\u00e9ga-3 EPA et DHA (issus d\u2019huile de poisson) ont un\u00a0<strong>effet b\u00e9n\u00e9fique sur la sant\u00e9 de la peau et du pelage, ainsi que sur les cartilages et la mobilit\u00e9 des articulations chez les chiens seniors<\/strong>.<\/li>\n<li>L\u2019aliment, complet et \u00e9quilibr\u00e9, a une densit\u00e9 \u00e9nerg\u00e9tique mod\u00e9r\u00e9e qui<strong>\u00a0favorise le maintien du poids optimal<\/strong>\u00a0chez les chiens seniors, dont le besoin \u00e9nerg\u00e9tique peut \u00eatre r\u00e9duit.<\/li>\n<li>La taurine est un nutriment n\u00e9cessaire \u00e0 de nombreux aspects du m\u00e9tabolisme. Elle\u00a0<strong>participe notamment au bon fonctionnement du myocarde et soutient ainsi la fonction cardiaque<\/strong>\u00a0des chiens seniors.<\/li>\n<li>Contient des \u00df-1,3\/1,6-glucanes issus de levure boulang\u00e8re, qui peuvent se lier aux r\u00e9cepteurs des macrophages et ainsi\u00a0<strong>stimuler le syst\u00e8me immunitaire et favoriser la r\u00e9ponse immunitaire<\/strong>.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p><strong>Aliment complet et \u00e9quilibr\u00e9 pour le chien senior de toute race. Il couvre tous les besoins nutritionnels du chien senior.<br \/>\n<\/strong><\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Alimentation quotidienne du chien senior de toute race (\u00e0 partir de 8 ans pour les petites races, \u00e0 partir de 7 ans pour les races moyennes, \u00e0 partir de 6 ans pour les grandes races et \u00e0 partir de 5 ans pour les races g\u00e9antes), st\u00e9rilis\u00e9 ou non.<\/li>\n<li>SPECIFIC\u00ae CGW Senior All Breeds est un soutien nutritionnel \u00e0 la sant\u00e9 du chien senior.<\/li>\n<\/ul>\n","protected":false},"featured_media":1474383,"template":"","meta":[],"product_cat":[12552,12584,2698],"product_tag":[],"class_list":{"0":"post-119174","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alimentation-du-chien","7":"product_cat-alimentation-premium-pour-chien","8":"product_cat-chien","9":"pa_marque-specific","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CGW Senior All Breeds \u2013 chien Specific - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Aliment complet et \u00e9quilibr\u00e9 pour le chien senior de toute race. Il couvre tous les besoins nutritionnels du chien senior.   Utilisation :   Alimentation quotidienne du chien senior de toute race (\u00e0 partir de 8 ans pour les petites races, \u00e0 partir de 7 ans pour les races moyennes, \u00e0 partir de 6 ans pour les grandes races et \u00e0 partir de 5 ans pour les races g\u00e9antes), st\u00e9rilis\u00e9 ou non.  SPECIFIC\u00ae CGW Senior All Breeds est un soutien nutritionnel \u00e0 la sant\u00e9 du chien senior.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CGW Senior All Breeds \u2013 chien Specific - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Aliment complet et \u00e9quilibr\u00e9 pour le chien senior de toute race. Il couvre tous les besoins nutritionnels du chien senior.   Utilisation :   Alimentation quotidienne du chien senior de toute race (\u00e0 partir de 8 ans pour les petites races, \u00e0 partir de 7 ans pour les races moyennes, \u00e0 partir de 6 ans pour les grandes races et \u00e0 partir de 5 ans pour les races g\u00e9antes), st\u00e9rilis\u00e9 ou non.  SPECIFIC\u00ae CGW Senior All Breeds est un soutien nutritionnel \u00e0 la sant\u00e9 du chien senior.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/product\/specific-cgw-senior-all-breeds-2\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-04T15:21:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/specific-cgw-senior-all-breeds.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"18,61&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-cgw-senior-all-breeds-2\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-cgw-senior-all-breeds-2\\\/\",\"name\":\"CGW Senior All Breeds \u2013 chien Specific - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-cgw-senior-all-breeds-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-cgw-senior-all-breeds-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/specific-cgw-senior-all-breeds.webp\",\"datePublished\":\"2020-10-05T17:00:50+00:00\",\"dateModified\":\"2025-11-04T15:21:00+00:00\",\"description\":\"Aliment complet et \u00e9quilibr\u00e9 pour le chien senior de toute race. Il couvre tous les besoins nutritionnels du chien senior. Utilisation : Alimentation quotidienne du chien senior de toute race (\u00e0 partir de 8 ans pour les petites races, \u00e0 partir de 7 ans pour les races moyennes, \u00e0 partir de 6 ans pour les grandes races et \u00e0 partir de 5 ans pour les races g\u00e9antes), st\u00e9rilis\u00e9 ou non. SPECIFIC\u00ae CGW Senior All Breeds est un soutien nutritionnel \u00e0 la sant\u00e9 du chien senior.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-cgw-senior-all-breeds-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-cgw-senior-all-breeds-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-cgw-senior-all-breeds-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/specific-cgw-senior-all-breeds.webp\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/specific-cgw-senior-all-breeds.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-cgw-senior-all-breeds-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CGW Senior All Breeds \u2013 chien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Specific\" \/>\n<meta property=\"product:price:amount\" content=\"18.61\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"O-76001\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CGW Senior All Breeds \u2013 chien Specific - V\u00e9torino","description":"Aliment complet et \u00e9quilibr\u00e9 pour le chien senior de toute race. Il couvre tous les besoins nutritionnels du chien senior.   Utilisation :   Alimentation quotidienne du chien senior de toute race (\u00e0 partir de 8 ans pour les petites races, \u00e0 partir de 7 ans pour les races moyennes, \u00e0 partir de 6 ans pour les grandes races et \u00e0 partir de 5 ans pour les races g\u00e9antes), st\u00e9rilis\u00e9 ou non.  SPECIFIC\u00ae CGW Senior All Breeds est un soutien nutritionnel \u00e0 la sant\u00e9 du chien senior.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"CGW Senior All Breeds \u2013 chien Specific - V\u00e9torino","og_description":"Aliment complet et \u00e9quilibr\u00e9 pour le chien senior de toute race. Il couvre tous les besoins nutritionnels du chien senior.   Utilisation :   Alimentation quotidienne du chien senior de toute race (\u00e0 partir de 8 ans pour les petites races, \u00e0 partir de 7 ans pour les races moyennes, \u00e0 partir de 6 ans pour les grandes races et \u00e0 partir de 5 ans pour les races g\u00e9antes), st\u00e9rilis\u00e9 ou non.  SPECIFIC\u00ae CGW Senior All Breeds est un soutien nutritionnel \u00e0 la sant\u00e9 du chien senior.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/product\/specific-cgw-senior-all-breeds-2\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2025-11-04T15:21:00+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/specific-cgw-senior-all-breeds.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"18,61&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-cgw-senior-all-breeds-2\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/specific-cgw-senior-all-breeds-2\/","name":"CGW Senior All Breeds \u2013 chien Specific - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-cgw-senior-all-breeds-2\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-cgw-senior-all-breeds-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/specific-cgw-senior-all-breeds.webp","datePublished":"2020-10-05T17:00:50+00:00","dateModified":"2025-11-04T15:21:00+00:00","description":"Aliment complet et \u00e9quilibr\u00e9 pour le chien senior de toute race. Il couvre tous les besoins nutritionnels du chien senior. Utilisation : Alimentation quotidienne du chien senior de toute race (\u00e0 partir de 8 ans pour les petites races, \u00e0 partir de 7 ans pour les races moyennes, \u00e0 partir de 6 ans pour les grandes races et \u00e0 partir de 5 ans pour les races g\u00e9antes), st\u00e9rilis\u00e9 ou non. SPECIFIC\u00ae CGW Senior All Breeds est un soutien nutritionnel \u00e0 la sant\u00e9 du chien senior.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-cgw-senior-all-breeds-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/specific-cgw-senior-all-breeds-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-cgw-senior-all-breeds-2\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/specific-cgw-senior-all-breeds.webp","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/specific-cgw-senior-all-breeds.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-cgw-senior-all-breeds-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"CGW Senior All Breeds \u2013 chien"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Specific","product_price_amount":"18.61","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"O-76001","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/wp-json\/wp\/v2\/product\/119174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/wp-json\/wp\/v2\/media\/1474383"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/wp-json\/wp\/v2\/media?parent=119174"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/wp-json\/wp\/v2\/product_cat?post=119174"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/athismons-91200\/boutique\/wp-json\/wp\/v2\/product_tag?post=119174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}