{"id":708696,"date":"2023-10-03T12:21:18","date_gmt":"2023-10-03T10:21:18","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/?post_type=product&#038;p=708696"},"modified":"2025-08-25T09:43:12","modified_gmt":"2025-08-25T07:43:12","slug":"specific-chien-ciw-digestive-support-barquettes-2","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/avoine-37420\/boutique\/product\/specific-chien-ciw-digestive-support-barquettes-2\/","title":{"rendered":"CIW Digestive Support &#8211; chien"},"content":{"rendered":"<p><strong>Aliment di\u00e9t\u00e9tique complet pour chien, permettant de diminuer les troubles aigus de l&#8217;absorption intestinale et de compenser la maldigestion et l&#8217;insuffisance pancr\u00e9atique exocrine.<\/strong><\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Affections gastro-intestinales aigu\u00ebs ou chroniques accompagn\u00e9es de diarrh\u00e9e, vomissements et\/ou flatulences.<\/li>\n<li>Insuffisance pancr\u00e9atique exocrine.<\/li>\n<li>Malabsorption, maldigestion.<\/li>\n<li>Prolif\u00e9ration bact\u00e9rienne dans l\u2019intestin gr\u00eale.<\/li>\n<li>Colite.<\/li>\n<li>Convalescence.<\/li>\n<\/ul>\n<p><strong>Bienfaits essentiels :<\/strong><\/p>\n<ul>\n<li>Les ingr\u00e9dients hautement digestibles compensent l\u2019activit\u00e9 enzymatique intestinale r\u00e9duite et assurent l\u2019absorption optimale des nutriments.\u00a0<strong>L\u2019aliment convient ainsi parfaitement aux chiens souffrant d\u2019affections gastrointestinales aigu\u00ebs ou chroniques \u00e0 l\u2019origine de diarrh\u00e9e, vomissements et\/ou flatulences.<\/strong><\/li>\n<li>Les teneurs \u00e9lev\u00e9es en min\u00e9raux et en vitamines liposolubles<strong>\u00a0compensent les troubles de l\u2019absorption au niveau du tube digestif<\/strong>. Le taux \u00e9lev\u00e9 d\u2019\u00e9lectrolytes\u00a0<strong>compense les pertes accrues pendant les \u00e9pisodes de diarrh\u00e9e et de vomissements<\/strong>.<\/li>\n<li>Contient des \u00df-1,3\/1,6-glucanes issus de levure boulang\u00e8re, qui peuvent se lier aux r\u00e9cepteurs des macrophages et ainsi\u00a0<strong>stimuler le syst\u00e8me immunitaire et favoriser la r\u00e9ponse immunitaire<\/strong>. L\u2019aliment contient \u00e9galement des mannan-oligo-saccharides (MOS) qui peuvent se lier aux bact\u00e9ries pathog\u00e8nes et ainsi les emp\u00eacher de se fixer \u00e0 la paroi intestinale. Les MOS<strong>\u00a0stimulent \u00e9galement l\u2019immunit\u00e9 locale du tractus intestinal.<\/strong><\/li>\n<li>Le psyllium est une fibre soluble mucilagineuse qui a la capacit\u00e9 d\u2019absorber plusieurs fois son poids en eau. Il est connu pour son<strong>\u00a0effet b\u00e9n\u00e9fique sur la r\u00e9gulation du transit intestinal et pour son action protectrice sur la muqueuse intestinale<\/strong><\/li>\n<li>Les extraits de Yucca\u00a0<strong>r\u00e9duisent la production de flatulences et l\u2019odeur des selles.<\/strong><\/li>\n<\/ul>\n<p><strong>Cet aliment est destin\u00e9 \u00e0 la prise en charge nutritionnelle d\u2019une maladie. Pour la sant\u00e9 de votre chien, il est recommand\u00e9 de consulter votre v\u00e9t\u00e9rinaire et de respecter scrupuleusement ses recommandations nutritionnelles.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Aliment di\u00e9t\u00e9tique complet pour chien, permettant de diminuer les troubles aigus de l&#8217;absorption intestinale et de compenser la maldigestion et l&#8217;insuffisance pancr\u00e9atique exocrine.<\/strong><\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Affections gastro-intestinales aigu\u00ebs ou chroniques accompagn\u00e9es de diarrh\u00e9e, vomissements et\/ou flatulences.<\/li>\n<li>Insuffisance pancr\u00e9atique exocrine.<\/li>\n<li>Malabsorption, maldigestion.<\/li>\n<li>Prolif\u00e9ration bact\u00e9rienne dans l\u2019intestin gr\u00eale.<\/li>\n<li>Colite.<\/li>\n<li>Convalescence.<\/li>\n<\/ul>\n<p><strong>Cet aliment est destin\u00e9 \u00e0 la prise en charge nutritionnelle d\u2019une maladie. Il est recommand\u00e9 de consulter votre v\u00e9t\u00e9rinaire.<\/strong><\/p>\n","protected":false},"featured_media":1249451,"template":"","meta":[],"product_cat":[12552,12582,2698],"product_tag":[],"class_list":{"0":"post-708696","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alimentation-du-chien","7":"product_cat-alimentation-medicalisee-pour-chien","8":"product_cat-chien","9":"pa_marque-specific","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CIW Digestive Support - chien Specific - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Aliment di\u00e9t\u00e9tique complet pour chien, permettant de diminuer les troubles aigus de l&#039;absorption intestinale et de compenser la maldigestion et l&#039;insuffisance pancr\u00e9atique exocrine.  Utilisation :   Affections gastro-intestinales aigu\u00ebs ou chroniques accompagn\u00e9es de diarrh\u00e9e, vomissements et\/ou flatulences.  Insuffisance pancr\u00e9atique exocrine.  Malabsorption, maldigestion.  Prolif\u00e9ration bact\u00e9rienne dans l\u2019intestin gr\u00eale.  Colite.  Convalescence.  Cet aliment est destin\u00e9 \u00e0 la prise en charge nutritionnelle d\u2019une maladie. Il est recommand\u00e9 de consulter votre v\u00e9t\u00e9rinaire.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CIW Digestive Support - chien Specific - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Aliment di\u00e9t\u00e9tique complet pour chien, permettant de diminuer les troubles aigus de l&#039;absorption intestinale et de compenser la maldigestion et l&#039;insuffisance pancr\u00e9atique exocrine.  Utilisation :   Affections gastro-intestinales aigu\u00ebs ou chroniques accompagn\u00e9es de diarrh\u00e9e, vomissements et\/ou flatulences.  Insuffisance pancr\u00e9atique exocrine.  Malabsorption, maldigestion.  Prolif\u00e9ration bact\u00e9rienne dans l\u2019intestin gr\u00eale.  Colite.  Convalescence.  Cet aliment est destin\u00e9 \u00e0 la prise en charge nutritionnelle d\u2019une maladie. Il est recommand\u00e9 de consulter votre v\u00e9t\u00e9rinaire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/avoine-37420\/boutique\/product\/specific-chien-ciw-digestive-support-barquettes-2\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-25T07:43:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/specific-ciw-digestive-support.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-chien-ciw-digestive-support-barquettes-2\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-chien-ciw-digestive-support-barquettes-2\\\/\",\"name\":\"CIW Digestive Support - chien Specific - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-chien-ciw-digestive-support-barquettes-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-chien-ciw-digestive-support-barquettes-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/specific-ciw-digestive-support.webp\",\"datePublished\":\"2023-10-03T10:21:18+00:00\",\"dateModified\":\"2025-08-25T07:43:12+00:00\",\"description\":\"Aliment di\u00e9t\u00e9tique complet pour chien, permettant de diminuer les troubles aigus de l'absorption intestinale et de compenser la maldigestion et l'insuffisance pancr\u00e9atique exocrine. Utilisation : Affections gastro-intestinales aigu\u00ebs ou chroniques accompagn\u00e9es de diarrh\u00e9e, vomissements et\\\/ou flatulences. Insuffisance pancr\u00e9atique exocrine. Malabsorption, maldigestion. Prolif\u00e9ration bact\u00e9rienne dans l\u2019intestin gr\u00eale. Colite. Convalescence. Cet aliment est destin\u00e9 \u00e0 la prise en charge nutritionnelle d\u2019une maladie. Il est recommand\u00e9 de consulter votre v\u00e9t\u00e9rinaire.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-chien-ciw-digestive-support-barquettes-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-chien-ciw-digestive-support-barquettes-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-chien-ciw-digestive-support-barquettes-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/specific-ciw-digestive-support.webp\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/specific-ciw-digestive-support.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-chien-ciw-digestive-support-barquettes-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CIW Digestive Support &#8211; chien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Specific\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CIW Digestive Support - chien Specific - V\u00e9torino","description":"Aliment di\u00e9t\u00e9tique complet pour chien, permettant de diminuer les troubles aigus de l'absorption intestinale et de compenser la maldigestion et l'insuffisance pancr\u00e9atique exocrine.  Utilisation :   Affections gastro-intestinales aigu\u00ebs ou chroniques accompagn\u00e9es de diarrh\u00e9e, vomissements et\/ou flatulences.  Insuffisance pancr\u00e9atique exocrine.  Malabsorption, maldigestion.  Prolif\u00e9ration bact\u00e9rienne dans l\u2019intestin gr\u00eale.  Colite.  Convalescence.  Cet aliment est destin\u00e9 \u00e0 la prise en charge nutritionnelle d\u2019une maladie. Il est recommand\u00e9 de consulter votre v\u00e9t\u00e9rinaire.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"CIW Digestive Support - chien Specific - V\u00e9torino","og_description":"Aliment di\u00e9t\u00e9tique complet pour chien, permettant de diminuer les troubles aigus de l'absorption intestinale et de compenser la maldigestion et l'insuffisance pancr\u00e9atique exocrine.  Utilisation :   Affections gastro-intestinales aigu\u00ebs ou chroniques accompagn\u00e9es de diarrh\u00e9e, vomissements et\/ou flatulences.  Insuffisance pancr\u00e9atique exocrine.  Malabsorption, maldigestion.  Prolif\u00e9ration bact\u00e9rienne dans l\u2019intestin gr\u00eale.  Colite.  Convalescence.  Cet aliment est destin\u00e9 \u00e0 la prise en charge nutritionnelle d\u2019une maladie. Il est recommand\u00e9 de consulter votre v\u00e9t\u00e9rinaire.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/avoine-37420\/boutique\/product\/specific-chien-ciw-digestive-support-barquettes-2\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2025-08-25T07:43:12+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/specific-ciw-digestive-support.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-chien-ciw-digestive-support-barquettes-2\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/specific-chien-ciw-digestive-support-barquettes-2\/","name":"CIW Digestive Support - chien Specific - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-chien-ciw-digestive-support-barquettes-2\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-chien-ciw-digestive-support-barquettes-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/specific-ciw-digestive-support.webp","datePublished":"2023-10-03T10:21:18+00:00","dateModified":"2025-08-25T07:43:12+00:00","description":"Aliment di\u00e9t\u00e9tique complet pour chien, permettant de diminuer les troubles aigus de l'absorption intestinale et de compenser la maldigestion et l'insuffisance pancr\u00e9atique exocrine. Utilisation : Affections gastro-intestinales aigu\u00ebs ou chroniques accompagn\u00e9es de diarrh\u00e9e, vomissements et\/ou flatulences. Insuffisance pancr\u00e9atique exocrine. Malabsorption, maldigestion. Prolif\u00e9ration bact\u00e9rienne dans l\u2019intestin gr\u00eale. Colite. Convalescence. Cet aliment est destin\u00e9 \u00e0 la prise en charge nutritionnelle d\u2019une maladie. Il est recommand\u00e9 de consulter votre v\u00e9t\u00e9rinaire.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-chien-ciw-digestive-support-barquettes-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/specific-chien-ciw-digestive-support-barquettes-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-chien-ciw-digestive-support-barquettes-2\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/specific-ciw-digestive-support.webp","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/specific-ciw-digestive-support.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-chien-ciw-digestive-support-barquettes-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"CIW Digestive Support &#8211; chien"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Specific","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/avoine-37420\/boutique\/wp-json\/wp\/v2\/product\/708696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/avoine-37420\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/avoine-37420\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/avoine-37420\/boutique\/wp-json\/wp\/v2\/media\/1249451"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/avoine-37420\/boutique\/wp-json\/wp\/v2\/media?parent=708696"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/avoine-37420\/boutique\/wp-json\/wp\/v2\/product_cat?post=708696"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/avoine-37420\/boutique\/wp-json\/wp\/v2\/product_tag?post=708696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}