{"id":1051679,"date":"2023-09-27T12:13:50","date_gmt":"2023-09-27T10:13:50","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/?p=1051679"},"modified":"2024-10-08T10:53:30","modified_gmt":"2024-10-08T08:53:30","slug":"pour-sa-sante-digestive-chaque-bouchee-compte","status":"publish","type":"post","link":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/2023\/09\/27\/pour-sa-sante-digestive-chaque-bouchee-compte\/","title":{"rendered":"Pour sa sant\u00e9 digestive, chaque bouch\u00e9e compte !"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1051679\" class=\"elementor elementor-1051679\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38d6036 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"38d6036\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b54c0fe\" data-id=\"b54c0fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90b5d84 elementor-widget elementor-widget-image\" data-id=\"90b5d84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.vetorino.com\/boutique\/marque\/royal-canin\/?s&#038;maladie=troubles-digestifs&#038;swcfpc=1\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2048\" height=\"1152\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/24-RC-VET-Banniere-GI-1280x720-V2-2048x1152.jpg\" class=\"attachment-2048x2048 size-2048x2048 wp-image-1051681\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/24-RC-VET-Banniere-GI-1280x720-V2-2048x1152.jpg 2048w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/24-RC-VET-Banniere-GI-1280x720-V2-300x169.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/24-RC-VET-Banniere-GI-1280x720-V2-1024x576.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/24-RC-VET-Banniere-GI-1280x720-V2-768x432.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/24-RC-VET-Banniere-GI-1280x720-V2-1536x864.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/24-RC-VET-Banniere-GI-1280x720-V2-555x312.jpg 555w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4747b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4747b9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f0a8be6\" data-id=\"f0a8be6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77b80b4 elementor-widget elementor-widget-text-editor\" data-id=\"77b80b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<section data-id=\"8j8qvkr\" data-element_type=\"section\"><div><div><div data-id=\"2u8kg9v\" data-element_type=\"column\"><div><div><div data-id=\"tcv8rwn\" data-element_type=\"heading.default\"><h2><strong><span style=\"color: #ff0000;\">POUR SA SANT\u00c9\u00a0<span style=\"font-size: clamp(1.375rem, 1rem + 2vw, 1.75rem); background-color: var(--bs-body-bg); font-family: var(--bs-body-font-family); text-align: var(--bs-body-text-align);\">DIGESTIVE, CHAQUE BOUCH\u00c9E COMPTE !<\/span><\/span><\/strong><\/h2><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86b51a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86b51a2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ca49f12\" data-id=\"ca49f12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d92d7f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2d92d7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dans une enqu\u00eate r\u00e9cente, 25 % des propri\u00e9taires de chats et de chiens ont d\u00e9clar\u00e9 avoir observ\u00e9 des signes cliniques de <b>troubles digestifs<\/b> chez leur animal de compagnie au cours des 12 derniers mois. (1)<br \/>Il est important de <b>pr\u00eater attention aux diff\u00e9rents signes<\/b> (liste non exhaustive) :<\/p><ul><li><span style=\"background-color: var(--bs-body-bg); color: var(--bs-body-color); font-family: var(--bs-body-font-family); font-size: var(--bs-body-font-size); font-weight: var(--bs-body-font-weight);\">Vomissement, diarrh\u00e9e ou constipation<\/span><\/li><li>Perte d\u2019app\u00e9tit et refus de s\u2019alimenter<\/li><li>Aggravation soudaine de la mauvaise haleine<\/li><li>Flatulence et gargouillements<\/li><li>Perte de poids malgr\u00e9 un app\u00e9tit normal<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5edf07d\" data-id=\"5edf07d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-888da5a elementor-widget elementor-widget-image\" data-id=\"888da5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"264\" height=\"132\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/Picture1.png\" class=\"attachment-large size-large wp-image-1051683\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/Picture1.png 264w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/Picture1-262x132.png 262w\" sizes=\"(max-width: 264px) 100vw, 264px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37f3744 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37f3744\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5abeb12\" data-id=\"5abeb12\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-448f199 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"448f199\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><span style=\"color: var(--bs-body-color); font-family: var(--bs-body-font-family); font-size: var(--bs-body-font-size); font-weight: var(--bs-body-font-weight); background-color: var(--bs-body-bg);\">Si votre animal pr\u00e9sente un ou plusieurs de ces signes, la premi\u00e8re \u00e9tape est de\u00a0<\/span><strong style=\"background-color: var(--bs-body-bg); color: var(--bs-body-color); font-family: var(--bs-body-font-family); font-size: var(--bs-body-font-size);\">consulter votre v\u00e9t\u00e9rinaire.<\/strong><\/div><p>Les causes de troubles digestifs sont vari\u00e9es et tr\u00e8s nombreuses\u00a0: intol\u00e9rance ou \u00e9carts alimentaires, infections virales ou bact\u00e9riennes, parasites, maladies inflammatoires, cancers etc \u2026<\/p><p>De plus, les sympt\u00f4mes digestifs peuvent \u00eatre secondaires \u00e0 une maladie ext\u00e9rieure du tube digestifs. Citons par exemple la maladie r\u00e9nale chronique ou encore le diab\u00e8te et l\u2019hyperthyro\u00efdie, autant de maladies malheureusement tr\u00e8s fr\u00e9quentes chez le chat.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6cb33a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6cb33a2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-89d7b48\" data-id=\"89d7b48\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50e8476 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"50e8476\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>C\u2019est pourquoi des examens compl\u00e9mentaires chez votre v\u00e9t\u00e9rinaire (imagerie m\u00e9dicale, analyses de sang, d\u2019urine ou encore de selles) peuvent \u00eatre n\u00e9cessaires pour \u00e9tablir un diagnostic pr\u00e9cis, d\u00e9terminer le traitement requis et <strong><span style=\"color: #ff0000;\">d\u00e9terminer l\u2019aliment adapt\u00e9 aux troubles digestifs de votre animal.<\/span><\/strong><\/p><p><strong><span style=\"color: #ff0000;\">La gamme d\u2019aliments di\u00e9t\u00e9tiques complets GASTROINTESTINAL permet d\u2019accompagner les chats et les chiens atteints de troubles digestifs.<\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7da0874 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7da0874\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/riedisheim-68400\/boutique\/https:\/\/www.vetorino.com\/boutique\/marque\/royal-canin\/?s&#038;maladie=troubles-digestifs&#038;swcfpc=1\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir les produits <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8cf9034\" data-id=\"8cf9034\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9befa6 elementor-widget elementor-widget-image\" data-id=\"f9befa6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"980\" height=\"980\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/RC-GastrointestinalDogDry-1024x1024.jpeg\" class=\"attachment-large size-large wp-image-1051693\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/RC-GastrointestinalDogDry-1024x1024.jpeg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/RC-GastrointestinalDogDry-300x300.jpeg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/RC-GastrointestinalDogDry-150x150.jpeg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/RC-GastrointestinalDogDry-768x768.jpeg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/RC-GastrointestinalDogDry-1536x1536.jpeg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/RC-GastrointestinalDogDry-2048x2048.jpeg 2048w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/RC-GastrointestinalDogDry-500x500.jpeg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/RC-GastrointestinalDogDry-555x555.jpeg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/RC-GastrointestinalDogDry-160x160.jpeg 160w\" sizes=\"(max-width: 980px) 100vw, 980px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8517964 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8517964\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-350b09f\" data-id=\"350b09f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39758f7 elementor-widget elementor-widget-heading\" data-id=\"39758f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">(1) 2020 PET OWNER CATEGORY UNDERSTANDING: Use of vet services, their journey, and incidence of different diseases\/conditions. Juin 2020\n(2) Offre valable pour l\u2019achat d\u2019un produit v\u00e9t\u00e9rinaire Royal Canin concern\u00e9 par la promotion : Offre Royal Canin : Profitez d&amp;#39;une remise imm\u00e9diate jusqu&amp;#39;\u00e0 17 \u20ac sur une s\u00e9lection\nde produits pour chien et jusqu&amp;#39;\u00e0 7 \u20ac sur une s\u00e9lection de produits pour chat, r\u00e9alis\u00e9 entre le 1er et le 31 octobre 2024. Offre valable dans la limite des stocks disponibles d\u00e8s le\npremier produit achet\u00e9.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>POUR SA SANT\u00c9\u00a0DIGESTIVE, CHAQUE BOUCH\u00c9E COMPTE ! Dans une enqu\u00eate r\u00e9cente, 25 % des propri\u00e9taires de chats et de chiens ont d\u00e9clar\u00e9 avoir observ\u00e9 des signes cliniques de troubles digestifs chez leur animal de compagnie au cours des 12 derniers mois. (1)Il est important de pr\u00eater attention aux diff\u00e9rents signes (liste non exhaustive) : Vomissement, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1051718,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[14089,14088,14086,14087,14090,14095],"tags":[],"class_list":["post-1051679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentation-chat","category-alimentation-chien","category-chat","category-chien","category-hygiene-et-bien-etre-chien","category-sante-et-prevention-chat"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pour sa sant\u00e9 digestive, chaque bouch\u00e9e compte ! - V\u00e9torino<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pour sa sant\u00e9 digestive, chaque bouch\u00e9e compte ! - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"POUR SA SANT\u00c9\u00a0DIGESTIVE, CHAQUE BOUCH\u00c9E COMPTE ! Dans une enqu\u00eate r\u00e9cente, 25 % des propri\u00e9taires de chats et de chiens ont d\u00e9clar\u00e9 avoir observ\u00e9 des signes cliniques de troubles digestifs chez leur animal de compagnie au cours des 12 derniers mois. (1)Il est important de pr\u00eater attention aux diff\u00e9rents signes (liste non exhaustive) : Vomissement, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/2023\/09\/27\/pour-sa-sante-digestive-chaque-bouchee-compte\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-27T10:13:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-08T08:53:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/royal-canin-gastro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1905\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre Desouches\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre Desouches\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/pour-sa-sante-digestive-chaque-bouchee-compte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/pour-sa-sante-digestive-chaque-bouchee-compte\\\/\"},\"author\":{\"name\":\"Pierre Desouches\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/b5521875cca3f2a28ed80d8bc458f092\"},\"headline\":\"Pour sa sant\u00e9 digestive, chaque bouch\u00e9e compte !\",\"datePublished\":\"2023-09-27T10:13:50+00:00\",\"dateModified\":\"2024-10-08T08:53:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/pour-sa-sante-digestive-chaque-bouchee-compte\\\/\"},\"wordCount\":348,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/pour-sa-sante-digestive-chaque-bouchee-compte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/royal-canin-gastro.jpg\",\"articleSection\":[\"Alimentation pour chat\",\"Alimentation pour chien\",\"Chat\",\"Chien\",\"Hygi\u00e8ne et bien-\u00eatre pour chien\",\"Sant\u00e9 et pr\u00e9vention pour chat\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/pour-sa-sante-digestive-chaque-bouchee-compte\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/pour-sa-sante-digestive-chaque-bouchee-compte\\\/\",\"name\":\"Pour sa sant\u00e9 digestive, chaque bouch\u00e9e compte ! - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/pour-sa-sante-digestive-chaque-bouchee-compte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/pour-sa-sante-digestive-chaque-bouchee-compte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/royal-canin-gastro.jpg\",\"datePublished\":\"2023-09-27T10:13:50+00:00\",\"dateModified\":\"2024-10-08T08:53:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/pour-sa-sante-digestive-chaque-bouchee-compte\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/pour-sa-sante-digestive-chaque-bouchee-compte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/pour-sa-sante-digestive-chaque-bouchee-compte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/royal-canin-gastro.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/royal-canin-gastro.jpg\",\"width\":1905,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/pour-sa-sante-digestive-chaque-bouchee-compte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chat\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/champs-sur-marne-77420\\\/boutique\\\/category\\\/chat\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pour sa sant\u00e9 digestive, chaque bouch\u00e9e compte !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/b5521875cca3f2a28ed80d8bc458f092\",\"name\":\"Pierre Desouches\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f2a83ff1a698fcad3ea07d919ba7d1d66dc073d14c2a5195e64dbc5dc2d55d34?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f2a83ff1a698fcad3ea07d919ba7d1d66dc073d14c2a5195e64dbc5dc2d55d34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f2a83ff1a698fcad3ea07d919ba7d1d66dc073d14c2a5195e64dbc5dc2d55d34?s=96&d=mm&r=g\",\"caption\":\"Pierre Desouches\"},\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/barbezieux-saint-hilaire\\\/boutique\\\/author\\\/pierre-desouchesgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pour sa sant\u00e9 digestive, chaque bouch\u00e9e compte ! - V\u00e9torino","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Pour sa sant\u00e9 digestive, chaque bouch\u00e9e compte ! - V\u00e9torino","og_description":"POUR SA SANT\u00c9\u00a0DIGESTIVE, CHAQUE BOUCH\u00c9E COMPTE ! Dans une enqu\u00eate r\u00e9cente, 25 % des propri\u00e9taires de chats et de chiens ont d\u00e9clar\u00e9 avoir observ\u00e9 des signes cliniques de troubles digestifs chez leur animal de compagnie au cours des 12 derniers mois. (1)Il est important de pr\u00eater attention aux diff\u00e9rents signes (liste non exhaustive) : Vomissement, [&hellip;]","og_url":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/2023\/09\/27\/pour-sa-sante-digestive-chaque-bouchee-compte\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_published_time":"2023-09-27T10:13:50+00:00","article_modified_time":"2024-10-08T08:53:30+00:00","og_image":[{"width":1905,"height":450,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/royal-canin-gastro.jpg","type":"image\/jpeg"}],"author":"Pierre Desouches","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Pierre Desouches","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/pour-sa-sante-digestive-chaque-bouchee-compte\/#article","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/pour-sa-sante-digestive-chaque-bouchee-compte\/"},"author":{"name":"Pierre Desouches","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/b5521875cca3f2a28ed80d8bc458f092"},"headline":"Pour sa sant\u00e9 digestive, chaque bouch\u00e9e compte !","datePublished":"2023-09-27T10:13:50+00:00","dateModified":"2024-10-08T08:53:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/pour-sa-sante-digestive-chaque-bouchee-compte\/"},"wordCount":348,"publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/pour-sa-sante-digestive-chaque-bouchee-compte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/royal-canin-gastro.jpg","articleSection":["Alimentation pour chat","Alimentation pour chien","Chat","Chien","Hygi\u00e8ne et bien-\u00eatre pour chien","Sant\u00e9 et pr\u00e9vention pour chat"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/pour-sa-sante-digestive-chaque-bouchee-compte\/","url":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/pour-sa-sante-digestive-chaque-bouchee-compte\/","name":"Pour sa sant\u00e9 digestive, chaque bouch\u00e9e compte ! - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/pour-sa-sante-digestive-chaque-bouchee-compte\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/pour-sa-sante-digestive-chaque-bouchee-compte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/royal-canin-gastro.jpg","datePublished":"2023-09-27T10:13:50+00:00","dateModified":"2024-10-08T08:53:30+00:00","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/pour-sa-sante-digestive-chaque-bouchee-compte\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/pour-sa-sante-digestive-chaque-bouchee-compte\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/pour-sa-sante-digestive-chaque-bouchee-compte\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/royal-canin-gastro.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/royal-canin-gastro.jpg","width":1905,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/pour-sa-sante-digestive-chaque-bouchee-compte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Chat","item":"https:\/\/www.vetorino.com\/veterinaire\/champs-sur-marne-77420\/boutique\/category\/chat\/"},{"@type":"ListItem","position":3,"name":"Pour sa sant\u00e9 digestive, chaque bouch\u00e9e compte !"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]},{"@type":"Person","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/b5521875cca3f2a28ed80d8bc458f092","name":"Pierre Desouches","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f2a83ff1a698fcad3ea07d919ba7d1d66dc073d14c2a5195e64dbc5dc2d55d34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f2a83ff1a698fcad3ea07d919ba7d1d66dc073d14c2a5195e64dbc5dc2d55d34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f2a83ff1a698fcad3ea07d919ba7d1d66dc073d14c2a5195e64dbc5dc2d55d34?s=96&d=mm&r=g","caption":"Pierre Desouches"},"url":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/author\/pierre-desouchesgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/wp-json\/wp\/v2\/posts\/1051679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/wp-json\/wp\/v2\/comments?post=1051679"}],"version-history":[{"count":5,"href":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/wp-json\/wp\/v2\/posts\/1051679\/revisions"}],"predecessor-version":[{"id":1051721,"href":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/wp-json\/wp\/v2\/posts\/1051679\/revisions\/1051721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/wp-json\/wp\/v2\/media\/1051718"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/wp-json\/wp\/v2\/media?parent=1051679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/wp-json\/wp\/v2\/categories?post=1051679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/wp-json\/wp\/v2\/tags?post=1051679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}