{"id":295690,"date":"2022-02-22T14:56:49","date_gmt":"2022-02-22T13:56:49","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/?p=295690"},"modified":"2024-08-08T17:22:21","modified_gmt":"2024-08-08T15:22:21","slug":"surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences","status":"publish","type":"post","link":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/2022\/02\/22\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\/","title":{"rendered":"Surpoids du chien et du chat, quelles sont les causes et les cons\u00e9quences ?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"295690\" class=\"elementor elementor-295690\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ebcb712 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ebcb712\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b4f6b8e\" data-id=\"5b4f6b8e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b8b006d elementor-widget elementor-widget-text-editor\" data-id=\"3b8b006d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<h2 class=\"wp-block-heading\">Facteurs et r\u00e9percussions de l&#8217;ob\u00e9sit\u00e9 et du surpoids chez un chien ou un chat<\/h2>\n<p><\/p>\n<p><\/p>\n<p class=\"wp-block-paragraph\">Le <strong>surpoids<\/strong>, comme pour les humains, est beaucoup plus fr\u00e9quent qu\u2019on ne le croit. Pour un <strong>petit chien<\/strong>, un seul kilo peut faire la diff\u00e9rence. Pour un <strong>chat adulte<\/strong>, un surpoids d\u2019\u00e0 peine 800g peut d\u00e9j\u00e0 \u00eatre probl\u00e9matique. Cela peut vous sembler ridicule mais pour votre chien ou votre chat, selon sa taille, cela peut faire un poids suppl\u00e9mentaire au quotidien tr\u00e8s lourd \u00e0 porter. Un <strong>surpoids<\/strong> qui au fur et \u00e0 mesure va entra\u00eener des <strong>probl\u00e8mes de sant\u00e9<\/strong>. En effet, un chien ou un chat en surpoids peut avoir des difficult\u00e9s \u00e0 se d\u00e9placer, \u00e0 courir, jouer, sauter ou m\u00eame respirer. Il ne pourra plus \u00eatre aussi vif qu\u2019auparavant et vivre normalement\u2026\u00a0 Les <strong>r\u00e9percussions<\/strong> peuvent \u00eatre graves mais ne vous inqui\u00e9tez pas, si votre <strong>animal de compagnie<\/strong> est bien suivi, maints soucis peuvent \u00eatre \u00e9cart\u00e9s.<\/p>\n<p><\/p>\n<p><\/p>\n<h2 class=\"has-text-align-left wp-block-heading\">Ob\u00e9sit\u00e9, surpoids : quelles sont les r\u00e9percussions pour un chien, un chat ?<\/h2>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-295695 alignleft\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/jorge-zapata-_siAu79dnBk-unsplash-300x201.jpg\" alt=\"Ob\u00e9sit\u00e9, surpoids : quelles sont les r\u00e9percussions pour un chien, un chat ?\" width=\"300\" height=\"201\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/jorge-zapata-_siAu79dnBk-unsplash-300x201.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/jorge-zapata-_siAu79dnBk-unsplash-1024x686.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/jorge-zapata-_siAu79dnBk-unsplash-768x514.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/jorge-zapata-_siAu79dnBk-unsplash-1536x1028.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/jorge-zapata-_siAu79dnBk-unsplash-2048x1371.jpg 2048w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/jorge-zapata-_siAu79dnBk-unsplash-750x500.jpg 750w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/jorge-zapata-_siAu79dnBk-unsplash-555x372.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/jorge-zapata-_siAu79dnBk-unsplash-64x43.jpg 64w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><\/p>\n<p><\/p>\n<p class=\"wp-block-paragraph\">Concr\u00e8tement, un surpoids peut avoir des r\u00e9percussions diff\u00e9rentes. Cela peut aller de la <strong>simple g\u00eane<\/strong>, \u00e0 des troubles ou des <strong>maladies<\/strong>. Ainsi, des \u00e9tudes montrent qu\u2019un surpoids de 20% peut, de fa\u00e7on significative, augmenter le <strong>d\u00e9veloppement de maladies cardiovasculaires<\/strong> pour votre <strong>chien<\/strong>, et pour votre <strong>chat<\/strong> des maladies urinaires. Le surpoids, l\u2019ob\u00e9sit\u00e9 du chien et du chat ne sont donc pas \u00e0 prendre avec des pincettes ! Cela alt\u00e8re son esp\u00e9rance et sa qualit\u00e9 de vie.<\/p>\n<p><\/p>\n<p><\/p>\n<p class=\"wp-block-paragraph\"><\/p>\n<p><\/p>\n<h2 class=\"has-text-align-left wp-block-heading\">De multiples facteurs entra\u00eenent de la prise de poids pour votre chien ou votre chat<\/h2>\n<p><\/p>\n<p><\/p>\n<p class=\"wp-block-paragraph\">Maints facteurs vont entra\u00eener une <strong>prise de poids<\/strong> importante, n\u00e9faste pour votre chien ou votre chat\u2026 Ici, nous avons voulu expliciter les facteurs qui sont moins \u00e9vidents qu\u2019un manque d\u2019activit\u00e9 physique et\/ou une alimentation excessive.<\/p>\n<p>Premi\u00e8rement, faites attention \u00e0 <strong>l\u2019\u00e2ge de votre animal<\/strong>. En effet, comme pour les humains, plus les chats et chiens vieillissent, moins ils seront actifs\u2026 Il s\u2019agit donc d\u2019<strong>adapter<\/strong> au fur et \u00e0 mesure leur r\u00e9gime alimentaire afin d\u2019anticiper des prises de poids.<\/p>\n<p>Ensuite, faites \u00e9galement attention \u00e0 la <strong>race<\/strong> de votre chien ou votre chat. En effet, certaines races seront beaucoup plus sensibles au surpoids que d\u2019autres. Pour les chiens\u00a0:<\/p>\n<ul>\n<li>Bergers allemands\u00a0;<\/li>\n<li>Labradors retrievers\u00a0;<\/li>\n<li>Cockers\u00a0;<\/li>\n<li>Teckels\u00a0;<\/li>\n<li>Colleys \u00e0 poils longs\u2026<\/li>\n<\/ul>\n<p>Pour les chats\u00a0:<\/p>\n<ul>\n<li>Persans\u00a0;<\/li>\n<li>Chartreux\u2026<\/li>\n<\/ul>\n<p>La <strong>liste est non exhaustive<\/strong> donc pensez bien \u00e0 v\u00e9rifier\u00a0!<\/p>\n<p>Troisi\u00e8mement, le <strong>sexe<\/strong> de votre animal est un autre facteur \u00e0 prendre en compte. Ainsi, les femmes sont plus sujettes \u00e0 l\u2019<strong>adiposit\u00e9<\/strong>.<\/p>\n<p><\/p>\n<p><\/p>\n<h2 class=\"wp-block-heading\">St\u00e9rilisation et prise de poids chez l&#8217;animal de compagnie<\/h2>\n<p><\/p>\n<p><\/p>\n<p class=\"wp-block-paragraph\">Dans cette logique, la <strong>st\u00e9rilisation<\/strong> est un facteur cons\u00e9quent. En un sens, c\u2019est <strong>b\u00e9n\u00e9fique<\/strong> pour la sant\u00e9 de votre chien ou votre chat mais de l\u2019autre, cela va venir jouer sur son comportement et ralentir un peu son <strong>m\u00e9tabolisme<\/strong>\u2026 Il s\u2019agit donc l\u00e0 aussi d\u2019<strong>adapter ses portions<\/strong> en cons\u00e9quence !<\/p>\n<p>Si la prise de poids de votre animal est due \u00e0 un <strong>probl\u00e8me de sant\u00e9<\/strong> \u2013 comme des <strong>troubles hormonaux<\/strong> -, renseignez-vous aupr\u00e8s de votre v\u00e9t\u00e9rinaire\u00a0! Il saura prescrire \u00e0 votre chien ou chat un <strong>traitement<\/strong> adapt\u00e9.<\/p>\n<p>Bien \u00e9videmment, parmi les facteurs principaux du surpoids, de l\u2019ob\u00e9sit\u00e9 chez un chien ou un chat, les <strong>mauvaises habitudes alimentaires<\/strong> sont encore trop souvent fr\u00e9quentes. Evitez de multiplier les friandises et les restes \u00e0 table. Achetez plut\u00f4t des friandises \u00ab\u00a0light\u00a0\u00bb et\/ou adapt\u00e9es \u00e0 son r\u00e9gime alimentaire.<\/p>\n<p>Enfin, faites attention dans le <strong>choix des croquettes<\/strong>, des produits alimentaires pour votre animal. Beaucoup sont trop riches en mati\u00e8res grasses, en sel. <strong>L\u2019apport nutritionnel<\/strong> doit correspondre aux besoins pr\u00e9cis de votre animal de compagnie.<\/p>\n<p><\/p>\n<p><\/p>\n<p class=\"wp-block-paragraph\"><\/p>\n<p><\/p>\n<h2 class=\"wp-block-heading\">Une alimentation saine : la cl\u00e9 pour lutter contre l&#8217;ob\u00e9sit\u00e9 et le surpoids de votre chien ou chat\u00a0<\/h2>\n<p><img decoding=\"async\" class=\"size-medium wp-image-295696 alignright\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/animal-gcf66213de_1920-300x225.jpg\" alt=\"Une alimentation saine : la cl\u00e9 pour lutter contre l'ob\u00e9sit\u00e9 et le surpoids de votre chien ou chat\u00a0\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/animal-gcf66213de_1920-300x225.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/animal-gcf66213de_1920-1024x768.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/animal-gcf66213de_1920-768x576.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/animal-gcf66213de_1920-1536x1152.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/animal-gcf66213de_1920-555x416.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/animal-gcf66213de_1920-64x48.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/animal-gcf66213de_1920.jpg 1920w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><\/p>\n<p><\/p>\n<p class=\"wp-block-paragraph\">Vous l\u2019aurez compris, une <strong>alimentation saine<\/strong> est la cl\u00e9 pour lutter contre l\u2019ob\u00e9sit\u00e9 et le<strong> surpoids de votre chien ou chat<\/strong>. C\u2019est primordial pour la sant\u00e9, la vitalit\u00e9, le confort de votre compagnon \u00e0 4 pattes. Veillez \u00e0 opter pour des produits qui maintiennent leur <strong>poids id\u00e9al<\/strong> ou favorisent directement la <strong>perte de poids<\/strong>.<\/p>\n<p>Gr\u00e2ce \u00e0 une alimentation saine, nutritionnelle, votre chien ou chat profitera d\u2019une belle <strong>qualit\u00e9 de vie<\/strong>. Prendre soin de son alimentation, c\u2019est prendre soin de lui, et de vous. Vous souhaitez vivre pleins de beaux moments avec lui n\u2019est-ce pas\u00a0? Alors, pensez \u00e0 bien adopter nos conseils\u00a0!<\/p>\n<p><\/p>\n<p><\/p>\n<p class=\"wp-block-paragraph\"><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-334f36a0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"334f36a0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1f766c5c\" data-id=\"1f766c5c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3132370c elementor-widget elementor-widget-heading\" data-id=\"3132370c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"line-height: 1.4;margin-top: 20px;margin-bottom: 10px;font-size: 18px;text-align: center\"> D\u00e9couvrez notre s\u00e9lection de produits contre le surpoids du chien ou du chat<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40a7c6a6 product_alcyon elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"40a7c6a6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-62e1a3fb\" data-id=\"62e1a3fb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1dc7374b elementor-widget elementor-widget-image\" data-id=\"1dc7374b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/royal-canin-cat-neutered-satiety-balance-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-298962\" alt=\"royal-canin-cat-neutered-satiety-balance-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/royal-canin-cat-neutered-satiety-balance-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/royal-canin-cat-neutered-satiety-balance-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/royal-canin-cat-neutered-satiety-balance-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/royal-canin-cat-neutered-satiety-balance-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/royal-canin-cat-neutered-satiety-balance-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/royal-canin-cat-neutered-satiety-balance-vetorino.png 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f94b9db elementor-widget elementor-widget-heading\" data-id=\"1f94b9db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Royal Canin\nCAT NEUTERED SATIETY BALANCE <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14cc7480 elementor-widget elementor-widget-text-editor\" data-id=\"14cc7480\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Alimentation di\u00e9t\u00e9tique et compl\u00e8te pour chats st\u00e9rilis\u00e9s jusqu\u2019\u00e0 7 ans. Permet aux foyers poss\u00e9dants plusieurs chats de proposer un aliment convenant \u00e0 tous.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-333965a6 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"333965a6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/saintlo-50000\/boutique\/product\/vcn-cat-neutered-satiety-balance\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-76318725\" data-id=\"76318725\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-68417393 elementor-widget elementor-widget-image\" data-id=\"68417393\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-chien-metabolic-au-poulet-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-298963\" alt=\"hill&apos;s-chien-metabolic-au-poulet-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-chien-metabolic-au-poulet-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-chien-metabolic-au-poulet-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-chien-metabolic-au-poulet-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-chien-metabolic-au-poulet-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-chien-metabolic-au-poulet-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-chien-metabolic-au-poulet-vetorino.jpg 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57c0b53d elementor-widget elementor-widget-heading\" data-id=\"57c0b53d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hill's METABOLIC CROQUETTES POUR CHIEN AU POULET<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76992088 elementor-widget elementor-widget-text-editor\" data-id=\"76992088\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Prescription Diet Canine Metabolic est un aliment complet et \u00e9quilibr\u00e9 qui a \u00e9t\u00e9 sp\u00e9cialement \u00e9labor\u00e9 pour la prise en charge des probl\u00e8mes de poids chez le chien.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9467f7 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"f9467f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/saintlo-50000\/boutique\/product\/canine-metabolic\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-53bfba6d\" data-id=\"53bfba6d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-72d18587 elementor-widget elementor-widget-image\" data-id=\"72d18587\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills_feline-adult-light-poulet_vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-298964\" alt=\"hill&apos;s_feline-adult-light-poulet_vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills_feline-adult-light-poulet_vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills_feline-adult-light-poulet_vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills_feline-adult-light-poulet_vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills_feline-adult-light-poulet_vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills_feline-adult-light-poulet_vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills_feline-adult-light-poulet_vetorino.jpg 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f5ed4e3 elementor-widget elementor-widget-heading\" data-id=\"4f5ed4e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hill's PRESCRIPTION DIET FELINE ADULT LIGHT POULET<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a084188 elementor-widget elementor-widget-text-editor\" data-id=\"6a084188\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hill&#8217;s Feline Adult Light Poulet aide \u00e0 maintenir un poids id\u00e9al. Favorise la conversion de graisses en \u00e9nergie. Alimentation quotidienne.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a40a13c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"a40a13c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/saintlo-50000\/boutique\/product\/feline-adult-light-poulet\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6a8100a9\" data-id=\"6a8100a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1e35514 elementor-widget elementor-widget-image\" data-id=\"1e35514\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w2-weight-loss-control-dog-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-298967\" alt=\"virbac-w2-weight-loss-control-dog-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w2-weight-loss-control-dog-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w2-weight-loss-control-dog-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w2-weight-loss-control-dog-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w2-weight-loss-control-dog-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w2-weight-loss-control-dog-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w2-weight-loss-control-dog-vetorino.jpg 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fc0bf6a elementor-widget elementor-widget-heading\" data-id=\"7fc0bf6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Virbac - W2 WEIGHT LOSS &amp; CONTROL DOG<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-491be74c elementor-widget elementor-widget-text-editor\" data-id=\"491be74c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217;aliment VETERINARY HMP &#8211; Weight Loss &amp; Control Dog est un aliment di\u00e9t\u00e9tique et \u00e9quilibr\u00e9 pour chien con\u00e7u pour r\u00e9duire le surpoids lorsqu&#8217;il est inf\u00e9rieur \u00e0 30%<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3935395 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3935395\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/saintlo-50000\/boutique\/product\/vet-hpm-chien-weight-loss-control\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48c398e product_centravet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48c398e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7295adb\" data-id=\"7295adb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae3a792 elementor-widget elementor-widget-image\" data-id=\"ae3a792\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/royal-canin-cat-neutered-satiety-balance-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-298962\" alt=\"royal-canin-cat-neutered-satiety-balance-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/royal-canin-cat-neutered-satiety-balance-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/royal-canin-cat-neutered-satiety-balance-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/royal-canin-cat-neutered-satiety-balance-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/royal-canin-cat-neutered-satiety-balance-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/royal-canin-cat-neutered-satiety-balance-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/royal-canin-cat-neutered-satiety-balance-vetorino.png 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b2b2b4 elementor-widget elementor-widget-heading\" data-id=\"7b2b2b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Royal Canin\nCAT NEUTERED SATIETY BALANCE <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5eeba11 elementor-widget elementor-widget-text-editor\" data-id=\"5eeba11\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Alimentation di\u00e9t\u00e9tique et compl\u00e8te pour chats st\u00e9rilis\u00e9s jusqu\u2019\u00e0 7 ans. Permet aux foyers poss\u00e9dants plusieurs chats de proposer un aliment convenant \u00e0 tous.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a02e4f0 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"a02e4f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/saintlo-50000\/boutique\/product\/vet-care-nutrition-cat-neutered-satiety-balance\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-592b834\" data-id=\"592b834\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6921f12 elementor-widget elementor-widget-image\" data-id=\"6921f12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-chien-metabolic-au-poulet-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-298963\" alt=\"hill&apos;s-chien-metabolic-au-poulet-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-chien-metabolic-au-poulet-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-chien-metabolic-au-poulet-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-chien-metabolic-au-poulet-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-chien-metabolic-au-poulet-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-chien-metabolic-au-poulet-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-chien-metabolic-au-poulet-vetorino.jpg 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3b05b8 elementor-widget elementor-widget-heading\" data-id=\"f3b05b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hill's METABOLIC CROQUETTES POUR CHIEN AU POULET<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-acb7e86 elementor-widget elementor-widget-text-editor\" data-id=\"acb7e86\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Prescription Diet Canine Metabolic est un aliment complet et \u00e9quilibr\u00e9 qui a \u00e9t\u00e9 sp\u00e9cialement \u00e9labor\u00e9 pour la prise en charge des probl\u00e8mes de poids chez le chien.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7230ff elementor-align-center elementor-widget elementor-widget-button\" data-id=\"a7230ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/saintlo-50000\/boutique\/product\/canine-metabolic-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3aa8406\" data-id=\"3aa8406\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c351aeb elementor-widget elementor-widget-image\" data-id=\"c351aeb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills_feline-adult-light-poulet_vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-298964\" alt=\"hill&apos;s_feline-adult-light-poulet_vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills_feline-adult-light-poulet_vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills_feline-adult-light-poulet_vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills_feline-adult-light-poulet_vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills_feline-adult-light-poulet_vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills_feline-adult-light-poulet_vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills_feline-adult-light-poulet_vetorino.jpg 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9d506ec elementor-widget elementor-widget-heading\" data-id=\"9d506ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hill's PRESCRIPTION DIET FELINE ADULT LIGHT POULET<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec82656 elementor-widget elementor-widget-text-editor\" data-id=\"ec82656\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hill&#8217;s Feline Adult Light Poulet aide \u00e0 maintenir un poids id\u00e9al. Favorise la conversion de graisses en \u00e9nergie. Alimentation quotidienne.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-236d96a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"236d96a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/saintlo-50000\/boutique\/product\/feline-adult-light-poulet-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-a18006d\" data-id=\"a18006d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-05f9af0 elementor-widget elementor-widget-image\" data-id=\"05f9af0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w2-weight-loss-control-dog-vetorino.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"virbac-w2-weight-loss-control-dog-vetorino\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6Mjk4OTY3LCJ1cmwiOiJodHRwczpcL1wvd3d3LnZldG9yaW5vLmNvbVwvYm91dGlxdWVcL3dwLWNvbnRlbnRcL3VwbG9hZHNcLzIwMjJcLzAyXC92aXJiYWMtdzItd2VpZ2h0LWxvc3MtY29udHJvbC1kb2ctdmV0b3Jpbm8uanBnIn0%3D\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w2-weight-loss-control-dog-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-298967\" alt=\"virbac-w2-weight-loss-control-dog-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w2-weight-loss-control-dog-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w2-weight-loss-control-dog-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w2-weight-loss-control-dog-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w2-weight-loss-control-dog-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w2-weight-loss-control-dog-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w2-weight-loss-control-dog-vetorino.jpg 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28f2d91 elementor-widget elementor-widget-heading\" data-id=\"28f2d91\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Virbac - W2 WEIGHT LOSS &amp; CONTROL DOG<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-893a414 elementor-widget elementor-widget-text-editor\" data-id=\"893a414\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217;aliment VETERINARY HMP &#8211; Weight Loss &amp; Control Dog est un aliment di\u00e9t\u00e9tique et \u00e9quilibr\u00e9 pour chien con\u00e7u pour r\u00e9duire le surpoids lorsqu&#8217;il est inf\u00e9rieur \u00e0 30%<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8663264 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"8663264\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/saintlo-50000\/boutique\/product\/veterinary-hpm-dog-w2-weight-loss-control\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-eb1da1c product_coveto elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"eb1da1c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-96a7f30\" data-id=\"96a7f30\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ac5226 elementor-widget elementor-widget-image\" data-id=\"4ac5226\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/royal-canin-cat-neutered-satiety-balance-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-298962\" alt=\"royal-canin-cat-neutered-satiety-balance-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/royal-canin-cat-neutered-satiety-balance-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/royal-canin-cat-neutered-satiety-balance-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/royal-canin-cat-neutered-satiety-balance-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/royal-canin-cat-neutered-satiety-balance-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/royal-canin-cat-neutered-satiety-balance-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/royal-canin-cat-neutered-satiety-balance-vetorino.png 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8e8f20 elementor-widget elementor-widget-heading\" data-id=\"d8e8f20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Royal Canin\nCAT NEUTERED SATIETY BALANCE <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bc2d5d elementor-widget elementor-widget-text-editor\" data-id=\"7bc2d5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Alimentation di\u00e9t\u00e9tique et compl\u00e8te pour chats st\u00e9rilis\u00e9s jusqu\u2019\u00e0 7 ans. Permet aux foyers poss\u00e9dants plusieurs chats de proposer un aliment convenant \u00e0 tous.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1df8b97 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1df8b97\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/saintlo-50000\/boutique\/product\/vet-care-nutrition-cat-neutered-satiety-balance-sac-de-12-kg-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7298262\" data-id=\"7298262\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b7b648 elementor-widget elementor-widget-image\" data-id=\"2b7b648\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-chien-metabolic-au-poulet-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-298963\" alt=\"hill&apos;s-chien-metabolic-au-poulet-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-chien-metabolic-au-poulet-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-chien-metabolic-au-poulet-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-chien-metabolic-au-poulet-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-chien-metabolic-au-poulet-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-chien-metabolic-au-poulet-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-chien-metabolic-au-poulet-vetorino.jpg 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-899be1a elementor-widget elementor-widget-heading\" data-id=\"899be1a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hill's METABOLIC CROQUETTES POUR CHIEN AU POULET<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-19a5357 elementor-widget elementor-widget-text-editor\" data-id=\"19a5357\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Prescription Diet Canine Metabolic est un aliment complet et \u00e9quilibr\u00e9 qui a \u00e9t\u00e9 sp\u00e9cialement \u00e9labor\u00e9 pour la prise en charge des probl\u00e8mes de poids chez le chien.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3013274 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3013274\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/saintlo-50000\/boutique\/product\/canine-metabolic-sac-de-12-kg\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-561a00f\" data-id=\"561a00f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37ca02a elementor-widget elementor-widget-image\" data-id=\"37ca02a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills_feline-adult-light-poulet_vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-298964\" alt=\"hill&apos;s_feline-adult-light-poulet_vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills_feline-adult-light-poulet_vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills_feline-adult-light-poulet_vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills_feline-adult-light-poulet_vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills_feline-adult-light-poulet_vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills_feline-adult-light-poulet_vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills_feline-adult-light-poulet_vetorino.jpg 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-384e4cb elementor-widget elementor-widget-heading\" data-id=\"384e4cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hill's PRESCRIPTION DIET FELINE ADULT LIGHT POULET<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b8849f6 elementor-widget elementor-widget-text-editor\" data-id=\"b8849f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hill&#8217;s Feline Adult Light Poulet aide \u00e0 maintenir un poids id\u00e9al. Favorise la conversion de graisses en \u00e9nergie. Alimentation quotidienne.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2bf54d5 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"2bf54d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/saintlo-50000\/boutique\/product\/feline-adult-light-poulet-sac-de-10-kg\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f3b2d8c\" data-id=\"f3b2d8c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-48f31d2 elementor-widget elementor-widget-image\" data-id=\"48f31d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w2-weight-loss-control-dog-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-298967\" alt=\"virbac-w2-weight-loss-control-dog-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w2-weight-loss-control-dog-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w2-weight-loss-control-dog-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w2-weight-loss-control-dog-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w2-weight-loss-control-dog-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w2-weight-loss-control-dog-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/virbac-w2-weight-loss-control-dog-vetorino.jpg 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f288889 elementor-widget elementor-widget-heading\" data-id=\"f288889\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Virbac - W2 WEIGHT LOSS &amp; CONTROL DOG<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2928c12 elementor-widget elementor-widget-text-editor\" data-id=\"2928c12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217;aliment VETERINARY HMP &#8211; Weight Loss &amp; Control Dog est un aliment di\u00e9t\u00e9tique et \u00e9quilibr\u00e9 pour chien con\u00e7u pour r\u00e9duire le surpoids lorsqu&#8217;il est inf\u00e9rieur \u00e0 30%<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9b1fec elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b9b1fec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/saintlo-50000\/boutique\/product\/veterinary-hpm-dog-w2-weight-loss-control-sac-de-12-kg-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3531d58e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3531d58e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-599d2190\" data-id=\"599d2190\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66a8eb8f elementor-widget elementor-widget-text-editor\" data-id=\"66a8eb8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong style=\"color: #078ed2;text-align: center\"><a href=\"https:\/\/www.vetorino.com\/boutique\/?s=weight&amp;post_type=product\">D\u00e9couvrez toute notre gamme de produits di\u00e9t\u00e9tiques pour votre chien ou votre chat\u00a0<\/a><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Facteurs et r\u00e9percussions de l&#8217;ob\u00e9sit\u00e9 et du surpoids chez un chien ou un chat Le surpoids, comme pour les humains, est beaucoup plus fr\u00e9quent qu\u2019on ne le croit. Pour un petit chien, un seul kilo peut faire la diff\u00e9rence. Pour un chat adulte, un surpoids d\u2019\u00e0 peine 800g peut d\u00e9j\u00e0 \u00eatre probl\u00e9matique. Cela peut vous [&hellip;]<\/p>\n","protected":false},"author":10426,"featured_media":295695,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[14086,14087,14095,14094],"tags":[],"class_list":["post-295690","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chat","category-chien","category-sante-et-prevention-chat","category-sante-chien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Surpoids du chien et du chat, quelles sont les causes et les cons\u00e9quences ? - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Cliquez ici pour d\u00e9couvrir tout sur le surpoids du chien et du chat ! Quelles sont les causes et les cons\u00e9quences ? Les solutions, produits ?\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Surpoids du chien et du chat, quelles sont les causes et les cons\u00e9quences ? - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Cliquez ici pour d\u00e9couvrir tout sur le surpoids du chien et du chat ! Quelles sont les causes et les cons\u00e9quences ? Les solutions, produits ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/2022\/02\/22\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-22T13:56:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-08T15:22:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/jorge-zapata-_siAu79dnBk-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1714\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe V\u00e9torino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe V\u00e9torino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\\\/\"},\"author\":{\"name\":\"Equipe V\u00e9torino\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/8f60afb04d773f2295479f6eb9cd43e4\"},\"headline\":\"Surpoids du chien et du chat, quelles sont les causes et les cons\u00e9quences ?\",\"datePublished\":\"2022-02-22T13:56:49+00:00\",\"dateModified\":\"2024-08-08T15:22:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\\\/\"},\"wordCount\":1253,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/jorge-zapata-_siAu79dnBk-unsplash-scaled.jpg\",\"articleSection\":[\"Chat\",\"Chien\",\"Sant\u00e9 et pr\u00e9vention pour chat\",\"Sant\u00e9 pour chien\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\\\/\",\"name\":\"Surpoids du chien et du chat, quelles sont les causes et les cons\u00e9quences ? - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/jorge-zapata-_siAu79dnBk-unsplash-scaled.jpg\",\"datePublished\":\"2022-02-22T13:56:49+00:00\",\"dateModified\":\"2024-08-08T15:22:21+00:00\",\"description\":\"Cliquez ici pour d\u00e9couvrir tout sur le surpoids du chien et du chat ! Quelles sont les causes et les cons\u00e9quences ? Les solutions, produits ?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/jorge-zapata-_siAu79dnBk-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/jorge-zapata-_siAu79dnBk-unsplash-scaled.jpg\",\"width\":2560,\"height\":1714,\"caption\":\"Ob\u00e9sit\u00e9, surpoids : quelles sont les r\u00e9percussions pour un chien, un chat ?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chat\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/champs-sur-marne-77420\\\/boutique\\\/category\\\/chat\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sant\u00e9 et pr\u00e9vention pour chat\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/category\\\/chat\\\/sante-et-prevention-chat\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Surpoids du chien et du chat, quelles sont les causes et les cons\u00e9quences ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/8f60afb04d773f2295479f6eb9cd43e4\",\"name\":\"Equipe V\u00e9torino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"caption\":\"Equipe V\u00e9torino\"},\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/barbezieux-saint-hilaire\\\/boutique\\\/author\\\/equipe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Surpoids du chien et du chat, quelles sont les causes et les cons\u00e9quences ? - V\u00e9torino","description":"Cliquez ici pour d\u00e9couvrir tout sur le surpoids du chien et du chat ! Quelles sont les causes et les cons\u00e9quences ? Les solutions, produits ?","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Surpoids du chien et du chat, quelles sont les causes et les cons\u00e9quences ? - V\u00e9torino","og_description":"Cliquez ici pour d\u00e9couvrir tout sur le surpoids du chien et du chat ! Quelles sont les causes et les cons\u00e9quences ? Les solutions, produits ?","og_url":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/2022\/02\/22\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_published_time":"2022-02-22T13:56:49+00:00","article_modified_time":"2024-08-08T15:22:21+00:00","og_image":[{"width":2560,"height":1714,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/jorge-zapata-_siAu79dnBk-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"Equipe V\u00e9torino","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Equipe V\u00e9torino","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\/#article","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\/"},"author":{"name":"Equipe V\u00e9torino","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/8f60afb04d773f2295479f6eb9cd43e4"},"headline":"Surpoids du chien et du chat, quelles sont les causes et les cons\u00e9quences ?","datePublished":"2022-02-22T13:56:49+00:00","dateModified":"2024-08-08T15:22:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\/"},"wordCount":1253,"commentCount":0,"publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/jorge-zapata-_siAu79dnBk-unsplash-scaled.jpg","articleSection":["Chat","Chien","Sant\u00e9 et pr\u00e9vention pour chat","Sant\u00e9 pour chien"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\/","url":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\/","name":"Surpoids du chien et du chat, quelles sont les causes et les cons\u00e9quences ? - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/jorge-zapata-_siAu79dnBk-unsplash-scaled.jpg","datePublished":"2022-02-22T13:56:49+00:00","dateModified":"2024-08-08T15:22:21+00:00","description":"Cliquez ici pour d\u00e9couvrir tout sur le surpoids du chien et du chat ! Quelles sont les causes et les cons\u00e9quences ? Les solutions, produits ?","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/jorge-zapata-_siAu79dnBk-unsplash-scaled.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/jorge-zapata-_siAu79dnBk-unsplash-scaled.jpg","width":2560,"height":1714,"caption":"Ob\u00e9sit\u00e9, surpoids : quelles sont les r\u00e9percussions pour un chien, un chat ?"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/surpoids-du-chien-et-du-chat-quelles-sont-les-causes-et-les-consequences\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Chat","item":"https:\/\/www.vetorino.com\/veterinaire\/champs-sur-marne-77420\/boutique\/category\/chat\/"},{"@type":"ListItem","position":3,"name":"Sant\u00e9 et pr\u00e9vention pour chat","item":"https:\/\/www.vetorino.com\/boutique\/category\/chat\/sante-et-prevention-chat\/"},{"@type":"ListItem","position":4,"name":"Surpoids du chien et du chat, quelles sont les causes et les cons\u00e9quences ?"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]},{"@type":"Person","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/8f60afb04d773f2295479f6eb9cd43e4","name":"Equipe V\u00e9torino","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","caption":"Equipe V\u00e9torino"},"url":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/author\/equipe\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/wp-json\/wp\/v2\/posts\/295690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/wp-json\/wp\/v2\/users\/10426"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/wp-json\/wp\/v2\/comments?post=295690"}],"version-history":[{"count":34,"href":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/wp-json\/wp\/v2\/posts\/295690\/revisions"}],"predecessor-version":[{"id":300848,"href":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/wp-json\/wp\/v2\/posts\/295690\/revisions\/300848"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/wp-json\/wp\/v2\/media\/295695"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/wp-json\/wp\/v2\/media?parent=295690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/wp-json\/wp\/v2\/categories?post=295690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/barbezieux-saint-hilaire\/boutique\/wp-json\/wp\/v2\/tags?post=295690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}