{"id":278,"date":"2021-12-24T17:18:20","date_gmt":"2021-12-24T16:18:20","guid":{"rendered":"http:\/\/service-client@vetorino.com"},"modified":"2024-08-08T17:22:38","modified_gmt":"2024-08-08T15:22:38","slug":"covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus","status":"publish","type":"post","link":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/2021\/12\/24\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\/","title":{"rendered":"COVID19 : Les animaux peuvent-ils \u00eatre vecteur du coronavirus ?"},"content":{"rendered":"\n<p>Jusqu\u2019\u00e0 preuve du contraire, les animaux ne peuvent pas \u00eatre atteint, ni vecteur du coronavirus COVID19. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Un cas de coronavirus chez un chien d\u00e9tect\u00e9 \u00e0 Hong-Kong<\/strong><\/h3>\n\n\n\n<p>Un chien test\u00e9 faiblement positif au coronavirus, est \u00e0 l&#8217;origine de nombreuses rumeurs concernant les infections humain-animal. En effet, son ma\u00eetre a \u00e9galement \u00e9t\u00e9 test\u00e9 positif au coronavirus, affolant les gens sur le fait que ce soit l\u2019animal qui lui aurait transmis. <\/p>\n\n\n\n<p>L&#8217;ANSES (Agence Nationale de S\u00e9curit\u00e9 Sanitaire de l&#8217;alimentation, de l&#8217;environnement et du travail) a donc r\u00e9unit un groupe d&#8217;expert en urgence pour se pencher sur cette question. <\/p>\n\n\n\n<p>N\u00e9anmoins, l\u2019homme \u00e9tait atteint du COVID19 et aurait transmis des traces de ce virus, dans les cavit\u00e9s nasales et buccales, de son animal, qui n\u2019a par la suite d\u00e9velopp\u00e9 aucuns sympt\u00f4mes.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Le coronavirus \u00e9met beaucoup d\u2019inqui\u00e9tude&nbsp;: <\/strong><\/h3>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Peut-il y avoir une transmission de la maladie entre les animaux domestiques et l\u2019homme&nbsp;?<\/strong><\/h4>\n\n\n\n<p>Ce nouveau coronavirus forme une psychose chez certains propri\u00e9taires d\u2019animaux domestiques, les menant \u00e0 accoutrer leurs animaux de masques de protection. Mais, \u00ab&nbsp;il n\u2019y aucune preuve que l\u2019animal de compagnie puisse contracter le coronavirus&nbsp;\u00bb selon l\u2019OMS. Les faits sont formels, puisqu\u2019aucun cas de transmission n\u2019a \u00e9t\u00e9 recens\u00e9 dans le monde entre les hommes et les animaux. <\/p>\n\n\n\n<p>M\u00eame si le virus parait probablement d\u2019origine animale, les analyses dont disposent les scientifiques et experts permettent de montrer que le passage du COVID19 de l\u2019animal domestique vers l\u2019homme semble actuellement peu probable.<\/p>\n\n\n\n<p>Un professeur v\u00e9t\u00e9rinaire de Paris, Dominique Grandjean, a \u00e9t\u00e9 interrog\u00e9 par LCI&nbsp;:<\/p>\n\n\n\n<p>\u00ab&nbsp;<em>On est dans un concept\nqui est d\u2019une stupidit\u00e9 sans nom. Ce qu\u2019on constate, c\u2019est que chaque fois qu\u2019il\ny a une maladie qui se r\u00e9pand, on commence \u00e0 chercher cette maladie un petit\npeu partout. On cherche le virus sur le chien d\u2019une personne qui \u00e9tait porteuse\net on trouve des particules du virus, mais on en a trouv\u00e9 sur les tables et les\nchaises qui sont \u00e0 c\u00f4t\u00e9s et on n\u2019a pas mis les tables et les chaises en quarantaine.<\/em>&nbsp;\u00bb<\/p>\n\n\n\n<p>Pour Dominique Grandjean, les animaux ne peuvent pas nous transmettre le COVID19, et il esp\u00e8re que la psychose qui parait chez les gens n\u2019ait pas d\u2019effets alarmants sur les animaux domestiques\u2026<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Certaines pr\u00e9cautions \u00e0 prendre <\/strong><\/h3>\n\n\n\n<p>Pour qu\u2019il y ait une contamination,\nil faut de toutes fa\u00e7ons \u00eatre en contact direct avec une personne d\u00e9j\u00e0 infect\u00e9e\npar le virus. <\/p>\n\n\n\n<p>M\u00eames si dans les faits, aucun cas de coronavirus n\u2019a \u00e9t\u00e9 d\u00e9tect\u00e9 chez le chien et le chat, ils restent tout de m\u00eame des mammif\u00e8res poss\u00e9dant certains types de r\u00e9cepteurs sur leurs cellules, identiques aux n\u00f4tres, permettant au virus de s\u2019y attacher. M\u00eame s\u2019il est peu probable qu\u2019il entre par la suite dans leurs cellules pour s\u2019y d\u00e9velopper.<\/p>\n\n\n\n<p>Les personnes atteintes du COVID19 devraient alors limiter le contact avec leurs animaux, se laver les mains r\u00e9guli\u00e8rement, et ne pas se laisser l\u00e9cher le visage.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Le coronavirus sur les animaux de compagnies<\/strong><\/h3>\n\n\n\n<p>Il ne faut pas oublier qu\u2019il existe plusieurs formes de coronavirus, dont une dizaine ont d\u00e9j\u00e0 \u00e9t\u00e9 identifi\u00e9es, comme le SRAS en 2003. Certaines formes peuvent toucher les animaux. Les sympt\u00f4mes chez le chien et le chat apparaissent sous formes d\u2019affections digestives.<\/p>\n\n\n\n<p>Une v\u00e9t\u00e9rinaire et r\u00e9dactrice web sp\u00e9cialis\u00e9e en sant\u00e9 humaine et animale \u00e0 Malakoff, Isabelle Vix\u00e8ge, explique au site Femina les cons\u00e9quences du virus sur nos animaux de compagnies&nbsp;: <\/p>\n\n\n\n<p>\u00ab&nbsp;<em>Chez le chien et le chat, les coronavirus sont surtout responsables d\u2019affections digestives. Le coronavirus du chat se manifeste par une gastro-ent\u00e9rite g\u00e9n\u00e9ralement peu s\u00e9v\u00e8re. Cependant, le coronavirus du chat peut parfois entrainer des diarrh\u00e9es plus importantes, voire h\u00e9morragiques. (\u2026) Dans certains cas, le coronavirus du chat peut muter et l\u2019animal va alors d\u00e9velopper une forme particuli\u00e8re de la maladie&nbsp;: la P\u00e9ritonite Infectieuse F\u00e9line.<\/em>&nbsp;\u00bb<\/p>\n\n\n\n<p><br><\/p>\n\n\n\n<p>V\u00e9torino peut vous aider \u00e0 trouver un v\u00e9t\u00e9rinaire pour votre animal de compagnie en <a href=\"https:\/\/www.vetorino.com\/\">cliquant ici<\/a>.  Vous pouvez contacter un membre de notre \u00e9quipe et obtenir plus de renseignements en <a href=\"https:\/\/www.vetorino.com\/pro\">cliquant ici<\/a>. <\/p>\n\n\n\n<p><a href=\"https:\/\/www.veterinaire.fr\/fileadmin\/cru-1584374826\/user_upload\/documents\/actualites\/COVID_19\/Affiche_ESV_16032020.pdf\"><strong>INFO COVID19<\/strong><\/a><strong> :<\/strong> <strong>D\u00e9placez vous chez votre v\u00e9t\u00e9rinaire en cas d&#8217;urgence, et d&#8217;urgence uniquement.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jusqu\u2019\u00e0 preuve du contraire, les animaux ne peuvent pas \u00eatre atteint, ni vecteur du coronavirus COVID19. Un cas de coronavirus chez un chien d\u00e9tect\u00e9 \u00e0 Hong-Kong Un chien test\u00e9 faiblement positif au coronavirus, est \u00e0 l&#8217;origine de nombreuses rumeurs concernant les infections humain-animal. En effet, son ma\u00eetre a \u00e9galement \u00e9t\u00e9 test\u00e9 positif au coronavirus, affolant [&hellip;]<\/p>\n","protected":false},"author":10426,"featured_media":279295,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[14095,14094],"tags":[],"class_list":["post-278","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sante-et-prevention-chat","category-sante-chien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COVID19 : Les animaux peuvent-ils \u00eatre vecteur du coronavirus?- V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Ce nouveau coronavirus, COVID19, forme une psychose chez certains propri\u00e9taires d\u2019animaux, jusqu\u2019\u00e0 preuve du contraire, ils ne peuvent pas en \u00eatre vecteur.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COVID19 : Les animaux peuvent-ils \u00eatre vecteur du coronavirus?- V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Ce nouveau coronavirus, COVID19, forme une psychose chez certains propri\u00e9taires d\u2019animaux, jusqu\u2019\u00e0 preuve du contraire, ils ne peuvent pas en \u00eatre vecteur.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/2021\/12\/24\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-24T16:18:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-08T15:22:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/02\/ROYAL-8118965.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"255\" \/>\n\t<meta property=\"og:image:height\" content=\"255\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe V\u00e9torino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"COVID19 : Les animaux peuvent-ils \u00eatre vecteur du coronavirus?- V\u00e9torino\" \/>\n<meta name=\"twitter:description\" content=\"Ce nouveau coronavirus, COVID19, forme une psychose chez certains propri\u00e9taires d\u2019animaux, jusqu\u2019\u00e0 preuve du contraire, ils ne peuvent pas en \u00eatre vecteur.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/02\/ROYAL-8118965.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe V\u00e9torino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\\\/\"},\"author\":{\"name\":\"Equipe V\u00e9torino\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/6c2a6631b1dafb889300d67266761861\"},\"headline\":\"COVID19 : Les animaux peuvent-ils \u00eatre vecteur du coronavirus ?\",\"datePublished\":\"2021-12-24T16:18:20+00:00\",\"dateModified\":\"2024-08-08T15:22:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\\\/\"},\"wordCount\":764,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/chien-covid.png\",\"articleSection\":[\"Sant\u00e9 et pr\u00e9vention pour chat\",\"Sant\u00e9 pour chien\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\\\/\",\"name\":\"COVID19 : Les animaux peuvent-ils \u00eatre vecteur du coronavirus?- V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/chien-covid.png\",\"datePublished\":\"2021-12-24T16:18:20+00:00\",\"dateModified\":\"2024-08-08T15:22:38+00:00\",\"description\":\"Ce nouveau coronavirus, COVID19, forme une psychose chez certains propri\u00e9taires d\u2019animaux, jusqu\u2019\u00e0 preuve du contraire, ils ne peuvent pas en \u00eatre vecteur.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/chien-covid.png\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/chien-covid.png\",\"width\":700,\"height\":181},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chat\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/champs-sur-marne-77420\\\/boutique\\\/category\\\/chat\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sant\u00e9 et pr\u00e9vention pour chat\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/category\\\/chat\\\/sante-et-prevention-chat\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"COVID19 : Les animaux peuvent-ils \u00eatre vecteur du coronavirus ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/6c2a6631b1dafb889300d67266761861\",\"name\":\"Equipe V\u00e9torino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"caption\":\"Equipe V\u00e9torino\"},\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/beaumontlesvalence-26760\\\/boutique\\\/author\\\/equipe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COVID19 : Les animaux peuvent-ils \u00eatre vecteur du coronavirus?- V\u00e9torino","description":"Ce nouveau coronavirus, COVID19, forme une psychose chez certains propri\u00e9taires d\u2019animaux, jusqu\u2019\u00e0 preuve du contraire, ils ne peuvent pas en \u00eatre vecteur.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"COVID19 : Les animaux peuvent-ils \u00eatre vecteur du coronavirus?- V\u00e9torino","og_description":"Ce nouveau coronavirus, COVID19, forme une psychose chez certains propri\u00e9taires d\u2019animaux, jusqu\u2019\u00e0 preuve du contraire, ils ne peuvent pas en \u00eatre vecteur.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/2021\/12\/24\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_published_time":"2021-12-24T16:18:20+00:00","article_modified_time":"2024-08-08T15:22:38+00:00","og_image":[{"width":255,"height":255,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/02\/ROYAL-8118965.jpg","type":"image\/jpeg"}],"author":"Equipe V\u00e9torino","twitter_card":"summary_large_image","twitter_title":"COVID19 : Les animaux peuvent-ils \u00eatre vecteur du coronavirus?- V\u00e9torino","twitter_description":"Ce nouveau coronavirus, COVID19, forme une psychose chez certains propri\u00e9taires d\u2019animaux, jusqu\u2019\u00e0 preuve du contraire, ils ne peuvent pas en \u00eatre vecteur.","twitter_image":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/02\/ROYAL-8118965.jpg","twitter_misc":{"\u00c9crit par":"Equipe V\u00e9torino","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\/#article","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\/"},"author":{"name":"Equipe V\u00e9torino","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/6c2a6631b1dafb889300d67266761861"},"headline":"COVID19 : Les animaux peuvent-ils \u00eatre vecteur du coronavirus ?","datePublished":"2021-12-24T16:18:20+00:00","dateModified":"2024-08-08T15:22:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\/"},"wordCount":764,"publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chien-covid.png","articleSection":["Sant\u00e9 et pr\u00e9vention pour chat","Sant\u00e9 pour chien"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\/","url":"https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\/","name":"COVID19 : Les animaux peuvent-ils \u00eatre vecteur du coronavirus?- V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chien-covid.png","datePublished":"2021-12-24T16:18:20+00:00","dateModified":"2024-08-08T15:22:38+00:00","description":"Ce nouveau coronavirus, COVID19, forme une psychose chez certains propri\u00e9taires d\u2019animaux, jusqu\u2019\u00e0 preuve du contraire, ils ne peuvent pas en \u00eatre vecteur.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chien-covid.png","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chien-covid.png","width":700,"height":181},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/covid19-les-animaux-peuvent-ils-etre-vecteur-du-coronavirus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Chat","item":"https:\/\/www.vetorino.com\/veterinaire\/champs-sur-marne-77420\/boutique\/category\/chat\/"},{"@type":"ListItem","position":3,"name":"Sant\u00e9 et pr\u00e9vention pour chat","item":"https:\/\/www.vetorino.com\/boutique\/category\/chat\/sante-et-prevention-chat\/"},{"@type":"ListItem","position":4,"name":"COVID19 : Les animaux peuvent-ils \u00eatre vecteur du coronavirus ?"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]},{"@type":"Person","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/6c2a6631b1dafb889300d67266761861","name":"Equipe V\u00e9torino","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","caption":"Equipe V\u00e9torino"},"url":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/author\/equipe\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/posts\/278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/users\/10426"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/comments?post=278"}],"version-history":[{"count":1,"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/posts\/278\/revisions"}],"predecessor-version":[{"id":300029,"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/posts\/278\/revisions\/300029"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/media\/279295"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/media?parent=278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/categories?post=278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/tags?post=278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}