{"id":101630,"date":"2020-06-30T11:49:49","date_gmt":"2020-06-30T09:49:49","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/roue-de-detente-pour-nac-pour-cages-nevo\/"},"modified":"2023-08-29T02:42:08","modified_gmt":"2023-08-29T00:42:08","slug":"roue-de-detente-pour-nac-pour-cages-nevo","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/product\/roue-de-detente-pour-nac-pour-cages-nevo\/","title":{"rendered":"Roue de d\u00e9tente pour NAC pour cages Nevo"},"content":{"rendered":"<div class='hidden'>MATERIEL<\/div>\n<div class='hidden'>Rongeurs<\/div>\n<p>Roue d&#039;exercice en plastique pour rongeur.<\/p>\n<ul>\n<li>Parfaite pour que l&#039;animal puisse faire de l&#039;exercice et jouer en s&eacute;curit&eacute; dans sa cage NEVO.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>MATERIEL Rongeurs Roue d&#039;exercice en plastique pour rongeur. Parfaite pour que l&#039;animal puisse faire de l&#039;exercice et jouer en s&eacute;curit&eacute; dans sa cage NEVO.<\/p>\n","protected":false},"featured_media":101629,"template":"","meta":[],"product_cat":[2727,12570],"product_tag":[],"class_list":{"0":"post-101630","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-nac","7":"product_cat-rongeur","8":"pa_marque-materiel","10":"first","11":"outofstock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Roue de d\u00e9tente pour NAC pour cages Nevo Mat\u00e9riel - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"MATERIELRongeursRoue d&#039;exercice en plastique pour rongeur. Parfaite pour que l&#039;animal puisse faire de l&#039;exercice et jouer en\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roue de d\u00e9tente pour NAC pour cages Nevo Mat\u00e9riel - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"MATERIELRongeursRoue d&#039;exercice en plastique pour rongeur. Parfaite pour que l&#039;animal puisse faire de l&#039;exercice et jouer en\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/product\/roue-de-detente-pour-nac-pour-cages-nevo\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-29T00:42:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsROU708FormatMediumTypeIM.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"6,67&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"Rupture de stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/roue-de-detente-pour-nac-pour-cages-nevo\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/roue-de-detente-pour-nac-pour-cages-nevo\\\/\",\"name\":\"Roue de d\u00e9tente pour NAC pour cages Nevo Mat\u00e9riel - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/roue-de-detente-pour-nac-pour-cages-nevo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/roue-de-detente-pour-nac-pour-cages-nevo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/FilsROU708FormatMediumTypeIM.png\",\"datePublished\":\"2020-06-30T09:49:49+00:00\",\"dateModified\":\"2023-08-29T00:42:08+00:00\",\"description\":\"MATERIELRongeursRoue d&#039;exercice en plastique pour rongeur. Parfaite pour que l&#039;animal puisse faire de l&#039;exercice et jouer en\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/roue-de-detente-pour-nac-pour-cages-nevo\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/roue-de-detente-pour-nac-pour-cages-nevo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/roue-de-detente-pour-nac-pour-cages-nevo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/FilsROU708FormatMediumTypeIM.png\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/FilsROU708FormatMediumTypeIM.png\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/roue-de-detente-pour-nac-pour-cages-nevo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Roue de d\u00e9tente pour NAC pour cages Nevo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Mat\u00e9riel\" \/>\n<meta property=\"product:price:amount\" content=\"6.67\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"C-ROU708\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Roue de d\u00e9tente pour NAC pour cages Nevo Mat\u00e9riel - V\u00e9torino","description":"MATERIELRongeursRoue d&#039;exercice en plastique pour rongeur. Parfaite pour que l&#039;animal puisse faire de l&#039;exercice et jouer en","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Roue de d\u00e9tente pour NAC pour cages Nevo Mat\u00e9riel - V\u00e9torino","og_description":"MATERIELRongeursRoue d&#039;exercice en plastique pour rongeur. Parfaite pour que l&#039;animal puisse faire de l&#039;exercice et jouer en","og_url":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/product\/roue-de-detente-pour-nac-pour-cages-nevo\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2023-08-29T00:42:08+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsROU708FormatMediumTypeIM.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"6,67&euro;","Disponibilit\u00e9":"Rupture de stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/roue-de-detente-pour-nac-pour-cages-nevo\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/roue-de-detente-pour-nac-pour-cages-nevo\/","name":"Roue de d\u00e9tente pour NAC pour cages Nevo Mat\u00e9riel - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/roue-de-detente-pour-nac-pour-cages-nevo\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/roue-de-detente-pour-nac-pour-cages-nevo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsROU708FormatMediumTypeIM.png","datePublished":"2020-06-30T09:49:49+00:00","dateModified":"2023-08-29T00:42:08+00:00","description":"MATERIELRongeursRoue d&#039;exercice en plastique pour rongeur. Parfaite pour que l&#039;animal puisse faire de l&#039;exercice et jouer en","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/roue-de-detente-pour-nac-pour-cages-nevo\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/roue-de-detente-pour-nac-pour-cages-nevo\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/roue-de-detente-pour-nac-pour-cages-nevo\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsROU708FormatMediumTypeIM.png","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsROU708FormatMediumTypeIM.png","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/roue-de-detente-pour-nac-pour-cages-nevo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Roue de d\u00e9tente pour NAC pour cages Nevo"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Mat\u00e9riel","product_price_amount":"6.67","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"C-ROU708","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/product\/101630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/media\/101629"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/media?parent=101630"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/product_cat?post=101630"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/product_tag?post=101630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}