{"id":107371,"date":"2020-07-09T20:08:05","date_gmt":"2020-07-09T18:08:05","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/corbeille-wouapy-moelleuse\/"},"modified":"2026-05-07T21:30:11","modified_gmt":"2026-05-07T19:30:11","slug":"corbeille-wouapy-moelleuse","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/product\/corbeille-wouapy-moelleuse\/","title":{"rendered":"Corbeille Wouapy Moelleuse"},"content":{"rendered":"<p><strong>Corbeille pour chats et chiens extr\u00eamement douce, confortable et moelleuse. Elle est confectionn\u00e9e avec une fausse fourrure \u00e0 poils longs 100% polyester et remplie d\u2019une ouate silicon\u00e9e, souple et douillette.<\/strong><\/p>\n<p>Le passage \u00e0 la machine \u00e0 laver est possible \u00e0 30\u00b0. S\u00e8che linge d\u00e9conseill\u00e9.<\/p>\n<ul>\n<li>Taille :\u00a0Diam\u00e8tre de 60 cm<\/li>\n<li>Taille : Diam\u00e8tre de 90 cm<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p><strong>Corbeille pour chats et chiens extr\u00eamement douce, confortable et moelleuse. Elle est confectionn\u00e9e avec une fausse fourrure \u00e0 poils longs 100% polyester et remplie d\u2019une ouate silicon\u00e9e, souple et douillette.<\/strong><\/p>\n<p>Le passage \u00e0 la machine \u00e0 laver est possible \u00e0 30\u00b0. S\u00e8che linge d\u00e9conseill\u00e9.<\/p>\n<p>Taille : Diam\u00e8tre de 60 cm<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"featured_media":908493,"template":"","meta":[],"product_cat":[2697,12595],"product_tag":[],"class_list":{"0":"post-107371","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-chat","7":"product_cat-confort-du-chat","8":"pa_marque-wouapy","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Corbeille Wouapy Moelleuse Wouapy - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Corbeille pour chats et chiens extr\u00eamement douce, confortable et moelleuse. Elle est confectionn\u00e9e avec une fausse fourrure \u00e0 poils longs 100% polyester et remplie d\u2019une ouate silicon\u00e9e, souple et douillette.  Le passage \u00e0 la machine \u00e0 laver est possible \u00e0 30\u00b0. S\u00e8che linge d\u00e9conseill\u00e9.  Taille : Diam\u00e8tre de 60 cm  \u00a0\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corbeille Wouapy Moelleuse Wouapy - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Corbeille pour chats et chiens extr\u00eamement douce, confortable et moelleuse. Elle est confectionn\u00e9e avec une fausse fourrure \u00e0 poils longs 100% polyester et remplie d\u2019une ouate silicon\u00e9e, souple et douillette.  Le passage \u00e0 la machine \u00e0 laver est possible \u00e0 30\u00b0. S\u00e8che linge d\u00e9conseill\u00e9.  Taille : Diam\u00e8tre de 60 cm  \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/product\/corbeille-wouapy-moelleuse\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-07T19:30:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/09\/logo-vetorino-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"539\" \/>\n\t<meta property=\"og:image:height\" content=\"224\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/corbeille-wouapy-moelleuse\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/corbeille-wouapy-moelleuse\\\/\",\"name\":\"Corbeille Wouapy Moelleuse Wouapy - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/corbeille-wouapy-moelleuse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/corbeille-wouapy-moelleuse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/corbeille-wouapy-moelleuse.jpg\",\"datePublished\":\"2020-07-09T18:08:05+00:00\",\"dateModified\":\"2026-05-07T19:30:11+00:00\",\"description\":\"Corbeille pour chats et chiens extr\u00eamement douce, confortable et moelleuse. Elle est confectionn\u00e9e avec une fausse fourrure \u00e0 poils longs 100% polyester et remplie d\u2019une ouate silicon\u00e9e, souple et douillette. Le passage \u00e0 la machine \u00e0 laver est possible \u00e0 30\u00b0. S\u00e8che linge d\u00e9conseill\u00e9. Taille : Diam\u00e8tre de 60 cm \u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/corbeille-wouapy-moelleuse\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/corbeille-wouapy-moelleuse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/corbeille-wouapy-moelleuse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/corbeille-wouapy-moelleuse.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/corbeille-wouapy-moelleuse.jpg\",\"width\":540,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/corbeille-wouapy-moelleuse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Corbeille Wouapy Moelleuse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Wouapy\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corbeille Wouapy Moelleuse Wouapy - V\u00e9torino","description":"Corbeille pour chats et chiens extr\u00eamement douce, confortable et moelleuse. Elle est confectionn\u00e9e avec une fausse fourrure \u00e0 poils longs 100% polyester et remplie d\u2019une ouate silicon\u00e9e, souple et douillette.  Le passage \u00e0 la machine \u00e0 laver est possible \u00e0 30\u00b0. S\u00e8che linge d\u00e9conseill\u00e9.  Taille : Diam\u00e8tre de 60 cm  \u00a0","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Corbeille Wouapy Moelleuse Wouapy - V\u00e9torino","og_description":"Corbeille pour chats et chiens extr\u00eamement douce, confortable et moelleuse. Elle est confectionn\u00e9e avec une fausse fourrure \u00e0 poils longs 100% polyester et remplie d\u2019une ouate silicon\u00e9e, souple et douillette.  Le passage \u00e0 la machine \u00e0 laver est possible \u00e0 30\u00b0. S\u00e8che linge d\u00e9conseill\u00e9.  Taille : Diam\u00e8tre de 60 cm  \u00a0","og_url":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/product\/corbeille-wouapy-moelleuse\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-05-07T19:30:11+00:00","og_image":[{"width":539,"height":224,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/09\/logo-vetorino-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/corbeille-wouapy-moelleuse\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/corbeille-wouapy-moelleuse\/","name":"Corbeille Wouapy Moelleuse Wouapy - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/corbeille-wouapy-moelleuse\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/corbeille-wouapy-moelleuse\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/12\/corbeille-wouapy-moelleuse.jpg","datePublished":"2020-07-09T18:08:05+00:00","dateModified":"2026-05-07T19:30:11+00:00","description":"Corbeille pour chats et chiens extr\u00eamement douce, confortable et moelleuse. Elle est confectionn\u00e9e avec une fausse fourrure \u00e0 poils longs 100% polyester et remplie d\u2019une ouate silicon\u00e9e, souple et douillette. Le passage \u00e0 la machine \u00e0 laver est possible \u00e0 30\u00b0. S\u00e8che linge d\u00e9conseill\u00e9. Taille : Diam\u00e8tre de 60 cm \u00a0","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/corbeille-wouapy-moelleuse\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/corbeille-wouapy-moelleuse\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/corbeille-wouapy-moelleuse\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/12\/corbeille-wouapy-moelleuse.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/12\/corbeille-wouapy-moelleuse.jpg","width":540,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/corbeille-wouapy-moelleuse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Corbeille Wouapy Moelleuse"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Wouapy","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/product\/107371","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/media\/908493"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/media?parent=107371"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/product_cat?post=107371"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/product_tag?post=107371"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}