{"id":107665,"date":"2020-07-09T21:19:33","date_gmt":"2020-07-09T19:19:33","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/friandises-chat-premio-freeze-dried\/"},"modified":"2026-04-01T02:42:12","modified_gmt":"2026-04-01T00:42:12","slug":"friandises-chat-premio-freeze-dried","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/product\/friandises-chat-premio-freeze-dried\/","title":{"rendered":"Friandises pour Chat lyophilis\u00e9es"},"content":{"rendered":"<p>Gr\u00e2ce \u00e0 la lyophilisation, les friandises pour chats Freeze Dried C\u0153urs de poulet et crevettes PREMIO sont r\u00e9put\u00e9es pour leur go\u00fbt inalt\u00e9r\u00e9 et la pr\u00e9servation de leurs pr\u00e9cieux ingr\u00e9dients.<\/p>\n<ul>\n<li style=\"list-style-type: none\">\n<ul>\n<li>100 % crevettes lyophilis\u00e9es.<\/li>\n<li>La lyophilisation conserve la totalit\u00e9 du go\u00fbt et les pr\u00e9cieux ingr\u00e9dients.<\/li>\n<li>convient particuli\u00e8rement aux animaux souffrant d&#8217;allergies alimentaires<\/li>\n<li>Riches en prot\u00e9ines<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Gr\u00e2ce \u00e0 la lyophilisation, les friandises pour chats Freeze Dried C\u0153urs de poulet et crevettes PREMIO sont r\u00e9put\u00e9es pour leur go\u00fbt inalt\u00e9r\u00e9 et la pr\u00e9servation de leurs pr\u00e9cieux ingr\u00e9dients.<\/p>\n","protected":false},"featured_media":947656,"template":"","meta":[],"product_cat":[12551,2697,2733],"product_tag":[],"class_list":{"0":"post-107665","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alimentation-du-chat","7":"product_cat-chat","8":"product_cat-friandises-pour-chat","9":"pa_marque-trixie","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Friandises pour Chat lyophilis\u00e9es Trixie - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Gr\u00e2ce \u00e0 la lyophilisation, les friandises pour chats Freeze Dried C\u0153urs de poulet et crevettes PREMIO sont r\u00e9put\u00e9es pour leur go\u00fbt inalt\u00e9r\u00e9 et la pr\u00e9servation de leurs pr\u00e9cieux ingr\u00e9dients.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Friandises pour Chat lyophilis\u00e9es Trixie - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Gr\u00e2ce \u00e0 la lyophilisation, les friandises pour chats Freeze Dried C\u0153urs de poulet et crevettes PREMIO sont r\u00e9put\u00e9es pour leur go\u00fbt inalt\u00e9r\u00e9 et la pr\u00e9servation de leurs pr\u00e9cieux ingr\u00e9dients.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/product\/friandises-chat-premio-freeze-dried\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T00:42:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/07\/PHO_PAC_42756-1_SALL_AWK_V1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/saintjean-31240\\\/boutique\\\/product\\\/friandises-chat-premio-freeze-dried\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/saintjean-31240\\\/boutique\\\/product\\\/friandises-chat-premio-freeze-dried\\\/\",\"name\":\"Friandises pour Chat lyophilis\u00e9es Trixie - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/saintjean-31240\\\/boutique\\\/product\\\/friandises-chat-premio-freeze-dried\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/saintjean-31240\\\/boutique\\\/product\\\/friandises-chat-premio-freeze-dried\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/PHO_PAC_42756-1_SALL_AWK_V1.jpg\",\"datePublished\":\"2020-07-09T19:19:33+00:00\",\"dateModified\":\"2026-04-01T00:42:12+00:00\",\"description\":\"Gr\u00e2ce \u00e0 la lyophilisation, les friandises pour chats Freeze Dried C\u0153urs de poulet et crevettes PREMIO sont r\u00e9put\u00e9es pour leur go\u00fbt inalt\u00e9r\u00e9 et la pr\u00e9servation de leurs pr\u00e9cieux ingr\u00e9dients.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/saintjean-31240\\\/boutique\\\/product\\\/friandises-chat-premio-freeze-dried\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/saintjean-31240\\\/boutique\\\/product\\\/friandises-chat-premio-freeze-dried\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/saintjean-31240\\\/boutique\\\/product\\\/friandises-chat-premio-freeze-dried\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/PHO_PAC_42756-1_SALL_AWK_V1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/PHO_PAC_42756-1_SALL_AWK_V1.jpg\",\"width\":640,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/saintjean-31240\\\/boutique\\\/product\\\/friandises-chat-premio-freeze-dried\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Friandises pour Chat lyophilis\u00e9es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Trixie\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Friandises pour Chat lyophilis\u00e9es Trixie - V\u00e9torino","description":"Gr\u00e2ce \u00e0 la lyophilisation, les friandises pour chats Freeze Dried C\u0153urs de poulet et crevettes PREMIO sont r\u00e9put\u00e9es pour leur go\u00fbt inalt\u00e9r\u00e9 et la pr\u00e9servation de leurs pr\u00e9cieux ingr\u00e9dients.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Friandises pour Chat lyophilis\u00e9es Trixie - V\u00e9torino","og_description":"Gr\u00e2ce \u00e0 la lyophilisation, les friandises pour chats Freeze Dried C\u0153urs de poulet et crevettes PREMIO sont r\u00e9put\u00e9es pour leur go\u00fbt inalt\u00e9r\u00e9 et la pr\u00e9servation de leurs pr\u00e9cieux ingr\u00e9dients.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/product\/friandises-chat-premio-freeze-dried\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-04-01T00:42:12+00:00","og_image":[{"width":640,"height":640,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/07\/PHO_PAC_42756-1_SALL_AWK_V1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/veterinaire\/saintjean-31240\/boutique\/product\/friandises-chat-premio-freeze-dried\/","url":"https:\/\/www.vetorino.com\/veterinaire\/saintjean-31240\/boutique\/product\/friandises-chat-premio-freeze-dried\/","name":"Friandises pour Chat lyophilis\u00e9es Trixie - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/saintjean-31240\/boutique\/product\/friandises-chat-premio-freeze-dried\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/saintjean-31240\/boutique\/product\/friandises-chat-premio-freeze-dried\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/07\/PHO_PAC_42756-1_SALL_AWK_V1.jpg","datePublished":"2020-07-09T19:19:33+00:00","dateModified":"2026-04-01T00:42:12+00:00","description":"Gr\u00e2ce \u00e0 la lyophilisation, les friandises pour chats Freeze Dried C\u0153urs de poulet et crevettes PREMIO sont r\u00e9put\u00e9es pour leur go\u00fbt inalt\u00e9r\u00e9 et la pr\u00e9servation de leurs pr\u00e9cieux ingr\u00e9dients.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/saintjean-31240\/boutique\/product\/friandises-chat-premio-freeze-dried\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/veterinaire\/saintjean-31240\/boutique\/product\/friandises-chat-premio-freeze-dried\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/veterinaire\/saintjean-31240\/boutique\/product\/friandises-chat-premio-freeze-dried\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/07\/PHO_PAC_42756-1_SALL_AWK_V1.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/07\/PHO_PAC_42756-1_SALL_AWK_V1.jpg","width":640,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/veterinaire\/saintjean-31240\/boutique\/product\/friandises-chat-premio-freeze-dried\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Friandises pour Chat lyophilis\u00e9es"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Trixie","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/product\/107665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/media\/947656"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/media?parent=107665"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/product_cat?post=107665"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/product_tag?post=107665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}