{"id":94633,"date":"2020-06-29T15:08:12","date_gmt":"2020-06-29T13:08:12","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/coupe-comprimes\/"},"modified":"2026-02-22T02:42:13","modified_gmt":"2026-02-22T01:42:13","slug":"coupe-comprimes","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/product\/coupe-comprimes\/","title":{"rendered":"Coupe comprim\u00e9s"},"content":{"rendered":"<div class='hidden'>MATERIEL<\/div>\n<div class='hidden'>Chiens<\/div>\n<p>Pour couper les comprim\u00e9s de toutes tailles en deux.<br \/>Avec r\u00e9servoir pour r\u00e9cup\u00e9rer les comprim\u00e9s coup\u00e9s qui ne sont pas encore utilis\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MATERIEL Chiens Pour couper les comprim\u00e9s de toutes tailles en deux.Avec r\u00e9servoir pour r\u00e9cup\u00e9rer les comprim\u00e9s coup\u00e9s qui ne sont pas encore utilis\u00e9s.<\/p>\n","protected":false},"featured_media":94632,"template":"","meta":[],"product_cat":[2698],"product_tag":[],"class_list":{"0":"post-94633","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-chien","7":"pa_marque-materiel","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coupe comprim\u00e9s Mat\u00e9riel - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"MATERIELChiensPour couper les comprim\u00e9s de toutes tailles en deux.Avec r\u00e9servoir pour r\u00e9cup\u00e9rer les comprim\u00e9s coup\u00e9s qui ne sont pas encore utilis\u00e9s.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coupe comprim\u00e9s Mat\u00e9riel - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"MATERIELChiensPour couper les comprim\u00e9s de toutes tailles en deux.Avec r\u00e9servoir pour r\u00e9cup\u00e9rer les comprim\u00e9s coup\u00e9s qui ne sont pas encore utilis\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/product\/coupe-comprimes\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-22T01:42:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsCOU401FormatMediumTypeIM.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"5,91&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/toulouse-31500\\\/boutique\\\/product\\\/coupe-comprimes\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/toulouse-31500\\\/boutique\\\/product\\\/coupe-comprimes\\\/\",\"name\":\"Coupe comprim\u00e9s Mat\u00e9riel - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/toulouse-31500\\\/boutique\\\/product\\\/coupe-comprimes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/toulouse-31500\\\/boutique\\\/product\\\/coupe-comprimes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/FilsCOU401FormatMediumTypeIM.png\",\"datePublished\":\"2020-06-29T13:08:12+00:00\",\"dateModified\":\"2026-02-22T01:42:13+00:00\",\"description\":\"MATERIELChiensPour couper les comprim\u00e9s de toutes tailles en deux.Avec r\u00e9servoir pour r\u00e9cup\u00e9rer les comprim\u00e9s coup\u00e9s qui ne sont pas encore utilis\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/toulouse-31500\\\/boutique\\\/product\\\/coupe-comprimes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/toulouse-31500\\\/boutique\\\/product\\\/coupe-comprimes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/toulouse-31500\\\/boutique\\\/product\\\/coupe-comprimes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/FilsCOU401FormatMediumTypeIM.png\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/FilsCOU401FormatMediumTypeIM.png\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/toulouse-31500\\\/boutique\\\/product\\\/coupe-comprimes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Coupe comprim\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Mat\u00e9riel\" \/>\n<meta property=\"product:price:amount\" content=\"5.91\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"C-COU401\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coupe comprim\u00e9s Mat\u00e9riel - V\u00e9torino","description":"MATERIELChiensPour couper les comprim\u00e9s de toutes tailles en deux.Avec r\u00e9servoir pour r\u00e9cup\u00e9rer les comprim\u00e9s coup\u00e9s qui ne sont pas encore utilis\u00e9s.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Coupe comprim\u00e9s Mat\u00e9riel - V\u00e9torino","og_description":"MATERIELChiensPour couper les comprim\u00e9s de toutes tailles en deux.Avec r\u00e9servoir pour r\u00e9cup\u00e9rer les comprim\u00e9s coup\u00e9s qui ne sont pas encore utilis\u00e9s.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/product\/coupe-comprimes\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-02-22T01:42:13+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsCOU401FormatMediumTypeIM.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"5,91&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/veterinaire\/toulouse-31500\/boutique\/product\/coupe-comprimes\/","url":"https:\/\/www.vetorino.com\/veterinaire\/toulouse-31500\/boutique\/product\/coupe-comprimes\/","name":"Coupe comprim\u00e9s Mat\u00e9riel - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/toulouse-31500\/boutique\/product\/coupe-comprimes\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/toulouse-31500\/boutique\/product\/coupe-comprimes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsCOU401FormatMediumTypeIM.png","datePublished":"2020-06-29T13:08:12+00:00","dateModified":"2026-02-22T01:42:13+00:00","description":"MATERIELChiensPour couper les comprim\u00e9s de toutes tailles en deux.Avec r\u00e9servoir pour r\u00e9cup\u00e9rer les comprim\u00e9s coup\u00e9s qui ne sont pas encore utilis\u00e9s.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/toulouse-31500\/boutique\/product\/coupe-comprimes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/veterinaire\/toulouse-31500\/boutique\/product\/coupe-comprimes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/veterinaire\/toulouse-31500\/boutique\/product\/coupe-comprimes\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsCOU401FormatMediumTypeIM.png","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsCOU401FormatMediumTypeIM.png","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/veterinaire\/toulouse-31500\/boutique\/product\/coupe-comprimes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Coupe comprim\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Mat\u00e9riel","product_price_amount":"5.91","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"C-COU401","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/product\/94633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/media\/94632"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/media?parent=94633"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/product_cat?post=94633"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/product_tag?post=94633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}