{"id":96098,"date":"2020-06-29T17:36:38","date_gmt":"2020-06-29T15:36:38","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/filtre-en-mousse-pour-fontaine-a-eau-drinkwell-avalon\/"},"modified":"2026-01-29T09:41:28","modified_gmt":"2026-01-29T08:41:28","slug":"filtre-en-mousse-pour-fontaine-a-eau-drinkwell-avalon","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/product\/filtre-en-mousse-pour-fontaine-a-eau-drinkwell-avalon\/","title":{"rendered":"Filtre en mousse blanc p\/fontaine Drinkwell Avalon\/360\u00b0\/7,5L"},"content":{"rendered":"<div class='hidden'>MATERIEL<\/div>\n<div class='hidden'>Chiens<\/div>\n<p>Le filtre en mousse rempla\u00e7able garde la pompe et l&#8217;eau plus propres en retenant les poils et les autres salet\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MATERIEL Chiens Le filtre en mousse rempla\u00e7able garde la pompe et l&#8217;eau plus propres en retenant les poils et les autres salet\u00e9s.<\/p>\n","protected":false},"featured_media":96097,"template":"","meta":[],"product_cat":[2697],"product_tag":[],"class_list":{"0":"post-96098","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-chat","7":"pa_marque-drinkwell","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Filtre en mousse blanc p\/fontaine Drinkwell Avalon\/360\u00b0\/7,5L Drinkwell - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"MATERIELChiensLe filtre en mousse rempla\u00e7able garde la pompe et l&#039;eau plus propres en retenant les poils et les autres salet\u00e9s.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Filtre en mousse blanc p\/fontaine Drinkwell Avalon\/360\u00b0\/7,5L Drinkwell - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"MATERIELChiensLe filtre en mousse rempla\u00e7able garde la pompe et l&#039;eau plus propres en retenant les poils et les autres salet\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/product\/filtre-en-mousse-pour-fontaine-a-eau-drinkwell-avalon\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-29T08:41:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsFIL472FormatMediumTypeIM.png\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"7,08&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/filtre-en-mousse-pour-fontaine-a-eau-drinkwell-avalon\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/filtre-en-mousse-pour-fontaine-a-eau-drinkwell-avalon\\\/\",\"name\":\"Filtre en mousse blanc p\\\/fontaine Drinkwell Avalon\\\/360\u00b0\\\/7,5L Drinkwell - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/filtre-en-mousse-pour-fontaine-a-eau-drinkwell-avalon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/filtre-en-mousse-pour-fontaine-a-eau-drinkwell-avalon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/FilsFIL472FormatMediumTypeIM.png\",\"datePublished\":\"2020-06-29T15:36:38+00:00\",\"dateModified\":\"2026-01-29T08:41:28+00:00\",\"description\":\"MATERIELChiensLe filtre en mousse rempla\u00e7able garde la pompe et l'eau plus propres en retenant les poils et les autres salet\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/filtre-en-mousse-pour-fontaine-a-eau-drinkwell-avalon\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/filtre-en-mousse-pour-fontaine-a-eau-drinkwell-avalon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/filtre-en-mousse-pour-fontaine-a-eau-drinkwell-avalon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/FilsFIL472FormatMediumTypeIM.png\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/FilsFIL472FormatMediumTypeIM.png\",\"width\":400,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/filtre-en-mousse-pour-fontaine-a-eau-drinkwell-avalon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Filtre en mousse blanc p\\\/fontaine Drinkwell Avalon\\\/360\u00b0\\\/7,5L\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Drinkwell\" \/>\n<meta property=\"product:price:amount\" content=\"7.08\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"C-FIL472\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Filtre en mousse blanc p\/fontaine Drinkwell Avalon\/360\u00b0\/7,5L Drinkwell - V\u00e9torino","description":"MATERIELChiensLe filtre en mousse rempla\u00e7able garde la pompe et l'eau plus propres en retenant les poils et les autres salet\u00e9s.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Filtre en mousse blanc p\/fontaine Drinkwell Avalon\/360\u00b0\/7,5L Drinkwell - V\u00e9torino","og_description":"MATERIELChiensLe filtre en mousse rempla\u00e7able garde la pompe et l'eau plus propres en retenant les poils et les autres salet\u00e9s.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/product\/filtre-en-mousse-pour-fontaine-a-eau-drinkwell-avalon\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-01-29T08:41:28+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsFIL472FormatMediumTypeIM.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"7,08&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/filtre-en-mousse-pour-fontaine-a-eau-drinkwell-avalon\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/filtre-en-mousse-pour-fontaine-a-eau-drinkwell-avalon\/","name":"Filtre en mousse blanc p\/fontaine Drinkwell Avalon\/360\u00b0\/7,5L Drinkwell - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/filtre-en-mousse-pour-fontaine-a-eau-drinkwell-avalon\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/filtre-en-mousse-pour-fontaine-a-eau-drinkwell-avalon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsFIL472FormatMediumTypeIM.png","datePublished":"2020-06-29T15:36:38+00:00","dateModified":"2026-01-29T08:41:28+00:00","description":"MATERIELChiensLe filtre en mousse rempla\u00e7able garde la pompe et l'eau plus propres en retenant les poils et les autres salet\u00e9s.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/filtre-en-mousse-pour-fontaine-a-eau-drinkwell-avalon\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/filtre-en-mousse-pour-fontaine-a-eau-drinkwell-avalon\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/filtre-en-mousse-pour-fontaine-a-eau-drinkwell-avalon\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsFIL472FormatMediumTypeIM.png","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/FilsFIL472FormatMediumTypeIM.png","width":400,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/filtre-en-mousse-pour-fontaine-a-eau-drinkwell-avalon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Filtre en mousse blanc p\/fontaine Drinkwell Avalon\/360\u00b0\/7,5L"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Drinkwell","product_price_amount":"7.08","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"C-FIL472","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/product\/96098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/media\/96097"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/media?parent=96098"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/product_cat?post=96098"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/beaumontlesvalence-26760\/boutique\/wp-json\/wp\/v2\/product_tag?post=96098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}