{"id":208024,"date":"2021-07-28T12:37:36","date_gmt":"2021-07-28T10:37:36","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/kof-eze-sirop\/"},"modified":"2022-01-04T16:54:09","modified_gmt":"2022-01-04T15:54:09","slug":"kof-eze-sirop","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/bergues-59380\/boutique\/product\/kof-eze-sirop\/","title":{"rendered":"Kof-eze Sirop"},"content":{"rendered":"<p>Horse Master Kof-Eze est une solution liquide permettant de lib\u00e9rer les voies respiratoires du cheval. Parfait pour lutter contre les toux d&#8217;irritation et les encombrements au niveau des voies respiratoires.<\/p>\n<p>KOF-EZE est une formule compos\u00e9e d&#8217;huiles essentielles d&#8217;eucalyptus, de thym et de romarin connues pour leurs propri\u00e9t\u00e9s expectorantes, anti-infectieuses et calmantes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Horse Master Kof-Eze<\/strong> est une solution liquide permettant de lib\u00e9rer les voies respiratoires du cheval. Parfait pour lutter contre les toux d&#8217;irritation et les encombrements au niveau des voies respiratoires.<\/p>\n","protected":false},"featured_media":208031,"template":"","meta":[],"product_cat":[12569,12547,14072],"product_tag":[],"class_list":{"0":"post-208024","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-respiration-du-cheval","7":"product_cat-cheval","8":"product_cat-dietetique-et-complements-alimentaires-du-cheval","9":"pa_marque-pommier-nutriti","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kof-eze Sirop Pommier Nutrition - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Horse Master Kof-Eze est une solution liquide permettant de lib\u00e9rer les voies respiratoires du cheval. Parfait pour lutter contre les toux d&#039;irritation et les encombrements au niveau des voies respiratoires.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kof-eze Sirop Pommier Nutrition - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Horse Master Kof-Eze est une solution liquide permettant de lib\u00e9rer les voies respiratoires du cheval. Parfait pour lutter contre les toux d&#039;irritation et les encombrements au niveau des voies respiratoires.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/bergues-59380\/boutique\/product\/kof-eze-sirop\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-04T15:54:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/kof-eze-1-l.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"34,66&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kof-eze-sirop\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kof-eze-sirop\\\/\",\"name\":\"Kof-eze Sirop Pommier Nutrition - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kof-eze-sirop\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kof-eze-sirop\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/kof-eze-1-l.jpg\",\"datePublished\":\"2021-07-28T10:37:36+00:00\",\"dateModified\":\"2022-01-04T15:54:09+00:00\",\"description\":\"Horse Master Kof-Eze est une solution liquide permettant de lib\u00e9rer les voies respiratoires du cheval. Parfait pour lutter contre les toux d'irritation et les encombrements au niveau des voies respiratoires.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kof-eze-sirop\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kof-eze-sirop\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kof-eze-sirop\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/kof-eze-1-l.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/kof-eze-1-l.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kof-eze-sirop\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kof-eze Sirop\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Pommier Nutrition\" \/>\n<meta property=\"product:price:amount\" content=\"34.66\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"A-7559147\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kof-eze Sirop Pommier Nutrition - V\u00e9torino","description":"Horse Master Kof-Eze est une solution liquide permettant de lib\u00e9rer les voies respiratoires du cheval. Parfait pour lutter contre les toux d'irritation et les encombrements au niveau des voies respiratoires.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Kof-eze Sirop Pommier Nutrition - V\u00e9torino","og_description":"Horse Master Kof-Eze est une solution liquide permettant de lib\u00e9rer les voies respiratoires du cheval. Parfait pour lutter contre les toux d'irritation et les encombrements au niveau des voies respiratoires.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/bergues-59380\/boutique\/product\/kof-eze-sirop\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2022-01-04T15:54:09+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/kof-eze-1-l.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"34,66&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/kof-eze-sirop\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/kof-eze-sirop\/","name":"Kof-eze Sirop Pommier Nutrition - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/kof-eze-sirop\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/kof-eze-sirop\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/kof-eze-1-l.jpg","datePublished":"2021-07-28T10:37:36+00:00","dateModified":"2022-01-04T15:54:09+00:00","description":"Horse Master Kof-Eze est une solution liquide permettant de lib\u00e9rer les voies respiratoires du cheval. Parfait pour lutter contre les toux d'irritation et les encombrements au niveau des voies respiratoires.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/kof-eze-sirop\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/kof-eze-sirop\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/kof-eze-sirop\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/kof-eze-1-l.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/kof-eze-1-l.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/kof-eze-sirop\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Kof-eze Sirop"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Pommier Nutrition","product_price_amount":"34.66","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"A-7559147","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/bergues-59380\/boutique\/wp-json\/wp\/v2\/product\/208024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/bergues-59380\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/bergues-59380\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/bergues-59380\/boutique\/wp-json\/wp\/v2\/media\/208031"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/bergues-59380\/boutique\/wp-json\/wp\/v2\/media?parent=208024"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/bergues-59380\/boutique\/wp-json\/wp\/v2\/product_cat?post=208024"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/bergues-59380\/boutique\/wp-json\/wp\/v2\/product_tag?post=208024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}