{"id":307550,"date":"2022-03-24T15:07:54","date_gmt":"2022-03-24T14:07:54","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/vet-hpm-wet-cat-urology-dp-12-scht-85g\/"},"modified":"2025-12-03T11:15:27","modified_gmt":"2025-12-03T10:15:27","slug":"vet-hpm-wet-cat-urology-dp-12-scht-85g","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/bergues-59380\/boutique\/product\/vet-hpm-wet-cat-urology-dp-12-scht-85g\/","title":{"rendered":"Urology Dissolution &amp; Prevention Cat"},"content":{"rendered":"<p><strong>Aliment di\u00e9t\u00e9tique et \u00e9quilibr\u00e9 sous forme de bouch\u00e9es en sachets fra\u00eecheur\u00a0destin\u00e9 \u00e0 la prise en charge nutritionnelle des chats sujets \u00e0 la formation de calculs de struvite et d\u2019oxalate.<\/strong><\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Chat sujet aux calculs urinaires de struvite et d&#8217;oxalate.<\/li>\n<\/ul>\n<p><strong>Bienfaits essentiels :<\/strong><\/p>\n<ul>\n<li><strong>Soutien de l&#8217;hydratation :<\/strong>\u00a0le taux \u00e9lev\u00e9 d\u2019humidit\u00e9 de l\u2019aliment augmente naturellement l\u2019apport total en eau (eau de l\u2019alimentation et eau de boisson) pour une hydratation de l\u2019organisme optimale.<\/li>\n<\/ul>\n<ul>\n<li><strong>RSS struvites bas :<\/strong>\u00a0la formulation induit une urine sous- satur\u00e9e pour les struvites, avec un index de supersaturation relative (RSS) des struvites &lt; 1, pour favoriser la dissolution des calculs de struvite existants et\u00a0 pr\u00e9venir la formation de nouveaux calculs.<\/li>\n<\/ul>\n<ul>\n<li><strong>Optimisation du pH urinaire :<\/strong>\u00a0le pH urinaire compris entre 6,0 et 6,5 permet de pr\u00e9venir la formation des calculs de struvite et d\u2019oxalate de calcium.<\/li>\n<\/ul>\n<ul>\n<li><strong>Poids optimal :\u00a0<\/strong>le faible apport \u00e9nerg\u00e9tique et l\u2019\u00e9quilibre \u00e9nerg\u00e9tique (prot\u00e9ines \/ mati\u00e8res grasses \/ glucides) limitent l\u2019apport calorique. La teneur \u00e9lev\u00e9e en eau aide \u00e0 la sensation de sati\u00e9t\u00e9.<\/li>\n<li><strong>App\u00e9tence \u00e9lev\u00e9e :<\/strong>\u00a0la richesse en ingr\u00e9dients animaux (87%) et la r\u00e9partition des macronutriments (riche en prot\u00e9ines \u2013 tr\u00e8s pauvre en glucides) respecte la pr\u00e9f\u00e9rence naturelle des chats.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p><strong>Aliment di\u00e9t\u00e9tique et \u00e9quilibr\u00e9 sous forme de bouch\u00e9es en sachets fra\u00eecheur\u00a0destin\u00e9 \u00e0 la prise en charge nutritionnelle des chats sujets \u00e0 la formation de calculs de struvite et d\u2019oxalate.<\/strong><\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Chat sujet aux calculs urinaires de struvite et d&#8217;oxalate.<\/li>\n<\/ul>\n","protected":false},"featured_media":307556,"template":"","meta":[],"product_cat":[12551,12581,2697,12645],"product_tag":[],"class_list":{"0":"post-307550","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alimentation-du-chat","7":"product_cat-alimentation-medicalisee-pour-chat","8":"product_cat-chat","9":"product_cat-systeme-urinaire-du-chat","10":"pa_marque-virbac","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Urology Dissolution &amp; Prevention Cat Bouch\u00e9es - HPM v\u00e9t\u00e9rinaire Virbac<\/title>\n<meta name=\"description\" content=\"Aliment di\u00e9t\u00e9tique et \u00e9quilibr\u00e9 sous forme de bouch\u00e9es en sachets fra\u00eecheur\u00a0destin\u00e9 \u00e0 la prise en charge nutritionnelle des chats sujets \u00e0 la formation de calculs de struvite et d\u2019oxalate.  Utilisation :   Chat sujet aux calculs urinaires de struvite et d&#039;oxalate.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Urology Dissolution &amp; Prevention Cat Bouch\u00e9es - HPM v\u00e9t\u00e9rinaire Virbac\" \/>\n<meta property=\"og:description\" content=\"Aliment di\u00e9t\u00e9tique et \u00e9quilibr\u00e9 sous forme de bouch\u00e9es en sachets fra\u00eecheur\u00a0destin\u00e9 \u00e0 la prise en charge nutritionnelle des chats sujets \u00e0 la formation de calculs de struvite et d\u2019oxalate.  Utilisation :   Chat sujet aux calculs urinaires de struvite et d&#039;oxalate.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/bergues-59380\/boutique\/product\/vet-hpm-wet-cat-urology-dp-12-scht-85g\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-03T10:15:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/03\/urology-dissolution-prevention-cat-bouchees-.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"19,10&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/vet-hpm-wet-cat-urology-dp-12-scht-85g\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/vet-hpm-wet-cat-urology-dp-12-scht-85g\\\/\",\"name\":\"Urology Dissolution & Prevention Cat Bouch\u00e9es - HPM v\u00e9t\u00e9rinaire Virbac\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/vet-hpm-wet-cat-urology-dp-12-scht-85g\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/vet-hpm-wet-cat-urology-dp-12-scht-85g\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/urology-dissolution-prevention-cat-bouchees-.jpeg\",\"datePublished\":\"2022-03-24T14:07:54+00:00\",\"dateModified\":\"2025-12-03T10:15:27+00:00\",\"description\":\"Aliment di\u00e9t\u00e9tique et \u00e9quilibr\u00e9 sous forme de bouch\u00e9es en sachets fra\u00eecheur\u00a0destin\u00e9 \u00e0 la prise en charge nutritionnelle des chats sujets \u00e0 la formation de calculs de struvite et d\u2019oxalate. Utilisation : Chat sujet aux calculs urinaires de struvite et d'oxalate.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/vet-hpm-wet-cat-urology-dp-12-scht-85g\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/vet-hpm-wet-cat-urology-dp-12-scht-85g\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/vet-hpm-wet-cat-urology-dp-12-scht-85g\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/urology-dissolution-prevention-cat-bouchees-.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/urology-dissolution-prevention-cat-bouchees-.jpeg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/vet-hpm-wet-cat-urology-dp-12-scht-85g\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Urology Dissolution &amp; Prevention Cat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Virbac\" \/>\n<meta property=\"product:price:amount\" content=\"19.10\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"A-1865480\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Urology Dissolution & Prevention Cat Bouch\u00e9es - HPM v\u00e9t\u00e9rinaire Virbac","description":"Aliment di\u00e9t\u00e9tique et \u00e9quilibr\u00e9 sous forme de bouch\u00e9es en sachets fra\u00eecheur\u00a0destin\u00e9 \u00e0 la prise en charge nutritionnelle des chats sujets \u00e0 la formation de calculs de struvite et d\u2019oxalate.  Utilisation :   Chat sujet aux calculs urinaires de struvite et d'oxalate.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Urology Dissolution & Prevention Cat Bouch\u00e9es - HPM v\u00e9t\u00e9rinaire Virbac","og_description":"Aliment di\u00e9t\u00e9tique et \u00e9quilibr\u00e9 sous forme de bouch\u00e9es en sachets fra\u00eecheur\u00a0destin\u00e9 \u00e0 la prise en charge nutritionnelle des chats sujets \u00e0 la formation de calculs de struvite et d\u2019oxalate.  Utilisation :   Chat sujet aux calculs urinaires de struvite et d'oxalate.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/bergues-59380\/boutique\/product\/vet-hpm-wet-cat-urology-dp-12-scht-85g\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2025-12-03T10:15:27+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/03\/urology-dissolution-prevention-cat-bouchees-.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"19,10&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/vet-hpm-wet-cat-urology-dp-12-scht-85g\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/vet-hpm-wet-cat-urology-dp-12-scht-85g\/","name":"Urology Dissolution & Prevention Cat Bouch\u00e9es - HPM v\u00e9t\u00e9rinaire Virbac","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/vet-hpm-wet-cat-urology-dp-12-scht-85g\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/vet-hpm-wet-cat-urology-dp-12-scht-85g\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/03\/urology-dissolution-prevention-cat-bouchees-.jpeg","datePublished":"2022-03-24T14:07:54+00:00","dateModified":"2025-12-03T10:15:27+00:00","description":"Aliment di\u00e9t\u00e9tique et \u00e9quilibr\u00e9 sous forme de bouch\u00e9es en sachets fra\u00eecheur\u00a0destin\u00e9 \u00e0 la prise en charge nutritionnelle des chats sujets \u00e0 la formation de calculs de struvite et d\u2019oxalate. Utilisation : Chat sujet aux calculs urinaires de struvite et d'oxalate.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/vet-hpm-wet-cat-urology-dp-12-scht-85g\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/vet-hpm-wet-cat-urology-dp-12-scht-85g\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/vet-hpm-wet-cat-urology-dp-12-scht-85g\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/03\/urology-dissolution-prevention-cat-bouchees-.jpeg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/03\/urology-dissolution-prevention-cat-bouchees-.jpeg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/vet-hpm-wet-cat-urology-dp-12-scht-85g\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Urology Dissolution &amp; Prevention Cat"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Virbac","product_price_amount":"19.10","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"A-1865480","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/bergues-59380\/boutique\/wp-json\/wp\/v2\/product\/307550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/bergues-59380\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/bergues-59380\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/bergues-59380\/boutique\/wp-json\/wp\/v2\/media\/307556"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/bergues-59380\/boutique\/wp-json\/wp\/v2\/media?parent=307550"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/bergues-59380\/boutique\/wp-json\/wp\/v2\/product_cat?post=307550"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/bergues-59380\/boutique\/wp-json\/wp\/v2\/product_tag?post=307550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}