{"id":1093084,"date":"2024-12-09T12:00:00","date_gmt":"2024-12-09T11:00:00","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/?p=1093084"},"modified":"2024-12-09T16:17:53","modified_gmt":"2024-12-09T15:17:53","slug":"arthrose-chien","status":"publish","type":"post","link":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/2024\/12\/09\/arthrose-chien\/","title":{"rendered":"Arthrose chez le chien"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1093084\" class=\"elementor elementor-1093084\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4747b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4747b9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f0a8be6\" data-id=\"f0a8be6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77b80b4 elementor-widget elementor-widget-text-editor\" data-id=\"77b80b4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<section data-id=\"8j8qvkr\" data-element_type=\"section\">\n<div>\n<div>\n<div data-id=\"2u8kg9v\" data-element_type=\"column\">\n<div>\n<div>\n<div data-id=\"tcv8rwn\" data-element_type=\"heading.default\">\n<h2>Arthrose chez le chien : savez-vous r\u00e9ellement \u00e0 quoi \u00e7a correspond ?<\/span><\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86b51a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86b51a2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca49f12\" data-id=\"ca49f12\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d92d7f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2d92d7f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019arthrose est une <strong>d\u00e9gradation progressive du cartilage au niveau d\u2019une ou plusieurs articulations telles que celles du genou, des hanches, du dos ou des coudes<\/strong>. \u00c0 mesure qu\u2019elle progresse dans le corps du chien, les douleurs deviennent plus importantes. Votre animal perd alors sa mobilit\u00e9 au quotidien.<\/p><p>Contrairement aux id\u00e9es re\u00e7ues, <strong>l\u2019arthrose ne touche pas que les animaux \u00e2g\u00e9s<\/strong>. Le surpoids et l\u2019ob\u00e9sit\u00e9 combin\u00e9 au manque d\u2019activit\u00e9 physique peuvent \u00e9galement d\u00e9clencher cette maladie.<\/p><p><!-- notionvc: f3365c80-e02e-467b-b5ae-31b62867bbca --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2520cb6 elementor-widget elementor-widget-text-editor\" data-id=\"2520cb6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L\u2019arthrose est aussi une cons\u00e9quence directe des dysplasies du coude et de la hanche. Elle se d\u00e9veloppe aussi fr\u00e9quemment \u00e0 la suite d\u2019une rupture des ligaments crois\u00e9s, m\u00eame apr\u00e8s une chirurgie.<\/p><p>Plus t\u00f4t, on la diagnostique et plus il est possible d\u2019agir pour ralentir l\u2019avanc\u00e9e de la maladie. Notamment gr\u00e2ce \u00e0 la physioth\u00e9rapie avec un programme de s\u00e9ances adapt\u00e9es.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37f3744 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37f3744\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5abeb12\" data-id=\"5abeb12\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90b5d84 elementor-widget elementor-widget-image\" data-id=\"90b5d84\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.vetorino.com\/boutique\/marque\/royal-canin\/?s&#038;maladie=troubles-digestifs&#038;swcfpc=1\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1536\" height=\"864\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/arthrose-chien2-1536x864.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-1093088\" alt=\"chien arthrosique qui marche dans l&#039;eau\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/arthrose-chien2-1536x864.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/arthrose-chien2-300x169.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/arthrose-chien2-1024x576.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/arthrose-chien2-768x432.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/arthrose-chien2-2048x1152.jpg 2048w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/arthrose-chien2-555x312.jpg 555w\" sizes=\"(max-width: 1536px) 100vw, 1536px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-448f199 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"448f199\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pour rep\u00e9rer les premiers signes, tout est dans l\u2019observation. <strong>S\u2019il peine \u00e0 monter les escaliers, \u00e0 se lever pour partir en promenade, ou encore \u00e0 monter sur le canap\u00e9, ces signes doivent vous pousser \u00e0 rechercher plus loin<\/strong>.<\/p><p>En particulier si le chien ou le chat est en surpoids, en d\u00e9ficit d\u2019activit\u00e9 physique r\u00e9guli\u00e8re, ou \u00e2g\u00e9. Les chiens de grande taille (<em>Labrador, Golden Retriever, Bouvier Bernois, \u2026<\/em>) sont souvent les principaux concern\u00e9s, mais il ne faut exclure aucune possibilit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6cb33a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6cb33a2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-89d7b48\" data-id=\"89d7b48\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50e8476 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"50e8476\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Dans ce cas, parlez-en \u00e0 votre v\u00e9t\u00e9rinaire et pensez \u00e0 la physioth\u00e9rapie. Elle peut \u00e9viter, ou retarder en fonction du cas, les traitements m\u00e9dicamenteux \u00e0 votre animal. Et surtout lui permettre de retrouver du confort au quotidien. \ud83d\udc99<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Arthrose chez le chien : savez-vous r\u00e9ellement \u00e0 quoi \u00e7a correspond ? L\u2019arthrose est une d\u00e9gradation progressive du cartilage au niveau d\u2019une ou plusieurs articulations telles que celles du genou, des hanches, du dos ou des coudes. \u00c0 mesure qu\u2019elle progresse dans le corps du chien, les douleurs deviennent plus importantes. Votre animal perd alors [&hellip;]<\/p>\n","protected":false},"author":68707,"featured_media":1093097,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[14087,14094],"tags":[],"class_list":["post-1093084","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chien","category-sante-chien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arthrose chez le chien : il n&#039;y a pas que les plus \u00e2g\u00e9s qui sont concern\u00e9s !<\/title>\n<meta name=\"description\" content=\"L&#039;arthrose peut toucher des animaux de tous \u00e2ges. D\u00e9couvrez l&#039;essentiel \u00e0 conna\u00eetre sur cette pathologie et les signes \u00e9vocateurs.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arthrose chez le chien : il n&#039;y a pas que les plus \u00e2g\u00e9s qui sont concern\u00e9s !\" \/>\n<meta property=\"og:description\" content=\"L&#039;arthrose peut toucher des animaux de tous \u00e2ges. D\u00e9couvrez l&#039;essentiel \u00e0 conna\u00eetre sur cette pathologie et les signes \u00e9vocateurs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/2024\/12\/09\/arthrose-chien\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-09T11:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-09T15:17:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/arthrose-chien.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1905\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Clemence Sully\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Clemence Sully\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/09\\\/arthrose-chien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/09\\\/arthrose-chien\\\/\"},\"author\":{\"name\":\"Clemence Sully\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/9bd231449b5dab066d32dab7d241eb4a\"},\"headline\":\"Arthrose chez le chien\",\"datePublished\":\"2024-12-09T11:00:00+00:00\",\"dateModified\":\"2024-12-09T15:17:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/09\\\/arthrose-chien\\\/\"},\"wordCount\":291,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/09\\\/arthrose-chien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/arthrose-chien.jpg\",\"articleSection\":[\"Chien\",\"Sant\u00e9 pour chien\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/09\\\/arthrose-chien\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/09\\\/arthrose-chien\\\/\",\"name\":\"Arthrose chez le chien : il n'y a pas que les plus \u00e2g\u00e9s qui sont concern\u00e9s !\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/09\\\/arthrose-chien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/09\\\/arthrose-chien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/arthrose-chien.jpg\",\"datePublished\":\"2024-12-09T11:00:00+00:00\",\"dateModified\":\"2024-12-09T15:17:53+00:00\",\"description\":\"L'arthrose peut toucher des animaux de tous \u00e2ges. D\u00e9couvrez l'essentiel \u00e0 conna\u00eetre sur cette pathologie et les signes \u00e9vocateurs.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/09\\\/arthrose-chien\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/09\\\/arthrose-chien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/09\\\/arthrose-chien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/arthrose-chien.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/arthrose-chien.jpg\",\"width\":1905,\"height\":450,\"caption\":\"arthrose chez le chien\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/09\\\/arthrose-chien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chien\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/champs-sur-marne-77420\\\/boutique\\\/category\\\/chien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Arthrose chez le chien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/9bd231449b5dab066d32dab7d241eb4a\",\"name\":\"Clemence Sully\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g\",\"caption\":\"Clemence Sully\"},\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/boiscolombes-92270\\\/boutique\\\/author\\\/clemence-sully\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arthrose chez le chien : il n'y a pas que les plus \u00e2g\u00e9s qui sont concern\u00e9s !","description":"L'arthrose peut toucher des animaux de tous \u00e2ges. D\u00e9couvrez l'essentiel \u00e0 conna\u00eetre sur cette pathologie et les signes \u00e9vocateurs.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Arthrose chez le chien : il n'y a pas que les plus \u00e2g\u00e9s qui sont concern\u00e9s !","og_description":"L'arthrose peut toucher des animaux de tous \u00e2ges. D\u00e9couvrez l'essentiel \u00e0 conna\u00eetre sur cette pathologie et les signes \u00e9vocateurs.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/2024\/12\/09\/arthrose-chien\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_published_time":"2024-12-09T11:00:00+00:00","article_modified_time":"2024-12-09T15:17:53+00:00","og_image":[{"width":1905,"height":450,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/arthrose-chien.jpg","type":"image\/jpeg"}],"author":"Clemence Sully","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Clemence Sully","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vetorino.com\/boutique\/2024\/12\/09\/arthrose-chien\/#article","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/2024\/12\/09\/arthrose-chien\/"},"author":{"name":"Clemence Sully","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/9bd231449b5dab066d32dab7d241eb4a"},"headline":"Arthrose chez le chien","datePublished":"2024-12-09T11:00:00+00:00","dateModified":"2024-12-09T15:17:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2024\/12\/09\/arthrose-chien\/"},"wordCount":291,"publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2024\/12\/09\/arthrose-chien\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/arthrose-chien.jpg","articleSection":["Chien","Sant\u00e9 pour chien"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/2024\/12\/09\/arthrose-chien\/","url":"https:\/\/www.vetorino.com\/boutique\/2024\/12\/09\/arthrose-chien\/","name":"Arthrose chez le chien : il n'y a pas que les plus \u00e2g\u00e9s qui sont concern\u00e9s !","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2024\/12\/09\/arthrose-chien\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2024\/12\/09\/arthrose-chien\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/arthrose-chien.jpg","datePublished":"2024-12-09T11:00:00+00:00","dateModified":"2024-12-09T15:17:53+00:00","description":"L'arthrose peut toucher des animaux de tous \u00e2ges. D\u00e9couvrez l'essentiel \u00e0 conna\u00eetre sur cette pathologie et les signes \u00e9vocateurs.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/2024\/12\/09\/arthrose-chien\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/2024\/12\/09\/arthrose-chien\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/2024\/12\/09\/arthrose-chien\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/arthrose-chien.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/arthrose-chien.jpg","width":1905,"height":450,"caption":"arthrose chez le chien"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/2024\/12\/09\/arthrose-chien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Chien","item":"https:\/\/www.vetorino.com\/veterinaire\/champs-sur-marne-77420\/boutique\/category\/chien\/"},{"@type":"ListItem","position":3,"name":"Arthrose chez le chien"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]},{"@type":"Person","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/9bd231449b5dab066d32dab7d241eb4a","name":"Clemence Sully","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g","caption":"Clemence Sully"},"url":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/author\/clemence-sully\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/posts\/1093084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/users\/68707"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/comments?post=1093084"}],"version-history":[{"count":13,"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/posts\/1093084\/revisions"}],"predecessor-version":[{"id":1128716,"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/posts\/1093084\/revisions\/1128716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/media\/1093097"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/media?parent=1093084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/categories?post=1093084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/tags?post=1093084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}