{"id":1093147,"date":"2024-12-30T12:00:00","date_gmt":"2024-12-30T11:00:00","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/?p=1093147"},"modified":"2024-12-09T16:22:37","modified_gmt":"2024-12-09T15:22:37","slug":"role-alimentation-insuffisance-renale-chat","status":"publish","type":"post","link":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/2024\/12\/30\/role-alimentation-insuffisance-renale-chat\/","title":{"rendered":"Le r\u00f4le de l&#8217;alimentation dans l&#8217;insuffisance r\u00e9nale chez le chat"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1093147\" class=\"elementor elementor-1093147\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4747b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4747b9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f0a8be6\" data-id=\"f0a8be6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77b80b4 elementor-widget elementor-widget-text-editor\" data-id=\"77b80b4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<section data-id=\"8j8qvkr\" data-element_type=\"section\">\n<div>\n<div>\n<div data-id=\"2u8kg9v\" data-element_type=\"column\">\n<div>\n<div>\n<div data-id=\"tcv8rwn\" data-element_type=\"heading.default\">\n<h2>Comment reconna\u00eetre l&#8217;insuffisance r\u00e9nale chez le chat ?<!-- notionvc: 5af60c17-bda6-435a-b790-601224d87c2e --><\/span><\/h2>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86b51a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86b51a2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca49f12\" data-id=\"ca49f12\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d92d7f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2d92d7f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>L&#8217;insuffisance r\u00e9nale est une maladie courante chez les chats, en particulier chez les plus \u00e2g\u00e9s. Elle se caract\u00e9rise par une diminution progressive de la fonction r\u00e9nale, ce qui affecte la capacit\u00e9 des reins \u00e0 filtrer les d\u00e9chets du sang. Une alimentation adapt\u00e9e joue un r\u00f4le clef dans la gestion de cette affection et peut am\u00e9liorer significativement la qualit\u00e9 de vie de votre compagnon.<\/p>\n<p><!-- notionvc: f3365c80-e02e-467b-b5ae-31b62867bbca --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2520cb6 elementor-widget elementor-widget-text-editor\" data-id=\"2520cb6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Les reins sont essentiels pour \u00e9liminer les toxines, r\u00e9guler l&#8217;\u00e9quilibre des fluides et des \u00e9lectrolytes, et produire certaines hormones<\/strong>. Lorsqu&#8217;ils ne fonctionnent plus correctement, des sympt\u00f4mes peuvent appara\u00eetre :<\/p>\n<ul>\n<li>Perte d&#8217;app\u00e9tit<\/li>\n<li>Augmentation de la soif et de la miction<\/li>\n<li>Perte de poids<\/li>\n<li>Vomissements<\/li>\n<li>Fatigue et l\u00e9thargie<\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90b5d84 elementor-widget elementor-widget-image\" data-id=\"90b5d84\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.vetorino.com\/boutique\/marque\/royal-canin\/?s&#038;maladie=troubles-digestifs&#038;swcfpc=1\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2048\" height=\"1152\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/insuffisance-renale-chat-2-2048x1152.jpg\" class=\"attachment-2048x2048 size-2048x2048 wp-image-1093154\" alt=\"chat malade insuffisance r\u00e9nale\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/insuffisance-renale-chat-2-2048x1152.jpg 2048w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/insuffisance-renale-chat-2-300x169.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/insuffisance-renale-chat-2-1024x576.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/insuffisance-renale-chat-2-768x432.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/insuffisance-renale-chat-2-1536x864.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/insuffisance-renale-chat-2-555x312.jpg 555w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6cb33a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6cb33a2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-89d7b48\" data-id=\"89d7b48\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-50e8476 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"50e8476\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Quel r\u00f4le joue l\u2019alimentation pour un chat atteint d\u2019insuffisance r\u00e9nale ?<\/p>\n<p>\u2705\u00a0R\u00e9duction du phosphore<\/p>\n<p>Un exc\u00e8s de phosphore peut acc\u00e9l\u00e9rer la progression de l&#8217;insuffisance r\u00e9nale. Les aliments sp\u00e9cifiques pour chats insuffisants r\u00e9naux contiennent des niveaux r\u00e9duits de phosphore pour prot\u00e9ger les reins.<\/p>\n<p>\u2705\u00a0Contr\u00f4le des prot\u00e9ines<\/p>\n<p>Limiter l&#8217;apport en prot\u00e9ines r\u00e9duit la production de d\u00e9chets azot\u00e9s, soulageant ainsi le travail des reins. Il est important de fournir des prot\u00e9ines de haute qualit\u00e9 pour r\u00e9pondre aux besoins nutritionnels sans surcharger l&#8217;organisme.<\/p>\n<p>\u2705\u00a0Enrichissement en om\u00e9ga-3<\/p>\n<p>Les acides gras om\u00e9ga-3 ont des propri\u00e9t\u00e9s anti-inflammatoires qui aident \u00e0 ralentir la progression de la maladie r\u00e9nale et am\u00e9liorer la circulation sanguine r\u00e9nale.<\/p>\n<p>\u2705\u00a0Augmentation de l&#8217;app\u00e9tence<\/p>\n<p>Les chats atteints d&#8217;insuffisance r\u00e9nale peuvent perdre l&#8217;app\u00e9tit. Des aliments sp\u00e9cialement formul\u00e9s sont plus app\u00e9tents pour encourager une alimentation suffisante.<\/p>\n<p>\u2705\u00a0Hydratation suppl\u00e9mentaire<\/p>\n<p>Une alimentation humide aide \u00e0 augmenter l&#8217;apport en eau, ce qui est essentiel pour soutenir la fonction r\u00e9nale et pr\u00e9venir la d\u00e9shydratation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-364b4ed elementor-widget elementor-widget-text-editor\" data-id=\"364b4ed\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Avant de modifier le r\u00e9gime alimentaire de votre chat, <strong>demandez conseil \u00e0 votre v\u00e9t\u00e9rinaire pour choisir l&#8217;aliment le plus adapt\u00e9<\/strong>.<\/p>\n<p>En parall\u00e8le, assurez-vous que votre chat a toujours acc\u00e8s \u00e0 de l&#8217;eau fra\u00eeche et propre. Offrez plusieurs petits repas tout au long de la journ\u00e9e pour faciliter la digestion. \u00c9vitez les friandises riches en phosphore ou en sel qui peuvent aggraver la maladie.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f66cce elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7f66cce\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/thononlesbains-74200-michel\/boutique\/\/product-category\/chat\/?s&#038;maladie=insuffisance-renale\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir tous les aliments v\u00e9t\u00e9rinaires pour chat atteint d'insuffisance r\u00e9nale<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Comment reconna\u00eetre l&#8217;insuffisance r\u00e9nale chez le chat ? L&#8217;insuffisance r\u00e9nale est une maladie courante chez les chats, en particulier chez les plus \u00e2g\u00e9s. Elle se caract\u00e9rise par une diminution progressive de la fonction r\u00e9nale, ce qui affecte la capacit\u00e9 des reins \u00e0 filtrer les d\u00e9chets du sang. Une alimentation adapt\u00e9e joue un r\u00f4le clef dans [&hellip;]<\/p>\n","protected":false},"author":68707,"featured_media":1093162,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[14089,14086,14095],"tags":[],"class_list":["post-1093147","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentation-chat","category-chat","category-sante-et-prevention-chat"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Insuffisance r\u00e9nale chat : quel r\u00f4le joue l&#039;alimentation v\u00e9t\u00e9rinaire ?<\/title>\n<meta name=\"description\" content=\"Les chats atteints d&#039;insuffisance r\u00e9nale ont besoin d&#039;une alimentation v\u00e9t\u00e9rinaire adapt\u00e9e. D\u00e9couvrez les raisons.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Insuffisance r\u00e9nale chat : quel r\u00f4le joue l&#039;alimentation v\u00e9t\u00e9rinaire ?\" \/>\n<meta property=\"og:description\" content=\"Les chats atteints d&#039;insuffisance r\u00e9nale ont besoin d&#039;une alimentation v\u00e9t\u00e9rinaire adapt\u00e9e. D\u00e9couvrez les raisons.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/2024\/12\/30\/role-alimentation-insuffisance-renale-chat\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-30T11:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/insuffisance-renale-chat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1905\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Clemence Sully\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Clemence Sully\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/30\\\/role-alimentation-insuffisance-renale-chat\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/30\\\/role-alimentation-insuffisance-renale-chat\\\/\"},\"author\":{\"name\":\"Clemence Sully\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/9bd231449b5dab066d32dab7d241eb4a\"},\"headline\":\"Le r\u00f4le de l&#8217;alimentation dans l&#8217;insuffisance r\u00e9nale chez le chat\",\"datePublished\":\"2024-12-30T11:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/30\\\/role-alimentation-insuffisance-renale-chat\\\/\"},\"wordCount\":427,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/30\\\/role-alimentation-insuffisance-renale-chat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/insuffisance-renale-chat.jpg\",\"articleSection\":[\"Alimentation pour chat\",\"Chat\",\"Sant\u00e9 et pr\u00e9vention pour chat\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/30\\\/role-alimentation-insuffisance-renale-chat\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/30\\\/role-alimentation-insuffisance-renale-chat\\\/\",\"name\":\"Insuffisance r\u00e9nale chat : quel r\u00f4le joue l'alimentation v\u00e9t\u00e9rinaire ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/30\\\/role-alimentation-insuffisance-renale-chat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/30\\\/role-alimentation-insuffisance-renale-chat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/insuffisance-renale-chat.jpg\",\"datePublished\":\"2024-12-30T11:00:00+00:00\",\"description\":\"Les chats atteints d'insuffisance r\u00e9nale ont besoin d'une alimentation v\u00e9t\u00e9rinaire adapt\u00e9e. D\u00e9couvrez les raisons.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/30\\\/role-alimentation-insuffisance-renale-chat\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/30\\\/role-alimentation-insuffisance-renale-chat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/30\\\/role-alimentation-insuffisance-renale-chat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/insuffisance-renale-chat.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/insuffisance-renale-chat.jpg\",\"width\":1905,\"height\":450,\"caption\":\"chat malade sur un muret\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2024\\\/12\\\/30\\\/role-alimentation-insuffisance-renale-chat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chat\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/champs-sur-marne-77420\\\/boutique\\\/category\\\/chat\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Le r\u00f4le de l&#8217;alimentation dans l&#8217;insuffisance r\u00e9nale chez le chat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/9bd231449b5dab066d32dab7d241eb4a\",\"name\":\"Clemence Sully\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g\",\"caption\":\"Clemence Sully\"},\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/boiscolombes-92270\\\/boutique\\\/author\\\/clemence-sully\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Insuffisance r\u00e9nale chat : quel r\u00f4le joue l'alimentation v\u00e9t\u00e9rinaire ?","description":"Les chats atteints d'insuffisance r\u00e9nale ont besoin d'une alimentation v\u00e9t\u00e9rinaire adapt\u00e9e. D\u00e9couvrez les raisons.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Insuffisance r\u00e9nale chat : quel r\u00f4le joue l'alimentation v\u00e9t\u00e9rinaire ?","og_description":"Les chats atteints d'insuffisance r\u00e9nale ont besoin d'une alimentation v\u00e9t\u00e9rinaire adapt\u00e9e. D\u00e9couvrez les raisons.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/2024\/12\/30\/role-alimentation-insuffisance-renale-chat\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_published_time":"2024-12-30T11:00:00+00:00","og_image":[{"width":1905,"height":450,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/insuffisance-renale-chat.jpg","type":"image\/jpeg"}],"author":"Clemence Sully","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Clemence Sully","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vetorino.com\/boutique\/2024\/12\/30\/role-alimentation-insuffisance-renale-chat\/#article","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/2024\/12\/30\/role-alimentation-insuffisance-renale-chat\/"},"author":{"name":"Clemence Sully","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/9bd231449b5dab066d32dab7d241eb4a"},"headline":"Le r\u00f4le de l&#8217;alimentation dans l&#8217;insuffisance r\u00e9nale chez le chat","datePublished":"2024-12-30T11:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2024\/12\/30\/role-alimentation-insuffisance-renale-chat\/"},"wordCount":427,"publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2024\/12\/30\/role-alimentation-insuffisance-renale-chat\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/insuffisance-renale-chat.jpg","articleSection":["Alimentation pour chat","Chat","Sant\u00e9 et pr\u00e9vention pour chat"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/2024\/12\/30\/role-alimentation-insuffisance-renale-chat\/","url":"https:\/\/www.vetorino.com\/boutique\/2024\/12\/30\/role-alimentation-insuffisance-renale-chat\/","name":"Insuffisance r\u00e9nale chat : quel r\u00f4le joue l'alimentation v\u00e9t\u00e9rinaire ?","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2024\/12\/30\/role-alimentation-insuffisance-renale-chat\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2024\/12\/30\/role-alimentation-insuffisance-renale-chat\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/insuffisance-renale-chat.jpg","datePublished":"2024-12-30T11:00:00+00:00","description":"Les chats atteints d'insuffisance r\u00e9nale ont besoin d'une alimentation v\u00e9t\u00e9rinaire adapt\u00e9e. D\u00e9couvrez les raisons.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/2024\/12\/30\/role-alimentation-insuffisance-renale-chat\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/2024\/12\/30\/role-alimentation-insuffisance-renale-chat\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/2024\/12\/30\/role-alimentation-insuffisance-renale-chat\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/insuffisance-renale-chat.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/12\/insuffisance-renale-chat.jpg","width":1905,"height":450,"caption":"chat malade sur un muret"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/2024\/12\/30\/role-alimentation-insuffisance-renale-chat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Chat","item":"https:\/\/www.vetorino.com\/veterinaire\/champs-sur-marne-77420\/boutique\/category\/chat\/"},{"@type":"ListItem","position":3,"name":"Le r\u00f4le de l&#8217;alimentation dans l&#8217;insuffisance r\u00e9nale chez le chat"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]},{"@type":"Person","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/9bd231449b5dab066d32dab7d241eb4a","name":"Clemence Sully","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g","caption":"Clemence Sully"},"url":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/author\/clemence-sully\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/posts\/1093147","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/users\/68707"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/comments?post=1093147"}],"version-history":[{"count":19,"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/posts\/1093147\/revisions"}],"predecessor-version":[{"id":1128727,"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/posts\/1093147\/revisions\/1128727"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/media\/1093162"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/media?parent=1093147"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/categories?post=1093147"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/tags?post=1093147"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}