{"id":1508029,"date":"2025-09-29T09:42:37","date_gmt":"2025-09-29T07:42:37","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/?post_type=product&#038;p=1508029"},"modified":"2026-06-08T17:29:15","modified_gmt":"2026-06-08T15:29:15","slug":"tiquanis-habitat-diffuseur-unidose-2","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/product\/tiquanis-habitat-diffuseur-unidose-2\/","title":{"rendered":"Tiquanis Habitat &#8211; Diffuseur unidose"},"content":{"rendered":"<p><strong>Tiquanis Habitat est un biocide (TP18) ayant une action puissante contre les insectes volants, rampant et autres parasites de l&#8217;habitation.<\/strong><\/p>\n<ul>\n<li>Permet de traiter les pi\u00e8ces ferm\u00e9es : salon, chambre, grenier, bureau\u2026<\/li>\n<li>\u00c9radique de fa\u00e7on imm\u00e9diate les parasites, les insectes rampants et volants de l\u2019habitation.<\/li>\n<li>Agit sur tous les stades de d\u00e9veloppement des parasites : oeufs, larves, adultes.<\/li>\n<\/ul>\n<p>Il permet d&#8217;\u00e9radiquer en une seule op\u00e9ration :<br \/>\n&#8211; les parasites : puces et punaises de lit \u00e0 tous les stades de leurs d\u00e9veloppements (adultes, larves, \u0153ufs), acariens de la poussi\u00e8re, sarcoptes de la gale, tiques, poux roues<br \/>\n&#8211; les insectes rampants : blattes, cafards, fourmis, araign\u00e9es,<br \/>\n&#8211; les insectes volants : mouches, gu\u00eapes, moustiques tigres, mites.<\/p>\n<p><strong>Utilisation<\/strong>\u00a0:<br \/>\nTiquanis Habitat diffuseur permet de traiter les locaux ferm\u00e9s. Dans le cas de locaux non ferm\u00e9s et pour une action r\u00e9p\u00e9t\u00e9es ur coussins, niches, etc, utiliser Tiquanis Habita spray. Traiter simultan\u00e9ment les animaux avec un produit antiparasitaire adapt\u00e9.<\/p>\n<p><strong>Mode d&#8217;emploi<\/strong>\u00a0:<br \/>\nEteindre tout appareil \u00e9lectrique en fonctionnement, toute flamme ou toute source de chaleur (chauffe-eau, \u2026). Fermer les fen\u00eatres et les portes et couper l&#8217;a\u00e9ration. Enlever la nourriture et les ustensiles de cuisine et fermer les portes de placard. D\u00e9housser les matelas et coussins, ouvrir les canap\u00e9s. Eloigner les animaux et d\u00e9placer ou couvrir avec un linge mouill\u00e9 les aquariums. Placer l&#8217;a\u00e9rosol au centre la pi\u00e8ce, en hauteur sur un tabouret. Enclencher le diffuseur jusqu&#8217;\u00e0 ce qu&#8217;il reste bloqu\u00e9, la diffusion commence. Quitter la pi\u00e8ce imm\u00e9diatement et fermer la porte. La vaporisation du produit se poursuivra jusqu&#8217;\u00e0 vidange compl\u00e8te de l&#8217;a\u00e9rosol (environ 2 minutes). Laisser agir 3h avant de r\u00e9int\u00e9grer la pi\u00e8ce, puis a\u00e9rer pendant 1h. Aspirer et laver les surfaces trait\u00e9es. Ne pas diffuser dans une pi\u00e8ce de moins 1m\u00b3.<\/p>\n<p><strong>Fr\u00e9quence d&#8217;utilisation<\/strong>\u00a0:<br \/>\n&#8211; 2 fois par an<br \/>\n&#8211; 1 pi\u00e8ce par jour dans la m\u00eame maison.<\/p>\n<p><strong>NE PAS PULV\u00c9RISER SUR ET EN PR\u00c9SENCE D&#8217;ANIMAUX<br \/>\nNE PAS UTILISER DANS UNE CUISINE<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<div id=\"product-description-short-5994\">\n<p><strong>Biocide pour l\u2019habitat<\/strong>\u00a0\u00e0 action puissante contre les insectes volants, rampants et autres parasites domestiques. Il permet d&#8217;<strong>\u00e9radiquer en une seule op\u00e9ration les parasites<\/strong>.<\/p>\n<p>Il permet d&#8217;\u00e9radiquer en <strong>une seule op\u00e9ration<\/strong> :<\/p>\n<p><em>&#8211; <strong>Les parasites<\/strong> : puces et punaises de lit \u00e0 tous les stades de leurs d\u00e9veloppements (adultes, larves, \u0153ufs), acariens de la poussi\u00e8re, sarcoptes de la gale, tiques, poux roues<\/em><br \/>\n<em>&#8211;<strong> Les insectes rampants<\/strong> : blattes, cafards, fourmis, araign\u00e9es,\u00a0<\/em><br \/>\n<em>&#8211; <strong>Les insectes volants<\/strong> : mouches, gu\u00eapes, moustiques tigres, mite<\/em>s.<\/p>\n<\/div>\n<div class=\"product-actions\">\n<div class=\"product-variants\"><\/div>\n<\/div>\n","protected":false},"featured_media":1508086,"template":"","meta":[],"product_cat":[12553,12554,2697,2698,12648,12649],"product_tag":[],"class_list":{"0":"post-1508029","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-antiparasitaire-du-chat","7":"product_cat-antiparasitaire-du-chien","8":"product_cat-chat","9":"product_cat-chien","10":"product_cat-traitement-de-lhabitat-du-chat","11":"product_cat-traitement-de-lhabitat-du-chien","12":"pa_marque-vetoquinol","14":"first","15":"instock","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tiquanis Habitat - Diffuseur unidose V\u00e9toquinol - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Biocide pour l\u2019habitat\u00a0\u00e0 action puissante contre les insectes volants, rampants et autres parasites domestiques. Il permet d&#039;\u00e9radiquer en une seule op\u00e9ration les parasites.  Il permet d&#039;\u00e9radiquer en une seule op\u00e9ration :  - Les parasites : puces et punaises de lit \u00e0 tous les stades de leurs d\u00e9veloppements (adultes, larves, \u0153ufs), acariens de la poussi\u00e8re, sarcoptes de la gale, tiques, poux roues - Les insectes rampants : blattes, cafards, fourmis, araign\u00e9es,\u00a0 - Les insectes volants : mouches, gu\u00eapes, moustiques tigres, mites.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tiquanis Habitat - Diffuseur unidose V\u00e9toquinol - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Biocide pour l\u2019habitat\u00a0\u00e0 action puissante contre les insectes volants, rampants et autres parasites domestiques. Il permet d&#039;\u00e9radiquer en une seule op\u00e9ration les parasites.  Il permet d&#039;\u00e9radiquer en une seule op\u00e9ration :  - Les parasites : puces et punaises de lit \u00e0 tous les stades de leurs d\u00e9veloppements (adultes, larves, \u0153ufs), acariens de la poussi\u00e8re, sarcoptes de la gale, tiques, poux roues - Les insectes rampants : blattes, cafards, fourmis, araign\u00e9es,\u00a0 - Les insectes volants : mouches, gu\u00eapes, moustiques tigres, mites.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/product\/tiquanis-habitat-diffuseur-unidose-2\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-08T15:29:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/09\/tiquanis-habitat-diffuseur-unidose.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"14,30&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/tiquanis-habitat-diffuseur-unidose-2\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/tiquanis-habitat-diffuseur-unidose-2\\\/\",\"name\":\"Tiquanis Habitat - Diffuseur unidose V\u00e9toquinol - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/tiquanis-habitat-diffuseur-unidose-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/tiquanis-habitat-diffuseur-unidose-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/tiquanis-habitat-diffuseur-unidose.jpg\",\"datePublished\":\"2025-09-29T07:42:37+00:00\",\"dateModified\":\"2026-06-08T15:29:15+00:00\",\"description\":\"Biocide pour l\u2019habitat\u00a0\u00e0 action puissante contre les insectes volants, rampants et autres parasites domestiques. Il permet d'\u00e9radiquer en une seule op\u00e9ration les parasites. Il permet d'\u00e9radiquer en une seule op\u00e9ration : - Les parasites : puces et punaises de lit \u00e0 tous les stades de leurs d\u00e9veloppements (adultes, larves, \u0153ufs), acariens de la poussi\u00e8re, sarcoptes de la gale, tiques, poux roues - Les insectes rampants : blattes, cafards, fourmis, araign\u00e9es,\u00a0 - Les insectes volants : mouches, gu\u00eapes, moustiques tigres, mites.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/tiquanis-habitat-diffuseur-unidose-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/tiquanis-habitat-diffuseur-unidose-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/tiquanis-habitat-diffuseur-unidose-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/tiquanis-habitat-diffuseur-unidose.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/tiquanis-habitat-diffuseur-unidose.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/tiquanis-habitat-diffuseur-unidose-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tiquanis Habitat &#8211; Diffuseur unidose\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"V\u00e9toquinol\" \/>\n<meta property=\"product:price:amount\" content=\"14.30\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"O-31983\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tiquanis Habitat - Diffuseur unidose V\u00e9toquinol - V\u00e9torino","description":"Biocide pour l\u2019habitat\u00a0\u00e0 action puissante contre les insectes volants, rampants et autres parasites domestiques. Il permet d'\u00e9radiquer en une seule op\u00e9ration les parasites.  Il permet d'\u00e9radiquer en une seule op\u00e9ration :  - Les parasites : puces et punaises de lit \u00e0 tous les stades de leurs d\u00e9veloppements (adultes, larves, \u0153ufs), acariens de la poussi\u00e8re, sarcoptes de la gale, tiques, poux roues - Les insectes rampants : blattes, cafards, fourmis, araign\u00e9es,\u00a0 - Les insectes volants : mouches, gu\u00eapes, moustiques tigres, mites.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Tiquanis Habitat - Diffuseur unidose V\u00e9toquinol - V\u00e9torino","og_description":"Biocide pour l\u2019habitat\u00a0\u00e0 action puissante contre les insectes volants, rampants et autres parasites domestiques. Il permet d'\u00e9radiquer en une seule op\u00e9ration les parasites.  Il permet d'\u00e9radiquer en une seule op\u00e9ration :  - Les parasites : puces et punaises de lit \u00e0 tous les stades de leurs d\u00e9veloppements (adultes, larves, \u0153ufs), acariens de la poussi\u00e8re, sarcoptes de la gale, tiques, poux roues - Les insectes rampants : blattes, cafards, fourmis, araign\u00e9es,\u00a0 - Les insectes volants : mouches, gu\u00eapes, moustiques tigres, mites.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/product\/tiquanis-habitat-diffuseur-unidose-2\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-06-08T15:29:15+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/09\/tiquanis-habitat-diffuseur-unidose.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"14,30&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/tiquanis-habitat-diffuseur-unidose-2\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/tiquanis-habitat-diffuseur-unidose-2\/","name":"Tiquanis Habitat - Diffuseur unidose V\u00e9toquinol - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/tiquanis-habitat-diffuseur-unidose-2\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/tiquanis-habitat-diffuseur-unidose-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/09\/tiquanis-habitat-diffuseur-unidose.jpg","datePublished":"2025-09-29T07:42:37+00:00","dateModified":"2026-06-08T15:29:15+00:00","description":"Biocide pour l\u2019habitat\u00a0\u00e0 action puissante contre les insectes volants, rampants et autres parasites domestiques. Il permet d'\u00e9radiquer en une seule op\u00e9ration les parasites. Il permet d'\u00e9radiquer en une seule op\u00e9ration : - Les parasites : puces et punaises de lit \u00e0 tous les stades de leurs d\u00e9veloppements (adultes, larves, \u0153ufs), acariens de la poussi\u00e8re, sarcoptes de la gale, tiques, poux roues - Les insectes rampants : blattes, cafards, fourmis, araign\u00e9es,\u00a0 - Les insectes volants : mouches, gu\u00eapes, moustiques tigres, mites.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/tiquanis-habitat-diffuseur-unidose-2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/tiquanis-habitat-diffuseur-unidose-2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/tiquanis-habitat-diffuseur-unidose-2\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/09\/tiquanis-habitat-diffuseur-unidose.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/09\/tiquanis-habitat-diffuseur-unidose.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/tiquanis-habitat-diffuseur-unidose-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Tiquanis Habitat &#8211; Diffuseur unidose"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"V\u00e9toquinol","product_price_amount":"14.30","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"O-31983","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/product\/1508029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/media\/1508086"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/media?parent=1508029"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/product_cat?post=1508029"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/boiscolombes-92270\/boutique\/wp-json\/wp\/v2\/product_tag?post=1508029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}