{"id":1273783,"date":"2025-04-02T14:54:25","date_gmt":"2025-04-02T12:54:25","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/shampoing-chiot-pet-head-mucky-pup\/"},"modified":"2025-12-17T09:41:33","modified_gmt":"2025-12-17T08:41:33","slug":"shampoing-chiot-pet-head-mucky-pup","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/product\/shampoing-chiot-pet-head-mucky-pup\/","title":{"rendered":"Shampoing Chiot Pet Head Mucky Pup"},"content":{"rendered":"<p><strong>Le shampooing pour chiots au parfum de poire permet de\u00a0nettoyer et de soigner la peau et le pelage en douceur.\u00a0<\/strong><\/p>\n<p><strong>Caract\u00e9ristiques<\/strong> :<\/p>\n<ul>\n<li>Huile de p\u00e9pins de figue de barbarie : hydrate et revitalise.<\/li>\n<li>Huile de rose musqu\u00e9e : hydratant et nourrissant.<\/li>\n<li>Extrait de camomille : Apaise et nourrit la peau.<\/li>\n<li>Prot\u00e9ine v\u00e9g\u00e9tale : renforce et hydrate le pelage.<\/li>\n<li>Jus d&#8217;aloe vera : propri\u00e9t\u00e9s apaisantes. Laisse le pelage doux et brillant.<\/li>\n<\/ul>\n<p><strong>Conseils d&#8217;utilisation :<\/strong><\/p>\n<p>Humidifier le pelage de chien et masser doucement avec le shampooing. Rincer soigneusement et s\u00e9cher le pelage avec une serviette ou un s\u00e8che-cheveux.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Le shampooing pour chiots au parfum de poire permet de\u00a0nettoyer et de soigner la peau et le pelage en douceur.<\/strong><\/p>\n<p><strong>Caract\u00e9ristiques<\/strong> :<\/p>\n<ul>\n<li>Huile de p\u00e9pins de figue de barbarie : hydrate et revitalise.<\/li>\n<li>Huile de rose musqu\u00e9e : hydratant et nourrissant.<\/li>\n<li>Extrait de camomille : Apaise et nourrit la peau.<\/li>\n<li>Prot\u00e9ine v\u00e9g\u00e9tale : renforce et hydrate le pelage.<\/li>\n<li>Jus d&#8217;aloe vera : propri\u00e9t\u00e9s apaisantes. Laisse le pelage doux et brillant.<\/li>\n<\/ul>\n","protected":false},"featured_media":1275314,"template":"","meta":[],"product_cat":[2698,12612,12561],"product_tag":[],"class_list":{"0":"post-1273783","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-chien","7":"product_cat-hygiene-de-la-peau-et-du-pelage-du-chien","8":"product_cat-hygiene-du-chien","9":"pa_marque-company-of-animals","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Shampoing Chiot Pet Head Mucky Pup Company of Animals - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Le shampooing pour chiots au parfum de poire permet de\u00a0nettoyer et de soigner la peau et le pelage en douceur.  Caract\u00e9ristiques :   Huile de p\u00e9pins de figue de barbarie : hydrate et revitalise.  Huile de rose musqu\u00e9e : hydratant et nourrissant.  Extrait de camomille : Apaise et nourrit la peau.  Prot\u00e9ine v\u00e9g\u00e9tale : renforce et hydrate le pelage.  Jus d&#039;aloe vera : propri\u00e9t\u00e9s apaisantes. Laisse le pelage doux et brillant.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Shampoing Chiot Pet Head Mucky Pup Company of Animals - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Le shampooing pour chiots au parfum de poire permet de\u00a0nettoyer et de soigner la peau et le pelage en douceur.  Caract\u00e9ristiques :   Huile de p\u00e9pins de figue de barbarie : hydrate et revitalise.  Huile de rose musqu\u00e9e : hydratant et nourrissant.  Extrait de camomille : Apaise et nourrit la peau.  Prot\u00e9ine v\u00e9g\u00e9tale : renforce et hydrate le pelage.  Jus d&#039;aloe vera : propri\u00e9t\u00e9s apaisantes. Laisse le pelage doux et brillant.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/product\/shampoing-chiot-pet-head-mucky-pup\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-17T08:41:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/04\/shampoing-chiot-pet-head-mucky-pup.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"10,63&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/shampoing-chiot-pet-head-mucky-pup\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/shampoing-chiot-pet-head-mucky-pup\\\/\",\"name\":\"Shampoing Chiot Pet Head Mucky Pup Company of Animals - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/shampoing-chiot-pet-head-mucky-pup\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/shampoing-chiot-pet-head-mucky-pup\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/shampoing-chiot-pet-head-mucky-pup.webp\",\"datePublished\":\"2025-04-02T12:54:25+00:00\",\"dateModified\":\"2025-12-17T08:41:33+00:00\",\"description\":\"Le shampooing pour chiots au parfum de poire permet de\u00a0nettoyer et de soigner la peau et le pelage en douceur. Caract\u00e9ristiques : Huile de p\u00e9pins de figue de barbarie : hydrate et revitalise. Huile de rose musqu\u00e9e : hydratant et nourrissant. Extrait de camomille : Apaise et nourrit la peau. Prot\u00e9ine v\u00e9g\u00e9tale : renforce et hydrate le pelage. Jus d'aloe vera : propri\u00e9t\u00e9s apaisantes. Laisse le pelage doux et brillant.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/shampoing-chiot-pet-head-mucky-pup\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/shampoing-chiot-pet-head-mucky-pup\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/shampoing-chiot-pet-head-mucky-pup\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/shampoing-chiot-pet-head-mucky-pup.webp\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/shampoing-chiot-pet-head-mucky-pup.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/shampoing-chiot-pet-head-mucky-pup\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Shampoing Chiot Pet Head Mucky Pup\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Company of Animals\" \/>\n<meta property=\"product:price:amount\" content=\"10.63\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"C-SHA440\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Shampoing Chiot Pet Head Mucky Pup Company of Animals - V\u00e9torino","description":"Le shampooing pour chiots au parfum de poire permet de\u00a0nettoyer et de soigner la peau et le pelage en douceur.  Caract\u00e9ristiques :   Huile de p\u00e9pins de figue de barbarie : hydrate et revitalise.  Huile de rose musqu\u00e9e : hydratant et nourrissant.  Extrait de camomille : Apaise et nourrit la peau.  Prot\u00e9ine v\u00e9g\u00e9tale : renforce et hydrate le pelage.  Jus d'aloe vera : propri\u00e9t\u00e9s apaisantes. Laisse le pelage doux et brillant.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Shampoing Chiot Pet Head Mucky Pup Company of Animals - V\u00e9torino","og_description":"Le shampooing pour chiots au parfum de poire permet de\u00a0nettoyer et de soigner la peau et le pelage en douceur.  Caract\u00e9ristiques :   Huile de p\u00e9pins de figue de barbarie : hydrate et revitalise.  Huile de rose musqu\u00e9e : hydratant et nourrissant.  Extrait de camomille : Apaise et nourrit la peau.  Prot\u00e9ine v\u00e9g\u00e9tale : renforce et hydrate le pelage.  Jus d'aloe vera : propri\u00e9t\u00e9s apaisantes. Laisse le pelage doux et brillant.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/product\/shampoing-chiot-pet-head-mucky-pup\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2025-12-17T08:41:33+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/04\/shampoing-chiot-pet-head-mucky-pup.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"10,63&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/shampoing-chiot-pet-head-mucky-pup\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/shampoing-chiot-pet-head-mucky-pup\/","name":"Shampoing Chiot Pet Head Mucky Pup Company of Animals - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/shampoing-chiot-pet-head-mucky-pup\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/shampoing-chiot-pet-head-mucky-pup\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/04\/shampoing-chiot-pet-head-mucky-pup.webp","datePublished":"2025-04-02T12:54:25+00:00","dateModified":"2025-12-17T08:41:33+00:00","description":"Le shampooing pour chiots au parfum de poire permet de\u00a0nettoyer et de soigner la peau et le pelage en douceur. Caract\u00e9ristiques : Huile de p\u00e9pins de figue de barbarie : hydrate et revitalise. Huile de rose musqu\u00e9e : hydratant et nourrissant. Extrait de camomille : Apaise et nourrit la peau. Prot\u00e9ine v\u00e9g\u00e9tale : renforce et hydrate le pelage. Jus d'aloe vera : propri\u00e9t\u00e9s apaisantes. Laisse le pelage doux et brillant.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/shampoing-chiot-pet-head-mucky-pup\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/shampoing-chiot-pet-head-mucky-pup\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/shampoing-chiot-pet-head-mucky-pup\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/04\/shampoing-chiot-pet-head-mucky-pup.webp","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/04\/shampoing-chiot-pet-head-mucky-pup.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/shampoing-chiot-pet-head-mucky-pup\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Shampoing Chiot Pet Head Mucky Pup"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Company of Animals","product_price_amount":"10.63","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"C-SHA440","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/wp-json\/wp\/v2\/product\/1273783","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/wp-json\/wp\/v2\/media\/1275314"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/wp-json\/wp\/v2\/media?parent=1273783"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/wp-json\/wp\/v2\/product_cat?post=1273783"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/wp-json\/wp\/v2\/product_tag?post=1273783"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}