{"id":969116,"date":"2024-07-09T10:06:44","date_gmt":"2024-07-09T08:06:44","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/dermoscent-physio-easy-brush\/"},"modified":"2026-05-08T02:42:04","modified_gmt":"2026-05-08T00:42:04","slug":"dermoscent-physio-easy-brush","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/product\/dermoscent-physio-easy-brush\/","title":{"rendered":"Physio Easy Brush"},"content":{"rendered":"<p><strong>Dermoscent\u00ae PHYSIO Easy Brush est une mousse naturelle d\u00e9m\u00ealante pour faciliter le brossage et le d\u00e9m\u00ealage du pelage des chiens et des chats.<\/strong><\/p>\n<p><b>Utilisation :<\/b><\/p>\n<ul>\n<li>Animaux \u00e0 poils longs sujets aux n\u0153uds<\/li>\n<li>Les races \u00e0 double-pelage (Husky, Samoy\u00e8de, Maine Coon, Persan, etc.)<\/li>\n<li>Pour l\u2019entretien du pelage<\/li>\n<\/ul>\n<p><strong>Mode d&#8217;emploi :<\/strong><\/p>\n<p>Cette mousse d\u00e9m\u00ealante peut \u00eatre utilis\u00e9e de deux fa\u00e7ons : sur pelage mouill\u00e9 apr\u00e8s le shampooing comme un conditionneur, ou sur pelage sec pour faciliter le brossage et le d\u00e9m\u00ealage des n\u0153uds. Sa formule biphasique n\u00e9cessite d&#8217;agiter le flacon avant utilisation<\/p>\n<p>Appliquez-la sur le pelage sec ou mouill\u00e9 en insistant sur les n\u0153uds, puis brossez. Elle ne n\u00e9cessite pas de rin\u00e7age.<\/p>\n<p>Une utilisation r\u00e9guli\u00e8re permet de limiter l\u2019apparition des n\u0153uds tout en apportant brillance, souplesse et volume pour un pelage en pleine sant\u00e9.<\/p>\n<p><strong>Avantages :\u00a0<\/strong><\/p>\n<p>PHYSIO Easy Brush <strong>facilite le brossage et le d\u00e9m\u00ealage<\/strong>, pr\u00e9vient la formation de n\u0153uds et am\u00e9liore la <strong>brillance<\/strong>, le <strong>volume<\/strong> et la <strong>douceur du pelage<\/strong> tout en prot\u00e9geant la structure du poil.<\/p>\n<p>Sa formule naturelle et sans silicones est con\u00e7ue avec un pH adapt\u00e9 pour faciliter le d\u00e9m\u00ealage.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Dermoscent\u00ae PHYSIO Easy Brush est une mousse naturelle d\u00e9m\u00ealante pour faciliter le brossage et le d\u00e9m\u00ealage du pelage des chiens et des chats.<\/strong><\/p>\n<p><b>Utilisation : <\/b><\/p>\n<ul>\n<li>Animaux \u00e0 poils longs sujets aux n\u0153uds<\/li>\n<li>Les races \u00e0 double-pelage (Husky, Samoy\u00e8de, Maine Coon, Persan, etc.)<\/li>\n<li>Pour l\u2019entretien du pelage<\/li>\n<\/ul>\n","protected":false},"featured_media":1319777,"template":"","meta":[],"product_cat":[2697,2698,12611,12612,12560,12561],"product_tag":[],"class_list":{"0":"post-969116","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-chat","7":"product_cat-chien","8":"product_cat-hygiene-de-la-peau-et-du-pelage-du-chat","9":"product_cat-hygiene-de-la-peau-et-du-pelage-du-chien","10":"product_cat-hygiene-du-chat","11":"product_cat-hygiene-du-chien","12":"pa_marque-dermoscent","14":"first","15":"instock","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Physio Easy Brush Dermoscent - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Dermoscent\u00ae PHYSIO Easy Brush est une mousse naturelle d\u00e9m\u00ealante pour faciliter le brossage et le d\u00e9m\u00ealage du pelage des chiens et des chats.  Utilisation :    Animaux \u00e0 poils longs sujets aux n\u0153uds  Les races \u00e0 double-pelage (Husky, Samoy\u00e8de, Maine Coon, Persan, etc.)  Pour l\u2019entretien du pelage\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Physio Easy Brush Dermoscent - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Dermoscent\u00ae PHYSIO Easy Brush est une mousse naturelle d\u00e9m\u00ealante pour faciliter le brossage et le d\u00e9m\u00ealage du pelage des chiens et des chats.  Utilisation :    Animaux \u00e0 poils longs sujets aux n\u0153uds  Les races \u00e0 double-pelage (Husky, Samoy\u00e8de, Maine Coon, Persan, etc.)  Pour l\u2019entretien du pelage\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/product\/dermoscent-physio-easy-brush\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-08T00:42:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/07\/dermoscent-physio-easy-brush.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"16,74&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/dermoscent-physio-easy-brush\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/dermoscent-physio-easy-brush\\\/\",\"name\":\"Physio Easy Brush Dermoscent - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/dermoscent-physio-easy-brush\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/dermoscent-physio-easy-brush\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/dermoscent-physio-easy-brush.webp\",\"datePublished\":\"2024-07-09T08:06:44+00:00\",\"dateModified\":\"2026-05-08T00:42:04+00:00\",\"description\":\"Dermoscent\u00ae PHYSIO Easy Brush est une mousse naturelle d\u00e9m\u00ealante pour faciliter le brossage et le d\u00e9m\u00ealage du pelage des chiens et des chats. Utilisation : Animaux \u00e0 poils longs sujets aux n\u0153uds Les races \u00e0 double-pelage (Husky, Samoy\u00e8de, Maine Coon, Persan, etc.) Pour l\u2019entretien du pelage\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/dermoscent-physio-easy-brush\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/dermoscent-physio-easy-brush\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/dermoscent-physio-easy-brush\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/dermoscent-physio-easy-brush.webp\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/dermoscent-physio-easy-brush.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/dermoscent-physio-easy-brush\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Physio Easy Brush\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Dermoscent\" \/>\n<meta property=\"product:price:amount\" content=\"16.74\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"C-DER096\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Physio Easy Brush Dermoscent - V\u00e9torino","description":"Dermoscent\u00ae PHYSIO Easy Brush est une mousse naturelle d\u00e9m\u00ealante pour faciliter le brossage et le d\u00e9m\u00ealage du pelage des chiens et des chats.  Utilisation :    Animaux \u00e0 poils longs sujets aux n\u0153uds  Les races \u00e0 double-pelage (Husky, Samoy\u00e8de, Maine Coon, Persan, etc.)  Pour l\u2019entretien du pelage","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Physio Easy Brush Dermoscent - V\u00e9torino","og_description":"Dermoscent\u00ae PHYSIO Easy Brush est une mousse naturelle d\u00e9m\u00ealante pour faciliter le brossage et le d\u00e9m\u00ealage du pelage des chiens et des chats.  Utilisation :    Animaux \u00e0 poils longs sujets aux n\u0153uds  Les races \u00e0 double-pelage (Husky, Samoy\u00e8de, Maine Coon, Persan, etc.)  Pour l\u2019entretien du pelage","og_url":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/product\/dermoscent-physio-easy-brush\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-05-08T00:42:04+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/07\/dermoscent-physio-easy-brush.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"16,74&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/dermoscent-physio-easy-brush\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/dermoscent-physio-easy-brush\/","name":"Physio Easy Brush Dermoscent - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/dermoscent-physio-easy-brush\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/dermoscent-physio-easy-brush\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/07\/dermoscent-physio-easy-brush.webp","datePublished":"2024-07-09T08:06:44+00:00","dateModified":"2026-05-08T00:42:04+00:00","description":"Dermoscent\u00ae PHYSIO Easy Brush est une mousse naturelle d\u00e9m\u00ealante pour faciliter le brossage et le d\u00e9m\u00ealage du pelage des chiens et des chats. Utilisation : Animaux \u00e0 poils longs sujets aux n\u0153uds Les races \u00e0 double-pelage (Husky, Samoy\u00e8de, Maine Coon, Persan, etc.) Pour l\u2019entretien du pelage","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/dermoscent-physio-easy-brush\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/dermoscent-physio-easy-brush\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/dermoscent-physio-easy-brush\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/07\/dermoscent-physio-easy-brush.webp","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/07\/dermoscent-physio-easy-brush.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/dermoscent-physio-easy-brush\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Physio Easy Brush"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Dermoscent","product_price_amount":"16.74","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"C-DER096","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/wp-json\/wp\/v2\/product\/969116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/wp-json\/wp\/v2\/media\/1319777"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/wp-json\/wp\/v2\/media?parent=969116"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/wp-json\/wp\/v2\/product_cat?post=969116"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/wp-json\/wp\/v2\/product_tag?post=969116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}