{"id":98444,"date":"2020-06-30T01:03:21","date_gmt":"2020-06-29T23:03:21","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/kong-stuffn-easy-treat-liver-recipe\/"},"modified":"2026-04-17T20:54:10","modified_gmt":"2026-04-17T18:54:10","slug":"kong-stuffn-easy-treat-liver-recipe","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/product\/kong-stuffn-easy-treat-liver-recipe\/","title":{"rendered":"Kong Stuff&#8217;N Easy Treat Liver Recipe"},"content":{"rendered":"<p><b>Caract\u00e9risiques<\/b><br \/>\nCette friandise sous forme de p\u00e2te rempli facilement l&#8217;int\u00e9rieur ou les jointure des jouets KONG. Elle peut \u00eatre refroidie pour occuper l?animal plus longtemps. Son go\u00fbt au foie de volaille est irr\u00e9sistible pour la plupart des chiots et la p\u00e2te est formul\u00e9e pour l?estomac sensible du chiot.\u00a0Fabriqu\u00e9e aux \u00c9tats-Unis. Conditionnement : 226 g.<br \/>\n<b>Bon \u00e0 savoir<\/b><br \/>\nDemandez conseil \u00e0 votre v\u00e9t\u00e9rinaire. De l&#8217;eau fra\u00eeche et propre doit \u00eatre disponible \u00e0 tout moment de la journ\u00e9e.<\/p>\n","protected":false},"excerpt":{"rendered":"<div class=\"weight\">KONG Stuff\u2019N Liver Easy Treat permettent de garnir les jouets KONG facilement. Appliquez simplement la p\u00e2te savoureuse \u00e0 l\u2019int\u00e9rieur d\u2019un jouet KONG ou dans les rainures d\u2019un jouet KONG pour soin dentaire. Faciles \u00e0 distribuer D\u00e9licieuse saveur de foie, irr\u00e9sistible pour la plupart des chiens Fabriqu\u00e9es aux \u00c9tats-Unis Disponibles en une seule taille : 226 g.<\/div>\n","protected":false},"featured_media":616624,"template":"","meta":[],"product_cat":[12552,2698,12603],"product_tag":[],"class_list":{"0":"post-98444","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alimentation-du-chien","7":"product_cat-chien","8":"product_cat-friandises-pour-chien","9":"pa_marque-kong","11":"first","12":"outofstock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kong Stuff&#039;N Easy Treat Liver Recipe Kong - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"KONG Stuff\u2019N Liver Easy Treat permettent de garnir les jouets KONG facilement. Appliquez simplement la p\u00e2te savoureuse \u00e0 l\u2019int\u00e9rieur d\u2019un jouet KONG ou dans les rainures d\u2019un jouet KONG pour soin dentaire. Faciles \u00e0 distribuer D\u00e9licieuse saveur de foie, irr\u00e9sistible pour la plupart des chiens Fabriqu\u00e9es aux \u00c9tats-Unis Disponibles en une seule taille : 226 g.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kong Stuff&#039;N Easy Treat Liver Recipe Kong - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"KONG Stuff\u2019N Liver Easy Treat permettent de garnir les jouets KONG facilement. Appliquez simplement la p\u00e2te savoureuse \u00e0 l\u2019int\u00e9rieur d\u2019un jouet KONG ou dans les rainures d\u2019un jouet KONG pour soin dentaire. Faciles \u00e0 distribuer D\u00e9licieuse saveur de foie, irr\u00e9sistible pour la plupart des chiens Fabriqu\u00e9es aux \u00c9tats-Unis Disponibles en une seule taille : 226 g.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/product\/kong-stuffn-easy-treat-liver-recipe\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-17T18:54:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/kong-easy-treat-88932_940x.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"940\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"9,33&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"Rupture de stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kong-stuffn-easy-treat-liver-recipe\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kong-stuffn-easy-treat-liver-recipe\\\/\",\"name\":\"Kong Stuff'N Easy Treat Liver Recipe Kong - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kong-stuffn-easy-treat-liver-recipe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kong-stuffn-easy-treat-liver-recipe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/kong-easy-treat-88932_940x.jpg\",\"datePublished\":\"2020-06-29T23:03:21+00:00\",\"dateModified\":\"2026-04-17T18:54:10+00:00\",\"description\":\"KONG Stuff\u2019N Liver Easy Treat permettent de garnir les jouets KONG facilement. Appliquez simplement la p\u00e2te savoureuse \u00e0 l\u2019int\u00e9rieur d\u2019un jouet KONG ou dans les rainures d\u2019un jouet KONG pour soin dentaire. Faciles \u00e0 distribuer D\u00e9licieuse saveur de foie, irr\u00e9sistible pour la plupart des chiens Fabriqu\u00e9es aux \u00c9tats-Unis Disponibles en une seule taille : 226 g.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kong-stuffn-easy-treat-liver-recipe\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kong-stuffn-easy-treat-liver-recipe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kong-stuffn-easy-treat-liver-recipe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/kong-easy-treat-88932_940x.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/kong-easy-treat-88932_940x.jpg\",\"width\":940,\"height\":940},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/kong-stuffn-easy-treat-liver-recipe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kong Stuff&#8217;N Easy Treat Liver Recipe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Kong\" \/>\n<meta property=\"product:price:amount\" content=\"9.33\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"C-KON750\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kong Stuff'N Easy Treat Liver Recipe Kong - V\u00e9torino","description":"KONG Stuff\u2019N Liver Easy Treat permettent de garnir les jouets KONG facilement. Appliquez simplement la p\u00e2te savoureuse \u00e0 l\u2019int\u00e9rieur d\u2019un jouet KONG ou dans les rainures d\u2019un jouet KONG pour soin dentaire. Faciles \u00e0 distribuer D\u00e9licieuse saveur de foie, irr\u00e9sistible pour la plupart des chiens Fabriqu\u00e9es aux \u00c9tats-Unis Disponibles en une seule taille : 226 g.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Kong Stuff'N Easy Treat Liver Recipe Kong - V\u00e9torino","og_description":"KONG Stuff\u2019N Liver Easy Treat permettent de garnir les jouets KONG facilement. Appliquez simplement la p\u00e2te savoureuse \u00e0 l\u2019int\u00e9rieur d\u2019un jouet KONG ou dans les rainures d\u2019un jouet KONG pour soin dentaire. Faciles \u00e0 distribuer D\u00e9licieuse saveur de foie, irr\u00e9sistible pour la plupart des chiens Fabriqu\u00e9es aux \u00c9tats-Unis Disponibles en une seule taille : 226 g.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/product\/kong-stuffn-easy-treat-liver-recipe\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-04-17T18:54:10+00:00","og_image":[{"width":940,"height":940,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/kong-easy-treat-88932_940x.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"9,33&euro;","Disponibilit\u00e9":"Rupture de stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/kong-stuffn-easy-treat-liver-recipe\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/kong-stuffn-easy-treat-liver-recipe\/","name":"Kong Stuff'N Easy Treat Liver Recipe Kong - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/kong-stuffn-easy-treat-liver-recipe\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/kong-stuffn-easy-treat-liver-recipe\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/kong-easy-treat-88932_940x.jpg","datePublished":"2020-06-29T23:03:21+00:00","dateModified":"2026-04-17T18:54:10+00:00","description":"KONG Stuff\u2019N Liver Easy Treat permettent de garnir les jouets KONG facilement. Appliquez simplement la p\u00e2te savoureuse \u00e0 l\u2019int\u00e9rieur d\u2019un jouet KONG ou dans les rainures d\u2019un jouet KONG pour soin dentaire. Faciles \u00e0 distribuer D\u00e9licieuse saveur de foie, irr\u00e9sistible pour la plupart des chiens Fabriqu\u00e9es aux \u00c9tats-Unis Disponibles en une seule taille : 226 g.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/kong-stuffn-easy-treat-liver-recipe\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/kong-stuffn-easy-treat-liver-recipe\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/kong-stuffn-easy-treat-liver-recipe\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/kong-easy-treat-88932_940x.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/kong-easy-treat-88932_940x.jpg","width":940,"height":940},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/kong-stuffn-easy-treat-liver-recipe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Kong Stuff&#8217;N Easy Treat Liver Recipe"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Kong","product_price_amount":"9.33","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"C-KON750","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/wp-json\/wp\/v2\/product\/98444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/wp-json\/wp\/v2\/media\/616624"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/wp-json\/wp\/v2\/media?parent=98444"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/wp-json\/wp\/v2\/product_cat?post=98444"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/ceyzeriat-01250\/boutique\/wp-json\/wp\/v2\/product_tag?post=98444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}