{"id":100062,"date":"2020-06-30T01:39:43","date_gmt":"2020-06-29T23:39:43","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/obionekk\/"},"modified":"2026-03-29T09:41:27","modified_gmt":"2026-03-29T07:41:27","slug":"obionekk","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/champignysurmarne-94500\/boutique\/product\/obionekk\/","title":{"rendered":"Obionekk"},"content":{"rendered":"<p><strong>Aliment di\u00e9t\u00e9tique pour veaux, chevreaux et agneaux indiqu\u00e9 lors de risques de troubles digestifs (diarrh\u00e9e), pendant ou apr\u00e8s ceux-ci.<\/strong><\/p>\n<p>Stabilisation du bilan des \u00e9lectrolytes et de l&#8217;eau. \u00c0 base de charbon v\u00e9g\u00e9tal et de zinc.<\/p>\n<p><strong>Obionekk<\/strong>\u00a0est \u00e0 utiliser d\u00e8s les premiers jours de la vie pour les veaux, les agneaux et les chevreaux.<\/p>\n<p><strong>Mode d&#8217;emploi :<\/strong><\/p>\n<ul>\n<li><em>Administrer par voie orale : au pistolet drogueur ou dans le lait.<\/em><br \/>\n<strong>\u00a0En cas de risque de diarrh\u00e9e\u00a0 :<\/strong><br \/>\n<em>60 ml pour les veaux, 1 \u00e0 2 fois par jour pendant 7 jours.<\/em><br \/>\n<em>10 ml pour les agneaux et chevreaux, 1 \u00e0 2 fois par jour pendant 7 jours.<\/em><\/li>\n<li><strong>\u00a0Pendant et apr\u00e8s ceux-ci :<\/strong><br \/>\n<em>60 ml pour les veaux, matin et soir pendant 4 jours.<\/em><br \/>\n<em>10 ml pour les agneaux et chevreaux, matin et soir pendant 4 jours.<\/em><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p><strong>Aliment di\u00e9t\u00e9tique pour veaux, chevreaux et agneaux indiqu\u00e9 lors de risques de troubles digestifs (diarrh\u00e9e), pendant ou apr\u00e8s ceux-ci.<\/strong><\/p>\n<p>Stabilisation du bilan des \u00e9lectrolytes et de l&#8217;eau.<\/p>\n<p><strong>Mode d&#8217;emploi :<\/strong><\/p>\n<ul>\n<li><em>Administrer par voie orale : au pistolet drogueur ou dans le lait.<\/em><br \/>\n<strong>\u00a0En cas de risque de diarrh\u00e9e\u00a0 :<\/strong><br \/>\n<em>60 ml pour les veaux, 1 \u00e0 2 fois par jour pendant 7 jours.<\/em><br \/>\n<em>10 ml pour les agneaux et chevreaux, 1 \u00e0 2 fois par jour pendant 7 jours.<\/em><\/li>\n<li><strong>\u00a0Pendant et apr\u00e8s ceux-ci :<\/strong><br \/>\n<em>60 ml pour les veaux, matin et soir pendant 4 jours.<\/em><br \/>\n<em>10 ml pour les agneaux et chevreaux, matin et soir pendant 4 jours.<\/em><\/li>\n<\/ul>\n","protected":false},"featured_media":1459505,"template":"","meta":[],"product_cat":[6864,6870,6871,6873],"product_tag":[],"class_list":{"0":"post-100062","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-animaux-delevage","7":"product_cat-bovins","8":"product_cat-caprins","9":"product_cat-ovins","10":"pa_marque-nutri-science","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Obionekk Obione - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Aliment di\u00e9t\u00e9tique pour veaux, chevreaux et agneaux indiqu\u00e9 lors de risques de troubles digestifs (diarrh\u00e9e), pendant ou apr\u00e8s ceux-ci.  Stabilisation du bilan des \u00e9lectrolytes et de l&#039;eau.  Mode d&#039;emploi :   Administrer par voie orale : au pistolet drogueur ou dans le lait. \u00a0En cas de risque de diarrh\u00e9e\u00a0 : 60 ml pour les veaux, 1 \u00e0 2 fois par jour pendant 7 jours. 10 ml pour les agneaux et chevreaux, 1 \u00e0 2 fois par jour pendant 7 jours.  \u00a0Pendant et apr\u00e8s ceux-ci : 60 ml pour les veaux, matin et soir pendant 4 jours. 10 ml pour les agneaux et chevreaux, matin et soir pendant 4 jours.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Obionekk Obione - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Aliment di\u00e9t\u00e9tique pour veaux, chevreaux et agneaux indiqu\u00e9 lors de risques de troubles digestifs (diarrh\u00e9e), pendant ou apr\u00e8s ceux-ci.  Stabilisation du bilan des \u00e9lectrolytes et de l&#039;eau.  Mode d&#039;emploi :   Administrer par voie orale : au pistolet drogueur ou dans le lait. \u00a0En cas de risque de diarrh\u00e9e\u00a0 : 60 ml pour les veaux, 1 \u00e0 2 fois par jour pendant 7 jours. 10 ml pour les agneaux et chevreaux, 1 \u00e0 2 fois par jour pendant 7 jours.  \u00a0Pendant et apr\u00e8s ceux-ci : 60 ml pour les veaux, matin et soir pendant 4 jours. 10 ml pour les agneaux et chevreaux, matin et soir pendant 4 jours.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/champignysurmarne-94500\/boutique\/product\/obionekk\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-29T07:41:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/Obionekk-5L-01.2024.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1668\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/obionekk\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/obionekk\\\/\",\"name\":\"Obionekk Obione - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/obionekk\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/obionekk\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Obionekk-5L-01.2024.webp\",\"datePublished\":\"2020-06-29T23:39:43+00:00\",\"dateModified\":\"2026-03-29T07:41:27+00:00\",\"description\":\"Aliment di\u00e9t\u00e9tique pour veaux, chevreaux et agneaux indiqu\u00e9 lors de risques de troubles digestifs (diarrh\u00e9e), pendant ou apr\u00e8s ceux-ci. Stabilisation du bilan des \u00e9lectrolytes et de l'eau. Mode d'emploi : Administrer par voie orale : au pistolet drogueur ou dans le lait. \u00a0En cas de risque de diarrh\u00e9e\u00a0 : 60 ml pour les veaux, 1 \u00e0 2 fois par jour pendant 7 jours. 10 ml pour les agneaux et chevreaux, 1 \u00e0 2 fois par jour pendant 7 jours. \u00a0Pendant et apr\u00e8s ceux-ci : 60 ml pour les veaux, matin et soir pendant 4 jours. 10 ml pour les agneaux et chevreaux, matin et soir pendant 4 jours.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/obionekk\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/obionekk\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/obionekk\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Obionekk-5L-01.2024.webp\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Obionekk-5L-01.2024.webp\",\"width\":1500,\"height\":1668},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/obionekk\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Obionekk\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Obione\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Obionekk Obione - V\u00e9torino","description":"Aliment di\u00e9t\u00e9tique pour veaux, chevreaux et agneaux indiqu\u00e9 lors de risques de troubles digestifs (diarrh\u00e9e), pendant ou apr\u00e8s ceux-ci.  Stabilisation du bilan des \u00e9lectrolytes et de l'eau.  Mode d'emploi :   Administrer par voie orale : au pistolet drogueur ou dans le lait. \u00a0En cas de risque de diarrh\u00e9e\u00a0 : 60 ml pour les veaux, 1 \u00e0 2 fois par jour pendant 7 jours. 10 ml pour les agneaux et chevreaux, 1 \u00e0 2 fois par jour pendant 7 jours.  \u00a0Pendant et apr\u00e8s ceux-ci : 60 ml pour les veaux, matin et soir pendant 4 jours. 10 ml pour les agneaux et chevreaux, matin et soir pendant 4 jours.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Obionekk Obione - V\u00e9torino","og_description":"Aliment di\u00e9t\u00e9tique pour veaux, chevreaux et agneaux indiqu\u00e9 lors de risques de troubles digestifs (diarrh\u00e9e), pendant ou apr\u00e8s ceux-ci.  Stabilisation du bilan des \u00e9lectrolytes et de l'eau.  Mode d'emploi :   Administrer par voie orale : au pistolet drogueur ou dans le lait. \u00a0En cas de risque de diarrh\u00e9e\u00a0 : 60 ml pour les veaux, 1 \u00e0 2 fois par jour pendant 7 jours. 10 ml pour les agneaux et chevreaux, 1 \u00e0 2 fois par jour pendant 7 jours.  \u00a0Pendant et apr\u00e8s ceux-ci : 60 ml pour les veaux, matin et soir pendant 4 jours. 10 ml pour les agneaux et chevreaux, matin et soir pendant 4 jours.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/champignysurmarne-94500\/boutique\/product\/obionekk\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-03-29T07:41:27+00:00","og_image":[{"width":1500,"height":1668,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/Obionekk-5L-01.2024.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/obionekk\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/obionekk\/","name":"Obionekk Obione - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/obionekk\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/obionekk\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/Obionekk-5L-01.2024.webp","datePublished":"2020-06-29T23:39:43+00:00","dateModified":"2026-03-29T07:41:27+00:00","description":"Aliment di\u00e9t\u00e9tique pour veaux, chevreaux et agneaux indiqu\u00e9 lors de risques de troubles digestifs (diarrh\u00e9e), pendant ou apr\u00e8s ceux-ci. Stabilisation du bilan des \u00e9lectrolytes et de l'eau. Mode d'emploi : Administrer par voie orale : au pistolet drogueur ou dans le lait. \u00a0En cas de risque de diarrh\u00e9e\u00a0 : 60 ml pour les veaux, 1 \u00e0 2 fois par jour pendant 7 jours. 10 ml pour les agneaux et chevreaux, 1 \u00e0 2 fois par jour pendant 7 jours. \u00a0Pendant et apr\u00e8s ceux-ci : 60 ml pour les veaux, matin et soir pendant 4 jours. 10 ml pour les agneaux et chevreaux, matin et soir pendant 4 jours.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/obionekk\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/obionekk\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/obionekk\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/Obionekk-5L-01.2024.webp","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/Obionekk-5L-01.2024.webp","width":1500,"height":1668},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/obionekk\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Obionekk"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Obione","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/champignysurmarne-94500\/boutique\/wp-json\/wp\/v2\/product\/100062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/champignysurmarne-94500\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/champignysurmarne-94500\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/champignysurmarne-94500\/boutique\/wp-json\/wp\/v2\/media\/1459505"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/champignysurmarne-94500\/boutique\/wp-json\/wp\/v2\/media?parent=100062"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/champignysurmarne-94500\/boutique\/wp-json\/wp\/v2\/product_cat?post=100062"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/champignysurmarne-94500\/boutique\/wp-json\/wp\/v2\/product_tag?post=100062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}