{"id":130430,"date":"2020-11-25T20:14:56","date_gmt":"2020-11-25T19:14:56","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/gamelle-anti-glouton-pop-os\/"},"modified":"2026-05-12T12:41:48","modified_gmt":"2026-05-12T10:41:48","slug":"gamelle-anti-glouton-pop-os","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/champignysurmarne-94500\/boutique\/product\/gamelle-anti-glouton-pop-os\/","title":{"rendered":"Gamelle Anti-glouton Pop Os &#8211; chien"},"content":{"rendered":"<p><strong>Gamelle pour chien favorisant une alimentation plus lente et plus naturelle, jusqu\u2019\u00e0 10 fois plus longue ! Cela permet une meilleure digestion.\u00a0<\/strong><\/p>\n<p>Id\u00e9ale pour les animaux gloutons ou en surpoids.<\/p>\n<p><strong>Avantages :<\/strong><\/p>\n<ul>\n<li>Stimule le chien mentalement et lui \u00e9vite de s&#8217;ennuyer.<\/li>\n<li>De petits patins en caoutchouc emp\u00eachent la gamelle de d\u00e9raper.<\/li>\n<li>Peut \u00eatre utilis\u00e9e en int\u00e9rieur comme en ext\u00e9rieur.<\/li>\n<li>Facile d\u2019entretien : la gamelle anti-glouton passe au lave-vaisselle !<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p><strong>Gamelle pour chien favorisant une alimentation plus lente et plus naturelle, jusqu\u2019\u00e0 10 fois plus longue ! Cela permet une meilleure digestion.\u00a0<\/strong><\/p>\n<p><strong>Id\u00e9ale pour les animaux gloutons ou en surpoids.<\/strong><\/p>\n<p><strong>Avantages :<\/strong><\/p>\n<ul>\n<li>Stimule le chien mentalement et lui \u00e9vite de s&#8217;ennuyer.<\/li>\n<li>De petits patins en caoutchouc emp\u00eachent la gamelle de d\u00e9raper.<\/li>\n<li>Peut \u00eatre utilis\u00e9e en int\u00e9rieur comme en ext\u00e9rieur.<\/li>\n<li>Facile d\u2019entretien : la gamelle anti-glouton passe au lave-vaisselle !<\/li>\n<\/ul>\n","protected":false},"featured_media":1465441,"template":"","meta":[],"product_cat":[12550,2698,12607],"product_tag":[],"class_list":{"0":"post-130430","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessoires-du-chien","7":"product_cat-chien","8":"product_cat-gamelles-pour-chien","9":"pa_marque-vetopop","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gamelle Anti-glouton Pop Os - chien V\u00e9topop - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Gamelle pour chien favorisant une alimentation plus lente et plus naturelle, jusqu\u2019\u00e0 10 fois plus longue ! Cela permet une meilleure digestion.\u00a0  Id\u00e9ale pour les animaux gloutons ou en surpoids.  Avantages :   Stimule le chien mentalement et lui \u00e9vite de s&#039;ennuyer.  De petits patins en caoutchouc emp\u00eachent la gamelle de d\u00e9raper.  Peut \u00eatre utilis\u00e9e en int\u00e9rieur comme en ext\u00e9rieur.  Facile d\u2019entretien : la gamelle anti-glouton passe au lave-vaisselle !\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gamelle Anti-glouton Pop Os - chien V\u00e9topop - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Gamelle pour chien favorisant une alimentation plus lente et plus naturelle, jusqu\u2019\u00e0 10 fois plus longue ! Cela permet une meilleure digestion.\u00a0  Id\u00e9ale pour les animaux gloutons ou en surpoids.  Avantages :   Stimule le chien mentalement et lui \u00e9vite de s&#039;ennuyer.  De petits patins en caoutchouc emp\u00eachent la gamelle de d\u00e9raper.  Peut \u00eatre utilis\u00e9e en int\u00e9rieur comme en ext\u00e9rieur.  Facile d\u2019entretien : la gamelle anti-glouton passe au lave-vaisselle !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/champignysurmarne-94500\/boutique\/product\/gamelle-anti-glouton-pop-os\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T10:41:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/11\/gamelle-anti-glouton-pop-os-bleu.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/gamelle-anti-glouton-pop-os\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/gamelle-anti-glouton-pop-os\\\/\",\"name\":\"Gamelle Anti-glouton Pop Os - chien V\u00e9topop - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/gamelle-anti-glouton-pop-os\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/gamelle-anti-glouton-pop-os\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/gamelle-anti-glouton-pop-os-bleu.webp\",\"datePublished\":\"2020-11-25T19:14:56+00:00\",\"dateModified\":\"2026-05-12T10:41:48+00:00\",\"description\":\"Gamelle pour chien favorisant une alimentation plus lente et plus naturelle, jusqu\u2019\u00e0 10 fois plus longue ! Cela permet une meilleure digestion.\u00a0 Id\u00e9ale pour les animaux gloutons ou en surpoids. Avantages : Stimule le chien mentalement et lui \u00e9vite de s'ennuyer. De petits patins en caoutchouc emp\u00eachent la gamelle de d\u00e9raper. Peut \u00eatre utilis\u00e9e en int\u00e9rieur comme en ext\u00e9rieur. Facile d\u2019entretien : la gamelle anti-glouton passe au lave-vaisselle !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/gamelle-anti-glouton-pop-os\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/gamelle-anti-glouton-pop-os\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/gamelle-anti-glouton-pop-os\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/gamelle-anti-glouton-pop-os-bleu.webp\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/gamelle-anti-glouton-pop-os-bleu.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/gamelle-anti-glouton-pop-os\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gamelle Anti-glouton Pop Os &#8211; chien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"V\u00e9topop\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gamelle Anti-glouton Pop Os - chien V\u00e9topop - V\u00e9torino","description":"Gamelle pour chien favorisant une alimentation plus lente et plus naturelle, jusqu\u2019\u00e0 10 fois plus longue ! Cela permet une meilleure digestion.\u00a0  Id\u00e9ale pour les animaux gloutons ou en surpoids.  Avantages :   Stimule le chien mentalement et lui \u00e9vite de s'ennuyer.  De petits patins en caoutchouc emp\u00eachent la gamelle de d\u00e9raper.  Peut \u00eatre utilis\u00e9e en int\u00e9rieur comme en ext\u00e9rieur.  Facile d\u2019entretien : la gamelle anti-glouton passe au lave-vaisselle !","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Gamelle Anti-glouton Pop Os - chien V\u00e9topop - V\u00e9torino","og_description":"Gamelle pour chien favorisant une alimentation plus lente et plus naturelle, jusqu\u2019\u00e0 10 fois plus longue ! Cela permet une meilleure digestion.\u00a0  Id\u00e9ale pour les animaux gloutons ou en surpoids.  Avantages :   Stimule le chien mentalement et lui \u00e9vite de s'ennuyer.  De petits patins en caoutchouc emp\u00eachent la gamelle de d\u00e9raper.  Peut \u00eatre utilis\u00e9e en int\u00e9rieur comme en ext\u00e9rieur.  Facile d\u2019entretien : la gamelle anti-glouton passe au lave-vaisselle !","og_url":"https:\/\/www.vetorino.com\/veterinaire\/champignysurmarne-94500\/boutique\/product\/gamelle-anti-glouton-pop-os\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-05-12T10:41:48+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/11\/gamelle-anti-glouton-pop-os-bleu.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/gamelle-anti-glouton-pop-os\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/gamelle-anti-glouton-pop-os\/","name":"Gamelle Anti-glouton Pop Os - chien V\u00e9topop - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/gamelle-anti-glouton-pop-os\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/gamelle-anti-glouton-pop-os\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/11\/gamelle-anti-glouton-pop-os-bleu.webp","datePublished":"2020-11-25T19:14:56+00:00","dateModified":"2026-05-12T10:41:48+00:00","description":"Gamelle pour chien favorisant une alimentation plus lente et plus naturelle, jusqu\u2019\u00e0 10 fois plus longue ! Cela permet une meilleure digestion.\u00a0 Id\u00e9ale pour les animaux gloutons ou en surpoids. Avantages : Stimule le chien mentalement et lui \u00e9vite de s'ennuyer. De petits patins en caoutchouc emp\u00eachent la gamelle de d\u00e9raper. Peut \u00eatre utilis\u00e9e en int\u00e9rieur comme en ext\u00e9rieur. Facile d\u2019entretien : la gamelle anti-glouton passe au lave-vaisselle !","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/gamelle-anti-glouton-pop-os\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/gamelle-anti-glouton-pop-os\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/gamelle-anti-glouton-pop-os\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/11\/gamelle-anti-glouton-pop-os-bleu.webp","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/11\/gamelle-anti-glouton-pop-os-bleu.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/gamelle-anti-glouton-pop-os\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Gamelle Anti-glouton Pop Os &#8211; chien"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"V\u00e9topop","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/champignysurmarne-94500\/boutique\/wp-json\/wp\/v2\/product\/130430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/champignysurmarne-94500\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/champignysurmarne-94500\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/champignysurmarne-94500\/boutique\/wp-json\/wp\/v2\/media\/1465441"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/champignysurmarne-94500\/boutique\/wp-json\/wp\/v2\/media?parent=130430"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/champignysurmarne-94500\/boutique\/wp-json\/wp\/v2\/product_cat?post=130430"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/champignysurmarne-94500\/boutique\/wp-json\/wp\/v2\/product_tag?post=130430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}