{"id":297542,"date":"2022-02-24T15:18:19","date_gmt":"2022-02-24T14:18:19","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/?p=297542"},"modified":"2024-08-08T17:22:04","modified_gmt":"2024-08-08T15:22:04","slug":"quelle-alimentation-pour-mon-chien-age","status":"publish","type":"post","link":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/2022\/02\/24\/quelle-alimentation-pour-mon-chien-age\/","title":{"rendered":"Quelle alimentation pour mon chien \u00e2g\u00e9 ?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"297542\" class=\"elementor elementor-297542\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-778d1c2b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"778d1c2b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7a2e9656\" data-id=\"7a2e9656\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6dbaec49 elementor-widget elementor-widget-text-editor\" data-id=\"6dbaec49\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<h2 class=\"wp-block-heading\">Bien adapter l&#8217;alimentation pour mon chien lorsqu&#8217;il vieillit<\/h2>\n<p><\/p>\n<p><\/p>\n<p>Comme l\u2019Homme, plus un <strong>chien vieillit<\/strong>, plus il est susceptible de <strong>prendre du poids<\/strong>. Il est donc fondamental d\u2019<strong>adapter son alimentation au fur et \u00e0 mesure de sa vieillesse<\/strong>\u2026 De ce fait, il faut r\u00e9duire ses portions, surtout les graisses. De plus, il faut bien adapter son alimentation, un <strong>chien s\u00e9nior<\/strong> ne mange plus comme un jeune chien. Ainsi, il faut donner \u00e0 votre chien \u00e2g\u00e9 une<strong> alimentation riche en prot\u00e9ines<\/strong> et riche en om\u00e9ga 3 et 6.<\/p>\n<p><\/p>\n<p><\/p>\n<h2 class=\"has-text-align-left wp-block-heading\">Bien nourrir son chien senior<\/h2>\n<p><\/p>\n<p><\/p>\n<p>D\u00e8s lors que votre <strong>chien est s\u00e9nior<\/strong>, il faut choisir son <strong>alimentation<\/strong> en cons\u00e9quence. Un chien est \u00e2g\u00e9 \u00e0 partir de 6 ans et jusqu\u2019\u00e0 10 ans selon sa race. Concr\u00e8tement, le <strong>vieillissement de votre chien<\/strong> affaiblit son m\u00e9tabolisme. Cela r\u00e9duit ses besoins \u00e9nerg\u00e9tiques de l\u2019ordre de 10%. En outre, il faut savoir qu\u2019\u00e0 portions \u00e9gales, un<strong> chien s\u00e9nior stocke beaucoup plus qu\u2019un chien adulte<\/strong>. Cerise sur le g\u00e2teau, en vieillissant, votre chien sera <strong>moins actif<\/strong> et donc br\u00fblera d\u2019autant moins les calories ing\u00e9r\u00e9es.<\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<h2 class=\"wp-block-heading\">Nos recommandations pour bien nourrir votre chien lorsqu&#8217;il vieillit<\/h2>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-297553 alignright\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mathew-coulton-zxqaAkkayP8-unsplash-300x200.jpg\" alt=\"Nos recommandations pour bien nourrir votre chien lorsqu'il vieillit\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mathew-coulton-zxqaAkkayP8-unsplash-300x200.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mathew-coulton-zxqaAkkayP8-unsplash-1024x683.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mathew-coulton-zxqaAkkayP8-unsplash-768x512.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mathew-coulton-zxqaAkkayP8-unsplash-1536x1024.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mathew-coulton-zxqaAkkayP8-unsplash-2048x1365.jpg 2048w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mathew-coulton-zxqaAkkayP8-unsplash-750x500.jpg 750w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mathew-coulton-zxqaAkkayP8-unsplash-555x370.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mathew-coulton-zxqaAkkayP8-unsplash-64x43.jpg 64w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><\/p>\n<p><\/p>\n<p>Nous vous recommandons pour <strong>bien nourrir votre chien lorsqu\u2019il vieillit<\/strong> de r\u00e9duire consid\u00e9rablement la part des graisses \u2013 limpides. <strong>Privil\u00e9giez les acides gras<\/strong> essentiels Omega 3 et 6. Les aliments qui en comportent sont excellents pour d\u00e9toxifier votre animal. Avec leur action anti-oxydant, ils am\u00e9lioreront la qualit\u00e9 du poil et de la peau de votre <strong>compagnon \u00e0 4 pattes<\/strong>. De plus, pour lutter contre la <strong>perte musculaire<\/strong>, il faut compenser avec un apport important de prot\u00e9ines. Faites tout de m\u00eame attention \u00e0 ce que les reins de votre chien ne soient pas d\u00e9faillants avec l\u2019\u00e2ge pour <strong>ing\u00e9rer<\/strong> cet apport.<\/p>\n<p>Pour apporter les <strong>min\u00e9raux<\/strong>, vitamines, n\u00e9cessaires au <strong>chien vieillissant<\/strong>, il faut consulter un <strong>v\u00e9t\u00e9rinaire<\/strong>. Seule son expertise saura \u00e0 m\u00eame de vous accompagner int\u00e9gralement \u00e0 ce sujet. En effet, cela n\u00e9cessite des connaissances accrues et les <strong>produits v\u00e9t\u00e9rinaires<\/strong> sont pens\u00e9s en ce sens. Pour le <strong>bien-\u00eatre des chiens s\u00e9niors<\/strong>, les croquettes adapt\u00e9es \u00e0 leurs \u00e2ges sont particuli\u00e8rement efficaces.<\/p>\n<p>Si votre chien perd l\u2019app\u00e9tit, a une dentition d\u00e9faillante, vous pouvez aussi lui proposer certains produits alimentaires sous forme humide. L\u2019important est vraiment de <strong>s\u2019adapter \u00e0 la condition de votre animal de compagnie<\/strong>.<\/p>\n<p><\/p>\n<p><\/p>\n<h2 class=\"wp-block-heading\">Am\u00e9liorer l&#8217;esp\u00e9rance de vie de votre chien gr\u00e2ce \u00e0 une bonne alimentation<\/h2>\n<p><img decoding=\"async\" class=\"size-medium wp-image-297552 alignleft\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-jean-alves-2123773-300x200.jpg\" alt=\"Am\u00e9liorer l'esp\u00e9rance de vie de votre chien gr\u00e2ce \u00e0 une bonne alimentation\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-jean-alves-2123773-300x200.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-jean-alves-2123773-1024x683.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-jean-alves-2123773-768x512.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-jean-alves-2123773-1536x1024.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-jean-alves-2123773-2048x1365.jpg 2048w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-jean-alves-2123773-750x500.jpg 750w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-jean-alves-2123773-555x370.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-jean-alves-2123773-64x43.jpg 64w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p><\/p>\n<p><\/p>\n<p>Gr\u00e2ce \u00e0 une <strong>bonne alimentation<\/strong>, vous allez consid\u00e9rablement am\u00e9liorer <strong>l\u2019esp\u00e9rance de vie de votre chien<\/strong>\u00a0! Une \u00e9tude men\u00e9e durant 15 ans sur l\u2019influence d\u2019une <strong>alimentation raisonn\u00e9e<\/strong> sur l\u2019esp\u00e9rance de vie des chiens, prouve qu\u2019un chien peut vivre au moins deux belles ann\u00e9es de plus lorsqu\u2019il n\u2019est pas en surpoids, qu\u2019il a une <strong>alimentation saine<\/strong>\u2026 Alors, d\u00e8s que votre <strong>animal vieillit<\/strong>, adoptez une alimentation adapt\u00e9e !<\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1e4d2660 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1e4d2660\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-604a4c9b\" data-id=\"604a4c9b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6aea1494 elementor-widget elementor-widget-heading\" data-id=\"6aea1494\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"line-height: 1.4;margin-top: 20px;margin-bottom: 10px;font-size: 18px;text-align: center\">S\u00e9lections de produits pour une bonne alimentation d'un chien s\u00e9nior<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1fcd835 product_alcyon elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1fcd835\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-280b5985\" data-id=\"280b5985\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-394f323f elementor-widget elementor-widget-image\" data-id=\"394f323f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/croquettes-mature-adult-7-light-medium-poulet-chien-sac-14-kg-science-plan-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299255\" alt=\"croquettes-mature-adult-7-light-medium-poulet-chien-sac-14-kg-science-plan-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/croquettes-mature-adult-7-light-medium-poulet-chien-sac-14-kg-science-plan-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/croquettes-mature-adult-7-light-medium-poulet-chien-sac-14-kg-science-plan-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/croquettes-mature-adult-7-light-medium-poulet-chien-sac-14-kg-science-plan-vetorino-160x160.jpg 160w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70c52e72 elementor-widget elementor-widget-heading\" data-id=\"70c52e72\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hill's\nCANINE ADULT 7+ MATURE MEDIUM LIGHT POULET<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15a6a2f5 elementor-widget elementor-widget-text-editor\" data-id=\"15a6a2f5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mature Adult 7+ Light Medium, pour chien senior de moyenne race, apportent une alimentation sp\u00e9cialement pour les chiens peu actifs.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a1ff110 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6a1ff110\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/boutique\/product\/canine-adult-7-mature-medium-light-poulet\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-67d7b7ba\" data-id=\"67d7b7ba\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-105fdd9c elementor-widget elementor-widget-image\" data-id=\"105fdd9c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-299253\" alt=\"mature-consult-medium-dog-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-768x768.png 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-555x555.png 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino.png 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d631e4c elementor-widget elementor-widget-heading\" data-id=\"6d631e4c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u200bRoyal Canin\nDOG MATURE CONSULT MEDIUM SAC 10 KG <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f101ef3 elementor-widget elementor-widget-text-editor\" data-id=\"3f101ef3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les croquettes premium Royal Canin Mature Medium Dog\u00a0sont recommand\u00e9es pour les\u00a0chiens senior de race moyenne.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4008d34 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4008d34\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/boutique\/product\/vetcare-chien-mature\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-456ceadf\" data-id=\"456ceadf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-282372b2 elementor-widget elementor-widget-image\" data-id=\"282372b2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299257\" alt=\"science-plan-chien-age-mature-boite-poulet-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-1024x1024.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-768x768.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-555x555.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino.jpg 1042w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53f86cd2 elementor-widget elementor-widget-heading\" data-id=\"53f86cd2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hill's CANINE MATURE ADULT 7+ POULET<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-204901a9 elementor-widget elementor-widget-text-editor\" data-id=\"204901a9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hill\u2019s\u00a0 Canine Mature Adult 7+ au Poulet est sp\u00e9cialement formul\u00e9 pour maintenir la mobilit\u00e9 et des organes vitaux en bonne sant\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69dc2617 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"69dc2617\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/boutique\/product\/canine-mature-poulet-boite-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-69f9a30b\" data-id=\"69f9a30b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-25c90b01 elementor-widget elementor-widget-image\" data-id=\"25c90b01\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/senior-dog-small-toy-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299254\" alt=\"senior-dog-small-toy-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/senior-dog-small-toy-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/senior-dog-small-toy-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/senior-dog-small-toy-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/senior-dog-small-toy-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/senior-dog-small-toy-vetorino.jpg 458w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-402ce059 elementor-widget elementor-widget-heading\" data-id=\"402ce059\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Virbac\nVET HPM DOG SENIOR SMALL ET TOY\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67b00e81 elementor-widget elementor-widget-text-editor\" data-id=\"67b00e81\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Virbac Vet HPM Baby Dog Small &amp; Toy est une alimentation compl\u00e8te et \u00e9quilibr\u00e9e pour les chiens matures de petite race.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-406fed5b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"406fed5b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/boutique\/product\/vet-hpm-dog-senior-small-toy\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9f76041 product_centravet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9f76041\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-2a9d8dd\" data-id=\"2a9d8dd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a2f3382 elementor-widget elementor-widget-image\" data-id=\"a2f3382\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/croquettes-mature-adult-7-light-medium-poulet-chien-sac-14-kg-science-plan-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299255\" alt=\"croquettes-mature-adult-7-light-medium-poulet-chien-sac-14-kg-science-plan-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/croquettes-mature-adult-7-light-medium-poulet-chien-sac-14-kg-science-plan-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/croquettes-mature-adult-7-light-medium-poulet-chien-sac-14-kg-science-plan-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/croquettes-mature-adult-7-light-medium-poulet-chien-sac-14-kg-science-plan-vetorino-160x160.jpg 160w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2089c15 elementor-widget elementor-widget-heading\" data-id=\"2089c15\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hill's\nCANINE ADULT 7+ MATURE MEDIUM LIGHT POULET<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3250096 elementor-widget elementor-widget-text-editor\" data-id=\"3250096\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mature Adult 7+ Light Medium, pour chien senior de moyenne race, apportent une alimentation sp\u00e9cialement pour les chiens peu actifs.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd3c959 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"dd3c959\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/boutique\/product\/canine-mature-adult-7-light-medium-poulet\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-2f10038\" data-id=\"2f10038\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0340d3e elementor-widget elementor-widget-image\" data-id=\"0340d3e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-299253\" alt=\"mature-consult-medium-dog-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-768x768.png 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-555x555.png 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino.png 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a1bfce elementor-widget elementor-widget-heading\" data-id=\"6a1bfce\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u200bRoyal Canin\nDOG MATURE CONSULT MEDIUM SAC 10 KG <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fc8e39 elementor-widget elementor-widget-text-editor\" data-id=\"2fc8e39\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les croquettes premium Royal Canin Mature Medium Dog\u00a0sont recommand\u00e9es pour les\u00a0chiens senior de race moyenne.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-69a55c5 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"69a55c5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/boutique\/product\/vet-care-nutrition-mature\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-b03f19e\" data-id=\"b03f19e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22d67bf elementor-widget elementor-widget-image\" data-id=\"22d67bf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299257\" alt=\"science-plan-chien-age-mature-boite-poulet-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-1024x1024.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-768x768.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-555x555.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino.jpg 1042w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89566a3 elementor-widget elementor-widget-heading\" data-id=\"89566a3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hill's CANINE MATURE ADULT 7+ POULET<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-925e527 elementor-widget elementor-widget-text-editor\" data-id=\"925e527\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hill\u2019s\u00a0 Canine Mature Adult 7+ au Poulet est sp\u00e9cialement formul\u00e9 pour maintenir la mobilit\u00e9 et des organes vitaux en bonne sant\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c74a51b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c74a51b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/boutique\/product\/canine-mature-adult-7-poulet-boite\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ef494d7\" data-id=\"ef494d7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-653e1c9 elementor-widget elementor-widget-image\" data-id=\"653e1c9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/senior-dog-small-toy-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299254\" alt=\"senior-dog-small-toy-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/senior-dog-small-toy-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/senior-dog-small-toy-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/senior-dog-small-toy-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/senior-dog-small-toy-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/senior-dog-small-toy-vetorino.jpg 458w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9159143 elementor-widget elementor-widget-heading\" data-id=\"9159143\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Virbac\nVET HPM DOG SENIOR SMALL ET TOY\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8e5aa5 elementor-widget elementor-widget-text-editor\" data-id=\"d8e5aa5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Virbac Vet HPM Baby Dog Small &amp; Toy est une alimentation compl\u00e8te et \u00e9quilibr\u00e9e pour les chiens matures de petite race.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4643d61 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"4643d61\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/boutique\/product\/veterinary-hpm-dog-senior-small-toy\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ddac0dc product_coveto elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ddac0dc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-98ed065\" data-id=\"98ed065\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7a4bbc7 elementor-widget elementor-widget-image\" data-id=\"7a4bbc7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/croquettes-mature-adult-7-light-medium-poulet-chien-sac-14-kg-science-plan-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299255\" alt=\"croquettes-mature-adult-7-light-medium-poulet-chien-sac-14-kg-science-plan-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/croquettes-mature-adult-7-light-medium-poulet-chien-sac-14-kg-science-plan-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/croquettes-mature-adult-7-light-medium-poulet-chien-sac-14-kg-science-plan-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/croquettes-mature-adult-7-light-medium-poulet-chien-sac-14-kg-science-plan-vetorino-160x160.jpg 160w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0ab01fd elementor-widget elementor-widget-heading\" data-id=\"0ab01fd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hill's\nCANINE ADULT 7+ MATURE MEDIUM LIGHT POULET<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a4706da elementor-widget elementor-widget-text-editor\" data-id=\"a4706da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mature Adult 7+ Light Medium, pour chien senior de moyenne race, apportent une alimentation sp\u00e9cialement pour les chiens peu actifs.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-888d464 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"888d464\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/boutique\/product\/canine-mature-adult-7-light-medium-poulet-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-30c86e3\" data-id=\"30c86e3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-470f1ff elementor-widget elementor-widget-image\" data-id=\"470f1ff\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-299253\" alt=\"mature-consult-medium-dog-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-768x768.png 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-555x555.png 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/mature-consult-medium-dog-vetorino.png 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13ac9cc elementor-widget elementor-widget-heading\" data-id=\"13ac9cc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u200bRoyal Canin\nDOG MATURE CONSULT MEDIUM SAC 10 KG <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea5cdf7 elementor-widget elementor-widget-text-editor\" data-id=\"ea5cdf7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les croquettes premium Royal Canin Mature Medium Dog\u00a0sont recommand\u00e9es pour les\u00a0chiens senior de race moyenne.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30a0199 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"30a0199\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/boutique\/product\/vet-care-nutrition-mature-3\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-54ebdf1\" data-id=\"54ebdf1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3169b2a elementor-widget elementor-widget-image\" data-id=\"3169b2a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299257\" alt=\"science-plan-chien-age-mature-boite-poulet-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-1024x1024.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-768x768.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-555x555.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/science-plan-chien-age-mature-boite-poulet-vetorino.jpg 1042w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbdcc57 elementor-widget elementor-widget-heading\" data-id=\"dbdcc57\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hill's CANINE MATURE ADULT 7+ POULET<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b817a8a elementor-widget elementor-widget-text-editor\" data-id=\"b817a8a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hill\u2019s\u00a0 Canine Mature Adult 7+ au Poulet est sp\u00e9cialement formul\u00e9 pour maintenir la mobilit\u00e9 et des organes vitaux en bonne sant\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6f29d8 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"a6f29d8\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/boutique\/product\/canine-mature-poulet-boite-3\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-bd559f4\" data-id=\"bd559f4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a9cd40 elementor-widget elementor-widget-image\" data-id=\"1a9cd40\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/senior-dog-small-toy-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299254\" alt=\"senior-dog-small-toy-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/senior-dog-small-toy-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/senior-dog-small-toy-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/senior-dog-small-toy-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/senior-dog-small-toy-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/senior-dog-small-toy-vetorino.jpg 458w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53a315e elementor-widget elementor-widget-heading\" data-id=\"53a315e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Virbac\nVET HPM DOG SENIOR SMALL ET TOY\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae7a49c elementor-widget elementor-widget-text-editor\" data-id=\"ae7a49c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Virbac Vet HPM Baby Dog Small &amp; Toy est une alimentation compl\u00e8te et \u00e9quilibr\u00e9e pour les chiens matures de petite race.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbe0726 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"cbe0726\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/boutique\/product\/veterinary-hpm-dog-senior-small-toy-sac-de-3-kg\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d174711 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d174711\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4d03cd35\" data-id=\"4d03cd35\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-17b36256 elementor-widget elementor-widget-text-editor\" data-id=\"17b36256\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong style=\"color: #078ed2;text-align: center\"><a href=\"https:\/\/www.vetorino.com\/boutique\/product-category\/chien\/?&amp;s=&amp;sante-de-lanimal=vieillissement\">D\u00e9couvrez ici notre s\u00e9lection de produits pour une bonne alimentation d&#8217;un chien qui vieillit<\/a><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Bien adapter l&#8217;alimentation pour mon chien lorsqu&#8217;il vieillit Comme l\u2019Homme, plus un chien vieillit, plus il est susceptible de prendre du poids. Il est donc fondamental d\u2019adapter son alimentation au fur et \u00e0 mesure de sa vieillesse\u2026 De ce fait, il faut r\u00e9duire ses portions, surtout les graisses. De plus, il faut bien adapter son [&hellip;]<\/p>\n","protected":false},"author":9451,"featured_media":297552,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[14088,14087,14094],"tags":[],"class_list":["post-297542","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentation-chien","category-chien","category-sante-chien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Quelle alimentation pour mon chien \u00e2g\u00e9 ? - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Cliquez ici pour d\u00e9couvrir quelle alimentation instaurer pour son chien \u00e2g\u00e9, s\u00e9nior ! Lorsqu&#039;il vieillit, un chien a besoin d&#039;adapter...\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quelle alimentation pour mon chien \u00e2g\u00e9 ? - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Cliquez ici pour d\u00e9couvrir quelle alimentation instaurer pour son chien \u00e2g\u00e9, s\u00e9nior ! Lorsqu&#039;il vieillit, un chien a besoin d&#039;adapter...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/2022\/02\/24\/quelle-alimentation-pour-mon-chien-age\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-24T14:18:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-08T15:22:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-jean-alves-2123773-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Marion Geyres\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Marion Geyres\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/quelle-alimentation-pour-mon-chien-age\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/quelle-alimentation-pour-mon-chien-age\\\/\"},\"author\":{\"name\":\"Marion Geyres\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/d2533581c37b078b40bb4ab86ec7d7da\"},\"headline\":\"Quelle alimentation pour mon chien \u00e2g\u00e9 ?\",\"datePublished\":\"2022-02-24T14:18:19+00:00\",\"dateModified\":\"2024-08-08T15:22:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/quelle-alimentation-pour-mon-chien-age\\\/\"},\"wordCount\":916,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/quelle-alimentation-pour-mon-chien-age\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/pexels-jean-alves-2123773-scaled.jpg\",\"articleSection\":[\"Alimentation pour chien\",\"Chien\",\"Sant\u00e9 pour chien\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/quelle-alimentation-pour-mon-chien-age\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/quelle-alimentation-pour-mon-chien-age\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/quelle-alimentation-pour-mon-chien-age\\\/\",\"name\":\"Quelle alimentation pour mon chien \u00e2g\u00e9 ? - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/quelle-alimentation-pour-mon-chien-age\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/quelle-alimentation-pour-mon-chien-age\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/pexels-jean-alves-2123773-scaled.jpg\",\"datePublished\":\"2022-02-24T14:18:19+00:00\",\"dateModified\":\"2024-08-08T15:22:04+00:00\",\"description\":\"Cliquez ici pour d\u00e9couvrir quelle alimentation instaurer pour son chien \u00e2g\u00e9, s\u00e9nior ! Lorsqu'il vieillit, un chien a besoin d'adapter...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/quelle-alimentation-pour-mon-chien-age\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/quelle-alimentation-pour-mon-chien-age\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/quelle-alimentation-pour-mon-chien-age\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/pexels-jean-alves-2123773-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/pexels-jean-alves-2123773-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Am\u00e9liorer l'esp\u00e9rance de vie de votre chien gr\u00e2ce \u00e0 une bonne alimentation\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/quelle-alimentation-pour-mon-chien-age\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chien\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/champs-sur-marne-77420\\\/boutique\\\/category\\\/chien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Alimentation pour chien\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/category\\\/chien\\\/alimentation-chien\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Quelle alimentation pour mon chien \u00e2g\u00e9 ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/d2533581c37b078b40bb4ab86ec7d7da\",\"name\":\"Marion Geyres\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/159f774603ef41756934feff9c9130c15e219c52dfed6bb8ac87db81494fb104?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/159f774603ef41756934feff9c9130c15e219c52dfed6bb8ac87db81494fb104?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/159f774603ef41756934feff9c9130c15e219c52dfed6bb8ac87db81494fb104?s=96&d=mm&r=g\",\"caption\":\"Marion Geyres\"},\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/chaumont-52000\\\/boutique\\\/author\\\/mariongeyres\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quelle alimentation pour mon chien \u00e2g\u00e9 ? - V\u00e9torino","description":"Cliquez ici pour d\u00e9couvrir quelle alimentation instaurer pour son chien \u00e2g\u00e9, s\u00e9nior ! Lorsqu'il vieillit, un chien a besoin d'adapter...","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Quelle alimentation pour mon chien \u00e2g\u00e9 ? - V\u00e9torino","og_description":"Cliquez ici pour d\u00e9couvrir quelle alimentation instaurer pour son chien \u00e2g\u00e9, s\u00e9nior ! Lorsqu'il vieillit, un chien a besoin d'adapter...","og_url":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/2022\/02\/24\/quelle-alimentation-pour-mon-chien-age\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_published_time":"2022-02-24T14:18:19+00:00","article_modified_time":"2024-08-08T15:22:04+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-jean-alves-2123773-scaled.jpg","type":"image\/jpeg"}],"author":"Marion Geyres","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Marion Geyres","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/quelle-alimentation-pour-mon-chien-age\/#article","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/quelle-alimentation-pour-mon-chien-age\/"},"author":{"name":"Marion Geyres","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/d2533581c37b078b40bb4ab86ec7d7da"},"headline":"Quelle alimentation pour mon chien \u00e2g\u00e9 ?","datePublished":"2022-02-24T14:18:19+00:00","dateModified":"2024-08-08T15:22:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/quelle-alimentation-pour-mon-chien-age\/"},"wordCount":916,"commentCount":0,"publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/quelle-alimentation-pour-mon-chien-age\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-jean-alves-2123773-scaled.jpg","articleSection":["Alimentation pour chien","Chien","Sant\u00e9 pour chien"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/quelle-alimentation-pour-mon-chien-age\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/quelle-alimentation-pour-mon-chien-age\/","url":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/quelle-alimentation-pour-mon-chien-age\/","name":"Quelle alimentation pour mon chien \u00e2g\u00e9 ? - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/quelle-alimentation-pour-mon-chien-age\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/quelle-alimentation-pour-mon-chien-age\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-jean-alves-2123773-scaled.jpg","datePublished":"2022-02-24T14:18:19+00:00","dateModified":"2024-08-08T15:22:04+00:00","description":"Cliquez ici pour d\u00e9couvrir quelle alimentation instaurer pour son chien \u00e2g\u00e9, s\u00e9nior ! Lorsqu'il vieillit, un chien a besoin d'adapter...","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/quelle-alimentation-pour-mon-chien-age\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/quelle-alimentation-pour-mon-chien-age\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/quelle-alimentation-pour-mon-chien-age\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-jean-alves-2123773-scaled.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-jean-alves-2123773-scaled.jpg","width":2560,"height":1707,"caption":"Am\u00e9liorer l'esp\u00e9rance de vie de votre chien gr\u00e2ce \u00e0 une bonne alimentation"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/quelle-alimentation-pour-mon-chien-age\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Chien","item":"https:\/\/www.vetorino.com\/veterinaire\/champs-sur-marne-77420\/boutique\/category\/chien\/"},{"@type":"ListItem","position":3,"name":"Alimentation pour chien","item":"https:\/\/www.vetorino.com\/boutique\/category\/chien\/alimentation-chien\/"},{"@type":"ListItem","position":4,"name":"Quelle alimentation pour mon chien \u00e2g\u00e9 ?"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]},{"@type":"Person","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/d2533581c37b078b40bb4ab86ec7d7da","name":"Marion Geyres","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/159f774603ef41756934feff9c9130c15e219c52dfed6bb8ac87db81494fb104?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/159f774603ef41756934feff9c9130c15e219c52dfed6bb8ac87db81494fb104?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/159f774603ef41756934feff9c9130c15e219c52dfed6bb8ac87db81494fb104?s=96&d=mm&r=g","caption":"Marion Geyres"},"url":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/author\/mariongeyres\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/posts\/297542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/users\/9451"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/comments?post=297542"}],"version-history":[{"count":31,"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/posts\/297542\/revisions"}],"predecessor-version":[{"id":300825,"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/posts\/297542\/revisions\/300825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/media\/297552"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/media?parent=297542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/categories?post=297542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/tags?post=297542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}