{"id":884723,"date":"2023-09-27T12:13:50","date_gmt":"2023-09-27T10:13:50","guid":{"rendered":"https:\/\/www.vetorino.com\/veterinaire\/evry-91000\/boutique\/?p=884723"},"modified":"2024-08-08T17:21:11","modified_gmt":"2024-08-08T15:21:11","slug":"mission-pour-la-vie-hill-s","status":"publish","type":"post","link":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/2023\/09\/27\/mission-pour-la-vie-hill-s\/","title":{"rendered":"1 commande = 1 repas offert"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"884723\" class=\"elementor elementor-884723\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38d6036 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"38d6036\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b54c0fe\" data-id=\"b54c0fe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90b5d84 elementor-widget elementor-widget-image\" data-id=\"90b5d84\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1100\" height=\"340\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/blog-amis-pour-la-vie-banniere-desktop.jpeg\" class=\"attachment-2048x2048 size-2048x2048 wp-image-885782\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/blog-amis-pour-la-vie-banniere-desktop.jpeg 1100w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/blog-amis-pour-la-vie-banniere-desktop-300x93.jpeg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/blog-amis-pour-la-vie-banniere-desktop-1024x317.jpeg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/blog-amis-pour-la-vie-banniere-desktop-768x237.jpeg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/blog-amis-pour-la-vie-banniere-desktop-555x172.jpeg 555w\" sizes=\"(max-width: 1100px) 100vw, 1100px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3888d1d elementor-widget elementor-widget-text-editor\" data-id=\"3888d1d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7bg7gso elementor-widget elementor-widget-text-editor\" data-id=\"7bg7gso\" data-element_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><div class=\"elementor-text-editor elementor-clearfix\">Tout au long du mois d&#8217;avril, et pour la 4\u00e8me ann\u00e9e cons\u00e9cutive, Hill&#8217;s organise son action solidaire Mission Amis Pour La Vie, le 1er \u00e9v\u00e9nement europ\u00e9en pour les animaux de refuge! Une commande Hill&#8217;s = 1 repas OFFERT aux animaux en refuge. 1 repas correspond \u00e0 environ 131 grammes d&#8217;aliments.<\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4747b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4747b9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f0a8be6\" data-id=\"f0a8be6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77b80b4 elementor-widget elementor-widget-text-editor\" data-id=\"77b80b4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-element elementor-element-8j8qvkr elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section elementor-top-section\" data-id=\"8j8qvkr\" data-element_type=\"section\"><div class=\"elementor-container elementor-column-gap-default\"><div class=\"elementor-row\"><div class=\"elementor-element elementor-element-2u8kg9v elementor-column elementor-col-100 elementor-top-column\" data-id=\"2u8kg9v\" data-element_type=\"column\"><div class=\"elementor-column-wrap elementor-element-populated\"><div class=\"elementor-widget-wrap\"><div class=\"elementor-element elementor-element-tcv8rwn elementor-widget elementor-widget-heading\" data-id=\"tcv8rwn\" data-element_type=\"heading.default\"><h2 class=\"elementor-widget-container\">Qu&#8217;est ce que l&#8217;op\u00e9ration Missions Amis pour la vie ?<\/h2><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-37f3744 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"37f3744\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c4ba9ae\" data-id=\"c4ba9ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-acf908e elementor-widget elementor-widget-image\" data-id=\"acf908e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"600\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/blog-amis-pour-la-vie-hills.jpeg\" class=\"attachment-large size-large wp-image-885786\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/blog-amis-pour-la-vie-hills.jpeg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/blog-amis-pour-la-vie-hills-150x300.jpeg 150w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5abeb12\" data-id=\"5abeb12\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-448f199 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"448f199\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Mission amis pour la vie est une\u00a0<strong>op\u00e9ration solidaire<\/strong>\u00a0organis\u00e9e par Hill&#8217;s dans le cadre de son programme &#8220;<strong>Nourrir<\/strong>,\u00a0<strong>Accueillir<\/strong>\u00a0et\u00a0<strong>Aimer<\/strong>&#8221; et qui vient en aide aux animaux des refuges \u00e0 travers l&#8217;Europe.<\/p><p>Gr\u00e2ce \u00e0 des dons d&#8217;aliments, Hill&#8217;s soutient l&#8217;action des refuges et\u00a0<strong>aide les animaux dans le besoin \u00e0 retrouver un nouveau foyer aimant pour la vie<\/strong>.<\/p><p>Cette cause vous touche et vous souhaitez y prendre part ?\u00a0<strong>Rejoignez le mouvement #MISSIONAMISPOURLAVIE du 1er au 30 avril<\/strong>.<\/p><div class=\"elementor-element elementor-element-oyu0pnx elementor-widget elementor-widget-heading\" data-id=\"oyu0pnx\" data-element_type=\"heading.default\"><div class=\"elementor-widget-container\"><h4>\u00a0<\/h4><h4 class=\"elementor-heading-title elementor-size-default\" style=\"text-align: left;\">Nourrir, Accueillir et Aimer<\/h4><\/div><\/div><div class=\"elementor-element elementor-element-wt9wuwu elementor-widget elementor-widget-text-editor\" style=\"text-align: center;\" data-id=\"wt9wuwu\" data-element_type=\"text-editor.default\"><div class=\"elementor-widget-container\"><div class=\"elementor-text-editor elementor-clearfix\"><p style=\"text-align: left;\">Le\u00a0programme Hill&#8217;s Nourrir, Accueillir et Aimer\u00a0<strong>vient en aide aux animaux des refuges tout au long de l&#8217;ann\u00e9e<\/strong>.<\/p><\/div><\/div><\/div><p style=\"text-align: center;\">\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b9851a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b9851a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f121d70\" data-id=\"f121d70\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62f1ed9 elementor-widget elementor-widget-text-editor\" data-id=\"62f1ed9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2>Comment participer ?<\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86b51a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86b51a2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ca49f12\" data-id=\"ca49f12\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d92d7f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2d92d7f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div data-id=\"t3ksmlb\" data-element_type=\"heading.default\"><div><p>En avril, chaque achat Hill&#8217;s sur les boutiques V\u00e9torino permettra d&#8217;offrir un repas et une nutrition v\u00e9t\u00e9rinaire aux animaux des refuges soutenus dans le cadre de cette op\u00e9ration. Heureux et en meilleure sant\u00e9, ils sont alors plus faciles \u00e0 adopter !<\/p><\/div><\/div><div data-id=\"3h6jf0h\" data-element_type=\"text-editor.default\"><div><div>\u00a0<\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c797a28 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"c797a28\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/pogny-51240\/boutique\/marque\/hills-pet-nutrition\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Pour d\u00e9couvrir les produits Hill's, Cliquez ici ! <\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5edf07d\" data-id=\"5edf07d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-888da5a elementor-widget elementor-widget-image\" data-id=\"888da5a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"540\" height=\"540\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/04\/image-croquette-paquet-hills-page-ami-pour-la-vie.jpeg\" class=\"attachment-large size-large wp-image-885820\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/04\/image-croquette-paquet-hills-page-ami-pour-la-vie.jpeg 540w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/04\/image-croquette-paquet-hills-page-ami-pour-la-vie-300x300.jpeg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/04\/image-croquette-paquet-hills-page-ami-pour-la-vie-150x150.jpeg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/04\/image-croquette-paquet-hills-page-ami-pour-la-vie-500x500.jpeg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/04\/image-croquette-paquet-hills-page-ami-pour-la-vie-160x160.jpeg 160w\" sizes=\"(max-width: 540px) 100vw, 540px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c8f6186 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c8f6186\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bb4151e\" data-id=\"bb4151e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dbc1cc8 elementor-widget elementor-widget-video\" data-id=\"dbc1cc8\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/Yhny9x6Q6l8&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-58c9801\" data-id=\"58c9801\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-044a8f2 elementor-widget elementor-widget-video\" data-id=\"044a8f2\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/youtu.be\\\/CM_uJq3B_c0&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5f9536c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5f9536c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c08ff64\" data-id=\"c08ff64\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-92313a1 elementor-widget elementor-widget-text-editor\" data-id=\"92313a1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-element elementor-element-txbxn41 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section elementor-top-section\" data-id=\"txbxn41\" data-element_type=\"section\">\n<div class=\"elementor-container elementor-column-gap-default\">\n<div class=\"elementor-row\">\n<div class=\"elementor-element elementor-element-1jmuqjw elementor-column elementor-col-100 elementor-top-column\" data-id=\"1jmuqjw\" data-element_type=\"column\">\n<div class=\"elementor-column-wrap elementor-element-populated\">\n<div class=\"elementor-widget-wrap\">\n<div class=\"elementor-element elementor-element-nn510zd elementor-widget elementor-widget-text-editor\" data-id=\"nn510zd\" data-element_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<p>En 2023,&nbsp;<strong>Hill&#8217;s a offert plus de 200 000 repas<\/strong>&nbsp;\u00e0 des milliers de refuges en Europe,&nbsp;<strong>dont 50 000 en France<\/strong>.&nbsp;<span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: var( --e-global-typography-text-font-size );\">Cette ann\u00e9e, avec votre aide, nous esp\u00e9rons faire encore plus.<\/span><\/p>\n<p><span style=\"color: var( --e-global-color-text ); font-family: var( --e-global-typography-text-font-family ), Sans-serif; font-size: var( --e-global-typography-text-font-size );\"><br><\/span><\/p>\n<p><\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<section class=\"elementor-element elementor-element-8e0bj1w elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-section elementor-top-section\" data-id=\"8e0bj1w\" data-element_type=\"section\">\n<div class=\"elementor-container elementor-column-gap-default\">\n<div class=\"elementor-row\">\n<div class=\"elementor-element elementor-element-gtfc874 elementor-column elementor-col-100 elementor-top-column\" data-id=\"gtfc874\" data-element_type=\"column\">\n<div class=\"elementor-column-wrap elementor-element-populated\">\n<div class=\"elementor-widget-wrap\">\n<div class=\"elementor-element elementor-element-rhohxch elementor-widget elementor-widget-text-editor\" data-id=\"rhohxch\" data-element_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"elementor-text-editor elementor-clearfix\">\n<p><strong>Plus vous serez nombreux, plus&nbsp;nous aurons&nbsp;de chances d&#8217;atteindre ces objectifs !<\/strong><\/p>\n<p><\/p>\n<p>Pour soutenir cette action solidaire et aider un maximum de chiens et de chats dans le besoin \u00e0 retrouver un foyer aimant pour la vie, il vous suffit de relayer l&#8217;op\u00e9ration sur les r\u00e9seaux sociaux !<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c00f9d2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c00f9d2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6a14ebb\" data-id=\"6a14ebb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-945d61d elementor-widget elementor-widget-image\" data-id=\"945d61d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"980\" height=\"232\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/banniere-hills-ami-pour-la-vie-fin-page-mission-1024x242.jpeg\" class=\"attachment-large size-large wp-image-886596\" alt=\"\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/banniere-hills-ami-pour-la-vie-fin-page-mission-1024x242.jpeg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/banniere-hills-ami-pour-la-vie-fin-page-mission-300x71.jpeg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/banniere-hills-ami-pour-la-vie-fin-page-mission-768x181.jpeg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/banniere-hills-ami-pour-la-vie-fin-page-mission-1536x363.jpeg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/banniere-hills-ami-pour-la-vie-fin-page-mission-555x131.jpeg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/banniere-hills-ami-pour-la-vie-fin-page-mission.jpeg 1905w\" sizes=\"(max-width: 980px) 100vw, 980px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8517964 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8517964\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-350b09f\" data-id=\"350b09f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a08b30 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1a08b30\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/pogny-51240\/boutique\/\/wp-content\/uploads\/2024\/04\/MFF-2024-TC-hillspet.fr_.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir les conditions de l'op\u00e9ration<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Tout au long du mois d&#8217;avril, et pour la 4\u00e8me ann\u00e9e cons\u00e9cutive, Hill&#8217;s organise son action solidaire Mission Amis Pour La Vie, le 1er \u00e9v\u00e9nement europ\u00e9en pour les animaux de refuge! Une commande Hill&#8217;s = 1 repas OFFERT aux animaux en refuge. 1 repas correspond \u00e0 environ 131 grammes d&#8217;aliments. Qu&#8217;est ce que l&#8217;op\u00e9ration Missions [&hellip;]<\/p>\n","protected":false},"author":16700,"featured_media":887375,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[14089,14086,14095],"tags":[],"class_list":["post-884723","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentation-chat","category-chat","category-sante-et-prevention-chat"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>1 commande = 1 repas offert - V\u00e9torino<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1 commande = 1 repas offert - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Tout au long du mois d&#8217;avril, et pour la 4\u00e8me ann\u00e9e cons\u00e9cutive, Hill&#8217;s organise son action solidaire Mission Amis Pour La Vie, le 1er \u00e9v\u00e9nement europ\u00e9en pour les animaux de refuge! Une commande Hill&#8217;s = 1 repas OFFERT aux animaux en refuge. 1 repas correspond \u00e0 environ 131 grammes d&#8217;aliments. Qu&#8217;est ce que l&#8217;op\u00e9ration Missions [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/2023\/09\/27\/mission-pour-la-vie-hill-s\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-27T10:13:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-08T15:21:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/banniere-hills-ami-pour-la-vie-fin-page-mission-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1905\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Agathe Daniel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Agathe Daniel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/mission-pour-la-vie-hill-s\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/mission-pour-la-vie-hill-s\\\/\"},\"author\":{\"name\":\"Agathe Daniel\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/1047c10be91a7ac087b673b34d348a11\"},\"headline\":\"1 commande = 1 repas offert\",\"datePublished\":\"2023-09-27T10:13:50+00:00\",\"dateModified\":\"2024-08-08T15:21:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/mission-pour-la-vie-hill-s\\\/\"},\"wordCount\":339,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/mission-pour-la-vie-hill-s\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/banniere-hills-ami-pour-la-vie-fin-page-mission-1.jpeg\",\"articleSection\":[\"Alimentation pour chat\",\"Chat\",\"Sant\u00e9 et pr\u00e9vention pour chat\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/mission-pour-la-vie-hill-s\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/mission-pour-la-vie-hill-s\\\/\",\"name\":\"1 commande = 1 repas offert - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/mission-pour-la-vie-hill-s\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/mission-pour-la-vie-hill-s\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/banniere-hills-ami-pour-la-vie-fin-page-mission-1.jpeg\",\"datePublished\":\"2023-09-27T10:13:50+00:00\",\"dateModified\":\"2024-08-08T15:21:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/mission-pour-la-vie-hill-s\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/mission-pour-la-vie-hill-s\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/mission-pour-la-vie-hill-s\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/banniere-hills-ami-pour-la-vie-fin-page-mission-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/banniere-hills-ami-pour-la-vie-fin-page-mission-1.jpeg\",\"width\":1905,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/mission-pour-la-vie-hill-s\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chat\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/champs-sur-marne-77420\\\/boutique\\\/category\\\/chat\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1 commande = 1 repas offert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/1047c10be91a7ac087b673b34d348a11\",\"name\":\"Agathe Daniel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/415bb761d76c9ec23a6224965a05e4605d70e01639794bbd92c5fb9fe12dc0a7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/415bb761d76c9ec23a6224965a05e4605d70e01639794bbd92c5fb9fe12dc0a7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/415bb761d76c9ec23a6224965a05e4605d70e01639794bbd92c5fb9fe12dc0a7?s=96&d=mm&r=g\",\"caption\":\"Agathe Daniel\"},\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/chaumont-52000\\\/boutique\\\/author\\\/agathedani\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1 commande = 1 repas offert - V\u00e9torino","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"1 commande = 1 repas offert - V\u00e9torino","og_description":"Tout au long du mois d&#8217;avril, et pour la 4\u00e8me ann\u00e9e cons\u00e9cutive, Hill&#8217;s organise son action solidaire Mission Amis Pour La Vie, le 1er \u00e9v\u00e9nement europ\u00e9en pour les animaux de refuge! Une commande Hill&#8217;s = 1 repas OFFERT aux animaux en refuge. 1 repas correspond \u00e0 environ 131 grammes d&#8217;aliments. Qu&#8217;est ce que l&#8217;op\u00e9ration Missions [&hellip;]","og_url":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/2023\/09\/27\/mission-pour-la-vie-hill-s\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_published_time":"2023-09-27T10:13:50+00:00","article_modified_time":"2024-08-08T15:21:11+00:00","og_image":[{"width":1905,"height":450,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/banniere-hills-ami-pour-la-vie-fin-page-mission-1.jpeg","type":"image\/jpeg"}],"author":"Agathe Daniel","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Agathe Daniel","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/mission-pour-la-vie-hill-s\/#article","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/mission-pour-la-vie-hill-s\/"},"author":{"name":"Agathe Daniel","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/1047c10be91a7ac087b673b34d348a11"},"headline":"1 commande = 1 repas offert","datePublished":"2023-09-27T10:13:50+00:00","dateModified":"2024-08-08T15:21:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/mission-pour-la-vie-hill-s\/"},"wordCount":339,"publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/mission-pour-la-vie-hill-s\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/banniere-hills-ami-pour-la-vie-fin-page-mission-1.jpeg","articleSection":["Alimentation pour chat","Chat","Sant\u00e9 et pr\u00e9vention pour chat"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/mission-pour-la-vie-hill-s\/","url":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/mission-pour-la-vie-hill-s\/","name":"1 commande = 1 repas offert - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/mission-pour-la-vie-hill-s\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/mission-pour-la-vie-hill-s\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/banniere-hills-ami-pour-la-vie-fin-page-mission-1.jpeg","datePublished":"2023-09-27T10:13:50+00:00","dateModified":"2024-08-08T15:21:11+00:00","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/mission-pour-la-vie-hill-s\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/mission-pour-la-vie-hill-s\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/mission-pour-la-vie-hill-s\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/banniere-hills-ami-pour-la-vie-fin-page-mission-1.jpeg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/banniere-hills-ami-pour-la-vie-fin-page-mission-1.jpeg","width":1905,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/mission-pour-la-vie-hill-s\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Chat","item":"https:\/\/www.vetorino.com\/veterinaire\/champs-sur-marne-77420\/boutique\/category\/chat\/"},{"@type":"ListItem","position":3,"name":"1 commande = 1 repas offert"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]},{"@type":"Person","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/1047c10be91a7ac087b673b34d348a11","name":"Agathe Daniel","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/415bb761d76c9ec23a6224965a05e4605d70e01639794bbd92c5fb9fe12dc0a7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/415bb761d76c9ec23a6224965a05e4605d70e01639794bbd92c5fb9fe12dc0a7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/415bb761d76c9ec23a6224965a05e4605d70e01639794bbd92c5fb9fe12dc0a7?s=96&d=mm&r=g","caption":"Agathe Daniel"},"url":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/author\/agathedani\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/posts\/884723","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/users\/16700"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/comments?post=884723"}],"version-history":[{"count":56,"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/posts\/884723\/revisions"}],"predecessor-version":[{"id":993054,"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/posts\/884723\/revisions\/993054"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/media\/887375"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/media?parent=884723"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/categories?post=884723"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/tags?post=884723"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}