{"id":624414,"date":"2023-05-30T11:36:12","date_gmt":"2023-05-30T09:36:12","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/chien-derm-complete-boite\/"},"modified":"2026-07-14T02:42:09","modified_gmt":"2026-07-14T00:42:09","slug":"chien-derm-complete-boite","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/product\/chien-derm-complete-boite\/","title":{"rendered":"Chien Derm Complete"},"content":{"rendered":"<p><strong>Alimentation\u00a0cliniquement con\u00e7ue pour\u00a0aider \u00e0 la gestion des allergies alimentaires\u00a0et\u00a0environnementales.<br \/>\n<\/strong><\/p>\n<p><strong><a href=\"https:\/\/www.youtube.com\/watch?v=4kTFonEmZLA\">Voir la vid\u00e9o de pr\u00e9sentation Derm Complete ICI<\/a><br \/>\n<\/strong><\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Aide \u00e0 g\u00e9rer les allergies, la peau s\u00e8che, les d\u00e9mangeaisons et le grattage chez le chien.<\/li>\n<li>Pour les sensibilit\u00e9s alimentaires et\/ou environnementales.<\/li>\n<\/ul>\n<p><strong>Contre indications :<\/strong><\/p>\n<ul>\n<li>Femelles gestantes ou allaitantes.<\/li>\n<li>Chiots.<\/li>\n<li>Chiens pr\u00e9sentant une hyperlipid\u00e9mie, une pancr\u00e9atite, des ant\u00e9c\u00e9dents de pancr\u00e9atite ou un risque de pancr\u00e9atite.<\/li>\n<\/ul>\n<p><strong>Bienfaits essentiels :<\/strong><\/p>\n<ul>\n<li>l&#8217;alimentation PRESCRIPTION DIET pour chiens est la nutrition cibl\u00e9e dont ils ont besoin\u00a0<strong>pour une vie longue et heureuse<\/strong>.<\/li>\n<li>Formul\u00e9 pour soutenir tout au long de l&#8217;ann\u00e9e la barri\u00e8re cutan\u00e9e\u00a0<strong>contre les allergies d&#8217;origine environnementale<\/strong>.<\/li>\n<li><strong>Am\u00e9lioration visible<\/strong>\u00a0de la peau en 21 jours seulement chez les chiens souffrant d&#8217;allergies alimentaires.<\/li>\n<li>Nutrition prouv\u00e9e pour r\u00e9duire en 28 jours seulement\u00a0<strong>l\u00e9chage, d\u00e9mangeaisons, mouvements de t\u00eate et rougeurs cutan\u00e9es<\/strong>, comme d\u00e9montr\u00e9 dans une \u00e9tude ouverte.<\/li>\n<li>Teneurs \u00e9lev\u00e9es en acides gras essentiels pour\u00a0<strong>favoriser la bonne sant\u00e9 de la peau<\/strong>.<\/li>\n<li>Nutrition cliniquement prouv\u00e9e pour aider \u00e0\u00a0<strong>g\u00e9rer les signes d&#8217;allergies de la peau<\/strong> tels que peau s\u00e8che, d\u00e9mangeaisons et grattage, afin de favoriser la cicatrisation et la bonne sant\u00e9 de la peau.<\/li>\n<\/ul>\n<p><strong>Ce produit est une alimentation v\u00e9t\u00e9rinaire. Demandez conseil \u00e0 votre v\u00e9t\u00e9rinaire avant tout achat et respectez ses recommandations.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Alimentation cliniquement con\u00e7ue pour aider \u00e0 la gestion des allergies alimentaires et environnementales.<br \/>\n<\/strong><\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Aide \u00e0 g\u00e9rer les allergies, la peau s\u00e8che, les d\u00e9mangeaisons et le grattage chez le chien.<\/li>\n<li>Pour les sensibilit\u00e9s alimentaires et\/ou environnementales.<\/li>\n<\/ul>\n<p><strong>Ce produit est une alimentation v\u00e9t\u00e9rinaire. Demandez conseil \u00e0 votre v\u00e9t\u00e9rinaire avant tout achat et respectez ses recommandations.<\/strong><\/p>\n","protected":false},"featured_media":1750986,"template":"","meta":[],"product_cat":[12552,12582,2698],"product_tag":[],"class_list":{"0":"post-624414","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alimentation-du-chien","7":"product_cat-alimentation-medicalisee-pour-chien","8":"product_cat-chien","9":"pa_marque-hills-pet-nutrition","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prescription Diet (Hill&#039;s) Chien Derm Complete Hill&#039;s - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Alimentation cliniquement con\u00e7ue pour aider \u00e0 la gestion des allergies alimentaires et environnementales.   Utilisation :   Aide \u00e0 g\u00e9rer les allergies, la peau s\u00e8che, les d\u00e9mangeaisons et le grattage chez le chien.  Pour les sensibilit\u00e9s alimentaires et\/ou environnementales.  Ce produit est une alimentation v\u00e9t\u00e9rinaire. Demandez conseil \u00e0 votre v\u00e9t\u00e9rinaire avant tout achat et respectez ses recommandations.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prescription Diet (Hill&#039;s) Chien Derm Complete Hill&#039;s - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Alimentation cliniquement con\u00e7ue pour aider \u00e0 la gestion des allergies alimentaires et environnementales.   Utilisation :   Aide \u00e0 g\u00e9rer les allergies, la peau s\u00e8che, les d\u00e9mangeaisons et le grattage chez le chien.  Pour les sensibilit\u00e9s alimentaires et\/ou environnementales.  Ce produit est une alimentation v\u00e9t\u00e9rinaire. Demandez conseil \u00e0 votre v\u00e9t\u00e9rinaire avant tout achat et respectez ses recommandations.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/product\/chien-derm-complete-boite\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T00:42:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/05\/179109_pla_hills_prescriptiondiet_caninederm_complete_hs_01_5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chien-derm-complete-boite\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chien-derm-complete-boite\\\/\",\"name\":\"Prescription Diet (Hill's) Chien Derm Complete Hill's - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chien-derm-complete-boite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chien-derm-complete-boite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/chien-derm-complete-1.webp\",\"datePublished\":\"2023-05-30T09:36:12+00:00\",\"dateModified\":\"2026-07-14T00:42:09+00:00\",\"description\":\"Alimentation cliniquement con\u00e7ue pour aider \u00e0 la gestion des allergies alimentaires et environnementales. Utilisation : Aide \u00e0 g\u00e9rer les allergies, la peau s\u00e8che, les d\u00e9mangeaisons et le grattage chez le chien. Pour les sensibilit\u00e9s alimentaires et\\\/ou environnementales. Ce produit est une alimentation v\u00e9t\u00e9rinaire. Demandez conseil \u00e0 votre v\u00e9t\u00e9rinaire avant tout achat et respectez ses recommandations.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chien-derm-complete-boite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chien-derm-complete-boite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chien-derm-complete-boite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/chien-derm-complete-1.webp\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/chien-derm-complete-1.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/chien-derm-complete-boite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Chien Derm Complete\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Hill&#039;s\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prescription Diet (Hill's) Chien Derm Complete Hill's - V\u00e9torino","description":"Alimentation cliniquement con\u00e7ue pour aider \u00e0 la gestion des allergies alimentaires et environnementales.   Utilisation :   Aide \u00e0 g\u00e9rer les allergies, la peau s\u00e8che, les d\u00e9mangeaisons et le grattage chez le chien.  Pour les sensibilit\u00e9s alimentaires et\/ou environnementales.  Ce produit est une alimentation v\u00e9t\u00e9rinaire. Demandez conseil \u00e0 votre v\u00e9t\u00e9rinaire avant tout achat et respectez ses recommandations.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Prescription Diet (Hill's) Chien Derm Complete Hill's - V\u00e9torino","og_description":"Alimentation cliniquement con\u00e7ue pour aider \u00e0 la gestion des allergies alimentaires et environnementales.   Utilisation :   Aide \u00e0 g\u00e9rer les allergies, la peau s\u00e8che, les d\u00e9mangeaisons et le grattage chez le chien.  Pour les sensibilit\u00e9s alimentaires et\/ou environnementales.  Ce produit est une alimentation v\u00e9t\u00e9rinaire. Demandez conseil \u00e0 votre v\u00e9t\u00e9rinaire avant tout achat et respectez ses recommandations.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/product\/chien-derm-complete-boite\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-07-14T00:42:09+00:00","og_image":[{"width":400,"height":400,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/05\/179109_pla_hills_prescriptiondiet_caninederm_complete_hs_01_5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chien-derm-complete-boite\/","url":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chien-derm-complete-boite\/","name":"Prescription Diet (Hill's) Chien Derm Complete Hill's - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chien-derm-complete-boite\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chien-derm-complete-boite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/06\/chien-derm-complete-1.webp","datePublished":"2023-05-30T09:36:12+00:00","dateModified":"2026-07-14T00:42:09+00:00","description":"Alimentation cliniquement con\u00e7ue pour aider \u00e0 la gestion des allergies alimentaires et environnementales. Utilisation : Aide \u00e0 g\u00e9rer les allergies, la peau s\u00e8che, les d\u00e9mangeaisons et le grattage chez le chien. Pour les sensibilit\u00e9s alimentaires et\/ou environnementales. Ce produit est une alimentation v\u00e9t\u00e9rinaire. Demandez conseil \u00e0 votre v\u00e9t\u00e9rinaire avant tout achat et respectez ses recommandations.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chien-derm-complete-boite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chien-derm-complete-boite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chien-derm-complete-boite\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/06\/chien-derm-complete-1.webp","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/06\/chien-derm-complete-1.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/chien-derm-complete-boite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Chien Derm Complete"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Hill's","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/product\/624414","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/media\/1750986"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/media?parent=624414"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/product_cat?post=624414"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/chaumont-52000\/boutique\/wp-json\/wp\/v2\/product_tag?post=624414"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}