{"id":297177,"date":"2022-02-24T16:01:33","date_gmt":"2022-02-24T15:01:33","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/?p=297177"},"modified":"2024-08-08T17:22:00","modified_gmt":"2024-08-08T15:22:00","slug":"steriliser-mon-chien","status":"publish","type":"post","link":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/2022\/02\/24\/steriliser-mon-chien\/","title":{"rendered":"St\u00e9riliser mon chien"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"297177\" class=\"elementor elementor-297177\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-174df8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"174df8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-22dc37a3\" data-id=\"22dc37a3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-63b2aa12 elementor-widget elementor-widget-text-editor\" data-id=\"63b2aa12\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p><h2 class=\"wp-block-heading\">La st\u00e9rilisation pour mon chien<\/h2><p><\/p><p><\/p><p>Pourquoi <strong>st\u00e9riliser son chien<\/strong>\u00a0? La st\u00e9rilisation du chien est d\u00e9sormais une pratique r\u00e9pandue en France et \u00e0 l\u2019\u00e9chelle europ\u00e9enne. En effet, <strong>40% des chiens sont st\u00e9rilis\u00e9s<\/strong>. Il y a ainsi plusieurs avantages reconnus \u00e0 la <strong>st\u00e9rilisation pour un chien<\/strong>. Concr\u00e8tement, l\u2019interruption de s\u00e9cr\u00e9tion d\u2019hormones sexuelles change le <strong>comportement d\u2019un chien<\/strong> et l\u2019emp\u00eache de se reproduire.<\/p><p>En fait, un <strong>chien<\/strong> aura moins tendance \u00e0 pr\u00e9senter des <strong>marques urinaires<\/strong> et \u00e0 <strong>chevaucher<\/strong> \u00e0 tout va. Une chienne, elle, n\u2019aura ses <strong>chaleurs<\/strong> que deux fois dans l\u2019ann\u00e9e.<\/p><p>Cependant, la <strong>st\u00e9rilisation pour le chien<\/strong> entraine de la prise du poids car son app\u00e9tit augmente et que ses besoins \u00e9nerg\u00e9tiques eux sont amoindris. Pour vous propri\u00e9taire, il s\u2019agit donc de veiller \u00e0 ajuster <strong>l\u2019alimentation<\/strong> de votre animal apr\u00e8s sa <strong>st\u00e9rilisation<\/strong>.<\/p><p><\/p><p><\/p><h2 class=\"has-text-align-left wp-block-heading\">Ce qu&#8217;il faut faire apr\u00e8s la st\u00e9rilisation de son chien<\/h2><p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-297186 alignright\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-nataliya-vaitkevich-4445622-200x300.jpg\" alt=\"Ce qu'il faut faire apr\u00e8s la st\u00e9rilisation de son chien\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-nataliya-vaitkevich-4445622-200x300.jpg 200w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-nataliya-vaitkevich-4445622-683x1024.jpg 683w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-nataliya-vaitkevich-4445622-768x1152.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-nataliya-vaitkevich-4445622-1024x1536.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-nataliya-vaitkevich-4445622-1365x2048.jpg 1365w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-nataliya-vaitkevich-4445622-555x833.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-nataliya-vaitkevich-4445622-64x96.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-nataliya-vaitkevich-4445622-scaled.jpg 1707w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/p><p><\/p><p><\/p><p>Pas moins de <strong>cinq actions<\/strong> sont \u00e0 faire apr\u00e8s la st\u00e9rilisation de votre chien. Les voici\u00a0:<\/p><ol><li>Limiter l\u2019apport de friandises et de restes \u00e0 table.<\/li><li>Bien contr\u00f4ler la ration journali\u00e8re de croquettes pour votre chien.<\/li><li>Peser fr\u00e9quemment votre chien.<\/li><li>Encourager votre chien \u00e0 faire r\u00e9guli\u00e8rement de l\u2019exercice.<\/li><li>Se rendre r\u00e9guli\u00e8rement chez son v\u00e9t\u00e9rinaire pour des visites de contr\u00f4le.<\/li><\/ol><p><\/p><p><\/p><h2 class=\"has-text-align-left wp-block-heading\">Le conseil nutritionnel bonus pour votre chien<\/h2><p><img decoding=\"async\" class=\"size-medium wp-image-297187 alignleft\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-heidi-meborg-6469221-200x300.jpg\" alt=\"Le conseil nutritionnel bonus pour votre chien\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-heidi-meborg-6469221-200x300.jpg 200w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-heidi-meborg-6469221-683x1024.jpg 683w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-heidi-meborg-6469221-768x1152.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-heidi-meborg-6469221-1024x1536.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-heidi-meborg-6469221-1365x2048.jpg 1365w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-heidi-meborg-6469221-555x833.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-heidi-meborg-6469221-64x96.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-heidi-meborg-6469221-scaled.jpg 1707w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/p><p><\/p><p><\/p><p>Sachez que votre <strong>chien<\/strong>, en tant qu\u2019<strong>animal carnivore<\/strong>, doit avoir une alimentation riche en prot\u00e9ines et pauvre en glucide. Il ne stocke pas les prot\u00e9ines, il les utilise pour son <strong>\u00e9nergie<\/strong>. En revanche, les exc\u00e8s de glucides vont eux se stocker sous forme de graisse.<\/p><p>En adoptant tous nos conseils, vous g\u00e9rerez la <strong>st\u00e9rilisation de votre chien<\/strong> au mieux !<\/p><p><\/p><p><\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-108539a7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"108539a7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-15380ad1\" data-id=\"15380ad1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-164939bf elementor-widget elementor-widget-heading\" data-id=\"164939bf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"line-height: 1.4;margin-top: 20px;margin-bottom: 10px;font-size: 18px;text-align: center\">S\u00e9lections de produits v\u00e9t\u00e9rinaire pour une bonne st\u00e9rilisation du chien<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4749402 product_alcyon elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4749402\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-61b2f1e8\" data-id=\"61b2f1e8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3a4c79 elementor-widget elementor-widget-image\" data-id=\"d3a4c79\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-image-299296\" alt=\"adult-neutered-dog-large-medium-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-150x150.jpeg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-300x300.jpeg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-768x768.jpeg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-500x500.jpeg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-555x555.jpeg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-160x160.jpeg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-64x64.jpeg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino.jpeg 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52165f8a elementor-widget elementor-widget-heading\" data-id=\"52165f8a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Virbac DOG ADULT NEUTERED LARGE ET MEDIUM<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f3e4e81 elementor-widget elementor-widget-text-editor\" data-id=\"5f3e4e81\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Virbac Vet HPM Dog Adult Neutered Large &amp; Medium sont des croquettes pour chiens st\u00e9rilis\u00e9s de moyennes et grandes races.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-534d1c3e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"534d1c3e\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/champigny-sur-marne-94\/boutique\/product\/vet-hpm-dog-adult-neutered-large-medium\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4105fab3\" data-id=\"4105fab3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24d174d4 elementor-widget elementor-widget-image\" data-id=\"24d174d4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-299292\" alt=\"neutered-junior-large-dog-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-768x768.png 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-555x555.png 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino.png 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5fd93213 elementor-widget elementor-widget-heading\" data-id=\"5fd93213\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Royal Canin\nCHIEN JUNIOR NEUTERED LARGE DOG <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-549cdc44 elementor-widget elementor-widget-text-editor\" data-id=\"549cdc44\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Royal Canin Neutered Junior Large Dog est un aliment complet pour le chien junior de taille importante (poids adulte sup\u00e9rieur \u00e0 25kg)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1ce2b9b6 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1ce2b9b6\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/champigny-sur-marne-94\/boutique\/product\/vetcare-chien-junior-neutered-large-dog\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-2cb5b5f6\" data-id=\"2cb5b5f6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6332091d elementor-widget elementor-widget-image\" data-id=\"6332091d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/tonivet-chien-adulte-mini-sterilise-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299293\" alt=\"tonivet-chien-adulte-mini-sterilise-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/tonivet-chien-adulte-mini-sterilise-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/tonivet-chien-adulte-mini-sterilise-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/tonivet-chien-adulte-mini-sterilise-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/tonivet-chien-adulte-mini-sterilise-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/tonivet-chien-adulte-mini-sterilise-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/tonivet-chien-adulte-mini-sterilise-vetorino.jpg 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b830c33 elementor-widget elementor-widget-heading\" data-id=\"7b830c33\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tonivet CHIEN ADULT MINI STERILISED<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44e05c48 elementor-widget elementor-widget-text-editor\" data-id=\"44e05c48\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><span style=\"font-weight: normal;\">Tonivet Chien Adult Mini St\u00e9rilis\u00e9 r\u00e9pondre au statut carnivore du chien gr\u00e2ce \u00e0 une alimentation riche en prot\u00e9ines d&#8217;origines animales.<\/span><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1aa3f8a5 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"1aa3f8a5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/champigny-sur-marne-94\/boutique\/product\/tonivet-chien-adulte-mini-sterilise\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-22db2e67\" data-id=\"22db2e67\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-426b0f44 elementor-widget elementor-widget-image\" data-id=\"426b0f44\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-299294\" alt=\"hills-neutered-dog-adult-medium-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-768x768.png 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-555x555.png 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1.png 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44cfbefe elementor-widget elementor-widget-heading\" data-id=\"44cfbefe\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hill's Vet essentials CANINE ADULT NEUTERED MEDIUM <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f3a83a4 elementor-widget elementor-widget-text-editor\" data-id=\"6f3a83a4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hill\u2019s Neutered Dog Adult Medium est une nutrition qui aide les chiens \u00e0 maintenir un poids id\u00e9al et \u00e0 rester en pleine forme apr\u00e8s la st\u00e9rilisation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf426ab elementor-align-center elementor-widget elementor-widget-button\" data-id=\"bf426ab\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/champigny-sur-marne-94\/boutique\/product\/vetessentials-canine-adult-neutered-medium\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a9f49e5 product_centravet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a9f49e5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-711cba1\" data-id=\"711cba1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01a91bb elementor-widget elementor-widget-image\" data-id=\"01a91bb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-image-299296\" alt=\"adult-neutered-dog-large-medium-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-150x150.jpeg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-300x300.jpeg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-768x768.jpeg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-500x500.jpeg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-555x555.jpeg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-160x160.jpeg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-64x64.jpeg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino.jpeg 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbc7691 elementor-widget elementor-widget-heading\" data-id=\"fbc7691\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Virbac DOG ADULT NEUTERED LARGE ET MEDIUM<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0b7ea9 elementor-widget elementor-widget-text-editor\" data-id=\"b0b7ea9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Virbac Vet HPM Dog Adult Neutered Large &amp; Medium sont des croquettes pour chiens st\u00e9rilis\u00e9s de moyennes et grandes races.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4190b5 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e4190b5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/champigny-sur-marne-94\/boutique\/product\/veterinary-hpm-dog-adult-neutered-large-medium\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ab4ecbf\" data-id=\"ab4ecbf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef411b4 elementor-widget elementor-widget-image\" data-id=\"ef411b4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-299292\" alt=\"neutered-junior-large-dog-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-768x768.png 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-555x555.png 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino.png 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d41e4d2 elementor-widget elementor-widget-heading\" data-id=\"d41e4d2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Royal Canin\nCHIEN JUNIOR NEUTERED LARGE DOG <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-44f7207 elementor-widget elementor-widget-text-editor\" data-id=\"44f7207\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Royal Canin Neutered Junior Large Dog est un aliment complet pour le chien junior de taille importante (poids adulte sup\u00e9rieur \u00e0 25kg)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-898f970 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"898f970\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/champigny-sur-marne-94\/boutique\/product\/vet-care-nutrition-neutered-junior-large-dog\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f53a127\" data-id=\"f53a127\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7eb4b20 elementor-widget elementor-widget-image\" data-id=\"7eb4b20\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/tonivet-chien-adulte-mini-sterilise-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299293\" alt=\"tonivet-chien-adulte-mini-sterilise-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/tonivet-chien-adulte-mini-sterilise-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/tonivet-chien-adulte-mini-sterilise-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/tonivet-chien-adulte-mini-sterilise-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/tonivet-chien-adulte-mini-sterilise-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/tonivet-chien-adulte-mini-sterilise-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/tonivet-chien-adulte-mini-sterilise-vetorino.jpg 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3e8527 elementor-widget elementor-widget-heading\" data-id=\"b3e8527\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tonivet CHIEN ADULT MINI STERILISED<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c00cfe elementor-widget elementor-widget-text-editor\" data-id=\"3c00cfe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><span style=\"font-weight: normal;\">Tonivet Chien Adult Mini St\u00e9rilis\u00e9 r\u00e9pondre au statut carnivore du chien gr\u00e2ce \u00e0 une alimentation riche en prot\u00e9ines d&#8217;origines animales.<\/span><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-027da71 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"027da71\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/champigny-sur-marne-94\/boutique\/product\/tonivet-chien-adulte-mini-sterilise-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-69b686a\" data-id=\"69b686a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42c51a5 elementor-widget elementor-widget-image\" data-id=\"42c51a5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-299294\" alt=\"hills-neutered-dog-adult-medium-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-768x768.png 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-555x555.png 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1.png 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-035cc05 elementor-widget elementor-widget-heading\" data-id=\"035cc05\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hill's Vet essentials CANINE ADULT NEUTERED MEDIUM <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6040564 elementor-widget elementor-widget-text-editor\" data-id=\"6040564\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hill\u2019s Neutered Dog Adult Medium est une nutrition qui aide les chiens \u00e0 maintenir un poids id\u00e9al et \u00e0 rester en pleine forme apr\u00e8s la st\u00e9rilisation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b48ea9a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"b48ea9a\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/champigny-sur-marne-94\/boutique\/product\/hills-neutered-dog-adult-medium\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7de2f87 product_coveto elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7de2f87\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-426b7b5\" data-id=\"426b7b5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58237ec elementor-widget elementor-widget-image\" data-id=\"58237ec\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-150x150.jpeg\" class=\"attachment-thumbnail size-thumbnail wp-image-299296\" alt=\"adult-neutered-dog-large-medium-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-150x150.jpeg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-300x300.jpeg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-768x768.jpeg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-500x500.jpeg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-555x555.jpeg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-160x160.jpeg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino-64x64.jpeg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/adult-neutered-dog-large-medium-vetorino.jpeg 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a06c4b7 elementor-widget elementor-widget-heading\" data-id=\"a06c4b7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Virbac DOG ADULT NEUTERED LARGE ET MEDIUM<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2e10c1 elementor-widget elementor-widget-text-editor\" data-id=\"f2e10c1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Virbac Vet HPM Dog Adult Neutered Large &amp; Medium sont des croquettes pour chiens st\u00e9rilis\u00e9s de moyennes et grandes races.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5dc8f2 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c5dc8f2\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/champigny-sur-marne-94\/boutique\/product\/veterinary-hpm-dog-adult-neutered-large-medium-sac-de-16-kg\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4d52c8f\" data-id=\"4d52c8f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af44084 elementor-widget elementor-widget-image\" data-id=\"af44084\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-299292\" alt=\"neutered-junior-large-dog-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-768x768.png 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-555x555.png 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/neutered-junior-large-dog-vetorino.png 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03f20dc elementor-widget elementor-widget-heading\" data-id=\"03f20dc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Royal Canin\nCHIEN JUNIOR NEUTERED LARGE DOG <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a695101 elementor-widget elementor-widget-text-editor\" data-id=\"a695101\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Royal Canin Neutered Junior Large Dog est un aliment complet pour le chien junior de taille importante (poids adulte sup\u00e9rieur \u00e0 25kg)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ea441b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7ea441b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/champigny-sur-marne-94\/boutique\/product\/vet-care-nutrition-neutered-junior-large-dog-sac-de-12-kg\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-133b119\" data-id=\"133b119\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38035ca elementor-widget elementor-widget-image\" data-id=\"38035ca\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/tonivet-chien-adulte-mini-sterilise-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-299293\" alt=\"tonivet-chien-adulte-mini-sterilise-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/tonivet-chien-adulte-mini-sterilise-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/tonivet-chien-adulte-mini-sterilise-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/tonivet-chien-adulte-mini-sterilise-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/tonivet-chien-adulte-mini-sterilise-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/tonivet-chien-adulte-mini-sterilise-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/tonivet-chien-adulte-mini-sterilise-vetorino.jpg 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f844e8 elementor-widget elementor-widget-heading\" data-id=\"6f844e8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tonivet CHIEN ADULT MINI STERILISED<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-366f22c elementor-widget elementor-widget-text-editor\" data-id=\"366f22c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><span style=\"font-weight: normal;\">Tonivet Chien Adult Mini St\u00e9rilis\u00e9 r\u00e9pondre au statut carnivore du chien gr\u00e2ce \u00e0 une alimentation riche en prot\u00e9ines d&#8217;origines animales.<\/span><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f124455 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"f124455\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/champigny-sur-marne-94\/boutique\/product\/tonivet-chien-adulte-mini-sterilise-sac-de-6-kg\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-8a45509\" data-id=\"8a45509\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d7b2455 elementor-widget elementor-widget-image\" data-id=\"d7b2455\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-299294\" alt=\"hills-neutered-dog-adult-medium-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-768x768.png 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-555x555.png 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/hills-neutered-dog-adult-medium-vetorino-1.png 800w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ff38094 elementor-widget elementor-widget-heading\" data-id=\"ff38094\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Hill's Vet essentials CANINE ADULT NEUTERED MEDIUM <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0d51fb elementor-widget elementor-widget-text-editor\" data-id=\"f0d51fb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hill\u2019s Neutered Dog Adult Medium est une nutrition qui aide les chiens \u00e0 maintenir un poids id\u00e9al et \u00e0 rester en pleine forme apr\u00e8s la st\u00e9rilisation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-579688b elementor-align-center elementor-widget elementor-widget-button\" data-id=\"579688b\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/champigny-sur-marne-94\/boutique\/product\/vetessentials-neutered-dog-adult-medium-sac-de-10-kg\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ec73cb8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ec73cb8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-32baa3a\" data-id=\"32baa3a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5b76f7bd elementor-widget elementor-widget-text-editor\" data-id=\"5b76f7bd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong style=\"color: #078ed2;text-align: center\"><a href=\"https:\/\/www.vetorino.com\/boutique\/product-category\/chien\/?&amp;s=&amp;sante-de-lanimal=sterilise\">Voir toutes les produits apr\u00e8s st\u00e9rilisation du chien<\/a><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>La st\u00e9rilisation pour mon chien Pourquoi st\u00e9riliser son chien\u00a0? La st\u00e9rilisation du chien est d\u00e9sormais une pratique r\u00e9pandue en France et \u00e0 l\u2019\u00e9chelle europ\u00e9enne. En effet, 40% des chiens sont st\u00e9rilis\u00e9s. Il y a ainsi plusieurs avantages reconnus \u00e0 la st\u00e9rilisation pour un chien. Concr\u00e8tement, l\u2019interruption de s\u00e9cr\u00e9tion d\u2019hormones sexuelles change le comportement d\u2019un chien [&hellip;]<\/p>\n","protected":false},"author":10426,"featured_media":297186,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[14087,14094],"tags":[],"class_list":["post-297177","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chien","category-sante-chien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>St\u00e9riliser mon chien - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Cliquez ici pour d\u00e9couvrir pourquoi faire st\u00e9riliser son chien, comment agir apr\u00e8s la st\u00e9rilisation du chien, comment s&#039;adapter \u00e0 cet acte...\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"St\u00e9riliser mon chien - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Cliquez ici pour d\u00e9couvrir pourquoi faire st\u00e9riliser son chien, comment agir apr\u00e8s la st\u00e9rilisation du chien, comment s&#039;adapter \u00e0 cet acte...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/2022\/02\/24\/steriliser-mon-chien\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-24T15:01:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-08T15:22:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-nataliya-vaitkevich-4445622-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe V\u00e9torino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe V\u00e9torino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/steriliser-mon-chien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/steriliser-mon-chien\\\/\"},\"author\":{\"name\":\"Equipe V\u00e9torino\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/6c2a6631b1dafb889300d67266761861\"},\"headline\":\"St\u00e9riliser mon chien\",\"datePublished\":\"2022-02-24T15:01:33+00:00\",\"dateModified\":\"2024-08-08T15:22:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/steriliser-mon-chien\\\/\"},\"wordCount\":740,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/steriliser-mon-chien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/pexels-nataliya-vaitkevich-4445622-scaled.jpg\",\"articleSection\":[\"Chien\",\"Sant\u00e9 pour chien\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/steriliser-mon-chien\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/steriliser-mon-chien\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/steriliser-mon-chien\\\/\",\"name\":\"St\u00e9riliser mon chien - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/steriliser-mon-chien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/steriliser-mon-chien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/pexels-nataliya-vaitkevich-4445622-scaled.jpg\",\"datePublished\":\"2022-02-24T15:01:33+00:00\",\"dateModified\":\"2024-08-08T15:22:00+00:00\",\"description\":\"Cliquez ici pour d\u00e9couvrir pourquoi faire st\u00e9riliser son chien, comment agir apr\u00e8s la st\u00e9rilisation du chien, comment s'adapter \u00e0 cet acte...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/steriliser-mon-chien\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/steriliser-mon-chien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/steriliser-mon-chien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/pexels-nataliya-vaitkevich-4445622-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/pexels-nataliya-vaitkevich-4445622-scaled.jpg\",\"width\":1707,\"height\":2560,\"caption\":\"Ce qu'il faut faire apr\u00e8s la st\u00e9rilisation de son chien\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/24\\\/steriliser-mon-chien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chien\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/champs-sur-marne-77420\\\/boutique\\\/category\\\/chien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sant\u00e9 pour chien\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/category\\\/chien\\\/sante-chien\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"St\u00e9riliser mon chien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/6c2a6631b1dafb889300d67266761861\",\"name\":\"Equipe V\u00e9torino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"caption\":\"Equipe V\u00e9torino\"},\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/conchesenouche-27190\\\/boutique\\\/author\\\/equipe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"St\u00e9riliser mon chien - V\u00e9torino","description":"Cliquez ici pour d\u00e9couvrir pourquoi faire st\u00e9riliser son chien, comment agir apr\u00e8s la st\u00e9rilisation du chien, comment s'adapter \u00e0 cet acte...","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"St\u00e9riliser mon chien - V\u00e9torino","og_description":"Cliquez ici pour d\u00e9couvrir pourquoi faire st\u00e9riliser son chien, comment agir apr\u00e8s la st\u00e9rilisation du chien, comment s'adapter \u00e0 cet acte...","og_url":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/2022\/02\/24\/steriliser-mon-chien\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_published_time":"2022-02-24T15:01:33+00:00","article_modified_time":"2024-08-08T15:22:00+00:00","og_image":[{"width":1707,"height":2560,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-nataliya-vaitkevich-4445622-scaled.jpg","type":"image\/jpeg"}],"author":"Equipe V\u00e9torino","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Equipe V\u00e9torino","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/steriliser-mon-chien\/#article","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/steriliser-mon-chien\/"},"author":{"name":"Equipe V\u00e9torino","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/6c2a6631b1dafb889300d67266761861"},"headline":"St\u00e9riliser mon chien","datePublished":"2022-02-24T15:01:33+00:00","dateModified":"2024-08-08T15:22:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/steriliser-mon-chien\/"},"wordCount":740,"commentCount":0,"publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/steriliser-mon-chien\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-nataliya-vaitkevich-4445622-scaled.jpg","articleSection":["Chien","Sant\u00e9 pour chien"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/steriliser-mon-chien\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/steriliser-mon-chien\/","url":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/steriliser-mon-chien\/","name":"St\u00e9riliser mon chien - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/steriliser-mon-chien\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/steriliser-mon-chien\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-nataliya-vaitkevich-4445622-scaled.jpg","datePublished":"2022-02-24T15:01:33+00:00","dateModified":"2024-08-08T15:22:00+00:00","description":"Cliquez ici pour d\u00e9couvrir pourquoi faire st\u00e9riliser son chien, comment agir apr\u00e8s la st\u00e9rilisation du chien, comment s'adapter \u00e0 cet acte...","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/steriliser-mon-chien\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/steriliser-mon-chien\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/steriliser-mon-chien\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-nataliya-vaitkevich-4445622-scaled.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/pexels-nataliya-vaitkevich-4445622-scaled.jpg","width":1707,"height":2560,"caption":"Ce qu'il faut faire apr\u00e8s la st\u00e9rilisation de son chien"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/24\/steriliser-mon-chien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Chien","item":"https:\/\/www.vetorino.com\/veterinaire\/champs-sur-marne-77420\/boutique\/category\/chien\/"},{"@type":"ListItem","position":3,"name":"Sant\u00e9 pour chien","item":"https:\/\/www.vetorino.com\/boutique\/category\/chien\/sante-chien\/"},{"@type":"ListItem","position":4,"name":"St\u00e9riliser mon chien"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]},{"@type":"Person","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/6c2a6631b1dafb889300d67266761861","name":"Equipe V\u00e9torino","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","caption":"Equipe V\u00e9torino"},"url":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/author\/equipe\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/posts\/297177","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/users\/10426"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/comments?post=297177"}],"version-history":[{"count":28,"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/posts\/297177\/revisions"}],"predecessor-version":[{"id":306651,"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/posts\/297177\/revisions\/306651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/media\/297186"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/media?parent=297177"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/categories?post=297177"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/tags?post=297177"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}