{"id":102267,"date":"2020-06-30T12:43:05","date_gmt":"2020-06-30T10:43:05","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/specific-ckd-heart-kidney\/"},"modified":"2026-07-13T21:28:39","modified_gmt":"2026-07-13T19:28:39","slug":"specific-ckd-heart-kidney","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/product\/specific-ckd-heart-kidney\/","title":{"rendered":"CKD Heart\/Kidney Support &#8211; chien"},"content":{"rendered":"<p><strong>Aliment di\u00e9t\u00e9tique complet pour le soutien des fonctions cardiaque et r\u00e9nale et\/ou en cas d\u2019insuffisance h\u00e9patique chez le chien adulte.<\/strong><\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Insuffisance cardiaque, hypertension, \u0153d\u00e8me.<\/li>\n<li>Insuffisance r\u00e9nale chronique.<\/li>\n<li>Insuffisance h\u00e9patique (sauf en cas de cholestase).<\/li>\n<li>Urolithiases \u00e0 urate, oxalate ou cystine.<\/li>\n<\/ul>\n<p><strong>Contre indications :<\/strong><\/p>\n<ul>\n<li>Chiot et chienne gestante ou allaitante.<\/li>\n<li>Chien ayant un besoin \u00e9lev\u00e9 en prot\u00e9ines.<\/li>\n<li>Cholestase : privil\u00e9gier un aliment \u00e0 teneur r\u00e9duite en mati\u00e8res grasses (comme SPECIFIC\u00ae CRD-1 Weight Reduction ou la gamme Senior).<\/li>\n<li>Urolithiases \u00e0 struvite.<\/li>\n<li>Hyperlipid\u00e9mie ou pancr\u00e9atite.<\/li>\n<\/ul>\n<p><strong>Bienfaits essentiels :<\/strong><\/p>\n<ul>\n<li>La teneur r\u00e9duite en prot\u00e9ines permet de baisser les concentrations urinaires d\u2019oxalate, de cystine et d\u2019urate. Combin\u00e9e \u00e0 un pH urinaire alcalin, cela pr\u00e9vient la formation de cristaux d\u2019oxalate de calcium, de cystine et d\u2019urate et<strong>\u00a0favorise la bonne sant\u00e9 du syst\u00e8me urinaire<\/strong>. L\u2019ajout de citrate de potassium aide \u00e0 maintenir le calcium en solution.<\/li>\n<li>SPECIFIC\u00ae CKD Heart &amp; Kidney Support pr\u00e9sente des teneurs tr\u00e8s \u00e9lev\u00e9es en acides gras Om\u00e9ga-3 EPA et DHA (issus d\u2019huile de poisson). Chez les chiens atteints d\u2019affections cardiaques, l\u2019EPA\u00a0<strong>contribue au maintien de la masse musculaire et de l\u2019app\u00e9tit<\/strong>,<strong>\u00a0et \u00e0 la normalisation du rythme cardiaque, de la tension art\u00e9rielle et de l\u2019agr\u00e9gation plaquettaire<\/strong>. Ces acides gras Om\u00e9ga-3 aident aussi \u00e0 ralentir la progression de l\u2019insuffisance r\u00e9nale.<\/li>\n<li>Lors d\u2019insuffisance cardiaque congestive, la mise en place de m\u00e9canismes compensateurs s\u2019opposant \u00e0 la diminution du d\u00e9bit cardiaque conduit \u00e0 une r\u00e9tention d\u2019eau et de sodium. La teneur r\u00e9duite en sodium de cet aliment contribue \u00e0 briser le cercle vicieux de la r\u00e9tention hydrique, ce qui est<strong>\u00a0essentiel pour les chiens souffrant d\u2019insuffisance r\u00e9nale, h\u00e9patique et\/ou ou cardiaque.<\/strong><\/li>\n<li>Une teneur limit\u00e9e en phosphore est\u00a0<strong>essentielle pour r\u00e9duire l\u2019hyperphosphat\u00e9mie et ralentir la progression de l\u2019insuffisance r\u00e9nale<\/strong>.<\/li>\n<li>L\u2019association de la teneur r\u00e9duite en prot\u00e9ines et de l\u2019utilisation de prot\u00e9ines de haute valeur biologique<strong>\u00a0r\u00e9duit l\u2019azot\u00e9mie chez les chiens insuffisants r\u00e9naux<\/strong>. En pr\u00e9sence d\u2019insuffisance h\u00e9patique, cela\u00a0<strong>r\u00e9duit le risque d\u2019hyperammoni\u00e9mie et d\u2019enc\u00e9phalopathie h\u00e9patique<\/strong>. La valeur biologique \u00e9lev\u00e9e des prot\u00e9ines\u00a0<strong>assure un apport suffisant d\u2019acides amin\u00e9s essentiels<\/strong>.<\/li>\n<\/ul>\n<p><strong>Cet aliment est destin\u00e9 \u00e0 la prise en charge nutritionnelle d\u2019une maladie. Pour la sant\u00e9 de votre chien, il est recommand\u00e9 de consulter votre v\u00e9t\u00e9rinaire et de respecter scrupuleusement ses recommandations nutritionnelles.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Aliment di\u00e9t\u00e9tique complet pour le soutien des fonctions cardiaque et r\u00e9nale et\/ou en cas d\u2019insuffisance h\u00e9patique chez le chien adulte.<\/strong><\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Insuffisance cardiaque, hypertension, \u0153d\u00e8me.<\/li>\n<li>Insuffisance r\u00e9nale chronique.<\/li>\n<li>Insuffisance h\u00e9patique (sauf en cas de cholestase).<\/li>\n<li>Urolithiases \u00e0 urate, oxalate ou cystine.<\/li>\n<\/ul>\n<p><strong>Cet aliment est destin\u00e9 \u00e0 la prise en charge nutritionnelle d\u2019une maladie. Il est recommand\u00e9 de consulter votre v\u00e9t\u00e9rinaire.<\/strong><\/p>\n<p><span style=\"color: #ff9900\"><strong>Le conditionnement 12kg est compos\u00e9 de 3 sacs de 4kg, pour tout retour le lot devra imp\u00e9rativement \u00eatre ramen\u00e9 en int\u00e9gralit\u00e9, soit les 3 sacs de 4kg.<\/strong><\/span><\/p>\n","protected":false},"featured_media":1473132,"template":"","meta":[],"product_cat":[12552,12582,2698],"product_tag":[],"class_list":{"0":"post-102267","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alimentation-du-chien","7":"product_cat-alimentation-medicalisee-pour-chien","8":"product_cat-chien","9":"pa_marque-specific","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CKD Heart\/Kidney Support - chien Specific - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Aliment di\u00e9t\u00e9tique complet pour le soutien des fonctions cardiaque et r\u00e9nale et\/ou en cas d\u2019insuffisance h\u00e9patique chez le chien adulte.  Utilisation :   Insuffisance cardiaque, hypertension, \u0153d\u00e8me.  Insuffisance r\u00e9nale chronique.  Insuffisance h\u00e9patique (sauf en cas de cholestase).  Urolithiases \u00e0 urate, oxalate ou cystine.  Cet aliment est destin\u00e9 \u00e0 la prise en charge nutritionnelle d\u2019une maladie. Il est recommand\u00e9 de consulter votre v\u00e9t\u00e9rinaire.  Le conditionnement 12kg est compos\u00e9 de 3 sacs de 4kg, pour tout retour le lot devra imp\u00e9rativement \u00eatre ramen\u00e9 en int\u00e9gralit\u00e9, soit les 3 sacs de 4kg.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CKD Heart\/Kidney Support - chien Specific - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Aliment di\u00e9t\u00e9tique complet pour le soutien des fonctions cardiaque et r\u00e9nale et\/ou en cas d\u2019insuffisance h\u00e9patique chez le chien adulte.  Utilisation :   Insuffisance cardiaque, hypertension, \u0153d\u00e8me.  Insuffisance r\u00e9nale chronique.  Insuffisance h\u00e9patique (sauf en cas de cholestase).  Urolithiases \u00e0 urate, oxalate ou cystine.  Cet aliment est destin\u00e9 \u00e0 la prise en charge nutritionnelle d\u2019une maladie. Il est recommand\u00e9 de consulter votre v\u00e9t\u00e9rinaire.  Le conditionnement 12kg est compos\u00e9 de 3 sacs de 4kg, pour tout retour le lot devra imp\u00e9rativement \u00eatre ramen\u00e9 en int\u00e9gralit\u00e9, soit les 3 sacs de 4kg.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/product\/specific-ckd-heart-kidney\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T19:28:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chien-ckd-heartkidney-8.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-ckd-heart-kidney\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-ckd-heart-kidney\\\/\",\"name\":\"CKD Heart\\\/Kidney Support - chien Specific - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-ckd-heart-kidney\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-ckd-heart-kidney\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/chien-ckd-heartkidney-8.webp\",\"datePublished\":\"2020-06-30T10:43:05+00:00\",\"dateModified\":\"2026-07-13T19:28:39+00:00\",\"description\":\"Aliment di\u00e9t\u00e9tique complet pour le soutien des fonctions cardiaque et r\u00e9nale et\\\/ou en cas d\u2019insuffisance h\u00e9patique chez le chien adulte. Utilisation : Insuffisance cardiaque, hypertension, \u0153d\u00e8me. Insuffisance r\u00e9nale chronique. Insuffisance h\u00e9patique (sauf en cas de cholestase). Urolithiases \u00e0 urate, oxalate ou cystine. Cet aliment est destin\u00e9 \u00e0 la prise en charge nutritionnelle d\u2019une maladie. Il est recommand\u00e9 de consulter votre v\u00e9t\u00e9rinaire. Le conditionnement 12kg est compos\u00e9 de 3 sacs de 4kg, pour tout retour le lot devra imp\u00e9rativement \u00eatre ramen\u00e9 en int\u00e9gralit\u00e9, soit les 3 sacs de 4kg.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-ckd-heart-kidney\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-ckd-heart-kidney\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-ckd-heart-kidney\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/chien-ckd-heartkidney-8.webp\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/chien-ckd-heartkidney-8.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/specific-ckd-heart-kidney\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CKD Heart\\\/Kidney Support &#8211; chien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Specific\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CKD Heart\/Kidney Support - chien Specific - V\u00e9torino","description":"Aliment di\u00e9t\u00e9tique complet pour le soutien des fonctions cardiaque et r\u00e9nale et\/ou en cas d\u2019insuffisance h\u00e9patique chez le chien adulte.  Utilisation :   Insuffisance cardiaque, hypertension, \u0153d\u00e8me.  Insuffisance r\u00e9nale chronique.  Insuffisance h\u00e9patique (sauf en cas de cholestase).  Urolithiases \u00e0 urate, oxalate ou cystine.  Cet aliment est destin\u00e9 \u00e0 la prise en charge nutritionnelle d\u2019une maladie. Il est recommand\u00e9 de consulter votre v\u00e9t\u00e9rinaire.  Le conditionnement 12kg est compos\u00e9 de 3 sacs de 4kg, pour tout retour le lot devra imp\u00e9rativement \u00eatre ramen\u00e9 en int\u00e9gralit\u00e9, soit les 3 sacs de 4kg.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"CKD Heart\/Kidney Support - chien Specific - V\u00e9torino","og_description":"Aliment di\u00e9t\u00e9tique complet pour le soutien des fonctions cardiaque et r\u00e9nale et\/ou en cas d\u2019insuffisance h\u00e9patique chez le chien adulte.  Utilisation :   Insuffisance cardiaque, hypertension, \u0153d\u00e8me.  Insuffisance r\u00e9nale chronique.  Insuffisance h\u00e9patique (sauf en cas de cholestase).  Urolithiases \u00e0 urate, oxalate ou cystine.  Cet aliment est destin\u00e9 \u00e0 la prise en charge nutritionnelle d\u2019une maladie. Il est recommand\u00e9 de consulter votre v\u00e9t\u00e9rinaire.  Le conditionnement 12kg est compos\u00e9 de 3 sacs de 4kg, pour tout retour le lot devra imp\u00e9rativement \u00eatre ramen\u00e9 en int\u00e9gralit\u00e9, soit les 3 sacs de 4kg.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/product\/specific-ckd-heart-kidney\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-07-13T19:28:39+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chien-ckd-heartkidney-8.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-ckd-heart-kidney\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/specific-ckd-heart-kidney\/","name":"CKD Heart\/Kidney Support - chien Specific - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-ckd-heart-kidney\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-ckd-heart-kidney\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chien-ckd-heartkidney-8.webp","datePublished":"2020-06-30T10:43:05+00:00","dateModified":"2026-07-13T19:28:39+00:00","description":"Aliment di\u00e9t\u00e9tique complet pour le soutien des fonctions cardiaque et r\u00e9nale et\/ou en cas d\u2019insuffisance h\u00e9patique chez le chien adulte. Utilisation : Insuffisance cardiaque, hypertension, \u0153d\u00e8me. Insuffisance r\u00e9nale chronique. Insuffisance h\u00e9patique (sauf en cas de cholestase). Urolithiases \u00e0 urate, oxalate ou cystine. Cet aliment est destin\u00e9 \u00e0 la prise en charge nutritionnelle d\u2019une maladie. Il est recommand\u00e9 de consulter votre v\u00e9t\u00e9rinaire. Le conditionnement 12kg est compos\u00e9 de 3 sacs de 4kg, pour tout retour le lot devra imp\u00e9rativement \u00eatre ramen\u00e9 en int\u00e9gralit\u00e9, soit les 3 sacs de 4kg.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-ckd-heart-kidney\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/specific-ckd-heart-kidney\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-ckd-heart-kidney\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chien-ckd-heartkidney-8.webp","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chien-ckd-heartkidney-8.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/specific-ckd-heart-kidney\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"CKD Heart\/Kidney Support &#8211; chien"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Specific","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/product\/102267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/media\/1473132"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/media?parent=102267"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/product_cat?post=102267"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/product_tag?post=102267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}