{"id":103681,"date":"2020-06-30T17:43:12","date_gmt":"2020-06-30T15:43:12","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/veggiedent-zen\/"},"modified":"2026-07-15T11:32:24","modified_gmt":"2026-07-15T09:32:24","slug":"veggiedent-zen","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/product\/veggiedent-zen\/","title":{"rendered":"Veggiedent Zen &#8211; Chien"},"content":{"rendered":"<p>Pour permettre \u00e0 votre chien d&#8217;avoir des dents en bonne sant\u00e9, il est essentiel de bien les lui nettoyer.\u00a0<strong>Formul\u00e9es \u00e0 base de plantes, les lamelles \u00e0 m\u00e2cher\u00a0<\/strong>VEGGIEDENT Fresh\u00a0<strong>favorisent la sant\u00e9 dentaire<\/strong>\u00a0et compl\u00e8tent parfaitement les brosses \u00e0 dents, b\u00e2tonnets et autres friandises pour chien.<\/p>\n<p>La taille, la forme et la texture de cet aliment compl\u00e9mentaire aident \u00e0<strong>\u00a0r\u00e9duire la plaque dentaire et le tartre,\u00a0<\/strong>et contribuent au nettoyage des dents. La forme en Z permettra \u00e0 votre chien de le prendre facilement dans sa gueule. Enfin, la formule des friandises VEGGIEDENT Fresh apporte une\u00a0<strong>sensation de fra\u00eecheur<\/strong>\u00a0et aide \u00e0 lutter contre la mauvaise haleine.<\/p>\n<p><strong>Caract\u00e9ristiques des friandises Virbac VEGGIEDENT Fresh pour chien :<\/strong><\/p>\n<ul>\n<li>friandises sans viande pour chien<\/li>\n<li><strong>lamelles v\u00e9g\u00e9tales :<\/strong>\u00a0id\u00e9ales en cas d&#8217;allergie au b\u0153uf ou \u00e0 la volaille<\/li>\n<li><strong>favorisent l&#8217;hygi\u00e8ne dentaire :<\/strong>\u00a0la taille, la forme et la texture des friandises aident \u00e0 r\u00e9duire le tartre et la plaque dentaire et favorisent le nettoyage des dents<\/li>\n<li><strong>technologie &#8220;Fresh&#8221; :<\/strong>\u00a0pour une haleine fra\u00eeche<\/li>\n<li><strong>forme en Z innovante :<\/strong>\u00a0permet au chien de prendre facilement la friandise dans sa gueule<\/li>\n<li><strong>plusieurs tailles disponibles :<\/strong>\u00a0pour s&#8217;adapter \u00e0 toutes les races de chien<\/li>\n<li><strong>faciles \u00e0 administrer :<\/strong>\u00a0\u00e0 donner comme une friandise<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>VEGGIEDENT\u00ae ZEN est une <strong>lamelle \u00e0 m\u00e2cher 2 en 1<\/strong> qui permet de lutter contre l<strong>a plaque dentaire et la mauvaise haleine<\/strong> gr\u00e2ce \u00e0 la technologie FRESH, mais \u00e9galement contre le <strong>stress<\/strong> gr\u00e2ce \u00e0 l\u2019ajout de L-th\u00e9anine (extrait de th\u00e9 vert) tout en faisant plaisir \u00e0 son animal.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":896437,"template":"","meta":[],"product_cat":[12552,2698,12603,12610,12561],"product_tag":[],"class_list":{"0":"post-103681","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alimentation-du-chien","7":"product_cat-chien","8":"product_cat-friandises-pour-chien","9":"product_cat-hygiene-bucco-dentaire-du-chien","10":"product_cat-hygiene-du-chien","11":"pa_marque-virbac","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Veggiedent Zen - Chien Virbac - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"VEGGIEDENT\u00ae ZEN est une lamelle \u00e0 m\u00e2cher 2 en 1 qui permet de lutter contre la plaque dentaire et la mauvaise haleine gr\u00e2ce \u00e0 la technologie FRESH, mais \u00e9galement contre le stress gr\u00e2ce \u00e0 l\u2019ajout de L-th\u00e9anine (extrait de th\u00e9 vert) tout en faisant plaisir \u00e0 son animal.  &nbsp;  &nbsp;\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veggiedent Zen - Chien Virbac - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"VEGGIEDENT\u00ae ZEN est une lamelle \u00e0 m\u00e2cher 2 en 1 qui permet de lutter contre la plaque dentaire et la mauvaise haleine gr\u00e2ce \u00e0 la technologie FRESH, mais \u00e9galement contre le stress gr\u00e2ce \u00e0 l\u2019ajout de L-th\u00e9anine (extrait de th\u00e9 vert) tout en faisant plaisir \u00e0 son animal.  &nbsp;  &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/product\/veggiedent-zen\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T09:32:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/veggiedent-zen-xs.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"458\" \/>\n\t<meta property=\"og:image:height\" content=\"458\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/veggiedent-zen\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/veggiedent-zen\\\/\",\"name\":\"Veggiedent Zen - Chien Virbac - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/veggiedent-zen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/veggiedent-zen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/veggiedent-zen-xs.jpg\",\"datePublished\":\"2020-06-30T15:43:12+00:00\",\"dateModified\":\"2026-07-15T09:32:24+00:00\",\"description\":\"VEGGIEDENT\u00ae ZEN est une lamelle \u00e0 m\u00e2cher 2 en 1 qui permet de lutter contre la plaque dentaire et la mauvaise haleine gr\u00e2ce \u00e0 la technologie FRESH, mais \u00e9galement contre le stress gr\u00e2ce \u00e0 l\u2019ajout de L-th\u00e9anine (extrait de th\u00e9 vert) tout en faisant plaisir \u00e0 son animal. &nbsp; &nbsp;\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/veggiedent-zen\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/veggiedent-zen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/veggiedent-zen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/veggiedent-zen-xs.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/veggiedent-zen-xs.jpg\",\"width\":458,\"height\":458},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/veggiedent-zen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Veggiedent Zen &#8211; Chien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Virbac\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Veggiedent Zen - Chien Virbac - V\u00e9torino","description":"VEGGIEDENT\u00ae ZEN est une lamelle \u00e0 m\u00e2cher 2 en 1 qui permet de lutter contre la plaque dentaire et la mauvaise haleine gr\u00e2ce \u00e0 la technologie FRESH, mais \u00e9galement contre le stress gr\u00e2ce \u00e0 l\u2019ajout de L-th\u00e9anine (extrait de th\u00e9 vert) tout en faisant plaisir \u00e0 son animal.  &nbsp;  &nbsp;","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Veggiedent Zen - Chien Virbac - V\u00e9torino","og_description":"VEGGIEDENT\u00ae ZEN est une lamelle \u00e0 m\u00e2cher 2 en 1 qui permet de lutter contre la plaque dentaire et la mauvaise haleine gr\u00e2ce \u00e0 la technologie FRESH, mais \u00e9galement contre le stress gr\u00e2ce \u00e0 l\u2019ajout de L-th\u00e9anine (extrait de th\u00e9 vert) tout en faisant plaisir \u00e0 son animal.  &nbsp;  &nbsp;","og_url":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/product\/veggiedent-zen\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-07-15T09:32:24+00:00","og_image":[{"width":458,"height":458,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/veggiedent-zen-xs.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/veggiedent-zen\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/veggiedent-zen\/","name":"Veggiedent Zen - Chien Virbac - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/veggiedent-zen\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/veggiedent-zen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/veggiedent-zen-xs.jpg","datePublished":"2020-06-30T15:43:12+00:00","dateModified":"2026-07-15T09:32:24+00:00","description":"VEGGIEDENT\u00ae ZEN est une lamelle \u00e0 m\u00e2cher 2 en 1 qui permet de lutter contre la plaque dentaire et la mauvaise haleine gr\u00e2ce \u00e0 la technologie FRESH, mais \u00e9galement contre le stress gr\u00e2ce \u00e0 l\u2019ajout de L-th\u00e9anine (extrait de th\u00e9 vert) tout en faisant plaisir \u00e0 son animal. &nbsp; &nbsp;","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/veggiedent-zen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/veggiedent-zen\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/veggiedent-zen\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/veggiedent-zen-xs.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/veggiedent-zen-xs.jpg","width":458,"height":458},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/veggiedent-zen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Veggiedent Zen &#8211; Chien"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Virbac","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/product\/103681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/media\/896437"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/media?parent=103681"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/product_cat?post=103681"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/product_tag?post=103681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}