{"id":92520,"date":"2020-06-26T15:12:27","date_gmt":"2020-06-26T13:12:27","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/feline-k-d-sachet-repas-saumon\/"},"modified":"2026-05-30T03:34:20","modified_gmt":"2026-05-30T01:34:20","slug":"feline-k-d-sachet-repas-saumon","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/product\/feline-k-d-sachet-repas-saumon\/","title":{"rendered":"k\/d Kidney Sachet Repas pour Chat Saumon"},"content":{"rendered":"<p><strong>Hill&#8217;s Prescription Diet Feline k\/d est cliniquement prouv\u00e9 pour\u00a0aider \u00e0 prolonger la vie et am\u00e9liorer consid\u00e9rablement la qualit\u00e9 de vie des\u00a0chats\u00a0souffrant de maladie r\u00e9nale.<\/strong><\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Chat souffrant de maladie r\u00e9nale<\/li>\n<\/ul>\n<p><strong>Bienfaits essentiels :<\/strong><\/p>\n<ul>\n<li>Formul\u00e9 avec des taux de phosphore contr\u00f4l\u00e9 et de sodium bas afin de\u00a0<strong>soutenir les fonctions r\u00e9nale et cardiaque<\/strong>.<\/li>\n<li>Avec la technologie r\u00e9volutionnaire EAT (Enhanced Appetite Trigger) qui\u00a0<strong>augmente de mani\u00e8re significative l&#8217;app\u00e9tit des chats souffrant de maladie r\u00e9nale.<\/strong><\/li>\n<li>Contient un profil adapt\u00e9 d&#8217;acides amin\u00e9s pour\u00a0<strong>soutenir l&#8217;aptitude naturelle des chats \u00e0 d\u00e9velopper de la masse musculaire<\/strong>.<\/li>\n<li><strong>Extr\u00eamement app\u00e9tent<\/strong>, et pour varier les plaisirs Feline k\/d est \u00e9galement disponible en bo\u00eete et en sachets repas au Poulet, au Boeuf et au Saumon.<\/li>\n<li>k\/d est \u00e9galement disponible en bo\u00eete, en sachets repas au Poulet, au Boeuf et au Saumon et en mijot\u00e9s.<\/li>\n<\/ul>\n<p><strong><br \/>\nCe produit est destin\u00e9 \u00e0 l&#8217;usage v\u00e9t\u00e9rinaire. Avant tout achat, nous vous conseillons de demander conseil \u00e0 votre v\u00e9t\u00e9rinaire.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Prouv\u00e9 pour\u00a0aider \u00e0 prolonger la vie et am\u00e9liorer consid\u00e9rablement la qualit\u00e9 de vie des\u00a0chats\u00a0souffrant de maladie r\u00e9nale.<\/strong><\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Chat souffrant de maladie r\u00e9nale<\/li>\n<\/ul>\n<p><strong>Ce produit est destin\u00e9 \u00e0 l&#8217;usage v\u00e9t\u00e9rinaire. Avant tout achat, nous vous conseillons de demander conseil \u00e0 votre v\u00e9t\u00e9rinaire.<\/strong><\/p>\n","protected":false},"featured_media":487056,"template":"","meta":[],"product_cat":[12551,12581,2697,12641],"product_tag":[],"class_list":{"0":"post-92520","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alimentation-du-chat","7":"product_cat-alimentation-medicalisee-pour-chat","8":"product_cat-chat","9":"product_cat-systeme-renal-du-chat","10":"pa_marque-hills-pet-nutrition","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prescription Diet (Hill&#039;s) k\/d Kidney Sachet Repas pour Chat Saumon Hill&#039;s - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Hill&#039;s Prescription Diet k\/d Kidney Care Sachet Repas est con\u00e7u pour prot\u00e9ger la fonction r\u00e9nale vitale et \u00e0 maintenir la masse musculaire.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prescription Diet (Hill&#039;s) k\/d Kidney Sachet Repas pour Chat Saumon Hill&#039;s - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Hill&#039;s Prescription Diet k\/d Kidney Care Sachet Repas est con\u00e7u pour prot\u00e9ger la fonction r\u00e9nale vitale et \u00e0 maintenir la masse musculaire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/product\/feline-k-d-sachet-repas-saumon\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-30T01:34:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/52742188416_1-prescription-diet-chat-k-d-sachet-repas-saumon.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"21,44&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/feline-k-d-sachet-repas-saumon\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/feline-k-d-sachet-repas-saumon\\\/\",\"name\":\"Prescription Diet (Hill's) k\\\/d Kidney Sachet Repas pour Chat Saumon Hill's - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/feline-k-d-sachet-repas-saumon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/feline-k-d-sachet-repas-saumon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/52742188416_1-prescription-diet-chat-k-d-sachet-repas-saumon.jpg\",\"datePublished\":\"2020-06-26T13:12:27+00:00\",\"dateModified\":\"2026-05-30T01:34:20+00:00\",\"description\":\"Hill's Prescription Diet k\\\/d Kidney Care Sachet Repas est con\u00e7u pour prot\u00e9ger la fonction r\u00e9nale vitale et \u00e0 maintenir la masse musculaire.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/feline-k-d-sachet-repas-saumon\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/feline-k-d-sachet-repas-saumon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/feline-k-d-sachet-repas-saumon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/52742188416_1-prescription-diet-chat-k-d-sachet-repas-saumon.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/52742188416_1-prescription-diet-chat-k-d-sachet-repas-saumon.jpg\",\"width\":2000,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/feline-k-d-sachet-repas-saumon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"k\\\/d Kidney Sachet Repas pour Chat Saumon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Hill&#039;s\" \/>\n<meta property=\"product:price:amount\" content=\"21.44\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"C-CHA262\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prescription Diet (Hill's) k\/d Kidney Sachet Repas pour Chat Saumon Hill's - V\u00e9torino","description":"Hill's Prescription Diet k\/d Kidney Care Sachet Repas est con\u00e7u pour prot\u00e9ger la fonction r\u00e9nale vitale et \u00e0 maintenir la masse musculaire.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Prescription Diet (Hill's) k\/d Kidney Sachet Repas pour Chat Saumon Hill's - V\u00e9torino","og_description":"Hill's Prescription Diet k\/d Kidney Care Sachet Repas est con\u00e7u pour prot\u00e9ger la fonction r\u00e9nale vitale et \u00e0 maintenir la masse musculaire.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/product\/feline-k-d-sachet-repas-saumon\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-05-30T01:34:20+00:00","og_image":[{"width":2000,"height":2000,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/52742188416_1-prescription-diet-chat-k-d-sachet-repas-saumon.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"21,44&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/feline-k-d-sachet-repas-saumon\/","url":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/feline-k-d-sachet-repas-saumon\/","name":"Prescription Diet (Hill's) k\/d Kidney Sachet Repas pour Chat Saumon Hill's - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/feline-k-d-sachet-repas-saumon\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/feline-k-d-sachet-repas-saumon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/52742188416_1-prescription-diet-chat-k-d-sachet-repas-saumon.jpg","datePublished":"2020-06-26T13:12:27+00:00","dateModified":"2026-05-30T01:34:20+00:00","description":"Hill's Prescription Diet k\/d Kidney Care Sachet Repas est con\u00e7u pour prot\u00e9ger la fonction r\u00e9nale vitale et \u00e0 maintenir la masse musculaire.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/feline-k-d-sachet-repas-saumon\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/feline-k-d-sachet-repas-saumon\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/feline-k-d-sachet-repas-saumon\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/52742188416_1-prescription-diet-chat-k-d-sachet-repas-saumon.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/52742188416_1-prescription-diet-chat-k-d-sachet-repas-saumon.jpg","width":2000,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/feline-k-d-sachet-repas-saumon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"k\/d Kidney Sachet Repas pour Chat Saumon"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Hill's","product_price_amount":"21.44","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"C-CHA262","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/product\/92520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/media\/487056"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/media?parent=92520"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/product_cat?post=92520"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/product_tag?post=92520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}