{"id":98215,"date":"2020-06-30T00:45:58","date_gmt":"2020-06-29T22:45:58","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-chien-zolux-friends\/"},"modified":"2024-11-15T02:42:37","modified_gmt":"2024-11-15T01:42:37","slug":"jouet-chien-zolux-friends","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/product\/jouet-chien-zolux-friends\/","title":{"rendered":"Jouet chien Zolux : Friends"},"content":{"rendered":"<div class=\"hidden\">MATERIEL<\/div>\n<div class=\"hidden\">Chiens<\/div>\n<div class=\"hidden\">Zolux<\/div>\n<p>Tendrement amusante !<br \/>\nCe jouet peluche sonore en forme de lapin attirera sans aucun doute l&#8217;attention de votre animal.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez le nouvelle famille de peluche Friends pour chien d\u00e9clinable dans diff\u00e9rents personnages sympathiques et rigolos : Gilda le rat, Firmin le lapin, Gaston le h\u00e9risson ou Hector le castor.<\/p>\n<p>La peluche compos\u00e9e de mati\u00e8re diff\u00e9rente est toute douce et douillette, elle a \u00e9t\u00e9 con\u00e7ue sp\u00e9cialement pour amuser votre chien.<\/p>\n<p>Ce jouet est d&#8217;un contact tr\u00e8s agr\u00e9able et extr\u00eamement doux. Et votre chien pourra se blottir tout contre lui.<\/p>\n","protected":false},"featured_media":633827,"template":"","meta":[],"product_cat":[12550,2698,12621],"product_tag":[],"class_list":{"0":"post-98215","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessoires-du-chien","7":"product_cat-chien","8":"product_cat-jeux-educatifs-pour-chien","9":"pa_marque-zolux","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jouet chien Zolux : Friends Zolux - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez le nouvelle famille de peluche Friends pour chien d\u00e9clinable dans diff\u00e9rents personnages sympathiques et rigolos : Gilda le rat, Firmin le lapin, Gaston le h\u00e9risson ou Hector le castor.  La peluche compos\u00e9e de mati\u00e8re diff\u00e9rente est toute douce et douillette, elle a \u00e9t\u00e9 con\u00e7ue sp\u00e9cialement pour amuser votre chien.  Ce jouet est d&#039;un contact tr\u00e8s agr\u00e9able et extr\u00eamement doux. Et votre chien pourra se blottir tout contre lui.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jouet chien Zolux : Friends Zolux - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez le nouvelle famille de peluche Friends pour chien d\u00e9clinable dans diff\u00e9rents personnages sympathiques et rigolos : Gilda le rat, Firmin le lapin, Gaston le h\u00e9risson ou Hector le castor.  La peluche compos\u00e9e de mati\u00e8re diff\u00e9rente est toute douce et douillette, elle a \u00e9t\u00e9 con\u00e7ue sp\u00e9cialement pour amuser votre chien.  Ce jouet est d&#039;un contact tr\u00e8s agr\u00e9able et extr\u00eamement doux. Et votre chien pourra se blottir tout contre lui.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/product\/jouet-chien-zolux-friends\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-15T01:42:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/chiens-zolux-peluche-friends-firmin-le-lapin-24869324593-500x500-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-chien-zolux-friends\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-chien-zolux-friends\\\/\",\"name\":\"Jouet chien Zolux : Friends Zolux - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-chien-zolux-friends\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-chien-zolux-friends\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/chiens-zolux-peluche-friends-firmin-le-lapin-24869324593-500x500-1.jpeg\",\"datePublished\":\"2020-06-29T22:45:58+00:00\",\"dateModified\":\"2024-11-15T01:42:37+00:00\",\"description\":\"D\u00e9couvrez le nouvelle famille de peluche Friends pour chien d\u00e9clinable dans diff\u00e9rents personnages sympathiques et rigolos : Gilda le rat, Firmin le lapin, Gaston le h\u00e9risson ou Hector le castor. La peluche compos\u00e9e de mati\u00e8re diff\u00e9rente est toute douce et douillette, elle a \u00e9t\u00e9 con\u00e7ue sp\u00e9cialement pour amuser votre chien. Ce jouet est d'un contact tr\u00e8s agr\u00e9able et extr\u00eamement doux. Et votre chien pourra se blottir tout contre lui.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-chien-zolux-friends\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-chien-zolux-friends\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-chien-zolux-friends\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/chiens-zolux-peluche-friends-firmin-le-lapin-24869324593-500x500-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/chiens-zolux-peluche-friends-firmin-le-lapin-24869324593-500x500-1.jpeg\",\"width\":500,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-chien-zolux-friends\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jouet chien Zolux : Friends\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Zolux\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jouet chien Zolux : Friends Zolux - V\u00e9torino","description":"D\u00e9couvrez le nouvelle famille de peluche Friends pour chien d\u00e9clinable dans diff\u00e9rents personnages sympathiques et rigolos : Gilda le rat, Firmin le lapin, Gaston le h\u00e9risson ou Hector le castor.  La peluche compos\u00e9e de mati\u00e8re diff\u00e9rente est toute douce et douillette, elle a \u00e9t\u00e9 con\u00e7ue sp\u00e9cialement pour amuser votre chien.  Ce jouet est d'un contact tr\u00e8s agr\u00e9able et extr\u00eamement doux. Et votre chien pourra se blottir tout contre lui.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Jouet chien Zolux : Friends Zolux - V\u00e9torino","og_description":"D\u00e9couvrez le nouvelle famille de peluche Friends pour chien d\u00e9clinable dans diff\u00e9rents personnages sympathiques et rigolos : Gilda le rat, Firmin le lapin, Gaston le h\u00e9risson ou Hector le castor.  La peluche compos\u00e9e de mati\u00e8re diff\u00e9rente est toute douce et douillette, elle a \u00e9t\u00e9 con\u00e7ue sp\u00e9cialement pour amuser votre chien.  Ce jouet est d'un contact tr\u00e8s agr\u00e9able et extr\u00eamement doux. Et votre chien pourra se blottir tout contre lui.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/product\/jouet-chien-zolux-friends\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2024-11-15T01:42:37+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/chiens-zolux-peluche-friends-firmin-le-lapin-24869324593-500x500-1.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-chien-zolux-friends\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-chien-zolux-friends\/","name":"Jouet chien Zolux : Friends Zolux - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-chien-zolux-friends\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-chien-zolux-friends\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/chiens-zolux-peluche-friends-firmin-le-lapin-24869324593-500x500-1.jpeg","datePublished":"2020-06-29T22:45:58+00:00","dateModified":"2024-11-15T01:42:37+00:00","description":"D\u00e9couvrez le nouvelle famille de peluche Friends pour chien d\u00e9clinable dans diff\u00e9rents personnages sympathiques et rigolos : Gilda le rat, Firmin le lapin, Gaston le h\u00e9risson ou Hector le castor. La peluche compos\u00e9e de mati\u00e8re diff\u00e9rente est toute douce et douillette, elle a \u00e9t\u00e9 con\u00e7ue sp\u00e9cialement pour amuser votre chien. Ce jouet est d'un contact tr\u00e8s agr\u00e9able et extr\u00eamement doux. Et votre chien pourra se blottir tout contre lui.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-chien-zolux-friends\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/jouet-chien-zolux-friends\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-chien-zolux-friends\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/chiens-zolux-peluche-friends-firmin-le-lapin-24869324593-500x500-1.jpeg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/chiens-zolux-peluche-friends-firmin-le-lapin-24869324593-500x500-1.jpeg","width":500,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-chien-zolux-friends\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Jouet chien Zolux : Friends"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Zolux","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/product\/98215","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/media\/633827"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/media?parent=98215"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/product_cat?post=98215"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/conchesenouche-27190\/boutique\/wp-json\/wp\/v2\/product_tag?post=98215"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}