{"id":1812457,"date":"2026-04-28T15:38:14","date_gmt":"2026-04-28T13:38:14","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/selective-urinary-care\/"},"modified":"2026-07-08T02:54:31","modified_gmt":"2026-07-08T00:54:31","slug":"selective-urinary-care","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/hesingue-68220\/boutique\/product\/selective-urinary-care\/","title":{"rendered":"Selective Urinary Care &#8211; lapin &#038; rongeurs"},"content":{"rendered":"<p><strong>Selective Urinary Care \u2013 Friandises Naturelles pour Lapins, Cochons d\u2019Inde et Chinchillas.<\/strong><\/p>\n<p>Formul\u00e9s \u00e0 base d\u2019<strong>ingr\u00e9dients naturellement purifiants<\/strong>, comme le pissenlit, la canneberge, l\u2019\u00e9chinac\u00e9e et la vitamine C, les compl\u00e9ments Science Selective Urinary Care contribuent \u00e0 la <strong>sant\u00e9 urinaire<\/strong> et au <strong>bien-\u00eatre g\u00e9n\u00e9ral<\/strong> de votre animal.<\/p>\n<p>Les\u00a0<strong>friandises Selective Urinary Care<\/strong>\u00a0au pissenlit, \u00e0 la canneberge et enrichies en vitamine C sont sp\u00e9cialement formul\u00e9es pour\u00a0<strong>soutenir le bon fonctionnement du syst\u00e8me urinaire des lapins, cochons d\u2019Inde et chinchillas.<\/strong>\u00a0Ces friandises, 100 % naturelles et en forme de petits palets, sont tr\u00e8s app\u00e9tentes et faciles \u00e0 int\u00e9grer dans l\u2019alimentation quotidienne de vos rongeurs.<\/p>\n<p><strong>Utilisation :\u00a0<\/strong><\/p>\n<ul>\n<li>Calculs v\u00e9sicaux (urolithiase)<\/li>\n<li>Infections urinaires<\/li>\n<li>Infections r\u00e9nales<\/li>\n<li>Cystites<\/li>\n<\/ul>\n<p><strong>Caract\u00e9ristiques\u00a0 :<\/strong><\/p>\n<ul>\n<li><strong>Soutien urinaire<\/strong>\u00a0: Contiennent du pissenlit, reconnu pour ses propri\u00e9t\u00e9s diur\u00e9tiques, et de la canneberge pour prot\u00e9ger le syst\u00e8me urinaire.<\/li>\n<li><strong>Riche en vitamine C<\/strong> : Id\u00e9al pour les cochons d\u2019Inde et autres rongeurs ayant des besoins accrus en cette vitamine essentielle.<\/li>\n<li><strong>Formule naturelle<\/strong>\u00a0: 100 % ingr\u00e9dients naturels, adapt\u00e9s aux pr\u00e9f\u00e9rences alimentaires des rongeurs.<\/li>\n<\/ul>\n<p><strong>Avantages :<\/strong><\/p>\n<p>Ces friandises offrent un moyen savoureux et naturel de prendre soin du syst\u00e8me urinaire de vos lapins et rongeurs tout en leur offrant un moment de plaisir.<\/p>\n<p><strong>\u00c0 utiliser comme friandise pour compl\u00e9menter l\u2019alimentation r\u00e9guli\u00e8re de votre animal de compagnie. Donner 1 \u00e0 2 friandises par jour. Avant et apr\u00e8s ouverture, conserver dans un endroit sec et frais.<\/strong><\/p>\n<p><strong>Toujours laisser de l\u2019eau fra\u00eeche \u00e0 disposition.\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Selective Urinary Care \u2013 Friandises Naturelles pour Lapins, Cochons d\u2019Inde et Chinchillas.<\/strong><\/p>\n<p><strong>Utilisation :\u00a0<\/strong><\/p>\n<ul>\n<li>Calculs v\u00e9sicaux (urolithiase)<\/li>\n<li>Infections urinaires<\/li>\n<li>Infections r\u00e9nales<\/li>\n<li>Cystites<\/li>\n<\/ul>\n<p><strong>Caract\u00e9ristiques\u00a0 :<\/strong><\/p>\n<ul>\n<li><strong>Soutien urinaire<\/strong>\u00a0: Contiennent du pissenlit, reconnu pour ses propri\u00e9t\u00e9s diur\u00e9tiques, et de la canneberge pour prot\u00e9ger le syst\u00e8me urinaire.<\/li>\n<li><strong>Riche en vitamine C<\/strong> : Id\u00e9al pour les cochons d\u2019Inde et autres rongeurs ayant des besoins accrus en cette vitamine essentielle.<\/li>\n<li><strong>Formule naturelle<\/strong>\u00a0: 100 % ingr\u00e9dients naturels, adapt\u00e9s aux pr\u00e9f\u00e9rences alimentaires des rongeurs.<\/li>\n<\/ul>\n","protected":false},"featured_media":1812459,"template":"","meta":[],"product_cat":[12578,12668,12563,2727,12570,15842],"product_tag":[],"class_list":{"0":"post-1812457","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alimentation-du-lapin","7":"product_cat-friandise-pour-lapin","8":"product_cat-lapin","9":"product_cat-nac","10":"product_cat-rongeur","11":"product_cat-rongeurs","12":"pa_marque-supreme-petfood","14":"first","15":"instock","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Selective Selective Urinary Care - lapin &amp; rongeurs Supreme Petfood - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Selective Urinary Care \u2013 Friandises Naturelles pour Lapins, Cochons d\u2019Inde et Chinchillas.  Utilisation :\u00a0   Calculs v\u00e9sicaux (urolithiase)  Infections urinaires  Infections r\u00e9nales  Cystites  Caract\u00e9ristiques\u00a0 :   Soutien urinaire\u00a0: Contiennent du pissenlit, reconnu pour ses propri\u00e9t\u00e9s diur\u00e9tiques, et de la canneberge pour prot\u00e9ger le syst\u00e8me urinaire.  Riche en vitamine C : Id\u00e9al pour les cochons d\u2019Inde et autres rongeurs ayant des besoins accrus en cette vitamine essentielle.  Formule naturelle\u00a0: 100 % ingr\u00e9dients naturels, adapt\u00e9s aux pr\u00e9f\u00e9rences alimentaires des rongeurs.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Selective Selective Urinary Care - lapin &amp; rongeurs Supreme Petfood - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Selective Urinary Care \u2013 Friandises Naturelles pour Lapins, Cochons d\u2019Inde et Chinchillas.  Utilisation :\u00a0   Calculs v\u00e9sicaux (urolithiase)  Infections urinaires  Infections r\u00e9nales  Cystites  Caract\u00e9ristiques\u00a0 :   Soutien urinaire\u00a0: Contiennent du pissenlit, reconnu pour ses propri\u00e9t\u00e9s diur\u00e9tiques, et de la canneberge pour prot\u00e9ger le syst\u00e8me urinaire.  Riche en vitamine C : Id\u00e9al pour les cochons d\u2019Inde et autres rongeurs ayant des besoins accrus en cette vitamine essentielle.  Formule naturelle\u00a0: 100 % ingr\u00e9dients naturels, adapt\u00e9s aux pr\u00e9f\u00e9rences alimentaires des rongeurs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/hesingue-68220\/boutique\/product\/selective-urinary-care\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T00:54:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2026\/04\/supreme-petfoods-selective-urinary-care-friandises-urinaires-lapin-rongeur.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"19,75&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/selective-urinary-care\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/selective-urinary-care\\\/\",\"name\":\"Selective Selective Urinary Care - lapin & rongeurs Supreme Petfood - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/selective-urinary-care\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/selective-urinary-care\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/supreme-petfoods-selective-urinary-care-friandises-urinaires-lapin-rongeur.webp\",\"datePublished\":\"2026-04-28T13:38:14+00:00\",\"dateModified\":\"2026-07-08T00:54:31+00:00\",\"description\":\"Selective Urinary Care \u2013 Friandises Naturelles pour Lapins, Cochons d\u2019Inde et Chinchillas. Utilisation :\u00a0 Calculs v\u00e9sicaux (urolithiase) Infections urinaires Infections r\u00e9nales Cystites Caract\u00e9ristiques\u00a0 : Soutien urinaire\u00a0: Contiennent du pissenlit, reconnu pour ses propri\u00e9t\u00e9s diur\u00e9tiques, et de la canneberge pour prot\u00e9ger le syst\u00e8me urinaire. Riche en vitamine C : Id\u00e9al pour les cochons d\u2019Inde et autres rongeurs ayant des besoins accrus en cette vitamine essentielle. Formule naturelle\u00a0: 100 % ingr\u00e9dients naturels, adapt\u00e9s aux pr\u00e9f\u00e9rences alimentaires des rongeurs.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/selective-urinary-care\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/selective-urinary-care\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/selective-urinary-care\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/supreme-petfoods-selective-urinary-care-friandises-urinaires-lapin-rongeur.webp\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/supreme-petfoods-selective-urinary-care-friandises-urinaires-lapin-rongeur.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/selective-urinary-care\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Selective Urinary Care &#8211; lapin &#038; rongeurs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Supreme Petfood\" \/>\n<meta property=\"product:price:amount\" content=\"19.75\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"C-SEL258\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Selective Selective Urinary Care - lapin & rongeurs Supreme Petfood - V\u00e9torino","description":"Selective Urinary Care \u2013 Friandises Naturelles pour Lapins, Cochons d\u2019Inde et Chinchillas.  Utilisation :\u00a0   Calculs v\u00e9sicaux (urolithiase)  Infections urinaires  Infections r\u00e9nales  Cystites  Caract\u00e9ristiques\u00a0 :   Soutien urinaire\u00a0: Contiennent du pissenlit, reconnu pour ses propri\u00e9t\u00e9s diur\u00e9tiques, et de la canneberge pour prot\u00e9ger le syst\u00e8me urinaire.  Riche en vitamine C : Id\u00e9al pour les cochons d\u2019Inde et autres rongeurs ayant des besoins accrus en cette vitamine essentielle.  Formule naturelle\u00a0: 100 % ingr\u00e9dients naturels, adapt\u00e9s aux pr\u00e9f\u00e9rences alimentaires des rongeurs.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Selective Selective Urinary Care - lapin & rongeurs Supreme Petfood - V\u00e9torino","og_description":"Selective Urinary Care \u2013 Friandises Naturelles pour Lapins, Cochons d\u2019Inde et Chinchillas.  Utilisation :\u00a0   Calculs v\u00e9sicaux (urolithiase)  Infections urinaires  Infections r\u00e9nales  Cystites  Caract\u00e9ristiques\u00a0 :   Soutien urinaire\u00a0: Contiennent du pissenlit, reconnu pour ses propri\u00e9t\u00e9s diur\u00e9tiques, et de la canneberge pour prot\u00e9ger le syst\u00e8me urinaire.  Riche en vitamine C : Id\u00e9al pour les cochons d\u2019Inde et autres rongeurs ayant des besoins accrus en cette vitamine essentielle.  Formule naturelle\u00a0: 100 % ingr\u00e9dients naturels, adapt\u00e9s aux pr\u00e9f\u00e9rences alimentaires des rongeurs.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/hesingue-68220\/boutique\/product\/selective-urinary-care\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-07-08T00:54:31+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2026\/04\/supreme-petfoods-selective-urinary-care-friandises-urinaires-lapin-rongeur.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"19,75&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/selective-urinary-care\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/selective-urinary-care\/","name":"Selective Selective Urinary Care - lapin & rongeurs Supreme Petfood - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/selective-urinary-care\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/selective-urinary-care\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2026\/04\/supreme-petfoods-selective-urinary-care-friandises-urinaires-lapin-rongeur.webp","datePublished":"2026-04-28T13:38:14+00:00","dateModified":"2026-07-08T00:54:31+00:00","description":"Selective Urinary Care \u2013 Friandises Naturelles pour Lapins, Cochons d\u2019Inde et Chinchillas. Utilisation :\u00a0 Calculs v\u00e9sicaux (urolithiase) Infections urinaires Infections r\u00e9nales Cystites Caract\u00e9ristiques\u00a0 : Soutien urinaire\u00a0: Contiennent du pissenlit, reconnu pour ses propri\u00e9t\u00e9s diur\u00e9tiques, et de la canneberge pour prot\u00e9ger le syst\u00e8me urinaire. Riche en vitamine C : Id\u00e9al pour les cochons d\u2019Inde et autres rongeurs ayant des besoins accrus en cette vitamine essentielle. Formule naturelle\u00a0: 100 % ingr\u00e9dients naturels, adapt\u00e9s aux pr\u00e9f\u00e9rences alimentaires des rongeurs.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/selective-urinary-care\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/selective-urinary-care\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/selective-urinary-care\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2026\/04\/supreme-petfoods-selective-urinary-care-friandises-urinaires-lapin-rongeur.webp","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2026\/04\/supreme-petfoods-selective-urinary-care-friandises-urinaires-lapin-rongeur.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/selective-urinary-care\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Selective Urinary Care &#8211; lapin &#038; rongeurs"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Supreme Petfood","product_price_amount":"19.75","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"C-SEL258","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/hesingue-68220\/boutique\/wp-json\/wp\/v2\/product\/1812457","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/hesingue-68220\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/hesingue-68220\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/hesingue-68220\/boutique\/wp-json\/wp\/v2\/media\/1812459"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/hesingue-68220\/boutique\/wp-json\/wp\/v2\/media?parent=1812457"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/hesingue-68220\/boutique\/wp-json\/wp\/v2\/product_cat?post=1812457"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/hesingue-68220\/boutique\/wp-json\/wp\/v2\/product_tag?post=1812457"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}