{"id":131286,"date":"2020-11-27T00:33:58","date_gmt":"2020-11-26T23:33:58","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/feline-c-d-ur-stress-metab-12scht-85g\/"},"modified":"2026-04-20T15:33:22","modified_gmt":"2026-04-20T13:33:22","slug":"c-d-urinary-stress-metabolic-sachet-repas-chat","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/legrandluce-72150\/boutique\/product\/c-d-urinary-stress-metabolic-sachet-repas-chat\/","title":{"rendered":"c\/d Urinary Stress Multicare + Metabolic Poulet &#8211; chat"},"content":{"rendered":"<p><strong>Hill&#8217;s Prescription Diet Metabolic + Urinary Feline est une alimentation pour chat cliniquement prouv\u00e9e pour soigner et pr\u00e9venir la r\u00e9cidive de la plupart des signes courants de troubles urinaires\u00a0et\u00a0pour r\u00e9duire et maintenir le poids.<\/strong><\/p>\n<div class=\"ficheArticleSmall\">\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Perte\u00a0et entretien du poids.<\/li>\n<li>Chat sujet aux signes les plus courants des Affections du Bas Urinaire F\u00e9lin.<\/li>\n<li>Chat sujet \u00e0 des probl\u00e8mes urinaires: cristaux et calculs de struvite, d\u2019oxalate de calcium et de phosphate de calcium.<\/li>\n<\/ul>\n<p><strong>Contre indications :<\/strong><\/p>\n<ul>\n<li>Chatons.<\/li>\n<li>Femelles en gestation ou en lactation.<\/li>\n<li>Chats affaiblis, en sous-poids ou d\u00e9shydrat\u00e9s.<\/li>\n<\/ul>\n<\/div>\n<p><strong>Bienfaits essentiels :<\/strong><\/p>\n<ul>\n<li>Des fibres solubles et insolubles pour aider \u00e0 maintenir la sati\u00e9t\u00e9.<\/li>\n<li>Facilite la conversion des graisses en \u00e9nergie.<\/li>\n<li>Contribue au maintien de la masse corporelle maigre.<\/li>\n<li>Contribue au maintien de la masse musculaire.<\/li>\n<li>Aide \u00e0 contr\u00f4ler le stress, un facteur de risque connu des signes les plus courants des Affections du Bas Urinaire F\u00e9lin.<\/li>\n<li>Diminue la concentration urinaire en composants de struvite (magn\u00e9sium, phosphate) et d\u2019oxalate de calcium.<\/li>\n<li>Un m\u00e9lange synergique d&#8217;ingr\u00e9dients qui fonctionne naturellement en agissant sur la consommation calorique propre \u00e0 chaque chat.<\/li>\n<\/ul>\n<p><strong>Cet aliment est destin\u00e9 \u00e0 la prise en charge nutritionnelle d\u2019une maladie. Il doit \u00eatre prescrit en accord avec l&#8217;\u00e9tat de sant\u00e9 de votre animal. Demandez conseil \u00e0 votre v\u00e9t\u00e9rinaire avant toute utilisation ou avant prolongation de la dur\u00e9e d\u2019utilisation.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Alimentation humide en sachets fra\u00eecheur pour chat, cliniquement prouv\u00e9e pour soigner et pr\u00e9venir la r\u00e9cidive de la plupart des signes courants de troubles urinaires et pour r\u00e9duire et maintenir le poids.<br \/>\n<\/strong><\/p>\n<div class=\"ficheArticleSmall\">\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>Perte\u00a0et entretien du poids.<\/li>\n<li>Chat sujet aux signes les plus courants des Affections du Bas Urinaire F\u00e9lin.<\/li>\n<li>Chat sujet \u00e0 des probl\u00e8mes urinaires: cristaux et calculs de struvite, d\u2019oxalate de calcium et de phosphate de calcium.<\/li>\n<\/ul>\n<\/div>\n","protected":false},"featured_media":1037004,"template":"","meta":[],"product_cat":[12551,12581,2697],"product_tag":[],"class_list":{"0":"post-131286","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alimentation-du-chat","7":"product_cat-alimentation-medicalisee-pour-chat","8":"product_cat-chat","9":"pa_marque-hills-pet-nutrition","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Prescription Diet (Hill&#039;s) c\/d Urinary Stress Multicare + Metabolic Poulet - chat Hill&#039;s - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Chat C\/D Urinary Stress + Metabolic Sachet Repas est formul\u00e9 par des v\u00e9t\u00e9rinaires pour favoriser la sant\u00e9 urinaire et le poids de votre chat.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prescription Diet (Hill&#039;s) c\/d Urinary Stress Multicare + Metabolic Poulet - chat Hill&#039;s - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Chat C\/D Urinary Stress + Metabolic Sachet Repas est formul\u00e9 par des v\u00e9t\u00e9rinaires pour favoriser la sant\u00e9 urinaire et le poids de votre chat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/legrandluce-72150\/boutique\/product\/c-d-urinary-stress-metabolic-sachet-repas-chat\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-20T13:33:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/11\/chat-cd-urinary-stress-multicare-metabolic-au-poulet.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"540\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"18,23&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/c-d-urinary-stress-metabolic-sachet-repas-chat\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/c-d-urinary-stress-metabolic-sachet-repas-chat\\\/\",\"name\":\"Prescription Diet (Hill's) c\\\/d Urinary Stress Multicare + Metabolic Poulet - chat Hill's - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/c-d-urinary-stress-metabolic-sachet-repas-chat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/c-d-urinary-stress-metabolic-sachet-repas-chat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/chat-cd-urinary-stress-multicare-metabolic-au-poulet.jpg\",\"datePublished\":\"2020-11-26T23:33:58+00:00\",\"dateModified\":\"2026-04-20T13:33:22+00:00\",\"description\":\"Chat C\\\/D Urinary Stress + Metabolic Sachet Repas est formul\u00e9 par des v\u00e9t\u00e9rinaires pour favoriser la sant\u00e9 urinaire et le poids de votre chat.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/c-d-urinary-stress-metabolic-sachet-repas-chat\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/c-d-urinary-stress-metabolic-sachet-repas-chat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/c-d-urinary-stress-metabolic-sachet-repas-chat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/chat-cd-urinary-stress-multicare-metabolic-au-poulet.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/chat-cd-urinary-stress-multicare-metabolic-au-poulet.jpg\",\"width\":540,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/vincennes-loup-94300\\\/boutique\\\/product\\\/c-d-urinary-stress-metabolic-sachet-repas-chat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"c\\\/d Urinary Stress Multicare + Metabolic Poulet &#8211; chat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Hill&#039;s\" \/>\n<meta property=\"product:price:amount\" content=\"18.23\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"A-1850890\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prescription Diet (Hill's) c\/d Urinary Stress Multicare + Metabolic Poulet - chat Hill's - V\u00e9torino","description":"Chat C\/D Urinary Stress + Metabolic Sachet Repas est formul\u00e9 par des v\u00e9t\u00e9rinaires pour favoriser la sant\u00e9 urinaire et le poids de votre chat.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Prescription Diet (Hill's) c\/d Urinary Stress Multicare + Metabolic Poulet - chat Hill's - V\u00e9torino","og_description":"Chat C\/D Urinary Stress + Metabolic Sachet Repas est formul\u00e9 par des v\u00e9t\u00e9rinaires pour favoriser la sant\u00e9 urinaire et le poids de votre chat.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/legrandluce-72150\/boutique\/product\/c-d-urinary-stress-metabolic-sachet-repas-chat\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-04-20T13:33:22+00:00","og_image":[{"width":540,"height":540,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/11\/chat-cd-urinary-stress-multicare-metabolic-au-poulet.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"18,23&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/c-d-urinary-stress-metabolic-sachet-repas-chat\/","url":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/c-d-urinary-stress-metabolic-sachet-repas-chat\/","name":"Prescription Diet (Hill's) c\/d Urinary Stress Multicare + Metabolic Poulet - chat Hill's - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/c-d-urinary-stress-metabolic-sachet-repas-chat\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/c-d-urinary-stress-metabolic-sachet-repas-chat\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/11\/chat-cd-urinary-stress-multicare-metabolic-au-poulet.jpg","datePublished":"2020-11-26T23:33:58+00:00","dateModified":"2026-04-20T13:33:22+00:00","description":"Chat C\/D Urinary Stress + Metabolic Sachet Repas est formul\u00e9 par des v\u00e9t\u00e9rinaires pour favoriser la sant\u00e9 urinaire et le poids de votre chat.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/c-d-urinary-stress-metabolic-sachet-repas-chat\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/c-d-urinary-stress-metabolic-sachet-repas-chat\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/c-d-urinary-stress-metabolic-sachet-repas-chat\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/11\/chat-cd-urinary-stress-multicare-metabolic-au-poulet.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/11\/chat-cd-urinary-stress-multicare-metabolic-au-poulet.jpg","width":540,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/veterinaire\/vincennes-loup-94300\/boutique\/product\/c-d-urinary-stress-metabolic-sachet-repas-chat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"c\/d Urinary Stress Multicare + Metabolic Poulet &#8211; chat"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Hill's","product_price_amount":"18.23","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"A-1850890","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/legrandluce-72150\/boutique\/wp-json\/wp\/v2\/product\/131286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/legrandluce-72150\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/legrandluce-72150\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/legrandluce-72150\/boutique\/wp-json\/wp\/v2\/media\/1037004"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/legrandluce-72150\/boutique\/wp-json\/wp\/v2\/media?parent=131286"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/legrandluce-72150\/boutique\/wp-json\/wp\/v2\/product_cat?post=131286"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/legrandluce-72150\/boutique\/wp-json\/wp\/v2\/product_tag?post=131286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}