{"id":38150,"date":"2020-03-04T23:58:49","date_gmt":"2020-03-04T22:58:49","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/biofood-chat-adult\/"},"modified":"2021-03-17T01:40:44","modified_gmt":"2021-03-17T00:40:44","slug":"biofood-chat-adult","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/legrandluce-72150\/boutique\/product\/biofood-chat-adult\/","title":{"rendered":"Biofood Chat adult"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Croquettes 100 % naturelles, sans bl\u00e9 pour les chats adultes d&#8217;int\u00e9rieur et d&#8217;ext\u00e9rieur. lles contiennent des pr\u00e9biotiques FOS (inuline), des acides gras om\u00e9ga 3 et 6 et de la taurine. Soutient la dentition, la peau , le pelage et les d\u00e9fenses naturelles. R\u00e9duit la formation de boules de poils, limite les odeurs et le volume des selles.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":[],"product_cat":[2697],"product_tag":[],"class_list":{"0":"post-38150","1":"product","2":"type-product","3":"status-publish","5":"product_cat-chat","6":"pa_marque-bella-bestia-sa","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Biofood Chat adult Bella Bestia SA - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Croquettes 100 % naturelles, sans bl\u00e9 pour les chats adultes d&#039;int\u00e9rieur et d&#039;ext\u00e9rieur. lles contiennent des pr\u00e9biotiques FOS (inuline), des acides gras om\u00e9ga 3 et 6 et de la taurine. Soutient la dentition, la peau , le pelage et les d\u00e9fenses naturelles. R\u00e9duit la formation de boules de poils, limite les odeurs et le volume des selles.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biofood Chat adult Bella Bestia SA - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Croquettes 100 % naturelles, sans bl\u00e9 pour les chats adultes d&#039;int\u00e9rieur et d&#039;ext\u00e9rieur. lles contiennent des pr\u00e9biotiques FOS (inuline), des acides gras om\u00e9ga 3 et 6 et de la taurine. Soutient la dentition, la peau , le pelage et les d\u00e9fenses naturelles. R\u00e9duit la formation de boules de poils, limite les odeurs et le volume des selles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/legrandluce-72150\/boutique\/product\/biofood-chat-adult\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-17T00:40:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/09\/logo-vetorino-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"539\" \/>\n\t<meta property=\"og:image:height\" content=\"224\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/biofood-chat-adult\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/biofood-chat-adult\\\/\",\"name\":\"Biofood Chat adult Bella Bestia SA - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"datePublished\":\"2020-03-04T22:58:49+00:00\",\"dateModified\":\"2021-03-17T00:40:44+00:00\",\"description\":\"Croquettes 100 % naturelles, sans bl\u00e9 pour les chats adultes d'int\u00e9rieur et d'ext\u00e9rieur. lles contiennent des pr\u00e9biotiques FOS (inuline), des acides gras om\u00e9ga 3 et 6 et de la taurine. Soutient la dentition, la peau , le pelage et les d\u00e9fenses naturelles. R\u00e9duit la formation de boules de poils, limite les odeurs et le volume des selles.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/biofood-chat-adult\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/biofood-chat-adult\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/biofood-chat-adult\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Biofood Chat adult\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Bella Bestia SA\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biofood Chat adult Bella Bestia SA - V\u00e9torino","description":"Croquettes 100 % naturelles, sans bl\u00e9 pour les chats adultes d'int\u00e9rieur et d'ext\u00e9rieur. lles contiennent des pr\u00e9biotiques FOS (inuline), des acides gras om\u00e9ga 3 et 6 et de la taurine. Soutient la dentition, la peau , le pelage et les d\u00e9fenses naturelles. R\u00e9duit la formation de boules de poils, limite les odeurs et le volume des selles.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Biofood Chat adult Bella Bestia SA - V\u00e9torino","og_description":"Croquettes 100 % naturelles, sans bl\u00e9 pour les chats adultes d'int\u00e9rieur et d'ext\u00e9rieur. lles contiennent des pr\u00e9biotiques FOS (inuline), des acides gras om\u00e9ga 3 et 6 et de la taurine. Soutient la dentition, la peau , le pelage et les d\u00e9fenses naturelles. R\u00e9duit la formation de boules de poils, limite les odeurs et le volume des selles.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/legrandluce-72150\/boutique\/product\/biofood-chat-adult\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2021-03-17T00:40:44+00:00","og_image":[{"width":539,"height":224,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/09\/logo-vetorino-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/biofood-chat-adult\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/biofood-chat-adult\/","name":"Biofood Chat adult Bella Bestia SA - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"datePublished":"2020-03-04T22:58:49+00:00","dateModified":"2021-03-17T00:40:44+00:00","description":"Croquettes 100 % naturelles, sans bl\u00e9 pour les chats adultes d'int\u00e9rieur et d'ext\u00e9rieur. lles contiennent des pr\u00e9biotiques FOS (inuline), des acides gras om\u00e9ga 3 et 6 et de la taurine. Soutient la dentition, la peau , le pelage et les d\u00e9fenses naturelles. R\u00e9duit la formation de boules de poils, limite les odeurs et le volume des selles.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/biofood-chat-adult\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/biofood-chat-adult\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/biofood-chat-adult\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Biofood Chat adult"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Bella Bestia SA","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/legrandluce-72150\/boutique\/wp-json\/wp\/v2\/product\/38150","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/legrandluce-72150\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/legrandluce-72150\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/legrandluce-72150\/boutique\/wp-json\/wp\/v2\/media?parent=38150"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/legrandluce-72150\/boutique\/wp-json\/wp\/v2\/product_cat?post=38150"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/legrandluce-72150\/boutique\/wp-json\/wp\/v2\/product_tag?post=38150"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}