{"id":296499,"date":"2022-02-22T14:56:56","date_gmt":"2022-02-22T13:56:56","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/?p=296499"},"modified":"2024-08-08T17:22:16","modified_gmt":"2024-08-08T15:22:16","slug":"comment-soigner-le-tartre-chez-le-chien-et-le-chat","status":"publish","type":"post","link":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/2022\/02\/22\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\/","title":{"rendered":"Comment soigner le tartre chez le chien et le chat"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"296499\" class=\"elementor elementor-296499\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7bfc90cf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7bfc90cf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f333fff\" data-id=\"f333fff\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4324234e elementor-widget elementor-widget-text-editor\" data-id=\"4324234e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p><h2 class=\"wp-block-heading\">Pr\u00e9venir les probl\u00e8mes de tartre pour son chat ou son chien<\/h2><p><\/p><p><\/p><p class=\"wp-block-paragraph\">Comme les humains, les <strong>chats et les chiens<\/strong> peuvent avoir des <strong>probl\u00e8mes bucco-dentaires<\/strong>, notamment l\u2019accumulation de tartre. Ce probl\u00e8me, bien plus r\u00e9current qu\u2019on ne le croit, entraine de la g\u00eane, des <strong>douleurs<\/strong> et des <strong>r\u00e9percussions<\/strong> plus graves pour votre animal de compagnie. Il n\u2019y a pas de recette miracle pour pr\u00e9venir les <strong>probl\u00e8mes de tartre<\/strong> et plus de votre chien ou de votre chat, il faut qu\u2019il ait une <strong>bonne hygi\u00e8ne bucco-dentaire<\/strong>. C\u2019est primordial non seulement pour sa sant\u00e9 dentaire mais aussi et surtout sa <strong>bonne sant\u00e9<\/strong> de mani\u00e8re g\u00e9n\u00e9rale.<\/p><p><\/p><p><\/p><h2 class=\"has-text-align-left wp-block-heading\">Le tartre en quelques mots<\/h2><p><\/p><p><\/p><p class=\"wp-block-paragraph\">La <strong>bouche d\u2019un chat ou d\u2019un chien<\/strong> comporte maintes bact\u00e9ries qui se prolif\u00e8rent facilement. Sans une <strong>bonne hygi\u00e8ne bucco-dentaire<\/strong>, cela va former de la <strong>plaque dentaire<\/strong>. Le probl\u00e8me c\u2019est que progressivement cette plaque se cumule, se min\u00e9ralise, se durcit et se transforme en <strong>tartre<\/strong>. Cet ensemble de tartre pour votre chat ou votre chien est une <strong>accumulation de r\u00e9sidus<\/strong>, de bact\u00e9ries qui n\u2019ont \u00e9t\u00e9 pas \u00e9t\u00e9 <strong>nettoy\u00e9es<\/strong>, et qui n\u2019ont donc pas disparues. De ce fait, il est fondamental de veiller \u00e0 bien <strong>prendre soin de l\u2019hygi\u00e8ne dentaire de votre chat ou votre chien<\/strong>. C\u2019est La meilleure mani\u00e8re de pr\u00e9venir l\u2019apparition et <strong>l\u2019accumulation de tartre<\/strong>. En plus, non seulement cela \u00e9vitera des r\u00e9percussions graves pour la sant\u00e9 de votre chien, mais cela am\u00e9liorera aussi son confort et son bien-\u00eatre gr\u00e2ce \u00e0 une <strong>meilleure haleine<\/strong>.<\/p><p><\/p><p><\/p><p class=\"wp-block-paragraph\"><\/p><p><\/p><h2 class=\"has-text-align-left wp-block-heading\">Les r\u00e9percussions du tartre sur la sant\u00e9 de votre chat ou votre chien<\/h2><p><img fetchpriority=\"high\" decoding=\"async\" class=\"size-medium wp-image-296512 alignleft\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cierra-voelkl-FVBNSmN531w-unsplash-300x200.jpg\" alt=\"Les r\u00e9percussions du tartre sur la sant\u00e9 de votre chat ou votre chien\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cierra-voelkl-FVBNSmN531w-unsplash-300x200.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cierra-voelkl-FVBNSmN531w-unsplash-1024x683.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cierra-voelkl-FVBNSmN531w-unsplash-768x512.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cierra-voelkl-FVBNSmN531w-unsplash-1536x1025.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cierra-voelkl-FVBNSmN531w-unsplash-2048x1367.jpg 2048w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cierra-voelkl-FVBNSmN531w-unsplash-750x500.jpg 750w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cierra-voelkl-FVBNSmN531w-unsplash-555x370.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cierra-voelkl-FVBNSmN531w-unsplash-64x43.jpg 64w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p><\/p><p><\/p><p class=\"wp-block-paragraph\">Plusieurs types de r\u00e9percussions dues au tartre existent quant \u00e0 la sant\u00e9 de votre chien ou de votre chien. Cela va des moins aux plus graves. Parmi elles :<\/p><p><\/p><p><\/p><ul><li>Une mauvaise haleine\u00a0: c\u2019est le tartre qui engendre la mauvaise haleine de votre chat ou de votre chien. C\u2019est donc un signe qu\u2019il est temps de le conduire chez le v\u00e9t\u00e9rinaire.<\/li><li>Gingivites : des accumulations de bact\u00e9ries sur les dents peuvent entra\u00eener des gingivites, soit des inflammations des gencives. Si vous remarquez que les gencives de votre animal de compagnie sont rouges, sont enflamm\u00e9es, cela doit vous alerter. C\u2019est douloureux pour votre animal qui aura des difficult\u00e9s \u00e0 manger. Pris \u00e0 temps, une gingivite se soigne bien.<\/li><li>Parodontites\u00a0: des infections dentaires comme des gingivites qui ne sont pas soign\u00e9es dans les temps peuvent entrainer des parodontites ou maladies parodontales. La parodontite est la maladie infectieuse la plus fr\u00e9quente chez les chiens et chats. Cette pathologie grave peut avoir des r\u00e9percussions graves comme le d\u00e9chaussement des dents pour votre animal.<\/li><\/ul><p class=\"wp-block-paragraph\">En outre, les chats et chiens qui ont une <strong>parodontite<\/strong> peuvent d\u00e9velopper d\u2019autres <strong>pathologies<\/strong> \u2013 notamment r\u00e9nales, cardiaques\u2026 Toutes ces <strong>bact\u00e9ries de la bouche<\/strong> peuvent circuler dans le sang de l\u2019animal pour se fixer ensuite sur des organes vitaux.<\/p><p><\/p><p><\/p><h2 class=\"wp-block-heading\">Bien pr\u00e9venir l&#8217;apparition et l&#8217;accumulation de tartre pour votre chien ou votre chat<\/h2><p><img decoding=\"async\" class=\"size-medium wp-image-296513 alignright\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/bree-carry-baylor-Hl_HaZBCs_8-unsplash-300x300.jpg\" alt=\"Bien pr\u00e9venir l'apparition et l'accumulation de tartre pour votre chien ou votre chat\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/bree-carry-baylor-Hl_HaZBCs_8-unsplash-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/bree-carry-baylor-Hl_HaZBCs_8-unsplash-1024x1024.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/bree-carry-baylor-Hl_HaZBCs_8-unsplash-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/bree-carry-baylor-Hl_HaZBCs_8-unsplash-768x768.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/bree-carry-baylor-Hl_HaZBCs_8-unsplash-1536x1536.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/bree-carry-baylor-Hl_HaZBCs_8-unsplash-2048x2048.jpg 2048w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/bree-carry-baylor-Hl_HaZBCs_8-unsplash-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/bree-carry-baylor-Hl_HaZBCs_8-unsplash-555x555.jpg 555w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/bree-carry-baylor-Hl_HaZBCs_8-unsplash-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/bree-carry-baylor-Hl_HaZBCs_8-unsplash-64x64.jpg 64w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p><p><\/p><p><\/p><p class=\"wp-block-paragraph\">Pour bien pr\u00e9venir les <strong>probl\u00e8mes de tartre<\/strong>, il vaut mieux \u00e9viter d\u2019en arriver \u00e0 la case <strong>d\u00e9tartrage<\/strong> ! En effet, ce n\u2019est pas un moyen pr\u00e9ventif. C\u2019est une <strong>op\u00e9ration<\/strong> sous anesth\u00e9sie g\u00e9n\u00e9rale pour votre animal\u2026 Vous ne pouvez donc pas les faire subir \u00e0 r\u00e9p\u00e9tition \u00e0 votre chien ou votre chat ! Voici donc trois <strong>vrais moyens<\/strong> pour bien pr\u00e9venir l\u2019apparition et l\u2019accumulation de tartre pour votre chien ou votre chat :<\/p><p><\/p><p><\/p><h2>Proposer \u00e0 votre animal une bonne alimentation<\/h2><p class=\"wp-block-paragraph\">Veillez \u00e0 proposer \u00e0 votre chat ou chien une <strong>bonne alimentation<\/strong>, adapt\u00e9e. Ainsi, il vaut mieux privil\u00e9gier les <strong>aliments secs<\/strong> \u2013 croquettes \u2013 que les aliments humides \u2013 les p\u00e2t\u00e9es, les bouch\u00e9es. En effet, les <strong>croquettes<\/strong> ont un effet interne \u00ab\u00a0nettoyant\u00a0\u00bb, qui retardent le <strong>d\u00e9p\u00f4t de plaque dentaire<\/strong>. Cela r\u00e9duit donc d\u00e9j\u00e0 de base l\u2019apparition et l\u2019accumulation du tartre. Pour bien prendre soin de l\u2019<strong>hygi\u00e8ne bucco-dentaire de votre compagnon \u00e0 4 pattes<\/strong>, pensez donc croquettes\u00a0! Et rien d\u2019autre\u00a0!<\/p><p>De plus, certains aliments et produits contribuent encore plus \u00e0 la sant\u00e9 bucco-dentaire de votre animal de compagnie. Regardez donc du c\u00f4t\u00e9 des <strong>croquettes dentaires<\/strong>\u00a0! Certaines agissent comme de vraies <strong>brosses \u00e0 dents dans la bouche de votre chien ou de votre chat<\/strong>\u2026 Rien de tel qu\u2019une alimentation saine qui fait en m\u00eame temps le <strong>travail de nettoyage<\/strong>\u2026\u00a0!<\/p><p>Par ailleurs, des <strong>friandises<\/strong> particuli\u00e8res sont un compl\u00e9ment aux croquettes dentaires. En effet, ces <strong>friandises dentaires, antitartre<\/strong> vont avoir une action d\u00e9capante. Elles vont directement permettre de la <strong>d\u00e9coller la plaque dentaire<\/strong> de la surface de la dent de votre animal. L\u00e0 aussi, cela va donc largement contribuer \u00e0 <strong>bien pr\u00e9venir les probl\u00e8mes de tartre<\/strong>.<\/p><h2>Brosser les dents de votre chien ou de votre chat<\/h2><p>En plus de ces produits dentaires, vous pouvez vous-m\u00eames <strong>brosser les dents de votre chien ou de votre chat<\/strong>\u00a0! Nous vous recommandons ainsi de commencer le plus t\u00f4t possible pour habituer votre animal. Cette bonne hygi\u00e8ne doit devenir une habitude. Brosser les dents de votre chien ou de votre chat se fait sur toutes ses dents, <strong>verticalement<\/strong>. Le rin\u00e7age de bouche de l&#8217;animal n\u2019est pas indispensable.<\/p><h2>Faire des visites r\u00e9guli\u00e8res chez un v\u00e9t\u00e9rinaire<\/h2><p>Enfin, bien \u00e9videmment, en plus de donner une alimentation saine \u00e0 votre chien ou chat, de lui brosser les dents, <strong>faire des visites r\u00e9guli\u00e8res chez un v\u00e9t\u00e9rinaire<\/strong> est essentiel\u00a0! A chaque visite, votre v\u00e9t\u00e9rinaire va v\u00e9rifier la <strong>bonne sant\u00e9 bucco-dentaire de votre animal de compagnie<\/strong>\u2026 Vous verrez qu\u2019en adoptant quelques r\u00e9flexes, tout le monde y trouvera son compte\u00a0!<\/p><p><\/p><p><\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d4a7829 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d4a7829\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-46212100\" data-id=\"46212100\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69e1c955 elementor-widget elementor-widget-heading\" data-id=\"69e1c955\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"line-height: 1.4;margin-top: 20px;margin-bottom: 10px;font-size: 18px;text-align: center\">S\u00e9lections de produits v\u00e9t\u00e9rinaire pour maintenir une bonne hygi\u00e8ne dentaire<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-10fc3f80 product_alcyon elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"10fc3f80\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-37bc84f\" data-id=\"37bc84f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74d8ea47 elementor-widget elementor-widget-image\" data-id=\"74d8ea47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dental-dog-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-298929\" alt=\"royal-canin-dental-dog-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dental-dog-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dental-dog-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dental-dog-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dental-dog-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dental-dog-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dental-dog-vetorino.png 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3862c20c elementor-widget elementor-widget-heading\" data-id=\"3862c20c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">DOG DENTAL - ROYAL CANIN <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65317f48 elementor-widget elementor-widget-text-editor\" data-id=\"65317f48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Royal Canin Dog Dental Medium &amp; Large\u00a0participe \u00e0 l\u2019entretien quotidien de l\u2019hygi\u00e8ne bucco-dentaire du chien de plus de 10 kg.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-314ee498 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"314ee498\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/tourrettes-83440\/boutique\/product\/royal-canin-dog-dental-medium-large\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-187e44cd\" data-id=\"187e44cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d343f93 elementor-widget elementor-widget-image\" data-id=\"2d343f93\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/veggiedent-lamelles-l-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-298930\" alt=\"veggiedent-lamelles-l-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/veggiedent-lamelles-l-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/veggiedent-lamelles-l-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/veggiedent-lamelles-l-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/veggiedent-lamelles-l-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/veggiedent-lamelles-l-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/veggiedent-lamelles-l-vetorino.jpg 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f57cfa7 elementor-widget elementor-widget-heading\" data-id=\"f57cfa7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">VEGGIEDENT LAMELLES L - VIRBAC\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2cea25ff elementor-widget elementor-widget-text-editor\" data-id=\"2cea25ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les lamelles \u00e0 m\u00e2cher Veggiedent permettent de lutter contre les probl\u00e8mes dentaires du chien tout en \u00e9tant attrayant pour votre chien<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40d3d5ae elementor-align-center elementor-widget elementor-widget-button\" data-id=\"40d3d5ae\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/tourrettes-83440\/boutique\/product\/veggiedent-fresh-l-chien30-kg\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3b7d8c43\" data-id=\"3b7d8c43\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4088ce26 elementor-widget elementor-widget-image\" data-id=\"4088ce26\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prozym-plaque-off-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-298931\" alt=\"prozym-plaque-off-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prozym-plaque-off-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prozym-plaque-off-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prozym-plaque-off-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prozym-plaque-off-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prozym-plaque-off-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prozym-plaque-off-vetorino.png 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e31920 elementor-widget elementor-widget-heading\" data-id=\"e31920\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PROZYM PLAQUE  OFF - CEVA\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78416c47 elementor-widget elementor-widget-text-editor\" data-id=\"78416c47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Prozym Plaque Off des laboratoires CEVA est une poudre orale destin\u00e9e \u00e0 la bonne hygi\u00e8ne bucco-dentaire des chiens et des chats.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6290ea6 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6290ea6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/tourrettes-83440\/boutique\/product\/prozym-plaque-off-2\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-646efc0a\" data-id=\"646efc0a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-44bcfadb elementor-widget elementor-widget-image\" data-id=\"44bcfadb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-dental_vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-298944\" alt=\"croquettes cat dental royal canin\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-dental_vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-dental_vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-dental_vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-dental_vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-dental_vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-dental_vetorino.png 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c8a706b elementor-widget elementor-widget-heading\" data-id=\"6c8a706b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CAT DENTAL -  ROYAL CANIN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-36331f4f elementor-widget elementor-widget-text-editor\" data-id=\"36331f4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Royal Canin Cat Dental participe \u00e0 l\u2019entretien quotidien de la bonne hygi\u00e8ne bucco-dentaire du chat. Valable pour toutes les races<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c46d487 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"2c46d487\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/tourrettes-83440\/boutique\/product\/vdiet-cat-dental-s-o\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2876243 product_centravet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2876243\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-bdf0bfe\" data-id=\"bdf0bfe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1d5b471 elementor-widget elementor-widget-image\" data-id=\"1d5b471\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dental-dog-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-298929\" alt=\"royal-canin-dental-dog-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dental-dog-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dental-dog-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dental-dog-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dental-dog-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dental-dog-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dental-dog-vetorino.png 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3e326c elementor-widget elementor-widget-heading\" data-id=\"c3e326c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">DOG DENTAL - ROYAL CANIN <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b6d41cd elementor-widget elementor-widget-text-editor\" data-id=\"b6d41cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Royal Canin Dog Dental Medium &amp; Large\u00a0participe \u00e0 l\u2019entretien quotidien de l\u2019hygi\u00e8ne bucco-dentaire du chien de plus de 10 kg.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e510f72 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e510f72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/tourrettes-83440\/boutique\/product\/dog-dental-medium-large\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-b7da33c\" data-id=\"b7da33c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-91a4458 elementor-widget elementor-widget-image\" data-id=\"91a4458\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/veggiedent-lamelles-l-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-298930\" alt=\"veggiedent-lamelles-l-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/veggiedent-lamelles-l-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/veggiedent-lamelles-l-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/veggiedent-lamelles-l-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/veggiedent-lamelles-l-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/veggiedent-lamelles-l-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/veggiedent-lamelles-l-vetorino.jpg 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-817f214 elementor-widget elementor-widget-heading\" data-id=\"817f214\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">VEGGIEDENT LAMELLES L - VIRBAC\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fea145d elementor-widget elementor-widget-text-editor\" data-id=\"fea145d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les lamelles \u00e0 m\u00e2cher Veggiedent permettent de lutter contre les probl\u00e8mes dentaires du chien tout en \u00e9tant attrayant pour votre chien<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6c700e2 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6c700e2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/tourrettes-83440\/boutique\/product\/veggiedent-fresh\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-2c7f1d7\" data-id=\"2c7f1d7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4658fc elementor-widget elementor-widget-image\" data-id=\"a4658fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prozym-plaque-off-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-298931\" alt=\"prozym-plaque-off-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prozym-plaque-off-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prozym-plaque-off-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prozym-plaque-off-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prozym-plaque-off-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prozym-plaque-off-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prozym-plaque-off-vetorino.png 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b69aa07 elementor-widget elementor-widget-heading\" data-id=\"b69aa07\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PROZYM PLAQUE  OFF - CEVA\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a382c16 elementor-widget elementor-widget-text-editor\" data-id=\"a382c16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Prozym Plaque Off des laboratoires CEVA est une poudre orale destin\u00e9e \u00e0 la bonne hygi\u00e8ne bucco-dentaire des chiens et des chats.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f990c3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0f990c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/tourrettes-83440\/boutique\/product\/prozym-plaque-off\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-fc64aca\" data-id=\"fc64aca\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ada69cb elementor-widget elementor-widget-image\" data-id=\"ada69cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-dental_vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-298944\" alt=\"croquettes cat dental royal canin\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-dental_vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-dental_vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-dental_vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-dental_vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-dental_vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-dental_vetorino.png 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e945382 elementor-widget elementor-widget-heading\" data-id=\"e945382\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CAT DENTAL -  ROYAL CANIN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49f36a1 elementor-widget elementor-widget-text-editor\" data-id=\"49f36a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Royal Canin Cat Dental participe \u00e0 l\u2019entretien quotidien de la bonne hygi\u00e8ne bucco-dentaire du chat. Valable pour toutes les races<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-adf09e1 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"adf09e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/tourrettes-83440\/boutique\/product\/veterinary-diet-cat-dental-s-o\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e5db772 product_coveto elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e5db772\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-993cb14\" data-id=\"993cb14\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e2e90b3 elementor-widget elementor-widget-image\" data-id=\"e2e90b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dental-dog-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-298929\" alt=\"royal-canin-dental-dog-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dental-dog-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dental-dog-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dental-dog-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dental-dog-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dental-dog-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/dental-dog-vetorino.png 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89eb01e elementor-widget elementor-widget-heading\" data-id=\"89eb01e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">DOG DENTAL - ROYAL CANIN <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0afeb4c elementor-widget elementor-widget-text-editor\" data-id=\"0afeb4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Royal Canin Dog Dental Medium &amp; Large\u00a0participe \u00e0 l\u2019entretien quotidien de l\u2019hygi\u00e8ne bucco-dentaire du chien de plus de 10 kg.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9846443 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"9846443\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/tourrettes-83440\/boutique\/product\/dog-dental-medium-large\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-64f269e\" data-id=\"64f269e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f76c181 elementor-widget elementor-widget-image\" data-id=\"f76c181\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/veggiedent-lamelles-l-vetorino-150x150.jpg\" class=\"attachment-thumbnail size-thumbnail wp-image-298930\" alt=\"veggiedent-lamelles-l-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/veggiedent-lamelles-l-vetorino-150x150.jpg 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/veggiedent-lamelles-l-vetorino-300x300.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/veggiedent-lamelles-l-vetorino-500x500.jpg 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/veggiedent-lamelles-l-vetorino-160x160.jpg 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/veggiedent-lamelles-l-vetorino-64x64.jpg 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/veggiedent-lamelles-l-vetorino.jpg 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dcda629 elementor-widget elementor-widget-heading\" data-id=\"dcda629\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">VEGGIEDENT LAMELLES L - VIRBAC\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b1dab6 elementor-widget elementor-widget-text-editor\" data-id=\"9b1dab6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les lamelles \u00e0 m\u00e2cher Veggiedent permettent de lutter contre les probl\u00e8mes dentaires du chien tout en \u00e9tant attrayant pour votre chien<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f88f4f7 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"f88f4f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/tourrettes-83440\/boutique\/product\/veggiedent-fresh-l-chien-a-30-kg-sachet-de-15-lamelles\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-d1c9e76\" data-id=\"d1c9e76\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5cc8b4e elementor-widget elementor-widget-image\" data-id=\"5cc8b4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prozym-plaque-off-vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-298931\" alt=\"prozym-plaque-off-vetorino\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prozym-plaque-off-vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prozym-plaque-off-vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prozym-plaque-off-vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prozym-plaque-off-vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prozym-plaque-off-vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/prozym-plaque-off-vetorino.png 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-38f47f6 elementor-widget elementor-widget-heading\" data-id=\"38f47f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">PROZYM PLAQUE  OFF - CEVA\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46cc304 elementor-widget elementor-widget-text-editor\" data-id=\"46cc304\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Prozym Plaque Off des laboratoires CEVA est une poudre orale destin\u00e9e \u00e0 la bonne hygi\u00e8ne bucco-dentaire des chiens et des chats.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8fa5d6 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c8fa5d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/tourrettes-83440\/boutique\/product\/prozym-plaque-off-pot-de-180-g\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3c2bc56\" data-id=\"3c2bc56\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4880c37 elementor-widget elementor-widget-image\" data-id=\"4880c37\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-dental_vetorino-150x150.png\" class=\"attachment-thumbnail size-thumbnail wp-image-298944\" alt=\"croquettes cat dental royal canin\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-dental_vetorino-150x150.png 150w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-dental_vetorino-300x300.png 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-dental_vetorino-500x500.png 500w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-dental_vetorino-160x160.png 160w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-dental_vetorino-64x64.png 64w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/cat-dental_vetorino.png 540w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-338b3c8 elementor-widget elementor-widget-heading\" data-id=\"338b3c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">CAT DENTAL -  ROYAL CANIN<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91e99bd elementor-widget elementor-widget-text-editor\" data-id=\"91e99bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Royal Canin Cat Dental participe \u00e0 l\u2019entretien quotidien de la bonne hygi\u00e8ne bucco-dentaire du chat. Valable pour toutes les races<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57634fe elementor-align-center elementor-widget elementor-widget-button\" data-id=\"57634fe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/tourrettes-83440\/boutique\/product\/cat-dental\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72abc9cf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72abc9cf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-68d07861\" data-id=\"68d07861\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b848029 elementor-widget elementor-widget-text-editor\" data-id=\"2b848029\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong style=\"color: #078ed2;text-align: center\"><a href=\"https:\/\/www.vetorino.com\/boutique\/?s=dental%20health&amp;post_type=product\">\u00a0D\u00e9couvrez ici notre s\u00e9lection de produits antitartre, dentaires pour votre chien ou votre chat<\/a><\/strong><\/p><p>\u00a0<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Pr\u00e9venir les probl\u00e8mes de tartre pour son chat ou son chien Comme les humains, les chats et les chiens peuvent avoir des probl\u00e8mes bucco-dentaires, notamment l\u2019accumulation de tartre. Ce probl\u00e8me, bien plus r\u00e9current qu\u2019on ne le croit, entraine de la g\u00eane, des douleurs et des r\u00e9percussions plus graves pour votre animal de compagnie. Il n\u2019y [&hellip;]<\/p>\n","protected":false},"author":10426,"featured_media":296513,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[14086,14087,14091,14090,14095,14094],"tags":[],"class_list":["post-296499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chat","category-chien","category-hygiene-et-bien-etre-chat","category-hygiene-et-bien-etre-chien","category-sante-et-prevention-chat","category-sante-chien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment soigner le tartre chez le chien et le chat - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Cliquez ici pour d\u00e9couvrir comment soigner le tartre chez le chien et le chat ! Votre animal doit avoir une bonne hygi\u00e8ne bucco-dentaire... !\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment soigner le tartre chez le chien et le chat - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Cliquez ici pour d\u00e9couvrir comment soigner le tartre chez le chien et le chat ! Votre animal doit avoir une bonne hygi\u00e8ne bucco-dentaire... !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/2022\/02\/22\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-22T13:56:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-08T15:22:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/bree-carry-baylor-Hl_HaZBCs_8-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2448\" \/>\n\t<meta property=\"og:image:height\" content=\"2448\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe V\u00e9torino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe V\u00e9torino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\\\/\"},\"author\":{\"name\":\"Equipe V\u00e9torino\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/8f60afb04d773f2295479f6eb9cd43e4\"},\"headline\":\"Comment soigner le tartre chez le chien et le chat\",\"datePublished\":\"2022-02-22T13:56:56+00:00\",\"dateModified\":\"2024-08-08T15:22:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\\\/\"},\"wordCount\":1379,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/bree-carry-baylor-Hl_HaZBCs_8-unsplash.jpg\",\"articleSection\":[\"Chat\",\"Chien\",\"Hygi\u00e8ne et bien-\u00eatre pour chat\",\"Hygi\u00e8ne et bien-\u00eatre pour chien\",\"Sant\u00e9 et pr\u00e9vention pour chat\",\"Sant\u00e9 pour chien\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\\\/\",\"name\":\"Comment soigner le tartre chez le chien et le chat - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/bree-carry-baylor-Hl_HaZBCs_8-unsplash.jpg\",\"datePublished\":\"2022-02-22T13:56:56+00:00\",\"dateModified\":\"2024-08-08T15:22:16+00:00\",\"description\":\"Cliquez ici pour d\u00e9couvrir comment soigner le tartre chez le chien et le chat ! Votre animal doit avoir une bonne hygi\u00e8ne bucco-dentaire... !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/bree-carry-baylor-Hl_HaZBCs_8-unsplash.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/bree-carry-baylor-Hl_HaZBCs_8-unsplash.jpg\",\"width\":2448,\"height\":2448,\"caption\":\"Bien pr\u00e9venir l'apparition et l'accumulation de tartre pour votre chien ou votre chat\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2022\\\/02\\\/22\\\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chat\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/champs-sur-marne-77420\\\/boutique\\\/category\\\/chat\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sant\u00e9 et pr\u00e9vention pour chat\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/category\\\/chat\\\/sante-et-prevention-chat\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Comment soigner le tartre chez le chien et le chat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/8f60afb04d773f2295479f6eb9cd43e4\",\"name\":\"Equipe V\u00e9torino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"caption\":\"Equipe V\u00e9torino\"},\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/levignac-31530\\\/boutique\\\/author\\\/equipe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment soigner le tartre chez le chien et le chat - V\u00e9torino","description":"Cliquez ici pour d\u00e9couvrir comment soigner le tartre chez le chien et le chat ! Votre animal doit avoir une bonne hygi\u00e8ne bucco-dentaire... !","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Comment soigner le tartre chez le chien et le chat - V\u00e9torino","og_description":"Cliquez ici pour d\u00e9couvrir comment soigner le tartre chez le chien et le chat ! Votre animal doit avoir une bonne hygi\u00e8ne bucco-dentaire... !","og_url":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/2022\/02\/22\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_published_time":"2022-02-22T13:56:56+00:00","article_modified_time":"2024-08-08T15:22:16+00:00","og_image":[{"width":2448,"height":2448,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/bree-carry-baylor-Hl_HaZBCs_8-unsplash.jpg","type":"image\/jpeg"}],"author":"Equipe V\u00e9torino","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Equipe V\u00e9torino","Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\/#article","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\/"},"author":{"name":"Equipe V\u00e9torino","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/8f60afb04d773f2295479f6eb9cd43e4"},"headline":"Comment soigner le tartre chez le chien et le chat","datePublished":"2022-02-22T13:56:56+00:00","dateModified":"2024-08-08T15:22:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\/"},"wordCount":1379,"commentCount":0,"publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/bree-carry-baylor-Hl_HaZBCs_8-unsplash.jpg","articleSection":["Chat","Chien","Hygi\u00e8ne et bien-\u00eatre pour chat","Hygi\u00e8ne et bien-\u00eatre pour chien","Sant\u00e9 et pr\u00e9vention pour chat","Sant\u00e9 pour chien"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\/","url":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\/","name":"Comment soigner le tartre chez le chien et le chat - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/bree-carry-baylor-Hl_HaZBCs_8-unsplash.jpg","datePublished":"2022-02-22T13:56:56+00:00","dateModified":"2024-08-08T15:22:16+00:00","description":"Cliquez ici pour d\u00e9couvrir comment soigner le tartre chez le chien et le chat ! Votre animal doit avoir une bonne hygi\u00e8ne bucco-dentaire... !","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/bree-carry-baylor-Hl_HaZBCs_8-unsplash.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/02\/bree-carry-baylor-Hl_HaZBCs_8-unsplash.jpg","width":2448,"height":2448,"caption":"Bien pr\u00e9venir l'apparition et l'accumulation de tartre pour votre chien ou votre chat"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/2022\/02\/22\/comment-soigner-le-tartre-chez-le-chien-et-le-chat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Chat","item":"https:\/\/www.vetorino.com\/veterinaire\/champs-sur-marne-77420\/boutique\/category\/chat\/"},{"@type":"ListItem","position":3,"name":"Sant\u00e9 et pr\u00e9vention pour chat","item":"https:\/\/www.vetorino.com\/boutique\/category\/chat\/sante-et-prevention-chat\/"},{"@type":"ListItem","position":4,"name":"Comment soigner le tartre chez le chien et le chat"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]},{"@type":"Person","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/8f60afb04d773f2295479f6eb9cd43e4","name":"Equipe V\u00e9torino","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","caption":"Equipe V\u00e9torino"},"url":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/author\/equipe\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/posts\/296499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/users\/10426"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/comments?post=296499"}],"version-history":[{"count":40,"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/posts\/296499\/revisions"}],"predecessor-version":[{"id":300845,"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/posts\/296499\/revisions\/300845"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/media\/296513"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/media?parent=296499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/categories?post=296499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/tags?post=296499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}