{"id":737525,"date":"2023-09-27T12:13:50","date_gmt":"2023-09-27T10:13:50","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/?p=737525"},"modified":"2025-06-30T11:29:46","modified_gmt":"2025-06-30T09:29:46","slug":"insuffisance-renale-chez-le-chat","status":"publish","type":"post","link":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/2023\/09\/27\/insuffisance-renale-chez-le-chat\/","title":{"rendered":"Insuffisance r\u00e9nale chronique chez le chat : comment savoir si mon chat est atteint et comment le gu\u00e9rir ?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"737525\" class=\"elementor elementor-737525\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0d1f193 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0d1f193\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d8bd3b2\" data-id=\"d8bd3b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76d6bce elementor-widget elementor-widget-post-info\" data-id=\"76d6bce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"post-info.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-inline-items elementor-icon-list-items elementor-post-info\">\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-b8ca39c elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-custom\">\n\t\t\t\t\t\t\t\t\t\tPubli\u00e9 le\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-bbe24d6 elementor-inline-item\" itemprop=\"datePublished\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/2023\/09\/27\/\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-calendar\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-date\">\n\t\t\t\t\t\t\t\t\t\t<time>septembre 27, 2023<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t<\/li>\n\t\t\t\t<li class=\"elementor-icon-list-item elementor-repeater-item-6bff815 elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-clock\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text elementor-post-info__item elementor-post-info__item--type-time\">\n\t\t\t\t\t\t\t\t\t\t<time>12:13<\/time>\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38d6036 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"38d6036\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b54c0fe\" data-id=\"b54c0fe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3888d1d elementor-widget elementor-widget-text-editor\" data-id=\"3888d1d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>L<\/strong><b>&#8216;insuffisance r\u00e9nale chronique (MRC) touche jusqu&#8217;\u00e0 20% des chats, en faisant l&#8217;une des maladies les plus courantes chez ces animaux.<\/b> Dans cet article, d\u00e9couvrez comment reconna\u00eetre les signes pr\u00e9coces de la MRC, les causes de cette maladie silencieuse, et les \u00e9tapes cruciales pour aider votre chat \u00e0 vivre confortablement malgr\u00e9 ce d\u00e9fi de sant\u00e9. Avec une vigilance accrue, une d\u00e9tection pr\u00e9coce et des mesures adapt\u00e9es, vous pouvez offrir \u00e0 votre compagnon f\u00e9lin une vie plus longue et plus saine \ud83d\ude3b<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-641c767 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"641c767\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8913aba\" data-id=\"8913aba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90b5d84 elementor-widget elementor-widget-image\" data-id=\"90b5d84\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/Design-sans-titre-10-1.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62c21d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62c21d5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a569011\" data-id=\"a569011\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a3ffe4c elementor-widget elementor-widget-heading\" data-id=\"a3ffe4c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quelles sont les causes de la maladie r\u00e9nale chronique ? \ud83e\uddd0<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b1338ec elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b1338ec\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-988d554\" data-id=\"988d554\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cb5b48 elementor-widget elementor-widget-text-editor\" data-id=\"6cb5b48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La maladie r\u00e9nale chronique est une maladie <strong>lentement progressive et irr\u00e9versible<\/strong>. Elle aboutit \u00e0 une r\u00e9duction de la fonctionnalit\u00e9 du rein. Jusqu&#8217;\u00e0 <strong>20% des chats peuvent \u00eatre touch\u00e9s par cette maladie<\/strong>. Il s\u2019agit d\u2019une des <a href=\"https:\/\/fr.virbac.com\/home\/toutes-les-maladies\/maladies-races-chats.html\">maladies les plus fr\u00e9quentes<\/a> chez le chat.\u00a0<\/p><p>Les causes de la maladie r\u00e9nale chronique sont nombreuses et multiples. Il faut noter que dans la plupart des cas, l\u2019origine de l\u2019apparition de cette maladie restera inconnue. Certains chats peuvent \u00eatre \u00e0 risque. L\u2019exemple le plus connu est le chat de race persan qui peut poss\u00e9der une pr\u00e9disposition g\u00e9n\u00e9tique \u00e0 une maladie du rein appel\u00e9e \u00ab polykystose r\u00e9nale \u00bb.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b093b31 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b093b31\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ba3348e\" data-id=\"ba3348e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a4ac2b5 elementor-widget elementor-widget-heading\" data-id=\"a4ac2b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quels signes peuvent faire suspecter une maladie r\u00e9nale chronique ? \ud83e\udd12<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-710b16a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"710b16a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e1300e2\" data-id=\"e1300e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3182354 elementor-widget elementor-widget-text-editor\" data-id=\"3182354\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La maladie r\u00e9nale chronique peut conduire \u00e0 une insuffisance r\u00e9nale. Elle touche principalement les <strong>chats \u00e2g\u00e9s de plus de 8 ans<\/strong>. Les signes les plus fr\u00e9quents de la MRC f\u00e9line sont <strong>l\u2019augmentation de la consommation d\u2019eau, la baisse de l\u2019app\u00e9tit et la perte de poids<\/strong>. Il est parfois difficile de mesurer la quantit\u00e9 d\u2019eau bue par un chat mais il est en revanche facile de le peser r\u00e9guli\u00e8rement. C\u2019est important de <strong>suivre l\u2019\u00e9volution de son poids<\/strong> car, chez un chat d\u00e9j\u00e0 amaigri au moment du diagnostic, le pronostic de la MRC sera plus sombre que chez un chat de poids normal.<\/p><p>Si votre chat pr\u00e9sente ces signes, une consultation chez votre v\u00e9t\u00e9rinaire traitant permettra d\u2019\u00e9tablir un diagnostic. Votre v\u00e9t\u00e9rinaire peut \u00eatre amen\u00e9 \u00e0 faire des examens compl\u00e9mentaires tels qu&#8217;une prise de sang ou un pr\u00e9l\u00e8vement d\u2019urines.\u00a0<\/p><p>Il est \u00e9galement possible de surveiller le fonctionnement des reins en faisant des bilans sanguins r\u00e9guliers sur un chat \u00e2g\u00e9. Ainsi le diagnostic sera pr\u00e9coce pour une prise en charge d\u00e8s le stade d\u00e9butant.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a31d87f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a31d87f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7db3c26\" data-id=\"7db3c26\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6cfc636 elementor-widget elementor-widget-heading\" data-id=\"6cfc636\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Comment confirmer une maladie r\u00e9nale chronique ? \ud83e\uddd1\ud83c\udffb\u200d\u2695\ufe0f<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8679983 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8679983\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fbc0651\" data-id=\"fbc0651\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d3690f5 elementor-widget elementor-widget-text-editor\" data-id=\"d3690f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Des <strong>examens v\u00e9t\u00e9rinaires<\/strong> sont n\u00e9cessaires pour confirmer un diagnostic de MRC. Si les reins fonctionnent moins bien, la densit\u00e9 de l\u2019urine sera par exemple anormalement faible et la concentration sanguine de plusieurs marqueurs de la maladie sera au contraire augment\u00e9e.<br \/><br \/>Pendant longtemps, le v\u00e9t\u00e9rinaire \u00e9valuait la fonction r\u00e9nale en se basant essentiellement sur les taux d\u2019ur\u00e9e et de cr\u00e9atinine dans le sang. Ces deux param\u00e8tres n\u2019\u00e9voluent cependant \u00e0 la hausse que lorsque le chat est insuffisant r\u00e9nal, c\u2019est-\u00e0-dire qu\u2019il exprime d\u00e9j\u00e0 des sympt\u00f4mes. \u00c0 ce stade, au moins 75 % de la fonction r\u00e9nale est alors alt\u00e9r\u00e9e ! D\u2019autres tests diagnostiques, plus sensibles, ont heureusement fait leur apparition et permettent de rep\u00e9rer une MRC \u00e0 un stade pr\u00e9coce.<br \/><br \/><strong>Le dosage de la dim\u00e9thylarginine sym\u00e9trique<\/strong> (SDMA) est actuellement un des tests les plus int\u00e9ressants : la SDMA d\u00e9rive du m\u00e9tabolisme des prot\u00e9ines et elle est quasiment exclusivement \u00e9limin\u00e9e dans l\u2019urine. Sa concentration plasmatique augmente d\u00e8s que le taux de filtration r\u00e9nale diminue d\u2019environ 25 %, ce qui se produit plusieurs mois avant que des sympt\u00f4mes de MRC n\u2019apparaissent.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d224e5d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d224e5d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-29ce1cd\" data-id=\"29ce1cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b08c509 elementor-widget elementor-widget-heading\" data-id=\"b08c509\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Que faire si mon chat est atteint de cette maladie ? \ud83e\udd37\ud83c\udffb\u200d\u2640\ufe0f <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e81fdfc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e81fdfc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8e7949b\" data-id=\"8e7949b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-514f626 elementor-widget elementor-widget-text-editor\" data-id=\"514f626\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>La maladie r\u00e9nale chronique ne se gu\u00e9rit pas. La prise en charge a pour but de ralentir l\u2019\u00e9volution pour que le chat vive plus longtemps. Lorsqu\u2019une MRC est d\u00e9pist\u00e9e t\u00f4t au cours de son \u00e9volution, il est possible d\u2019agir efficacement par le <strong>biais de l\u2019alimentation<\/strong>. Il est prouv\u00e9 que la mise en place rapide de certaines mesures di\u00e9t\u00e9tiques peut avoir une influence tr\u00e8s positive sur la fonction r\u00e9nale du chat. Par exemple, d\u00e8s le premier stade de la maladie r\u00e9nale, il est conseill\u00e9 de <strong>r\u00e9duire l\u00e9g\u00e8rement l\u2019apport alimentaire en phosphore<\/strong>.<br \/><br \/>Limiter l\u2019apport en prot\u00e9ines n\u2019a d\u2019int\u00e9r\u00eat que lorsque la maladie est plus \u00e9volu\u00e9e et cette restriction doit \u00eatre progressive, pour \u00e9viter que le chat ne \u00ab consomme \u00bb ses propres prot\u00e9ines (notamment musculaires) pour couvrir ses besoins nutritionnels. Le chat est un carnivore qui exige une <strong>quantit\u00e9 importante de prot\u00e9ines pour produire de l\u2019\u00e9nergie<\/strong>.<br \/><br \/>Il existe des <strong>aliments sp\u00e9cialement formul\u00e9s pour les chats \u00e0 MRC<\/strong>, qui prennent en compte les objectifs nutritionnels particuliers des chats dont les reins fonctionnent moins bien. Ces \u00ab <strong>aliments \u00e0 vis\u00e9e r\u00e9nale<\/strong> \u00bb contiennent en g\u00e9n\u00e9ral moins de sodium que des aliments d\u2019entretien standard car l\u2019hypertension art\u00e9rielle accompagne fr\u00e9quemment la maladie r\u00e9nale. Ces aliments d\u00e9di\u00e9s apportent en revanche <strong>plus d\u2019\u00e9nergie, d\u2019antioxydants et d\u2019acides gras om\u00e9ga 3<\/strong> que les aliments d\u2019entretien.<br \/><br \/>Si n\u00e9cessaire, le v\u00e9t\u00e9rinaire pourra aussi prescrire un m\u00e9dicament \u00e0 donner tous les jours au chat, pour l\u2019aider \u00e0 \u00e9liminer toutes les toxines susceptibles de s\u2019accumuler dans sa circulation sanguine.<br \/>A un stade d\u00e9butant, un <strong>changement d\u2019alimentation<\/strong> et un <strong>traitement m\u00e9dical<\/strong> permettent souvent de <strong>stabiliser la maladie r\u00e9nale et l\u2019esp\u00e9rance de vie du chat<\/strong> d\u2019au moins 3 ans. En revanche, quand une MRC est diagnostiqu\u00e9e \u00e0 un stade tr\u00e8s avanc\u00e9, l\u2019esp\u00e9rance de vie du chat ne d\u00e9passe en g\u00e9n\u00e9ral pas 3,5 mois.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a6b238c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a6b238c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a1073b3\" data-id=\"a1073b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f10847 elementor-widget elementor-widget-image\" data-id=\"3f10847\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/Design-sans-titre-11-1.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec7d090 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ec7d090\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e221fb9\" data-id=\"e221fb9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43046ee elementor-widget elementor-widget-text-editor\" data-id=\"43046ee\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tous ces \u00e9l\u00e9ments soulignent <strong>l\u2019importance de suivre de pr\u00e8s le poids, le comportement alimentaire et la sant\u00e9 d\u2019un chat \u00e2g\u00e9<\/strong>. Des <strong>visites v\u00e9t\u00e9rinaires annuelles<\/strong> aident \u00e0 mieux surveiller le fonctionnement r\u00e9nal et, en cas de maladie r\u00e9nale d\u00e9butante, ce suivi permettra de v\u00e9rifier que les modifications apport\u00e9es au r\u00e9gime alimentaire du chat permettent de stabiliser la situation. \ud83d\udc3e\u2764\ufe0f<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c7151b8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7151b8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56b08e2\" data-id=\"56b08e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff2e1aa elementor-widget elementor-widget-spacer\" data-id=\"ff2e1aa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34d9fd8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34d9fd8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8b0d85d\" data-id=\"8b0d85d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f1ae16 elementor-widget elementor-widget-heading\" data-id=\"2f1ae16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Produits recommand\u00e9s pour l'insufisance r\u00e9nale chronique chez Le Chat<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6c8c850 product_alcyon elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6c8c850\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3541e7d\" data-id=\"3541e7d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f76fe75 elementor-widget elementor-widget-image\" data-id=\"f76fe75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/HPM-Early-Kidney-Cat_3KG_face-1.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad5cced elementor-widget elementor-widget-heading\" data-id=\"ad5cced\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">CAT KJ1 EARLY KIDNEY JOINT<br><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce55f72 elementor-widget elementor-widget-text-editor\" data-id=\"ce55f72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aliment di\u00e9t\u00e9tique et \u00e9quilibr\u00e9 destin\u00e9 au soutien de la fonction r\u00e9nale lors d\u2019insuffisance r\u00e9nale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60277a0 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"60277a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/aurignac-31420\/boutique\/\/product\/vet-hpm-cat-kj1-early-kidney-joint\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1838776\" data-id=\"1838776\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4699787 elementor-widget elementor-widget-image\" data-id=\"4699787\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/HPM_Cat-Early-Kidney-Joint_85g_face-1.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da487f0 elementor-widget elementor-widget-heading\" data-id=\"da487f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">WET CAT KJ1 EARLY KIDNEY JOINT (SACHETS)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87bb9a3 elementor-widget elementor-widget-text-editor\" data-id=\"87bb9a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aliment complet di\u00e9t\u00e9tique humide pour chats en soutien\u00a0 de la fonction r\u00e9nale.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce390d2 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ce390d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/aurignac-31420\/boutique\/\/product\/vet-hpm-wet-cat-kj1-early-kidney-joint-sachets\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f6917f7\" data-id=\"f6917f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fde4078 elementor-widget elementor-widget-image\" data-id=\"fde4078\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/HPM_Cat_Kidney_Joint_85g_face.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77fa04f elementor-widget elementor-widget-heading\" data-id=\"77fa04f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">WET CAT KJ2 KIDNEY JOINT<br><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c73f8e9 elementor-widget elementor-widget-text-editor\" data-id=\"c73f8e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nourriture humide sous forme de mousse formul\u00e9e en cas d\u2019insuffisance r\u00e9nale.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7901e8 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"f7901e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/aurignac-31420\/boutique\/\/product\/vet-hpm-wet-cat-kj2-kidney-joint-barquettes\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bad7d17 product_centravet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bad7d17\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8304e4f\" data-id=\"8304e4f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-792dc08 elementor-widget elementor-widget-image\" data-id=\"792dc08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/HPM-Early-Kidney-Cat_3KG_face-1.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-837836f elementor-widget elementor-widget-heading\" data-id=\"837836f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">CAT KJ1 EARLY KIDNEY JOINT<br><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-216a95b elementor-widget elementor-widget-text-editor\" data-id=\"216a95b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aliment di\u00e9t\u00e9tique et \u00e9quilibr\u00e9 destin\u00e9 au soutien de la fonction r\u00e9nale lors d\u2019insuffisance r\u00e9nale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0bac0c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"c0bac0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/aurignac-31420\/boutique\/\/product\/veterinary-hpm-cat-kj1-early-kidney-joint\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7d817b3\" data-id=\"7d817b3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-548939d elementor-widget elementor-widget-image\" data-id=\"548939d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/HPM_Cat-Early-Kidney-Joint_85g_face-1.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf4d6dc elementor-widget elementor-widget-heading\" data-id=\"cf4d6dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">WET CAT KJ1 EARLY KIDNEY JOINT (SACHETS)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb3a20e elementor-widget elementor-widget-text-editor\" data-id=\"eb3a20e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aliment complet di\u00e9t\u00e9tique humide pour chats en soutien\u00a0 de la fonction r\u00e9nale.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-724452a elementor-align-center elementor-widget elementor-widget-button\" data-id=\"724452a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/aurignac-31420\/boutique\/\/product\/veterinary-hpm-cat-kj1-early-kidney-joint-sachet-repas\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-51edbb9\" data-id=\"51edbb9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2339b80 elementor-widget elementor-widget-image\" data-id=\"2339b80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/HPM_Cat_Kidney_Joint_85g_face.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10d534c elementor-widget elementor-widget-heading\" data-id=\"10d534c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">WET CAT KJ2 KIDNEY JOINT<br><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ab370b elementor-widget elementor-widget-text-editor\" data-id=\"6ab370b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nourriture humide sous forme de mousse formul\u00e9e en cas d\u2019insuffisance r\u00e9nale.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e2f5eb3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"e2f5eb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/aurignac-31420\/boutique\/\/product\/veterinary-hpm-cat-kj2-kidney-joint-mousse-boite\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0cd29d0 product_coveto elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0cd29d0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-f6e6b8e\" data-id=\"f6e6b8e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a16ff4b elementor-widget elementor-widget-image\" data-id=\"a16ff4b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/HPM-Early-Kidney-Cat_3KG_face-1.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa430f5 elementor-widget elementor-widget-heading\" data-id=\"fa430f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">CAT KJ1 EARLY KIDNEY JOINT<br><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b8f624 elementor-widget elementor-widget-text-editor\" data-id=\"7b8f624\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aliment di\u00e9t\u00e9tique et \u00e9quilibr\u00e9 destin\u00e9 au soutien de la fonction r\u00e9nale lors d\u2019insuffisance r\u00e9nale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-672ba5c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"672ba5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/aurignac-31420\/boutique\/\/product\/cat-kj1-early-kidney-joint\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-529e309\" data-id=\"529e309\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b2969f0 elementor-widget elementor-widget-image\" data-id=\"b2969f0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/HPM_Cat-Early-Kidney-Joint_85g_face-1.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77c2cb2 elementor-widget elementor-widget-heading\" data-id=\"77c2cb2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">WET CAT KJ1 EARLY KIDNEY JOINT (SACHETS)\u200b\u200b<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f9f70e7 elementor-widget elementor-widget-text-editor\" data-id=\"f9f70e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Aliment complet di\u00e9t\u00e9tique humide pour chats en soutien\u00a0 de la fonction r\u00e9nale.<\/p><p>\u00a0<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-204bd35 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"204bd35\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/aurignac-31420\/boutique\/\/product\/wet-cat-kj1-early-kidney-joint-sachets\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8b661ea\" data-id=\"8b661ea\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f038b6b elementor-widget elementor-widget-image\" data-id=\"f038b6b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/HPM_Cat_Kidney_Joint_85g_face.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1db5e2c elementor-widget elementor-widget-heading\" data-id=\"1db5e2c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">WET CAT KJ2 KIDNEY JOINT<br><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-077f69d elementor-widget elementor-widget-text-editor\" data-id=\"077f69d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nourriture humide sous forme de mousse formul\u00e9e en cas d\u2019insuffisance r\u00e9nale.<\/p><p>\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d64884 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3d64884\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/aurignac-31420\/boutique\/\/product\/wet-cat-kj2-kidney-joint-barquettes\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le produit<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66ad442 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"66ad442\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0c13549\" data-id=\"0c13549\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ea32e69 elementor-widget elementor-widget-text-editor\" data-id=\"ea32e69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sources<br \/>MARINO C.L., et al., \u00ab Prevalence and classification of chronic kidney disease in cats randomly selected from four age groups and in cats recruited for degenerative joint disease studies \u00bb, J. Fel. Med. Surg., 2014, 16, 465-472.<br \/>INTERNATIONAL RENAL INTEREST SOCIETY (IRIS), \u201cTreatment recommendations for CKD in cats\u201d, 2023, www.iris-kidney.com\/pdf\/IRIS_CAT_Treatment_Recommendations_2023.pdf<br \/>BOYD L.M., et al., \u201cSurvival in Cats with Naturally Occurring Chronic Kidney Disease (2000\u20132002)\u201d, J. Vet. Intern. Med., 2008, 22, 1111\u20131117.<br \/>HALL J.A., et al., \u00ab Positive impact of nutritional interventions on serum symmetric dimethylarginine and creatinine concentrations in client-owned geriatric cats\u201d, PLoS One, 2016, 11, e0153654.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6639836 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6639836\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bf44a18\" data-id=\"bf44a18\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d91f97d elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"d91f97d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/Virbac_logo_CMYK-1.svg.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e8827d elementor-widget elementor-widget-text-editor\" data-id=\"7e8827d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Article r\u00e9dig\u00e9 en partenariat avec le laboratoire Virbac.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>L&#8216;insuffisance r\u00e9nale chronique (MRC) touche jusqu&#8217;\u00e0 20% des chats, en faisant l&#8217;une des maladies les plus courantes chez ces animaux. Dans cet article, d\u00e9couvrez comment reconna\u00eetre les signes pr\u00e9coces de la MRC, les causes de cette maladie silencieuse, et les \u00e9tapes cruciales pour aider votre chat \u00e0 vivre confortablement malgr\u00e9 ce d\u00e9fi de sant\u00e9. Avec [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":894020,"comment_status":"open","ping_status":"open","sticky":true,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[14089,14086,14095],"tags":[],"class_list":["post-737525","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentation-chat","category-chat","category-sante-et-prevention-chat"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Insuffisance r\u00e9nale chronique chez le chat : comment savoir si mon chat est atteint et comment le gu\u00e9rir ? - V\u00e9torino<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Insuffisance r\u00e9nale chronique chez le chat : comment savoir si mon chat est atteint et comment le gu\u00e9rir ? - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"L&#8216;insuffisance r\u00e9nale chronique (MRC) touche jusqu&#8217;\u00e0 20% des chats, en faisant l&#8217;une des maladies les plus courantes chez ces animaux. Dans cet article, d\u00e9couvrez comment reconna\u00eetre les signes pr\u00e9coces de la MRC, les causes de cette maladie silencieuse, et les \u00e9tapes cruciales pour aider votre chat \u00e0 vivre confortablement malgr\u00e9 ce d\u00e9fi de sant\u00e9. Avec [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/2023\/09\/27\/insuffisance-renale-chez-le-chat\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-27T10:13:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-30T09:29:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/calcul-renale-chat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"241\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Pierre Desouches\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pierre Desouches\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/insuffisance-renale-chez-le-chat\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/insuffisance-renale-chez-le-chat\\\/\"},\"author\":{\"name\":\"Pierre Desouches\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/b5521875cca3f2a28ed80d8bc458f092\"},\"headline\":\"Insuffisance r\u00e9nale chronique chez le chat : comment savoir si mon chat est atteint et comment le gu\u00e9rir ?\",\"datePublished\":\"2023-09-27T10:13:50+00:00\",\"dateModified\":\"2025-06-30T09:29:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/insuffisance-renale-chez-le-chat\\\/\"},\"wordCount\":1417,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/insuffisance-renale-chez-le-chat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/calcul-renale-chat.jpg\",\"articleSection\":[\"Alimentation pour chat\",\"Chat\",\"Sant\u00e9 et pr\u00e9vention pour chat\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/insuffisance-renale-chez-le-chat\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/insuffisance-renale-chez-le-chat\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/insuffisance-renale-chez-le-chat\\\/\",\"name\":\"Insuffisance r\u00e9nale chronique chez le chat : comment savoir si mon chat est atteint et comment le gu\u00e9rir ? - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/insuffisance-renale-chez-le-chat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/insuffisance-renale-chez-le-chat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/calcul-renale-chat.jpg\",\"datePublished\":\"2023-09-27T10:13:50+00:00\",\"dateModified\":\"2025-06-30T09:29:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/insuffisance-renale-chez-le-chat\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/insuffisance-renale-chez-le-chat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/insuffisance-renale-chez-le-chat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/calcul-renale-chat.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/calcul-renale-chat.jpg\",\"width\":1000,\"height\":241},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2023\\\/09\\\/27\\\/insuffisance-renale-chez-le-chat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chat\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/champs-sur-marne-77420\\\/boutique\\\/category\\\/chat\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Insuffisance r\u00e9nale chronique chez le chat : comment savoir si mon chat est atteint et comment le gu\u00e9rir ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/b5521875cca3f2a28ed80d8bc458f092\",\"name\":\"Pierre Desouches\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f2a83ff1a698fcad3ea07d919ba7d1d66dc073d14c2a5195e64dbc5dc2d55d34?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f2a83ff1a698fcad3ea07d919ba7d1d66dc073d14c2a5195e64dbc5dc2d55d34?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f2a83ff1a698fcad3ea07d919ba7d1d66dc073d14c2a5195e64dbc5dc2d55d34?s=96&d=mm&r=g\",\"caption\":\"Pierre Desouches\"},\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/levignac-31530\\\/boutique\\\/author\\\/pierre-desouchesgmail-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Insuffisance r\u00e9nale chronique chez le chat : comment savoir si mon chat est atteint et comment le gu\u00e9rir ? - V\u00e9torino","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Insuffisance r\u00e9nale chronique chez le chat : comment savoir si mon chat est atteint et comment le gu\u00e9rir ? - V\u00e9torino","og_description":"L&#8216;insuffisance r\u00e9nale chronique (MRC) touche jusqu&#8217;\u00e0 20% des chats, en faisant l&#8217;une des maladies les plus courantes chez ces animaux. Dans cet article, d\u00e9couvrez comment reconna\u00eetre les signes pr\u00e9coces de la MRC, les causes de cette maladie silencieuse, et les \u00e9tapes cruciales pour aider votre chat \u00e0 vivre confortablement malgr\u00e9 ce d\u00e9fi de sant\u00e9. Avec [&hellip;]","og_url":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/2023\/09\/27\/insuffisance-renale-chez-le-chat\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_published_time":"2023-09-27T10:13:50+00:00","article_modified_time":"2025-06-30T09:29:46+00:00","og_image":[{"width":1000,"height":241,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/calcul-renale-chat.jpg","type":"image\/jpeg"}],"author":"Pierre Desouches","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Pierre Desouches","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/insuffisance-renale-chez-le-chat\/#article","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/insuffisance-renale-chez-le-chat\/"},"author":{"name":"Pierre Desouches","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/b5521875cca3f2a28ed80d8bc458f092"},"headline":"Insuffisance r\u00e9nale chronique chez le chat : comment savoir si mon chat est atteint et comment le gu\u00e9rir ?","datePublished":"2023-09-27T10:13:50+00:00","dateModified":"2025-06-30T09:29:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/insuffisance-renale-chez-le-chat\/"},"wordCount":1417,"commentCount":0,"publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/insuffisance-renale-chez-le-chat\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/calcul-renale-chat.jpg","articleSection":["Alimentation pour chat","Chat","Sant\u00e9 et pr\u00e9vention pour chat"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/insuffisance-renale-chez-le-chat\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/insuffisance-renale-chez-le-chat\/","url":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/insuffisance-renale-chez-le-chat\/","name":"Insuffisance r\u00e9nale chronique chez le chat : comment savoir si mon chat est atteint et comment le gu\u00e9rir ? - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/insuffisance-renale-chez-le-chat\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/insuffisance-renale-chez-le-chat\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/calcul-renale-chat.jpg","datePublished":"2023-09-27T10:13:50+00:00","dateModified":"2025-06-30T09:29:46+00:00","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/insuffisance-renale-chez-le-chat\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/insuffisance-renale-chez-le-chat\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/insuffisance-renale-chez-le-chat\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/calcul-renale-chat.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2023\/09\/calcul-renale-chat.jpg","width":1000,"height":241},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/2023\/09\/27\/insuffisance-renale-chez-le-chat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Chat","item":"https:\/\/www.vetorino.com\/veterinaire\/champs-sur-marne-77420\/boutique\/category\/chat\/"},{"@type":"ListItem","position":3,"name":"Insuffisance r\u00e9nale chronique chez le chat : comment savoir si mon chat est atteint et comment le gu\u00e9rir ?"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]},{"@type":"Person","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/b5521875cca3f2a28ed80d8bc458f092","name":"Pierre Desouches","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f2a83ff1a698fcad3ea07d919ba7d1d66dc073d14c2a5195e64dbc5dc2d55d34?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f2a83ff1a698fcad3ea07d919ba7d1d66dc073d14c2a5195e64dbc5dc2d55d34?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f2a83ff1a698fcad3ea07d919ba7d1d66dc073d14c2a5195e64dbc5dc2d55d34?s=96&d=mm&r=g","caption":"Pierre Desouches"},"url":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/author\/pierre-desouchesgmail-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/posts\/737525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/comments?post=737525"}],"version-history":[{"count":16,"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/posts\/737525\/revisions"}],"predecessor-version":[{"id":1395495,"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/posts\/737525\/revisions\/1395495"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/media\/894020"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/media?parent=737525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/categories?post=737525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/tags?post=737525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}