{"id":1337095,"date":"2025-05-20T09:53:31","date_gmt":"2025-05-20T07:53:31","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/chat-adult-sterilised-cat-saumon-sachet-repas\/"},"modified":"2026-08-24T16:09:57","modified_gmt":"2026-08-24T14:09:57","slug":"chat-adult-sterilised-cat-saumon-sachet-repas","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/product\/chat-adult-sterilised-cat-saumon-sachet-repas\/","title":{"rendered":"Adulte Sterilised &#8211; \u00e9minc\u00e9s chat saumon en sauce"},"content":{"rendered":"<p>Votre chat va adorer le<strong> go\u00fbt d\u00e9licieux<\/strong> de ces tendres bouch\u00e9es en sauce HILL&#8217;S SCIENCE PLAN Sterilised Cat Adult au saumon.<\/p>\n<p>Le parfait \u00e9quilibre entre go\u00fbt et nutrition avec une<strong> formule unique de gestion de poids<\/strong> pour aider les chats st\u00e9rilis\u00e9s \u00e0 rester minces.<\/p>\n<p>Fabriqu\u00e9 \u00e0 partir d\u2019<strong>ingr\u00e9dients de haute qualit\u00e9 et faciles \u00e0 dig\u00e9rer.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Tendres morceaux<\/strong> de saumon en sauce pour chats adultes, pour le <strong>maintien du poids et la sant\u00e9 urinaire<\/strong> apr\u00e8s la st\u00e9rilisation.<\/p>\n<p>Contient des <strong>prot\u00e9ines de haute qualit\u00e9<\/strong> pour la <strong>masse musculaire<\/strong> et des om\u00e9ga-3 et 6 pour<strong> un syst\u00e8me immunitaire sain.<\/strong><\/p>\n","protected":false},"featured_media":1937890,"template":"","meta":[],"product_cat":[12551,12583,2697],"product_tag":[],"class_list":["post-1337095","product","type-product","status-publish","has-post-thumbnail","product_cat-alimentation-du-chat","product_cat-alimentation-premium-pour-chat","product_cat-chat","pa_marque-hills-pet-nutrition","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Adulte Sterilised - \u00e9minc\u00e9s chat saumon en sauce Hill&#039;s - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Tendres morceaux de saumon en sauce pour chats adultes, pour le maintien du poids et la sant\u00e9 urinaire apr\u00e8s la st\u00e9rilisation.  Contient des prot\u00e9ines de haute qualit\u00e9 pour la masse musculaire et des om\u00e9ga-3 et 6 pour un syst\u00e8me immunitaire sain.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adulte Sterilised - \u00e9minc\u00e9s chat saumon en sauce Hill&#039;s - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Tendres morceaux de saumon en sauce pour chats adultes, pour le maintien du poids et la sant\u00e9 urinaire apr\u00e8s la st\u00e9rilisation.  Contient des prot\u00e9ines de haute qualit\u00e9 pour la masse musculaire et des om\u00e9ga-3 et 6 pour un syst\u00e8me immunitaire sain.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/product\/chat-adult-sterilised-cat-saumon-sachet-repas\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-24T14:09:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/05\/52742083766_1-science-plan-sachets-repas-chat-sterilised-saumon.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"21,20&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/chat-adult-sterilised-cat-saumon-sachet-repas\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/chat-adult-sterilised-cat-saumon-sachet-repas\\\/\",\"name\":\"Adulte Sterilised - \u00e9minc\u00e9s chat saumon en sauce Hill's - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/chat-adult-sterilised-cat-saumon-sachet-repas\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/chat-adult-sterilised-cat-saumon-sachet-repas\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/52742083766_1-science-plan-sachets-repas-chat-sterilised-saumon.jpg\",\"datePublished\":\"2025-05-20T07:53:31+00:00\",\"dateModified\":\"2026-08-24T14:09:57+00:00\",\"description\":\"Tendres morceaux de saumon en sauce pour chats adultes, pour le maintien du poids et la sant\u00e9 urinaire apr\u00e8s la st\u00e9rilisation. Contient des prot\u00e9ines de haute qualit\u00e9 pour la masse musculaire et des om\u00e9ga-3 et 6 pour un syst\u00e8me immunitaire sain.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/chat-adult-sterilised-cat-saumon-sachet-repas\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/chat-adult-sterilised-cat-saumon-sachet-repas\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/chat-adult-sterilised-cat-saumon-sachet-repas\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/52742083766_1-science-plan-sachets-repas-chat-sterilised-saumon.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/52742083766_1-science-plan-sachets-repas-chat-sterilised-saumon.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/chat-adult-sterilised-cat-saumon-sachet-repas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Adulte Sterilised &#8211; \u00e9minc\u00e9s chat saumon en sauce\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Hill&#039;s\" \/>\n<meta property=\"product:price:amount\" content=\"21.20\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"C-HCT068\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adulte Sterilised - \u00e9minc\u00e9s chat saumon en sauce Hill's - V\u00e9torino","description":"Tendres morceaux de saumon en sauce pour chats adultes, pour le maintien du poids et la sant\u00e9 urinaire apr\u00e8s la st\u00e9rilisation.  Contient des prot\u00e9ines de haute qualit\u00e9 pour la masse musculaire et des om\u00e9ga-3 et 6 pour un syst\u00e8me immunitaire sain.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Adulte Sterilised - \u00e9minc\u00e9s chat saumon en sauce Hill's - V\u00e9torino","og_description":"Tendres morceaux de saumon en sauce pour chats adultes, pour le maintien du poids et la sant\u00e9 urinaire apr\u00e8s la st\u00e9rilisation.  Contient des prot\u00e9ines de haute qualit\u00e9 pour la masse musculaire et des om\u00e9ga-3 et 6 pour un syst\u00e8me immunitaire sain.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/product\/chat-adult-sterilised-cat-saumon-sachet-repas\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-08-24T14:09:57+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/05\/52742083766_1-science-plan-sachets-repas-chat-sterilised-saumon.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"21,20&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/chat-adult-sterilised-cat-saumon-sachet-repas\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/chat-adult-sterilised-cat-saumon-sachet-repas\/","name":"Adulte Sterilised - \u00e9minc\u00e9s chat saumon en sauce Hill's - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/chat-adult-sterilised-cat-saumon-sachet-repas\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/chat-adult-sterilised-cat-saumon-sachet-repas\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/05\/52742083766_1-science-plan-sachets-repas-chat-sterilised-saumon.jpg","datePublished":"2025-05-20T07:53:31+00:00","dateModified":"2026-08-24T14:09:57+00:00","description":"Tendres morceaux de saumon en sauce pour chats adultes, pour le maintien du poids et la sant\u00e9 urinaire apr\u00e8s la st\u00e9rilisation. Contient des prot\u00e9ines de haute qualit\u00e9 pour la masse musculaire et des om\u00e9ga-3 et 6 pour un syst\u00e8me immunitaire sain.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/chat-adult-sterilised-cat-saumon-sachet-repas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/chat-adult-sterilised-cat-saumon-sachet-repas\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/chat-adult-sterilised-cat-saumon-sachet-repas\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/05\/52742083766_1-science-plan-sachets-repas-chat-sterilised-saumon.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/05\/52742083766_1-science-plan-sachets-repas-chat-sterilised-saumon.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/chat-adult-sterilised-cat-saumon-sachet-repas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Adulte Sterilised &#8211; \u00e9minc\u00e9s chat saumon en sauce"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Hill's","product_price_amount":"21.20","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"C-HCT068","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/product\/1337095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/media\/1937890"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/media?parent=1337095"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/product_cat?post=1337095"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/levignac-31530\/boutique\/wp-json\/wp\/v2\/product_tag?post=1337095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}