{"id":177190,"date":"2021-05-04T18:44:23","date_gmt":"2021-05-04T16:44:23","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/equizyme-poudre\/"},"modified":"2026-02-23T11:39:27","modified_gmt":"2026-02-23T10:39:27","slug":"equizyme-poudre","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/marboz-01851\/boutique\/product\/equizyme-poudre\/","title":{"rendered":"Equizyme Poudre"},"content":{"rendered":"<p>Aliment compl\u00e9mentaire<strong> \u00e0 base d&#8217;enzymes et de ferments lactiques<\/strong> pour chevaux. <strong>R\u00e9gularisation et normalisation de la fonction digestive.<\/strong><\/p>\n<p>Stimule la digestion et aide \u00e0 constituer <strong>la flore intestinale.<\/strong><\/p>\n<p><strong>Utilisation<\/strong> :<\/p>\n<ul>\n<li>Pour les animaux gestants et allaitants et pour les animaux \u00e2g\u00e9s.<\/li>\n<li>Pour les animaux qui doivent atteindre des performances optimales.<\/li>\n<li>Pendant des p\u00e9riodes de stress lors de transitions alimentaires.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Aliment compl\u00e9mentaire<strong> \u00e0 base d&#8217;enzymes et de ferments lactiques<\/strong> pour chevaux. <strong>R\u00e9gularisation et normalisation de la fonction digestive.<\/strong><\/p>\n<p>Stimule la digestion et aide \u00e0 constituer <strong>la flore intestinale.<\/strong><\/p>\n<p><strong>Utilisation<\/strong> :<\/p>\n<ul>\n<li>Pour les animaux gestants et allaitants et pour les animaux \u00e2g\u00e9s.<\/li>\n<li>Pour les animaux qui doivent atteindre des performances optimales.<\/li>\n<li>Pendant des p\u00e9riodes de stress lors de transitions alimentaires.<\/li>\n<\/ul>\n","protected":false},"featured_media":1422466,"template":"","meta":[],"product_cat":[12556,12547],"product_tag":[],"class_list":{"0":"post-177190","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-digestion-du-cheval","7":"product_cat-cheval","8":"pa_marque-novactiv","10":"first","11":"outofstock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Equizyme Poudre Nutri-Science - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Aliment compl\u00e9mentaire \u00e0 base d&#039;enzymes et de ferments lactiques pour chevaux. R\u00e9gularisation et normalisation de la fonction digestive.  Stimule la digestion et aide \u00e0 constituer la flore intestinale.  Utilisation :   Pour les animaux gestants et allaitants et pour les animaux \u00e2g\u00e9s.  Pour les animaux qui doivent atteindre des performances optimales.  Pendant des p\u00e9riodes de stress lors de transitions alimentaires.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Equizyme Poudre Nutri-Science - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Aliment compl\u00e9mentaire \u00e0 base d&#039;enzymes et de ferments lactiques pour chevaux. R\u00e9gularisation et normalisation de la fonction digestive.  Stimule la digestion et aide \u00e0 constituer la flore intestinale.  Utilisation :   Pour les animaux gestants et allaitants et pour les animaux \u00e2g\u00e9s.  Pour les animaux qui doivent atteindre des performances optimales.  Pendant des p\u00e9riodes de stress lors de transitions alimentaires.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/marboz-01851\/boutique\/product\/equizyme-poudre\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-23T10:39:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/equizyme-poudre.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"54,18&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"Rupture de stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/equizyme-poudre\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/equizyme-poudre\\\/\",\"name\":\"Equizyme Poudre Nutri-Science - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/equizyme-poudre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/equizyme-poudre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/equizyme-poudre.jpg\",\"datePublished\":\"2021-05-04T16:44:23+00:00\",\"dateModified\":\"2026-02-23T10:39:27+00:00\",\"description\":\"Aliment compl\u00e9mentaire \u00e0 base d'enzymes et de ferments lactiques pour chevaux. R\u00e9gularisation et normalisation de la fonction digestive. Stimule la digestion et aide \u00e0 constituer la flore intestinale. Utilisation : Pour les animaux gestants et allaitants et pour les animaux \u00e2g\u00e9s. Pour les animaux qui doivent atteindre des performances optimales. Pendant des p\u00e9riodes de stress lors de transitions alimentaires.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/equizyme-poudre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/equizyme-poudre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/equizyme-poudre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/equizyme-poudre.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/equizyme-poudre.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/equizyme-poudre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Equizyme Poudre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Nutri-Science\" \/>\n<meta property=\"product:price:amount\" content=\"54.18\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"out of stock\" \/>\n<meta property=\"product:availability\" content=\"out of stock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"A-6655541\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Equizyme Poudre Nutri-Science - V\u00e9torino","description":"Aliment compl\u00e9mentaire \u00e0 base d'enzymes et de ferments lactiques pour chevaux. R\u00e9gularisation et normalisation de la fonction digestive.  Stimule la digestion et aide \u00e0 constituer la flore intestinale.  Utilisation :   Pour les animaux gestants et allaitants et pour les animaux \u00e2g\u00e9s.  Pour les animaux qui doivent atteindre des performances optimales.  Pendant des p\u00e9riodes de stress lors de transitions alimentaires.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Equizyme Poudre Nutri-Science - V\u00e9torino","og_description":"Aliment compl\u00e9mentaire \u00e0 base d'enzymes et de ferments lactiques pour chevaux. R\u00e9gularisation et normalisation de la fonction digestive.  Stimule la digestion et aide \u00e0 constituer la flore intestinale.  Utilisation :   Pour les animaux gestants et allaitants et pour les animaux \u00e2g\u00e9s.  Pour les animaux qui doivent atteindre des performances optimales.  Pendant des p\u00e9riodes de stress lors de transitions alimentaires.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/marboz-01851\/boutique\/product\/equizyme-poudre\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-02-23T10:39:27+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/equizyme-poudre.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"54,18&euro;","Disponibilit\u00e9":"Rupture de stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/equizyme-poudre\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/equizyme-poudre\/","name":"Equizyme Poudre Nutri-Science - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/equizyme-poudre\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/equizyme-poudre\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/equizyme-poudre.jpg","datePublished":"2021-05-04T16:44:23+00:00","dateModified":"2026-02-23T10:39:27+00:00","description":"Aliment compl\u00e9mentaire \u00e0 base d'enzymes et de ferments lactiques pour chevaux. R\u00e9gularisation et normalisation de la fonction digestive. Stimule la digestion et aide \u00e0 constituer la flore intestinale. Utilisation : Pour les animaux gestants et allaitants et pour les animaux \u00e2g\u00e9s. Pour les animaux qui doivent atteindre des performances optimales. Pendant des p\u00e9riodes de stress lors de transitions alimentaires.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/equizyme-poudre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/equizyme-poudre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/equizyme-poudre\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/equizyme-poudre.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/equizyme-poudre.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/equizyme-poudre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Equizyme Poudre"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Nutri-Science","product_price_amount":"54.18","product_price_currency":"EUR","og_availability":"out of stock","product_availability":"out of stock","product_retailer_item_id":"A-6655541","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/marboz-01851\/boutique\/wp-json\/wp\/v2\/product\/177190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/marboz-01851\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/marboz-01851\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/marboz-01851\/boutique\/wp-json\/wp\/v2\/media\/1422466"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/marboz-01851\/boutique\/wp-json\/wp\/v2\/media?parent=177190"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/marboz-01851\/boutique\/wp-json\/wp\/v2\/product_cat?post=177190"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/marboz-01851\/boutique\/wp-json\/wp\/v2\/product_tag?post=177190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}