{"id":186991,"date":"2021-05-31T20:28:17","date_gmt":"2021-05-31T18:28:17","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/wamine-proteostress-petits-animaux\/"},"modified":"2022-05-24T16:47:36","modified_gmt":"2022-05-24T14:47:36","slug":"wamine-proteostress-petits-animaux","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/marboz-01851\/boutique\/product\/wamine-proteostress-petits-animaux\/","title":{"rendered":"Proteostress Petits animaux"},"content":{"rendered":"<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;G\u00e9latine, huile vierge de bourrache Borago officinalis (graine) 30 %, glyc\u00e9rine, Porphyral HSP* (extrait d\u2019algue Porphyra umbilicalis) 7,75 %, cire d\u2019abeille, triglyc\u00e9rides \u00e0 cha\u00eene moyenne.\\n* Ingr\u00e9dient brevet\u00e9.&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:12733,&quot;3&quot;:{&quot;1&quot;:0,&quot;3&quot;:1},&quot;5&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;6&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;7&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;8&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;10&quot;:0,&quot;11&quot;:4,&quot;15&quot;:&quot;Calibri&quot;,&quot;16&quot;:11}\" data-sheets-textstyleruns=\"{&quot;1&quot;:0}\uee10{&quot;1&quot;:36,&quot;2&quot;:{&quot;3&quot;:&quot;Calibri&quot;,&quot;4&quot;:11,&quot;6&quot;:1}}\uee10{&quot;1&quot;:54,&quot;2&quot;:{&quot;3&quot;:&quot;Calibri&quot;,&quot;4&quot;:11}}\uee10{&quot;1&quot;:113,&quot;2&quot;:{&quot;3&quot;:&quot;Calibri&quot;,&quot;4&quot;:11,&quot;6&quot;:1}}\uee10{&quot;1&quot;:133,&quot;2&quot;:{&quot;3&quot;:&quot;Calibri&quot;,&quot;4&quot;:11}}\uee10{&quot;1&quot;:193,&quot;2&quot;:{&quot;3&quot;:&quot;Calibri&quot;,&quot;4&quot;:10,&quot;6&quot;:1}}\">G\u00e9latine, huile vierge de bourrache Borago officinalis (graine) 30 %, glyc\u00e9rine, Porphyral HSP* (extrait d\u2019algue Porphyra umbilicalis) 7,75 %, cire d\u2019abeille, triglyc\u00e9rides \u00e0 cha\u00eene moyenne.<br \/>\n* Ingr\u00e9dient brevet\u00e9.<\/span><\/p>\n<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Une posologie en fonction du poids, pour chiens et chats :\\n\u2022 Jusqu\u2019\u00e0 15 kg \u25b6 1 capsule\/jour.\\n\u2022 Jusqu\u2019\u00e0 30 kg \u25b6 2 capsules\/jour.\\n\u2022 Au-del\u00e0 de 30 kg \u25b6 3 capsules\/jour.\\nPour les chats et petits chiens, il est possible de percer la capsule et administrer le contenu sur les babines ou dans la nourriture.&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:12733,&quot;3&quot;:{&quot;1&quot;:0,&quot;3&quot;:1},&quot;5&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;6&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;7&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;8&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;10&quot;:0,&quot;11&quot;:4,&quot;15&quot;:&quot;Calibri&quot;,&quot;16&quot;:11}\">Une posologie en fonction du poids, pour chiens et chats :<br \/>\n\u2022 Jusqu\u2019\u00e0 15 kg \u25b6 1 capsule\/jour.<br \/>\n\u2022 Jusqu\u2019\u00e0 30 kg \u25b6 2 capsules\/jour.<br \/>\n\u2022 Au-del\u00e0 de 30 kg \u25b6 3 capsules\/jour.<br \/>\nPour les chats et petits chiens, il est possible de percer la capsule et administrer le contenu sur les babines ou dans la nourriture.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p><span data-sheets-value=\"{&quot;1&quot;:2,&quot;2&quot;:&quot;Soutient la lutte contre les stress environnementaux et contribue \u00e0 une meilleure r\u00e9cup\u00e9ration&quot;}\" data-sheets-userformat=\"{&quot;2&quot;:14781,&quot;3&quot;:{&quot;1&quot;:0,&quot;3&quot;:1},&quot;5&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;6&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;7&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;8&quot;:{&quot;1&quot;:[{&quot;1&quot;:2,&quot;2&quot;:0,&quot;5&quot;:{&quot;1&quot;:2,&quot;2&quot;:0}},{&quot;1&quot;:0,&quot;2&quot;:0,&quot;3&quot;:3},{&quot;1&quot;:1,&quot;2&quot;:0,&quot;4&quot;:1}]},&quot;10&quot;:0,&quot;11&quot;:4,&quot;14&quot;:{&quot;1&quot;:3,&quot;3&quot;:1},&quot;15&quot;:&quot;Calibri&quot;,&quot;16&quot;:11}\">Soutient la lutte contre les stress environnementaux et contribue \u00e0 une meilleure r\u00e9cup\u00e9ration<\/span><\/p>\n<p><strong>Aliment compl\u00e9mentaire pour chiens et chats<\/strong><\/p>\n","protected":false},"featured_media":326140,"template":"","meta":[],"product_cat":[2698],"product_tag":[],"class_list":{"0":"post-186991","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-chien","7":"pa_marque-wamine","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Proteostress Petits animaux Wamine - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Soutient la lutte contre les stress environnementaux et contribue \u00e0 une meilleure r\u00e9cup\u00e9ration  Aliment compl\u00e9mentaire pour chiens et chats\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proteostress Petits animaux Wamine - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Soutient la lutte contre les stress environnementaux et contribue \u00e0 une meilleure r\u00e9cup\u00e9ration  Aliment compl\u00e9mentaire pour chiens et chats\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/marboz-01851\/boutique\/product\/wamine-proteostress-petits-animaux\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-24T14:47:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/PROTEOSTRESS-PA-RV10v3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2142\" \/>\n\t<meta property=\"og:image:height\" content=\"2244\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"31,36&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/wamine-proteostress-petits-animaux\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/wamine-proteostress-petits-animaux\\\/\",\"name\":\"Proteostress Petits animaux Wamine - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/wamine-proteostress-petits-animaux\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/wamine-proteostress-petits-animaux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/PROTEOSTRESS-PA-RV10v3.jpg\",\"datePublished\":\"2021-05-31T18:28:17+00:00\",\"dateModified\":\"2022-05-24T14:47:36+00:00\",\"description\":\"Soutient la lutte contre les stress environnementaux et contribue \u00e0 une meilleure r\u00e9cup\u00e9ration Aliment compl\u00e9mentaire pour chiens et chats\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/wamine-proteostress-petits-animaux\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/wamine-proteostress-petits-animaux\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/wamine-proteostress-petits-animaux\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/PROTEOSTRESS-PA-RV10v3.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/PROTEOSTRESS-PA-RV10v3.jpg\",\"width\":2142,\"height\":2244},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/wamine-proteostress-petits-animaux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Proteostress Petits animaux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Wamine\" \/>\n<meta property=\"product:price:amount\" content=\"31.36\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"A-8112365\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proteostress Petits animaux Wamine - V\u00e9torino","description":"Soutient la lutte contre les stress environnementaux et contribue \u00e0 une meilleure r\u00e9cup\u00e9ration  Aliment compl\u00e9mentaire pour chiens et chats","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Proteostress Petits animaux Wamine - V\u00e9torino","og_description":"Soutient la lutte contre les stress environnementaux et contribue \u00e0 une meilleure r\u00e9cup\u00e9ration  Aliment compl\u00e9mentaire pour chiens et chats","og_url":"https:\/\/www.vetorino.com\/veterinaire\/marboz-01851\/boutique\/product\/wamine-proteostress-petits-animaux\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2022-05-24T14:47:36+00:00","og_image":[{"width":2142,"height":2244,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/PROTEOSTRESS-PA-RV10v3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"31,36&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/wamine-proteostress-petits-animaux\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/wamine-proteostress-petits-animaux\/","name":"Proteostress Petits animaux Wamine - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/wamine-proteostress-petits-animaux\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/wamine-proteostress-petits-animaux\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/PROTEOSTRESS-PA-RV10v3.jpg","datePublished":"2021-05-31T18:28:17+00:00","dateModified":"2022-05-24T14:47:36+00:00","description":"Soutient la lutte contre les stress environnementaux et contribue \u00e0 une meilleure r\u00e9cup\u00e9ration Aliment compl\u00e9mentaire pour chiens et chats","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/wamine-proteostress-petits-animaux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/wamine-proteostress-petits-animaux\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/wamine-proteostress-petits-animaux\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/PROTEOSTRESS-PA-RV10v3.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/PROTEOSTRESS-PA-RV10v3.jpg","width":2142,"height":2244},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/wamine-proteostress-petits-animaux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Proteostress Petits animaux"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Wamine","product_price_amount":"31.36","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"A-8112365","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/marboz-01851\/boutique\/wp-json\/wp\/v2\/product\/186991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/marboz-01851\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/marboz-01851\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/marboz-01851\/boutique\/wp-json\/wp\/v2\/media\/326140"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/marboz-01851\/boutique\/wp-json\/wp\/v2\/media?parent=186991"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/marboz-01851\/boutique\/wp-json\/wp\/v2\/product_cat?post=186991"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/marboz-01851\/boutique\/wp-json\/wp\/v2\/product_tag?post=186991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}