{"id":33707,"date":"2020-03-04T21:58:17","date_gmt":"2020-03-04T20:58:17","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-jumbler-kong\/"},"modified":"2024-03-22T14:42:11","modified_gmt":"2024-03-22T13:42:11","slug":"jouet-jumbler-kong","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/meyzieu-69330\/boutique\/product\/jouet-jumbler-kong\/","title":{"rendered":"Jouet Jumbler"},"content":{"rendered":"<p>Le <strong>KONG Jumbler<\/strong> est une balle deux en un pour deux fois plus de divertissement ludique et interactif. La balle de tennis \u00e0 l\u2019int\u00e9rieur et le couineur puissant incitent au jeu. Les poignets du jouet permettent de le ramasser et de le secouer facilement. Le Jumbler est assez solide pour jouer pendant des heures, ce qui le rend pratique pour les parties de lancer\/rapporter. Disponible en \u00a0deux tailles diff\u00e9rentes, le KONG Jumbler garantit des parties de jeu dynamiques entre vous et votre chien.<\/p>\n<ul>\n<li>Le couineur et la balle int\u00e9rieure mobile incitent au jeu<\/li>\n<li>Id\u00e9al pour s\u2019amuser de mani\u00e8re interactive<\/li>\n<li>Les poignets du jouet permettent de le ramasser et de le secouer facilement<\/li>\n<li>Disponible en deux tailles : moyen\/grand et grand\/extra grand<\/li>\n<li>Couleur vari\u00e9e en fonction arrivage fournisseur<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Le <strong>KONG Jumbler<\/strong> est une balle deux en un pour deux fois plus de divertissement ludique et interactif. La balle de tennis \u00e0 l\u2019int\u00e9rieur et le couineur puissant incitent au jeu. Les poignets du jouet permettent de le ramasser et de le secouer facilement. Le Jumbler est assez solide pour jouer pendant des heures, ce qui le rend pratique pour les parties de lancer\/rapporter.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":76636,"template":"","meta":[],"product_cat":[12550,2698,12621],"product_tag":[],"class_list":{"0":"post-33707","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessoires-du-chien","7":"product_cat-chien","8":"product_cat-jeux-educatifs-pour-chien","9":"pa_marque-kong","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jouet Jumbler Kong - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Le KONG Jumbler est une balle deux en un pour deux fois plus de divertissement ludique et interactif. La balle de tennis \u00e0 l\u2019int\u00e9rieur et le couineur puissant incitent au jeu. Les poignets du jouet permettent de le ramasser et de le secouer facilement. Le Jumbler est assez solide pour jouer pendant des heures, ce qui le rend pratique pour les parties de lancer\/rapporter.  &nbsp;\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jouet Jumbler Kong - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Le KONG Jumbler est une balle deux en un pour deux fois plus de divertissement ludique et interactif. La balle de tennis \u00e0 l\u2019int\u00e9rieur et le couineur puissant incitent au jeu. Les poignets du jouet permettent de le ramasser et de le secouer facilement. Le Jumbler est assez solide pour jouer pendant des heures, ce qui le rend pratique pour les parties de lancer\/rapporter.  &nbsp;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/meyzieu-69330\/boutique\/product\/jouet-jumbler-kong\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-22T13:42:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/balle-jumbler-medium-large-chien-72.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-jumbler-kong\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-jumbler-kong\\\/\",\"name\":\"Jouet Jumbler Kong - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-jumbler-kong\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-jumbler-kong\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/balle-jumbler-medium-large-chien-72.jpg\",\"datePublished\":\"2020-03-04T20:58:17+00:00\",\"dateModified\":\"2024-03-22T13:42:11+00:00\",\"description\":\"Le KONG Jumbler est une balle deux en un pour deux fois plus de divertissement ludique et interactif. La balle de tennis \u00e0 l\u2019int\u00e9rieur et le couineur puissant incitent au jeu. Les poignets du jouet permettent de le ramasser et de le secouer facilement. Le Jumbler est assez solide pour jouer pendant des heures, ce qui le rend pratique pour les parties de lancer\\\/rapporter. &nbsp;\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-jumbler-kong\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-jumbler-kong\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-jumbler-kong\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/balle-jumbler-medium-large-chien-72.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/balle-jumbler-medium-large-chien-72.jpg\",\"width\":700,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/jouet-jumbler-kong\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Jouet Jumbler\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Kong\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jouet Jumbler Kong - V\u00e9torino","description":"Le KONG Jumbler est une balle deux en un pour deux fois plus de divertissement ludique et interactif. La balle de tennis \u00e0 l\u2019int\u00e9rieur et le couineur puissant incitent au jeu. Les poignets du jouet permettent de le ramasser et de le secouer facilement. Le Jumbler est assez solide pour jouer pendant des heures, ce qui le rend pratique pour les parties de lancer\/rapporter.  &nbsp;","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Jouet Jumbler Kong - V\u00e9torino","og_description":"Le KONG Jumbler est une balle deux en un pour deux fois plus de divertissement ludique et interactif. La balle de tennis \u00e0 l\u2019int\u00e9rieur et le couineur puissant incitent au jeu. Les poignets du jouet permettent de le ramasser et de le secouer facilement. Le Jumbler est assez solide pour jouer pendant des heures, ce qui le rend pratique pour les parties de lancer\/rapporter.  &nbsp;","og_url":"https:\/\/www.vetorino.com\/veterinaire\/meyzieu-69330\/boutique\/product\/jouet-jumbler-kong\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2024-03-22T13:42:11+00:00","og_image":[{"width":700,"height":800,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/balle-jumbler-medium-large-chien-72.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-jumbler-kong\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-jumbler-kong\/","name":"Jouet Jumbler Kong - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-jumbler-kong\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-jumbler-kong\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/balle-jumbler-medium-large-chien-72.jpg","datePublished":"2020-03-04T20:58:17+00:00","dateModified":"2024-03-22T13:42:11+00:00","description":"Le KONG Jumbler est une balle deux en un pour deux fois plus de divertissement ludique et interactif. La balle de tennis \u00e0 l\u2019int\u00e9rieur et le couineur puissant incitent au jeu. Les poignets du jouet permettent de le ramasser et de le secouer facilement. Le Jumbler est assez solide pour jouer pendant des heures, ce qui le rend pratique pour les parties de lancer\/rapporter. &nbsp;","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-jumbler-kong\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/jouet-jumbler-kong\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-jumbler-kong\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/balle-jumbler-medium-large-chien-72.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/balle-jumbler-medium-large-chien-72.jpg","width":700,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/jouet-jumbler-kong\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Jouet Jumbler"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Kong","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/meyzieu-69330\/boutique\/wp-json\/wp\/v2\/product\/33707","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/meyzieu-69330\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/meyzieu-69330\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/meyzieu-69330\/boutique\/wp-json\/wp\/v2\/media\/76636"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/meyzieu-69330\/boutique\/wp-json\/wp\/v2\/media?parent=33707"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/meyzieu-69330\/boutique\/wp-json\/wp\/v2\/product_cat?post=33707"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/meyzieu-69330\/boutique\/wp-json\/wp\/v2\/product_tag?post=33707"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}