{"id":34302,"date":"2020-03-04T22:01:55","date_gmt":"2020-03-04T21:01:55","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/easypill-gingiva-chat\/"},"modified":"2026-06-03T11:00:23","modified_gmt":"2026-06-03T09:00:23","slug":"easypill-gingiva-chat","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/meyzieu-69330\/boutique\/product\/easypill-gingiva-chat\/","title":{"rendered":"Easypill Gingiva &#8211; compl\u00e9ment pour chat"},"content":{"rendered":"<p>Compl\u00e9ment alimentaire sous forme de\u00a0<strong>bouch\u00e9es app\u00e9tentes pour chats<\/strong> formul\u00e9 pour contribuer \u00e0 r\u00e9duire l\u2019inflammation du chat adulte et soutenir la <strong>sant\u00e9 gingivale.<\/strong><\/p>\n<p><strong>B\u00e9n\u00e9fices constat\u00e9s :<\/strong><\/p>\n<ul>\n<li>Diminution de l\u2019ulc\u00e9ration<\/li>\n<li>R\u00e9duction du ptyalisme<\/li>\n<li>Augmentation de la prise alimentaire<\/li>\n<li>R\u00e9duction significative de perception de douleur de l\u2019animal<\/li>\n<li>Am\u00e9lioration du confort buccale<\/li>\n<li>Diminution du gonflement des gencives<\/li>\n<li>R\u00e9duction de l\u2019halitose<\/li>\n<\/ul>\n<p>M<strong>ode d&#8217;emploi<\/strong> :<\/p>\n<p><em>Administrer 1 boulette par jour selon les cas pendant 40 jours, renouvelables ou en continu jusqu&#8217;\u00e0 r\u00e9cup\u00e9ration compl\u00e8te.<\/em><\/p>\n<p><strong>Demander conseil \u00e0 un v\u00e9t\u00e9rinaire avant utilisation.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Compl\u00e9ment alimentaire sous forme de\u00a0<strong>bouch\u00e9es app\u00e9tentes pour chats<\/strong>\u00a0formul\u00e9 pour contribuer \u00e0 r\u00e9duire l\u2019inflammation du chat adulte et soutenir la <strong>sant\u00e9 gingivale.<\/strong><\/p>\n<p>Cet aliment est compos\u00e9 d\u2019Om\u00e9ga 3 (DHA), acides gras essentiels pour la formation de mol\u00e9cules qui vont permettre de r\u00e9duire consid\u00e9rablement l\u2019inflammation et contient du saule blanc, connu pour ses propri\u00e9t\u00e9s analg\u00e9siques.<\/p>\n<p><strong>Demander conseil \u00e0 un v\u00e9t\u00e9rinaire avant utilisation.<\/strong><\/p>\n","protected":false},"featured_media":1864871,"template":"","meta":[],"product_cat":[12551,2730,2697],"product_tag":[],"class_list":{"0":"post-34302","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alimentation-du-chat","7":"product_cat-aliments-complementaires-pour-chat","8":"product_cat-chat","9":"pa_marque-osalia","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Easypill Easypill Gingiva - compl\u00e9ment pour chat Osalia - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Compl\u00e9ment alimentaire sous forme de\u00a0bouch\u00e9es app\u00e9tentes pour chats\u00a0formul\u00e9 pour contribuer \u00e0 r\u00e9duire l\u2019inflammation du chat adulte et soutenir la sant\u00e9 gingivale.  Cet aliment est compos\u00e9 d\u2019Om\u00e9ga 3 (DHA), acides gras essentiels pour la formation de mol\u00e9cules qui vont permettre de r\u00e9duire consid\u00e9rablement l\u2019inflammation et contient du saule blanc, connu pour ses propri\u00e9t\u00e9s analg\u00e9siques.  Demander conseil \u00e0 un v\u00e9t\u00e9rinaire avant utilisation.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Easypill Easypill Gingiva - compl\u00e9ment pour chat Osalia - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Compl\u00e9ment alimentaire sous forme de\u00a0bouch\u00e9es app\u00e9tentes pour chats\u00a0formul\u00e9 pour contribuer \u00e0 r\u00e9duire l\u2019inflammation du chat adulte et soutenir la sant\u00e9 gingivale.  Cet aliment est compos\u00e9 d\u2019Om\u00e9ga 3 (DHA), acides gras essentiels pour la formation de mol\u00e9cules qui vont permettre de r\u00e9duire consid\u00e9rablement l\u2019inflammation et contient du saule blanc, connu pour ses propri\u00e9t\u00e9s analg\u00e9siques.  Demander conseil \u00e0 un v\u00e9t\u00e9rinaire avant utilisation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/meyzieu-69330\/boutique\/product\/easypill-gingiva-chat\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-03T09:00:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chat-gingiva-2.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"11,75&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/easypill-gingiva-chat\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/easypill-gingiva-chat\\\/\",\"name\":\"Easypill Easypill Gingiva - compl\u00e9ment pour chat Osalia - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/easypill-gingiva-chat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/easypill-gingiva-chat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/chat-gingiva-2.webp\",\"datePublished\":\"2020-03-04T21:01:55+00:00\",\"dateModified\":\"2026-06-03T09:00:23+00:00\",\"description\":\"Compl\u00e9ment alimentaire sous forme de\u00a0bouch\u00e9es app\u00e9tentes pour chats\u00a0formul\u00e9 pour contribuer \u00e0 r\u00e9duire l\u2019inflammation du chat adulte et soutenir la sant\u00e9 gingivale. Cet aliment est compos\u00e9 d\u2019Om\u00e9ga 3 (DHA), acides gras essentiels pour la formation de mol\u00e9cules qui vont permettre de r\u00e9duire consid\u00e9rablement l\u2019inflammation et contient du saule blanc, connu pour ses propri\u00e9t\u00e9s analg\u00e9siques. Demander conseil \u00e0 un v\u00e9t\u00e9rinaire avant utilisation.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/easypill-gingiva-chat\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/easypill-gingiva-chat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/easypill-gingiva-chat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/chat-gingiva-2.webp\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/chat-gingiva-2.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/easypill-gingiva-chat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Easypill Gingiva &#8211; compl\u00e9ment pour chat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Osalia\" \/>\n<meta property=\"product:price:amount\" content=\"11.75\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"A-1834480\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Easypill Easypill Gingiva - compl\u00e9ment pour chat Osalia - V\u00e9torino","description":"Compl\u00e9ment alimentaire sous forme de\u00a0bouch\u00e9es app\u00e9tentes pour chats\u00a0formul\u00e9 pour contribuer \u00e0 r\u00e9duire l\u2019inflammation du chat adulte et soutenir la sant\u00e9 gingivale.  Cet aliment est compos\u00e9 d\u2019Om\u00e9ga 3 (DHA), acides gras essentiels pour la formation de mol\u00e9cules qui vont permettre de r\u00e9duire consid\u00e9rablement l\u2019inflammation et contient du saule blanc, connu pour ses propri\u00e9t\u00e9s analg\u00e9siques.  Demander conseil \u00e0 un v\u00e9t\u00e9rinaire avant utilisation.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Easypill Easypill Gingiva - compl\u00e9ment pour chat Osalia - V\u00e9torino","og_description":"Compl\u00e9ment alimentaire sous forme de\u00a0bouch\u00e9es app\u00e9tentes pour chats\u00a0formul\u00e9 pour contribuer \u00e0 r\u00e9duire l\u2019inflammation du chat adulte et soutenir la sant\u00e9 gingivale.  Cet aliment est compos\u00e9 d\u2019Om\u00e9ga 3 (DHA), acides gras essentiels pour la formation de mol\u00e9cules qui vont permettre de r\u00e9duire consid\u00e9rablement l\u2019inflammation et contient du saule blanc, connu pour ses propri\u00e9t\u00e9s analg\u00e9siques.  Demander conseil \u00e0 un v\u00e9t\u00e9rinaire avant utilisation.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/meyzieu-69330\/boutique\/product\/easypill-gingiva-chat\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-06-03T09:00:23+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chat-gingiva-2.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"11,75&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/easypill-gingiva-chat\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/easypill-gingiva-chat\/","name":"Easypill Easypill Gingiva - compl\u00e9ment pour chat Osalia - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/easypill-gingiva-chat\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/easypill-gingiva-chat\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chat-gingiva-2.webp","datePublished":"2020-03-04T21:01:55+00:00","dateModified":"2026-06-03T09:00:23+00:00","description":"Compl\u00e9ment alimentaire sous forme de\u00a0bouch\u00e9es app\u00e9tentes pour chats\u00a0formul\u00e9 pour contribuer \u00e0 r\u00e9duire l\u2019inflammation du chat adulte et soutenir la sant\u00e9 gingivale. Cet aliment est compos\u00e9 d\u2019Om\u00e9ga 3 (DHA), acides gras essentiels pour la formation de mol\u00e9cules qui vont permettre de r\u00e9duire consid\u00e9rablement l\u2019inflammation et contient du saule blanc, connu pour ses propri\u00e9t\u00e9s analg\u00e9siques. Demander conseil \u00e0 un v\u00e9t\u00e9rinaire avant utilisation.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/easypill-gingiva-chat\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/easypill-gingiva-chat\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/easypill-gingiva-chat\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chat-gingiva-2.webp","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/chat-gingiva-2.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/easypill-gingiva-chat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Easypill Gingiva &#8211; compl\u00e9ment pour chat"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Osalia","product_price_amount":"11.75","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"A-1834480","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/meyzieu-69330\/boutique\/wp-json\/wp\/v2\/product\/34302","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/meyzieu-69330\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/meyzieu-69330\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/meyzieu-69330\/boutique\/wp-json\/wp\/v2\/media\/1864871"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/meyzieu-69330\/boutique\/wp-json\/wp\/v2\/media?parent=34302"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/meyzieu-69330\/boutique\/wp-json\/wp\/v2\/product_cat?post=34302"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/meyzieu-69330\/boutique\/wp-json\/wp\/v2\/product_tag?post=34302"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}