{"id":103681,"date":"2020-06-30T17:43:12","date_gmt":"2020-06-30T15:43:12","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/veggiedent-zen\/"},"modified":"2026-05-11T08:23:32","modified_gmt":"2026-05-11T06:23:32","slug":"veggiedent-zen","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/mezidonvalleedauge-14270\/boutique\/product\/veggiedent-zen\/","title":{"rendered":"Veggiedent Zen"},"content":{"rendered":"<p><strong>Virbac Veggiedent Zen<\/strong> est une lamelle \u00e0 m\u00e2cher 2 en 1 qui permet de lutter contre la plaque dentaire et la mauvaise haleine, mais \u00e9galement contre le stress tout en faisant plaisir \u00e0 son animal.<\/p>\n<p><strong><br \/>\nUtilisation :<\/strong><\/p>\n<ul>\n<li>Chien de moins de 5 kg<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p><strong>Virbac Veggiedent Zen<\/strong> est une lamelle \u00e0 m\u00e2cher 2 en 1 qui permet de lutter contre la plaque dentaire et la mauvaise haleine, mais \u00e9galement contre le stress tout en faisant plaisir \u00e0 son animal.<\/p>\n","protected":false},"featured_media":896437,"template":"","meta":[],"product_cat":[12552,2698,12603,12610,12561],"product_tag":[],"class_list":{"0":"post-103681","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alimentation-du-chien","7":"product_cat-chien","8":"product_cat-friandises-pour-chien","9":"product_cat-hygiene-bucco-dentaire-du-chien","10":"product_cat-hygiene-du-chien","11":"pa_marque-virbac","13":"first","14":"instock","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Veggiedent Zen Virbac - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Virbac Veggiedent Zen est une lamelle \u00e0 m\u00e2cher 2 en 1 qui permet de lutter contre la plaque dentaire et la mauvaise haleine, mais \u00e9galement contre le stress tout en faisant plaisir \u00e0 son animal.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Veggiedent Zen Virbac - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Virbac Veggiedent Zen est une lamelle \u00e0 m\u00e2cher 2 en 1 qui permet de lutter contre la plaque dentaire et la mauvaise haleine, mais \u00e9galement contre le stress tout en faisant plaisir \u00e0 son animal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/mezidonvalleedauge-14270\/boutique\/product\/veggiedent-zen\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T06:23:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/09\/logo-vetorino-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"539\" \/>\n\t<meta property=\"og:image:height\" content=\"224\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/veggiedent-zen\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/veggiedent-zen\\\/\",\"name\":\"Veggiedent Zen Virbac - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/veggiedent-zen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/veggiedent-zen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/veggiedent-zen-xs.jpg\",\"datePublished\":\"2020-06-30T15:43:12+00:00\",\"dateModified\":\"2026-05-11T06:23:32+00:00\",\"description\":\"Virbac Veggiedent Zen est une lamelle \u00e0 m\u00e2cher 2 en 1 qui permet de lutter contre la plaque dentaire et la mauvaise haleine, mais \u00e9galement contre le stress tout en faisant plaisir \u00e0 son animal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/veggiedent-zen\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/veggiedent-zen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/veggiedent-zen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/veggiedent-zen-xs.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/veggiedent-zen-xs.jpg\",\"width\":458,\"height\":458},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/pontarlier-25300\\\/boutique\\\/product\\\/veggiedent-zen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Veggiedent Zen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Virbac\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Veggiedent Zen Virbac - V\u00e9torino","description":"Virbac Veggiedent Zen est une lamelle \u00e0 m\u00e2cher 2 en 1 qui permet de lutter contre la plaque dentaire et la mauvaise haleine, mais \u00e9galement contre le stress tout en faisant plaisir \u00e0 son animal.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Veggiedent Zen Virbac - V\u00e9torino","og_description":"Virbac Veggiedent Zen est une lamelle \u00e0 m\u00e2cher 2 en 1 qui permet de lutter contre la plaque dentaire et la mauvaise haleine, mais \u00e9galement contre le stress tout en faisant plaisir \u00e0 son animal.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/mezidonvalleedauge-14270\/boutique\/product\/veggiedent-zen\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-05-11T06:23:32+00:00","og_image":[{"width":539,"height":224,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/09\/logo-vetorino-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/veggiedent-zen\/","url":"https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/veggiedent-zen\/","name":"Veggiedent Zen Virbac - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/veggiedent-zen\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/veggiedent-zen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/veggiedent-zen-xs.jpg","datePublished":"2020-06-30T15:43:12+00:00","dateModified":"2026-05-11T06:23:32+00:00","description":"Virbac Veggiedent Zen est une lamelle \u00e0 m\u00e2cher 2 en 1 qui permet de lutter contre la plaque dentaire et la mauvaise haleine, mais \u00e9galement contre le stress tout en faisant plaisir \u00e0 son animal.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/veggiedent-zen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/veggiedent-zen\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/veggiedent-zen\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/veggiedent-zen-xs.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/veggiedent-zen-xs.jpg","width":458,"height":458},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/veterinaire\/pontarlier-25300\/boutique\/product\/veggiedent-zen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Veggiedent Zen"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Virbac","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/mezidonvalleedauge-14270\/boutique\/wp-json\/wp\/v2\/product\/103681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/mezidonvalleedauge-14270\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/mezidonvalleedauge-14270\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/mezidonvalleedauge-14270\/boutique\/wp-json\/wp\/v2\/media\/896437"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/mezidonvalleedauge-14270\/boutique\/wp-json\/wp\/v2\/media?parent=103681"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/mezidonvalleedauge-14270\/boutique\/wp-json\/wp\/v2\/product_cat?post=103681"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/mezidonvalleedauge-14270\/boutique\/wp-json\/wp\/v2\/product_tag?post=103681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}