{"id":201,"date":"2021-12-24T17:18:20","date_gmt":"2021-12-24T16:18:20","guid":{"rendered":"http:\/\/service-client@vetorino.com"},"modified":"2024-08-08T17:22:38","modified_gmt":"2024-08-08T15:22:38","slug":"des-medicaments-a-base-de-cannabis-pour-les-animaux","status":"publish","type":"post","link":"https:\/\/www.vetorino.com\/veterinaire\/mielan-32170\/boutique\/2021\/12\/24\/des-medicaments-a-base-de-cannabis-pour-les-animaux\/","title":{"rendered":"Des m\u00e9dicaments \u00e0 base de cannabis pour les animaux ?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"201\" class=\"elementor elementor-201\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75d57b5d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75d57b5d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4d353451\" data-id=\"4d353451\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f22c86a elementor-widget elementor-widget-text-editor\" data-id=\"7f22c86a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p>Le cannabis, en France, est consid\u00e9r\u00e9 comme une drogue, mais fait parler de lui depuis quelques ann\u00e9es. M\u00eame si plus d\u2019une trentaine de pays ont l\u00e9galis\u00e9 en m\u00e9decine humaine l\u2019usage du cannabis et des cannabino\u00efdes, c\u2019est un autre secteur, celui de la sant\u00e9 animale, qui s\u2019y int\u00e9resse. Concernant l&#8217;usage de m\u00e9dicaments \u00e0 base de cannabis pour les animaux, \u00e0 des fins m\u00e9dicales, mais \u00e9galement pour le bien-\u00eatre.<\/p>\n\n\n\n<p>Depuis 10 ans, l\u2019esp\u00e9rance de vie des animaux domestiques a augment\u00e9 d\u2019au\nmoins 20%, mais les animaux domestiques \u00e2g\u00e9s souffrent de douleurs. En effet,\non sait que 90% des chats de plus de 12 ans ont des signes de d\u00e9g\u00e9n\u00e9rescence\narticulaire et que la pr\u00e9dominance de l\u2019arthrose est de 20% chez le chien. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>L\u2019utilisation de m\u00e9dicaments \u00e0 base de cannabis pour les animaux est-elle pertinente&nbsp;?<\/strong><\/h4>\n\n\n\n<p>Des friandises \u00e0 m\u00e2cher, des r\u00e9sines, des g\u00e9lules\u2026 De nombreux produits contenant du cannabidiol (CBD) sont apparus sur le march\u00e9. Selon plusieurs propri\u00e9taires d\u2019animaux, ces m\u00e9dicaments permettent de soulager leurs animaux, en \u00e9vitant les effets d\u00e9sagr\u00e9ables des traditionnels m\u00e9dicaments. <\/p>\n\n\n\n<p>De nombreuses \u00e9tudes<em>*<\/em> peuvent prouver les bienfaits du cannabis sur les animaux de compagnies. Notamment l\u2019huile de CBD, qui peut aider \u00e0 r\u00e9duire les crises d\u2019\u00e9pilepsie chez les chiens. Elles semblent montrer de nombreux effets th\u00e9rapeutiques utilisables en m\u00e9decine, permettant de soulager les maladies chronique, d\u00e9g\u00e9n\u00e9ratives, provoquant des douleurs, comme par exemple les maladies inflammatoires, canc\u00e9rologie, neurologie\u2026<\/p>\n\n\n\n<p>Certains v\u00e9t\u00e9rinaires et chercheurs sont contre cet usage, comme le sp\u00e9cialiste en anesth\u00e9sie et analg\u00e9sie v\u00e9t\u00e9rinaires, St\u00e9phane Junot, qui n\u2019approuve pas le traitement. Mais d\u2019un point de vue scientifique pense qu\u2019il y aurait probablement une place th\u00e9rapeutique pour ces m\u00e9dicaments, qui remplaceraient les m\u00e9dicaments antalgiques aupr\u00e8s des animaux vieillissants ayant des probl\u00e8mes de tol\u00e9rance. <\/p>\n\n\n\n<p>Prenons l\u2019exemple de Little Kitty aux \u00c9tats-Unis, une chatte atteinte d\u2019arthrose depuis ses 12 ans qui passait toutes ses journ\u00e9es cach\u00e9e dans un placard. Lorsque sa propri\u00e9taire lui a donn\u00e9 des m\u00e9dicaments \u00e0 base de cannabis pour les animaux, elle redemandait de l\u2019affection, sortait et se sociabilisait. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Quels effets n\u00e9gatifs peut-il y avoir&nbsp;? <\/strong><\/h4>\n\n\n\n<p>Selon des \u00e9tudes, le CBD n\u2019engendre g\u00e9n\u00e9ralement que peu d\u2019effets secondaires et n\u2019entraine pas de risques de d\u00e9pendance. Cependant, il existe certains risques. Des \u00e9tudes plus pouss\u00e9es sont men\u00e9es afin de prendre le temps d\u2019isoler les substances et d\u2019effectuer des tests de toxicit\u00e9, d\u2019efficacit\u00e9 et d\u2019innocuit\u00e9.<\/p>\n\n\n\n<p>Certains produits humains contiennent des substances pouvant \u00eatre toxiques pour les animaux. Il ne faut donc pas se lancer dans une autom\u00e9dication. Il faut toujours demander conseils \u00e0 votre v\u00e9t\u00e9rinaire. De plus, si l\u2019animal re\u00e7oit d\u00e9j\u00e0 un traitement, l\u2019ajout de cannabino\u00efdes peut \u00eatre dangereux. Un r\u00e9ajustement de la prise de m\u00e9dicaments s\u2019impose et ne peut se faire que par le biais d\u2019un professionnel. <\/p>\n\n\n\n<p>Enfin, les m\u00e9dicaments \u00e0 base de cannabino\u00efdes doivent \u00eatre conserv\u00e9s \u00e0 l\u2019abri du soleil ou de la lumi\u00e8re vive, ainsi qu\u2019\u00e0 temp\u00e9rature ambiante, au risque d&#8217;une modification radicale de la composition chimique des m\u00e9dicaments. <\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Quels sont les sympt\u00f4mes de l\u2019intoxication au cannabis chez l\u2019animal&nbsp;? <\/strong><\/h4>\n\n\n\n<p>Selon le centre antipoison animal, les intoxications au cannabis chez les animaux sont de plus en plus fr\u00e9quentes. Celles-ci concernent l\u2019ingestion accidentelle des produits de leur propri\u00e9taire (space cake, joint\u2026).<\/p>\n\n\n\n<p>Lors d\u2019une intoxication au cannabis, les principaux sympt\u00f4mes sont des troubles neurologiques (tremblements, convulsions, dilatations des pupilles, troubles de l\u2019\u00e9quilibre\u2026), des troubles digestifs (hyper salivation, vomissements\u2026), des troubles respiratoires et cardio-vasculaires ou bien des troubles g\u00e9n\u00e9raux (comme l\u2019hypothermie\u2026). On conseille d\u2019emmener rapidement votre animal chez le v\u00e9t\u00e9rinaire.<\/p>\n\n\n\n<p>S\u2019il a r\u00e9cemment ing\u00e9r\u00e9 du cannabis, le v\u00e9t\u00e9rinaire essaiera de faire vomir votre animal. Ou bien il essaiera de limiter la concentration des principes actifs du cannabis dans le tube digestif en donnant du charbon activ\u00e9. Cependant, si votre animal pr\u00e9sente d\u00e9j\u00e0 les sympt\u00f4mes, il ne faut pas le faire vomir. Le cannabis n\u2019\u00e9tant plus pr\u00e9sent dans l\u2019estomac, il devient dangereux de faire vomir votre animal. D\u2019autant plus s\u2019il pr\u00e9sente des troubles neurologiques.<\/p>\n\n\n\n<p>Le v\u00e9t\u00e9rinaire met alors en place un traitement pour ses sympt\u00f4mes. Mais le pronostic face \u00e0 l\u2019intoxication au cannabis est g\u00e9n\u00e9ralement bon&nbsp;! <\/p>\n\n\n\n<p>De nos jours, en France, peu de m\u00e9dicaments compos\u00e9s de cannabino\u00efdes sont accessibles, et leur utilisation par les v\u00e9t\u00e9rinaires reste anecdotique. Vous pouvez tout de m\u00eame en parler \u00e0 votre v\u00e9t\u00e9rinaire&nbsp;!<\/p>\n\n\n\n<p><br><\/p>\n\n\n\n<p>V\u00e9torino peut vous aider \u00e0 trouver un v\u00e9t\u00e9rinaire pour votre animal de compagnie en <a href=\"https:\/\/www.vetorino.com\/\">cliquant ici<\/a>. <\/p>\n\n\n\n<p> V\u00e9torino peut vous aider dans la digitalisation de vos pratiques. Vous pouvez contacter un membre de notre \u00e9quipe et obtenir plus de renseignements en <a href=\"https:\/\/www.vetorino.com\/pro\">cliquant ici<\/a>.<\/p>\n\n\n\n<p><br><\/p>\n\n\n\n<p style=\"font-size:16px\">*Des chercheurs ont prescrit, en 2018, \u00e0 16 chiens atteints d\u2019arthrose, pendant quatre semaines, de l&#8217;huile de CBD. Les chiens ayant pris l\u2019huile de CBD avaient moins de douleur que ceux \u00e0 qui on avait donn\u00e9 un placebo. C&#8217;est \u00e0 l&#8217;universit\u00e9 d&#8217;\u00c9tat du Colorado qu&#8217;\u00e0 \u00e9t\u00e9 d\u00e9couvert que l\u2019huile de CBD permettait de contribuer \u00e0 r\u00e9duire les crises d\u2019\u00e9pilepsie chez les chiens.&nbsp;<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Le cannabis, en France, est consid\u00e9r\u00e9 comme une drogue, mais fait parler de lui depuis quelques ann\u00e9es. M\u00eame si plus d\u2019une trentaine de pays ont l\u00e9galis\u00e9 en m\u00e9decine humaine l\u2019usage du cannabis et des cannabino\u00efdes, c\u2019est un autre secteur, celui de la sant\u00e9 animale, qui s\u2019y int\u00e9resse. Concernant l&#8217;usage de m\u00e9dicaments \u00e0 base de cannabis [&hellip;]<\/p>\n","protected":false},"author":10426,"featured_media":210,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[14091,14090,14095,14094],"tags":[],"class_list":["post-201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hygiene-et-bien-etre-chat","category-hygiene-et-bien-etre-chien","category-sante-et-prevention-chat","category-sante-chien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Des m\u00e9dicaments \u00e0 base de cannabis pour les animaux ? - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Les m\u00e9dicaments \u00e0 base de cannabis pour les animaux qui permettent de les soulager en \u00e9vitant les effets d\u00e9sagr\u00e9ables des traditionnels m\u00e9dicaments.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Des m\u00e9dicaments \u00e0 base de cannabis pour les animaux ? - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Les m\u00e9dicaments \u00e0 base de cannabis pour les animaux qui permettent de les soulager en \u00e9vitant les effets d\u00e9sagr\u00e9ables des traditionnels m\u00e9dicaments.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/mielan-32170\/boutique\/2021\/12\/24\/des-medicaments-a-base-de-cannabis-pour-les-animaux\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-24T16:18:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-08-08T15:22:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/02\/ROYAL-8101953_9500744_9500750_9500767.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"255\" \/>\n\t<meta property=\"og:image:height\" content=\"255\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Equipe V\u00e9torino\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Des m\u00e9dicaments \u00e0 base de cannabis pour les animaux ? - V\u00e9torino\" \/>\n<meta name=\"twitter:description\" content=\"Les m\u00e9dicaments \u00e0 base de cannabis pour les animaux qui permettent de les soulager en \u00e9vitant les effets d\u00e9sagr\u00e9ables des traditionnels m\u00e9dicaments.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/02\/ROYAL-8101953_9500744_9500750_9500767.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Equipe V\u00e9torino\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/des-medicaments-a-base-de-cannabis-pour-les-animaux\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/des-medicaments-a-base-de-cannabis-pour-les-animaux\\\/\"},\"author\":{\"name\":\"Equipe V\u00e9torino\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/6c2a6631b1dafb889300d67266761861\"},\"headline\":\"Des m\u00e9dicaments \u00e0 base de cannabis pour les animaux ?\",\"datePublished\":\"2021-12-24T16:18:20+00:00\",\"dateModified\":\"2024-08-08T15:22:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/des-medicaments-a-base-de-cannabis-pour-les-animaux\\\/\"},\"wordCount\":944,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/des-medicaments-a-base-de-cannabis-pour-les-animaux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/cannabis-chien-animaux@2x.jpg\",\"articleSection\":[\"Hygi\u00e8ne et bien-\u00eatre pour chat\",\"Hygi\u00e8ne et bien-\u00eatre pour chien\",\"Sant\u00e9 et pr\u00e9vention pour chat\",\"Sant\u00e9 pour chien\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/des-medicaments-a-base-de-cannabis-pour-les-animaux\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/des-medicaments-a-base-de-cannabis-pour-les-animaux\\\/\",\"name\":\"Des m\u00e9dicaments \u00e0 base de cannabis pour les animaux ? - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/des-medicaments-a-base-de-cannabis-pour-les-animaux\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/des-medicaments-a-base-de-cannabis-pour-les-animaux\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/cannabis-chien-animaux@2x.jpg\",\"datePublished\":\"2021-12-24T16:18:20+00:00\",\"dateModified\":\"2024-08-08T15:22:38+00:00\",\"description\":\"Les m\u00e9dicaments \u00e0 base de cannabis pour les animaux qui permettent de les soulager en \u00e9vitant les effets d\u00e9sagr\u00e9ables des traditionnels m\u00e9dicaments.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/des-medicaments-a-base-de-cannabis-pour-les-animaux\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/des-medicaments-a-base-de-cannabis-pour-les-animaux\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/des-medicaments-a-base-de-cannabis-pour-les-animaux\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/cannabis-chien-animaux@2x.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/cannabis-chien-animaux@2x.jpg\",\"width\":700,\"height\":181},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2021\\\/12\\\/24\\\/des-medicaments-a-base-de-cannabis-pour-les-animaux\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chat\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/champs-sur-marne-77420\\\/boutique\\\/category\\\/chat\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sant\u00e9 et pr\u00e9vention pour chat\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/category\\\/chat\\\/sante-et-prevention-chat\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Des m\u00e9dicaments \u00e0 base de cannabis pour les animaux ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/6c2a6631b1dafb889300d67266761861\",\"name\":\"Equipe V\u00e9torino\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g\",\"caption\":\"Equipe V\u00e9torino\"},\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/mielan-32170\\\/boutique\\\/author\\\/equipe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Des m\u00e9dicaments \u00e0 base de cannabis pour les animaux ? - V\u00e9torino","description":"Les m\u00e9dicaments \u00e0 base de cannabis pour les animaux qui permettent de les soulager en \u00e9vitant les effets d\u00e9sagr\u00e9ables des traditionnels m\u00e9dicaments.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Des m\u00e9dicaments \u00e0 base de cannabis pour les animaux ? - V\u00e9torino","og_description":"Les m\u00e9dicaments \u00e0 base de cannabis pour les animaux qui permettent de les soulager en \u00e9vitant les effets d\u00e9sagr\u00e9ables des traditionnels m\u00e9dicaments.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/mielan-32170\/boutique\/2021\/12\/24\/des-medicaments-a-base-de-cannabis-pour-les-animaux\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_published_time":"2021-12-24T16:18:20+00:00","article_modified_time":"2024-08-08T15:22:38+00:00","og_image":[{"width":255,"height":255,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/02\/ROYAL-8101953_9500744_9500750_9500767.jpg","type":"image\/jpeg"}],"author":"Equipe V\u00e9torino","twitter_card":"summary_large_image","twitter_title":"Des m\u00e9dicaments \u00e0 base de cannabis pour les animaux ? - V\u00e9torino","twitter_description":"Les m\u00e9dicaments \u00e0 base de cannabis pour les animaux qui permettent de les soulager en \u00e9vitant les effets d\u00e9sagr\u00e9ables des traditionnels m\u00e9dicaments.","twitter_image":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/02\/ROYAL-8101953_9500744_9500750_9500767.jpg","twitter_misc":{"\u00c9crit par":"Equipe V\u00e9torino","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/des-medicaments-a-base-de-cannabis-pour-les-animaux\/#article","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/des-medicaments-a-base-de-cannabis-pour-les-animaux\/"},"author":{"name":"Equipe V\u00e9torino","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/6c2a6631b1dafb889300d67266761861"},"headline":"Des m\u00e9dicaments \u00e0 base de cannabis pour les animaux ?","datePublished":"2021-12-24T16:18:20+00:00","dateModified":"2024-08-08T15:22:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/des-medicaments-a-base-de-cannabis-pour-les-animaux\/"},"wordCount":944,"publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/des-medicaments-a-base-de-cannabis-pour-les-animaux\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/02\/cannabis-chien-animaux@2x.jpg","articleSection":["Hygi\u00e8ne et bien-\u00eatre pour chat","Hygi\u00e8ne et bien-\u00eatre pour chien","Sant\u00e9 et pr\u00e9vention pour chat","Sant\u00e9 pour chien"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/des-medicaments-a-base-de-cannabis-pour-les-animaux\/","url":"https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/des-medicaments-a-base-de-cannabis-pour-les-animaux\/","name":"Des m\u00e9dicaments \u00e0 base de cannabis pour les animaux ? - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/des-medicaments-a-base-de-cannabis-pour-les-animaux\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/des-medicaments-a-base-de-cannabis-pour-les-animaux\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/02\/cannabis-chien-animaux@2x.jpg","datePublished":"2021-12-24T16:18:20+00:00","dateModified":"2024-08-08T15:22:38+00:00","description":"Les m\u00e9dicaments \u00e0 base de cannabis pour les animaux qui permettent de les soulager en \u00e9vitant les effets d\u00e9sagr\u00e9ables des traditionnels m\u00e9dicaments.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/des-medicaments-a-base-de-cannabis-pour-les-animaux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/des-medicaments-a-base-de-cannabis-pour-les-animaux\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/des-medicaments-a-base-de-cannabis-pour-les-animaux\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/02\/cannabis-chien-animaux@2x.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/02\/cannabis-chien-animaux@2x.jpg","width":700,"height":181},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/2021\/12\/24\/des-medicaments-a-base-de-cannabis-pour-les-animaux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Chat","item":"https:\/\/www.vetorino.com\/veterinaire\/champs-sur-marne-77420\/boutique\/category\/chat\/"},{"@type":"ListItem","position":3,"name":"Sant\u00e9 et pr\u00e9vention pour chat","item":"https:\/\/www.vetorino.com\/boutique\/category\/chat\/sante-et-prevention-chat\/"},{"@type":"ListItem","position":4,"name":"Des m\u00e9dicaments \u00e0 base de cannabis pour les animaux ?"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]},{"@type":"Person","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/6c2a6631b1dafb889300d67266761861","name":"Equipe V\u00e9torino","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a05f555e7217cbeee391402c641974e9221b820a888a558ef1d134b030fe072c?s=96&d=mm&r=g","caption":"Equipe V\u00e9torino"},"url":"https:\/\/www.vetorino.com\/veterinaire\/mielan-32170\/boutique\/author\/equipe\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/mielan-32170\/boutique\/wp-json\/wp\/v2\/posts\/201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/mielan-32170\/boutique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/mielan-32170\/boutique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/mielan-32170\/boutique\/wp-json\/wp\/v2\/users\/10426"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/mielan-32170\/boutique\/wp-json\/wp\/v2\/comments?post=201"}],"version-history":[{"count":5,"href":"https:\/\/www.vetorino.com\/veterinaire\/mielan-32170\/boutique\/wp-json\/wp\/v2\/posts\/201\/revisions"}],"predecessor-version":[{"id":572961,"href":"https:\/\/www.vetorino.com\/veterinaire\/mielan-32170\/boutique\/wp-json\/wp\/v2\/posts\/201\/revisions\/572961"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/mielan-32170\/boutique\/wp-json\/wp\/v2\/media\/210"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/mielan-32170\/boutique\/wp-json\/wp\/v2\/media?parent=201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/mielan-32170\/boutique\/wp-json\/wp\/v2\/categories?post=201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/mielan-32170\/boutique\/wp-json\/wp\/v2\/tags?post=201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}