{"id":1164477,"date":"2025-02-03T12:00:00","date_gmt":"2025-02-03T11:00:00","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/?p=1164477"},"modified":"2025-01-08T09:13:16","modified_gmt":"2025-01-08T08:13:16","slug":"ulcere-oeil","status":"publish","type":"post","link":"https:\/\/www.vetorino.com\/veterinaire\/monsegur-33580\/boutique\/2025\/02\/03\/ulcere-oeil\/","title":{"rendered":"Ulc\u00e8re \u00e0 l\u2019oeil, quels sont les signes ?"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1164477\" class=\"elementor elementor-1164477\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4747b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4747b9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f0a8be6\" data-id=\"f0a8be6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77b80b4 elementor-widget elementor-widget-text-editor\" data-id=\"77b80b4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<section data-id=\"8j8qvkr\" data-element_type=\"section\"><div data-id=\"2u8kg9v\" data-element_type=\"column\"><div data-id=\"tcv8rwn\" data-element_type=\"heading.default\"><h2>Ulc\u00e8re \u00e0 l\u2019\u0153il : quels sont les signes chez le chien et le chat ?<!-- notionvc: 10c14f65-c25d-473a-bad5-0aa553f78560 --><br \/><!-- notionvc: 5af60c17-bda6-435a-b790-601224d87c2e --><\/h2><\/div><\/div><\/section>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86b51a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86b51a2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca49f12\" data-id=\"ca49f12\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d92d7f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2d92d7f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u27a1\ufe0f&nbsp;Larmoiement excessif<\/p>\n<p>Votre animal produit beaucoup de larmes, parfois accompagn\u00e9es d\u2019un \u00e9coulement clair ou purulent.<\/p>\n<p>\u27a1\ufe0f&nbsp;Clignements fr\u00e9quents ou \u0153il ferm\u00e9<\/p>\n<p>Si votre chien ou votre chat garde un \u0153il ferm\u00e9 ou le cligne plus souvent, cela peut indiquer une douleur oculaire.<\/p>\n<p>\u27a1\ufe0f&nbsp;\u0152il rouge ou irrit\u00e9<\/p>\n<p>Une rougeur autour de l\u2019\u0153il ou sur la surface peut signaler une inflammation.<\/p>\n<p>\u27a1\ufe0f&nbsp;Sensibilit\u00e9 \u00e0 la lumi\u00e8re<\/p>\n<p>Votre animal \u00e9vite les endroits lumineux et pr\u00e9f\u00e8re rester dans des zones plus sombres.<\/p>\n<p>\u27a1\ufe0f&nbsp;Grattage ou frottement de l\u2019\u0153il<\/p>\n<p>Les chiens et les chats touchent ou frottent souvent leur \u0153il avec leur patte, ce qui peut aggraver la blessure.<\/p>\n<p>\u27a1\ufe0f&nbsp;Apparence trouble ou blanc-bleu<\/p>\n<p>La corn\u00e9e peut devenir trouble ou sembler avoir une tache blanche ou bleut\u00e9e.<\/p>\n<p>Consultez rapidement un v\u00e9t\u00e9rinaire si vous suspectez un ulc\u00e8re et observez un ou plusieurs de ces signes. Plus vite vous obtenez un diagnostic et moins votre animal souffrira.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90b5d84 elementor-widget elementor-widget-image\" data-id=\"90b5d84\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.vetorino.com\/boutique\/marque\/royal-canin\/?s&#038;maladie=troubles-digestifs&#038;swcfpc=1\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2048\" height=\"1152\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/ulcere-oeil-symptomes-2048x1152.jpg\" class=\"attachment-2048x2048 size-2048x2048 wp-image-1164486\" alt=\"ulce\u0300re oeil chat symptomes\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/ulcere-oeil-symptomes-2048x1152.jpg 2048w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/ulcere-oeil-symptomes-300x169.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/ulcere-oeil-symptomes-1024x576.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/ulcere-oeil-symptomes-768x432.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/ulcere-oeil-symptomes-1536x864.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/ulcere-oeil-symptomes-555x312.jpg 555w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6cb33a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6cb33a2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-89d7b48\" data-id=\"89d7b48\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b008557 elementor-widget elementor-widget-heading\" data-id=\"b008557\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Quelles sont les causes possibles ?\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50e8476 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"50e8476\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Traumatismes<\/strong> : griffe, \u00e9pine ou coup port\u00e9 \u00e0 l\u2019\u0153il.<\/li><li><strong>Corps \u00e9tranger<\/strong> : poussi\u00e8re, herbe ou d\u00e9bris bloqu\u00e9s sous la paupi\u00e8re.<\/li><li>Infections : <strong>bact\u00e9ries, virus<\/strong> (comme l\u2019herp\u00e8s chez les chats) ou champignons.<\/li><li><strong>S\u00e9cheresse oculaire<\/strong> : un manque de larmes peut fragiliser la corn\u00e9e.<\/li><li>Races pr\u00e9dispos\u00e9es : <strong>les animaux \u00e0 yeux pro\u00e9minents<\/strong> (carlin, bouledogue, persan) sont plus \u00e0 risque.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eacaeea elementor-widget elementor-widget-heading\" data-id=\"eacaeea\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Que faire si vous suspectez un ulc\u00e8re ?\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-56f5457 elementor-widget elementor-widget-text-editor\" data-id=\"56f5457\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Consultez votre v\u00e9t\u00e9rinaire imm\u00e9diatement. En parall\u00e8le, ne tentez pas de nettoyer ou d\u2019appliquer des produits non prescrits, cela pourrait aggraver la situation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ulc\u00e8re \u00e0 l\u2019\u0153il : quels sont les signes chez le chien et le chat ? \u27a1\ufe0f&nbsp;Larmoiement excessif Votre animal produit beaucoup de larmes, parfois accompagn\u00e9es d\u2019un \u00e9coulement clair ou purulent. \u27a1\ufe0f&nbsp;Clignements fr\u00e9quents ou \u0153il ferm\u00e9 Si votre chien ou votre chat garde un \u0153il ferm\u00e9 ou le cligne plus souvent, cela peut indiquer une douleur [&hellip;]<\/p>\n","protected":false},"author":68707,"featured_media":1164484,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[14086,14087,14095,14094],"tags":[],"class_list":["post-1164477","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chat","category-chien","category-sante-et-prevention-chat","category-sante-chien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ulc\u00e8re \u00e0 l\u2019oeil chez le chien ou le chat : apprenez \u00e0 le d\u00e9tecter<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez les sympt\u00f4mes de l&#039;ulc\u00e8re \u00e0 l&#039;oeil chez le chien et le chat pour mieux agir pour la sant\u00e9 de votre animal.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ulc\u00e8re \u00e0 l\u2019oeil chez le chien ou le chat : apprenez \u00e0 le d\u00e9tecter\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez les sympt\u00f4mes de l&#039;ulc\u00e8re \u00e0 l&#039;oeil chez le chien et le chat pour mieux agir pour la sant\u00e9 de votre animal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/monsegur-33580\/boutique\/2025\/02\/03\/ulcere-oeil\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-03T11:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/ulcere-a-loeil-chien-chat.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1905\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Clemence Sully\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Clemence Sully\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/02\\\/03\\\/ulcere-oeil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/02\\\/03\\\/ulcere-oeil\\\/\"},\"author\":{\"name\":\"Clemence Sully\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/9bd231449b5dab066d32dab7d241eb4a\"},\"headline\":\"Ulc\u00e8re \u00e0 l\u2019oeil, quels sont les signes ?\",\"datePublished\":\"2025-02-03T11:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/02\\\/03\\\/ulcere-oeil\\\/\"},\"wordCount\":288,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/02\\\/03\\\/ulcere-oeil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/ulcere-a-loeil-chien-chat.jpg\",\"articleSection\":[\"Chat\",\"Chien\",\"Sant\u00e9 et pr\u00e9vention pour chat\",\"Sant\u00e9 pour chien\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/02\\\/03\\\/ulcere-oeil\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/02\\\/03\\\/ulcere-oeil\\\/\",\"name\":\"Ulc\u00e8re \u00e0 l\u2019oeil chez le chien ou le chat : apprenez \u00e0 le d\u00e9tecter\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/02\\\/03\\\/ulcere-oeil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/02\\\/03\\\/ulcere-oeil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/ulcere-a-loeil-chien-chat.jpg\",\"datePublished\":\"2025-02-03T11:00:00+00:00\",\"description\":\"D\u00e9couvrez les sympt\u00f4mes de l'ulc\u00e8re \u00e0 l'oeil chez le chien et le chat pour mieux agir pour la sant\u00e9 de votre animal.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/02\\\/03\\\/ulcere-oeil\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/02\\\/03\\\/ulcere-oeil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/02\\\/03\\\/ulcere-oeil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/ulcere-a-loeil-chien-chat.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/ulcere-a-loeil-chien-chat.jpg\",\"width\":1905,\"height\":450,\"caption\":\"ulce\u0300re a\u0300 l'oeil chien chat\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/02\\\/03\\\/ulcere-oeil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chien\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/champs-sur-marne-77420\\\/boutique\\\/category\\\/chien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ulc\u00e8re \u00e0 l\u2019oeil, quels sont les signes ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/9bd231449b5dab066d32dab7d241eb4a\",\"name\":\"Clemence Sully\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g\",\"caption\":\"Clemence Sully\"},\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/monsegur-33580\\\/boutique\\\/author\\\/clemence-sully\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ulc\u00e8re \u00e0 l\u2019oeil chez le chien ou le chat : apprenez \u00e0 le d\u00e9tecter","description":"D\u00e9couvrez les sympt\u00f4mes de l'ulc\u00e8re \u00e0 l'oeil chez le chien et le chat pour mieux agir pour la sant\u00e9 de votre animal.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Ulc\u00e8re \u00e0 l\u2019oeil chez le chien ou le chat : apprenez \u00e0 le d\u00e9tecter","og_description":"D\u00e9couvrez les sympt\u00f4mes de l'ulc\u00e8re \u00e0 l'oeil chez le chien et le chat pour mieux agir pour la sant\u00e9 de votre animal.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/monsegur-33580\/boutique\/2025\/02\/03\/ulcere-oeil\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_published_time":"2025-02-03T11:00:00+00:00","og_image":[{"width":1905,"height":450,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/ulcere-a-loeil-chien-chat.jpg","type":"image\/jpeg"}],"author":"Clemence Sully","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Clemence Sully","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vetorino.com\/boutique\/2025\/02\/03\/ulcere-oeil\/#article","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/02\/03\/ulcere-oeil\/"},"author":{"name":"Clemence Sully","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/9bd231449b5dab066d32dab7d241eb4a"},"headline":"Ulc\u00e8re \u00e0 l\u2019oeil, quels sont les signes ?","datePublished":"2025-02-03T11:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/02\/03\/ulcere-oeil\/"},"wordCount":288,"publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/02\/03\/ulcere-oeil\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/ulcere-a-loeil-chien-chat.jpg","articleSection":["Chat","Chien","Sant\u00e9 et pr\u00e9vention pour chat","Sant\u00e9 pour chien"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/2025\/02\/03\/ulcere-oeil\/","url":"https:\/\/www.vetorino.com\/boutique\/2025\/02\/03\/ulcere-oeil\/","name":"Ulc\u00e8re \u00e0 l\u2019oeil chez le chien ou le chat : apprenez \u00e0 le d\u00e9tecter","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/02\/03\/ulcere-oeil\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/02\/03\/ulcere-oeil\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/ulcere-a-loeil-chien-chat.jpg","datePublished":"2025-02-03T11:00:00+00:00","description":"D\u00e9couvrez les sympt\u00f4mes de l'ulc\u00e8re \u00e0 l'oeil chez le chien et le chat pour mieux agir pour la sant\u00e9 de votre animal.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/02\/03\/ulcere-oeil\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/2025\/02\/03\/ulcere-oeil\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/2025\/02\/03\/ulcere-oeil\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/ulcere-a-loeil-chien-chat.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/ulcere-a-loeil-chien-chat.jpg","width":1905,"height":450,"caption":"ulce\u0300re a\u0300 l'oeil chien chat"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/2025\/02\/03\/ulcere-oeil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Chien","item":"https:\/\/www.vetorino.com\/veterinaire\/champs-sur-marne-77420\/boutique\/category\/chien\/"},{"@type":"ListItem","position":3,"name":"Ulc\u00e8re \u00e0 l\u2019oeil, quels sont les signes ?"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]},{"@type":"Person","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/9bd231449b5dab066d32dab7d241eb4a","name":"Clemence Sully","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g","caption":"Clemence Sully"},"url":"https:\/\/www.vetorino.com\/veterinaire\/monsegur-33580\/boutique\/author\/clemence-sully\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/monsegur-33580\/boutique\/wp-json\/wp\/v2\/posts\/1164477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/monsegur-33580\/boutique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/monsegur-33580\/boutique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/monsegur-33580\/boutique\/wp-json\/wp\/v2\/users\/68707"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/monsegur-33580\/boutique\/wp-json\/wp\/v2\/comments?post=1164477"}],"version-history":[{"count":5,"href":"https:\/\/www.vetorino.com\/veterinaire\/monsegur-33580\/boutique\/wp-json\/wp\/v2\/posts\/1164477\/revisions"}],"predecessor-version":[{"id":1164504,"href":"https:\/\/www.vetorino.com\/veterinaire\/monsegur-33580\/boutique\/wp-json\/wp\/v2\/posts\/1164477\/revisions\/1164504"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/monsegur-33580\/boutique\/wp-json\/wp\/v2\/media\/1164484"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/monsegur-33580\/boutique\/wp-json\/wp\/v2\/media?parent=1164477"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/monsegur-33580\/boutique\/wp-json\/wp\/v2\/categories?post=1164477"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/monsegur-33580\/boutique\/wp-json\/wp\/v2\/tags?post=1164477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}