{"id":174601,"date":"2021-04-29T20:22:38","date_gmt":"2021-04-29T18:22:38","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/phytobiovet-nettoyant-oreilles-pour-chien\/"},"modified":"2026-06-30T17:44:17","modified_gmt":"2026-06-30T15:44:17","slug":"phytobiovet-nettoyant-oreilles-pour-chien","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/montpon-menesterol-24700\/boutique\/product\/phytobiovet-nettoyant-oreilles-pour-chien\/","title":{"rendered":"Phytobiovet Nettoyant oreilles &#8211; chien"},"content":{"rendered":"<div class=\"tabs product-tabs visible--desktop\">\n<div id=\"tab-content\" class=\"tab-content mb-4\">\n<div id=\"description\" class=\"tab-pane fade show active\" role=\"tabpanel\">\n<div class=\"product-description\">\n<p><strong>Le nettoyant pour les oreilles Phytobiovet aux extraits d\u2019agrumes bio dissout le c\u00e9rumen et permet un nettoyage en douceur des oreilles chez le chien, tout en nourrissant l\u2019\u00e9piderme.<\/strong><\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>En entretien r\u00e9gulier ou avant l\u2019application d\u2019un produit de traitement.<\/li>\n<li>Chez le chien<\/li>\n<\/ul>\n<p><strong>Mode d&#8217;emploi :<\/strong><\/p>\n<p>Introduire la canule \u00e0 l\u2019entr\u00e9e de l\u2019oreille. Appliquer une l\u00e9g\u00e8re pression sur le flacon. Instiller d\u00e9licatement quelques gouttes dans le conduit auditif. Masser quelques secondes. Peut \u00e9galement \u00eatre appliqu\u00e9 sur un coton pour nettoyer le pavillon de l\u2019oreille.<\/p>\n<p>Utiliser 1 \u00e0 2 fois par jour avant un traitement ; 1 \u00e0 2 fois par semaine en entretien r\u00e9gulier.<\/p>\n<p><strong>Avantages :<\/strong><\/p>\n<ul>\n<li>Les hydrolats de citron et d\u2019orange apportent des vitamines et des min\u00e9raux, qui sont les nutriments essentiels au renforcement de l\u2019\u00e9piderme d\u00e9licat de l\u2019oreille et \u00e0 sa protection des agressions ext\u00e9rieures.<\/li>\n<li>La glyc\u00e9rine est hydratante et \u00e9molliente. Elle permet la dissolution et l\u2019\u00e9limination du c\u00e9rumen.<\/li>\n<li>L\u2019huile essentielle de lavandin aux propri\u00e9t\u00e9s cicatrisantes et anti-inflammatoires et l\u2019huile essentielle de zeste de citron connue pour ses propri\u00e9t\u00e9s antimicrobiennes favorisent le bon \u00e9quilibre de l\u2019oreille.<\/li>\n<li>La solution ne pique pas et son odeur est agr\u00e9able.<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"js-product-list-bottom\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nettoyant pour les\u00a0<strong>oreilles du chien<\/strong>\u00a0\u00e0 base d&#8217;extraits d\u2019agrumes bio formul\u00e9 pour dissoudre le c\u00e9rumen, nettoyer les oreilles en douceur et nourrir l\u2019\u00e9piderme.<\/p>\n<p><strong>Ne pas utiliser chez le chat.<\/strong><\/p>\n","protected":false},"featured_media":1907596,"template":"","meta":[],"product_cat":[2698,12614,12561],"product_tag":[],"class_list":{"0":"post-174601","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-chien","7":"product_cat-hygiene-des-oreilles-du-chien","8":"product_cat-hygiene-du-chien","9":"pa_marque-mp-labo","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Phytobiovet Nettoyant oreilles - chien Mp Labo - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Nettoyant pour les\u00a0oreilles du chien\u00a0\u00e0 base d&#039;extraits d\u2019agrumes bio formul\u00e9 pour dissoudre le c\u00e9rumen, nettoyer les oreilles en douceur et nourrir l\u2019\u00e9piderme.  Ne pas utiliser chez le chat.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Phytobiovet Nettoyant oreilles - chien Mp Labo - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Nettoyant pour les\u00a0oreilles du chien\u00a0\u00e0 base d&#039;extraits d\u2019agrumes bio formul\u00e9 pour dissoudre le c\u00e9rumen, nettoyer les oreilles en douceur et nourrir l\u2019\u00e9piderme.  Ne pas utiliser chez le chat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/montpon-menesterol-24700\/boutique\/product\/phytobiovet-nettoyant-oreilles-pour-chien\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-30T15:44:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/04\/phytobiovet-nettoyant-oreilles.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"17,05&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/phytobiovet-nettoyant-oreilles-pour-chien\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/phytobiovet-nettoyant-oreilles-pour-chien\\\/\",\"name\":\"Phytobiovet Nettoyant oreilles - chien Mp Labo - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/phytobiovet-nettoyant-oreilles-pour-chien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/phytobiovet-nettoyant-oreilles-pour-chien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/phytobiovet-nettoyant-oreilles.webp\",\"datePublished\":\"2021-04-29T18:22:38+00:00\",\"dateModified\":\"2026-06-30T15:44:17+00:00\",\"description\":\"Nettoyant pour les\u00a0oreilles du chien\u00a0\u00e0 base d'extraits d\u2019agrumes bio formul\u00e9 pour dissoudre le c\u00e9rumen, nettoyer les oreilles en douceur et nourrir l\u2019\u00e9piderme. Ne pas utiliser chez le chat.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/phytobiovet-nettoyant-oreilles-pour-chien\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/phytobiovet-nettoyant-oreilles-pour-chien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/phytobiovet-nettoyant-oreilles-pour-chien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/phytobiovet-nettoyant-oreilles.webp\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/phytobiovet-nettoyant-oreilles.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/phytobiovet-nettoyant-oreilles-pour-chien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Phytobiovet Nettoyant oreilles &#8211; chien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Mp Labo\" \/>\n<meta property=\"product:price:amount\" content=\"17.05\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"A-1849210\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Phytobiovet Nettoyant oreilles - chien Mp Labo - V\u00e9torino","description":"Nettoyant pour les\u00a0oreilles du chien\u00a0\u00e0 base d'extraits d\u2019agrumes bio formul\u00e9 pour dissoudre le c\u00e9rumen, nettoyer les oreilles en douceur et nourrir l\u2019\u00e9piderme.  Ne pas utiliser chez le chat.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Phytobiovet Nettoyant oreilles - chien Mp Labo - V\u00e9torino","og_description":"Nettoyant pour les\u00a0oreilles du chien\u00a0\u00e0 base d'extraits d\u2019agrumes bio formul\u00e9 pour dissoudre le c\u00e9rumen, nettoyer les oreilles en douceur et nourrir l\u2019\u00e9piderme.  Ne pas utiliser chez le chat.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/montpon-menesterol-24700\/boutique\/product\/phytobiovet-nettoyant-oreilles-pour-chien\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-06-30T15:44:17+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/04\/phytobiovet-nettoyant-oreilles.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"17,05&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/phytobiovet-nettoyant-oreilles-pour-chien\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/phytobiovet-nettoyant-oreilles-pour-chien\/","name":"Phytobiovet Nettoyant oreilles - chien Mp Labo - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/phytobiovet-nettoyant-oreilles-pour-chien\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/phytobiovet-nettoyant-oreilles-pour-chien\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/04\/phytobiovet-nettoyant-oreilles.webp","datePublished":"2021-04-29T18:22:38+00:00","dateModified":"2026-06-30T15:44:17+00:00","description":"Nettoyant pour les\u00a0oreilles du chien\u00a0\u00e0 base d'extraits d\u2019agrumes bio formul\u00e9 pour dissoudre le c\u00e9rumen, nettoyer les oreilles en douceur et nourrir l\u2019\u00e9piderme. Ne pas utiliser chez le chat.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/phytobiovet-nettoyant-oreilles-pour-chien\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/phytobiovet-nettoyant-oreilles-pour-chien\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/phytobiovet-nettoyant-oreilles-pour-chien\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/04\/phytobiovet-nettoyant-oreilles.webp","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/04\/phytobiovet-nettoyant-oreilles.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/phytobiovet-nettoyant-oreilles-pour-chien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Phytobiovet Nettoyant oreilles &#8211; chien"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Mp Labo","product_price_amount":"17.05","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"A-1849210","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/montpon-menesterol-24700\/boutique\/wp-json\/wp\/v2\/product\/174601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/montpon-menesterol-24700\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/montpon-menesterol-24700\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/montpon-menesterol-24700\/boutique\/wp-json\/wp\/v2\/media\/1907596"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/montpon-menesterol-24700\/boutique\/wp-json\/wp\/v2\/media?parent=174601"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/montpon-menesterol-24700\/boutique\/wp-json\/wp\/v2\/product_cat?post=174601"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/montpon-menesterol-24700\/boutique\/wp-json\/wp\/v2\/product_tag?post=174601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}