{"id":507740,"date":"2022-11-17T20:36:07","date_gmt":"2022-11-17T19:36:07","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/acti-selen-solution-orale\/"},"modified":"2025-07-22T18:01:36","modified_gmt":"2025-07-22T16:01:36","slug":"acti-selen-solution-orale","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/muret-31600\/boutique\/product\/acti-selen-solution-orale\/","title":{"rendered":"Acti Selen"},"content":{"rendered":"<p><strong>Suppl\u00e9ment nutritionnel<\/strong> de vitamine E et de s\u00e9l\u00e9nium <strong>pour bovins, ovins, caprins, porcins, volailles et lapins.<\/strong><br \/>\nRecommand\u00e9 lors des p\u00e9riodes o\u00f9 les besoins sont accrus : sevrage, phases critiques de croissance.<\/p>\n<p><strong>Voie orale<\/strong>, dans le lait ou l&#8217;eau de boisson.<\/p>\n<p>\u2022 Volailles, lapins : 1 mL pour 10 kg de poids vif, soit 10 mL pour 10 litres d&#8217;eau.<\/p>\n<p>\u2022 Veaux nouveau-n\u00e9s laitiers : 5 mL \u00e0 la naissance ; renouveler apr\u00e8s 15 jours.<\/p>\n<p>\u2022 Vaches laiti\u00e8res : au tarissement : 30 mL tous les 5 jours pendant 15 jours le mois qui pr\u00e9c\u00e8de le v\u00ealage. En lactation : 30 mL par semaine.<\/p>\n<p>\u2022 Ovins, caprins : 1 mL pour 10 kg de poids vif.<\/p>\n<p>\u2022 Truies : une semaine avant la mise-bas : 15 mL par jour pendant 4 jours.<\/p>\n<p>Dur\u00e9e maximale d&#8217;utilisation : 10 jours.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><strong>Suppl\u00e9ment nutritionnel<\/strong> de vitamine E et de s\u00e9l\u00e9nium <strong>pour bovins, ovins, caprins, porcins, volailles et lapins.<\/strong><br \/>\nRecommand\u00e9 lors des p\u00e9riodes o\u00f9 les besoins sont accrus : sevrage, phases critiques de croissance.<\/p>\n<p><strong>Voie orale<\/strong>, dans le lait ou l&#8217;eau de boisson.<\/p>\n<p>\u2022 Volailles, lapins : 1 mL pour 10 kg de poids vif, soit 10 mL pour 10 litres d&#8217;eau.<\/p>\n<p>\u2022 Veaux nouveau-n\u00e9s laitiers : 5 mL \u00e0 la naissance ; renouveler apr\u00e8s 15 jours.<\/p>\n<p>\u2022 Vaches laiti\u00e8res : au tarissement : 30 mL tous les 5 jours pendant 15 jours le mois qui pr\u00e9c\u00e8de le v\u00ealage. En lactation : 30 mL par semaine.<\/p>\n<p>\u2022 Ovins, caprins : 1 mL pour 10 kg de poids vif.<\/p>\n<p>\u2022 Truies : une semaine avant la mise-bas : 15 mL par jour pendant 4 jours.<\/p>\n<p>Dur\u00e9e maximale d&#8217;utilisation : 10 jours.<\/p>\n","protected":false},"featured_media":1423976,"template":"","meta":[],"product_cat":[2813,6864,6869,6870,6871,12563,6873,6874,6897],"product_tag":[],"class_list":{"0":"post-507740","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-aliments-complementaires-pour-lapin-rongeur","7":"product_cat-animaux-delevage","8":"product_cat-basse-cour","9":"product_cat-bovins","10":"product_cat-caprins","11":"product_cat-lapin","12":"product_cat-ovins","13":"product_cat-porcins","14":"product_cat-poules","15":"pa_marque-biove","17":"first","18":"instock","19":"taxable","20":"shipping-taxable","21":"purchasable","22":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Acti Selen Biove - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Suppl\u00e9ment nutritionnel de vitamine E et de s\u00e9l\u00e9nium pour bovins, ovins, caprins, porcins, volailles et lapins. Recommand\u00e9 lors des p\u00e9riodes o\u00f9 les besoins sont accrus : sevrage, phases critiques de croissance.  Voie orale, dans le lait ou l&#039;eau de boisson.  \u2022 Volailles, lapins : 1 mL pour 10 kg de poids vif, soit 10 mL pour 10 litres d&#039;eau.  \u2022 Veaux nouveau-n\u00e9s laitiers : 5 mL \u00e0 la naissance ; renouveler apr\u00e8s 15 jours.  \u2022 Vaches laiti\u00e8res : au tarissement : 30 mL tous les 5 jours pendant 15 jours le mois qui pr\u00e9c\u00e8de le v\u00ealage. En lactation : 30 mL par semaine.  \u2022 Ovins, caprins : 1 mL pour 10 kg de poids vif.  \u2022 Truies : une semaine avant la mise-bas : 15 mL par jour pendant 4 jours.  Dur\u00e9e maximale d&#039;utilisation : 10 jours.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acti Selen Biove - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Suppl\u00e9ment nutritionnel de vitamine E et de s\u00e9l\u00e9nium pour bovins, ovins, caprins, porcins, volailles et lapins. Recommand\u00e9 lors des p\u00e9riodes o\u00f9 les besoins sont accrus : sevrage, phases critiques de croissance.  Voie orale, dans le lait ou l&#039;eau de boisson.  \u2022 Volailles, lapins : 1 mL pour 10 kg de poids vif, soit 10 mL pour 10 litres d&#039;eau.  \u2022 Veaux nouveau-n\u00e9s laitiers : 5 mL \u00e0 la naissance ; renouveler apr\u00e8s 15 jours.  \u2022 Vaches laiti\u00e8res : au tarissement : 30 mL tous les 5 jours pendant 15 jours le mois qui pr\u00e9c\u00e8de le v\u00ealage. En lactation : 30 mL par semaine.  \u2022 Ovins, caprins : 1 mL pour 10 kg de poids vif.  \u2022 Truies : une semaine avant la mise-bas : 15 mL par jour pendant 4 jours.  Dur\u00e9e maximale d&#039;utilisation : 10 jours.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/muret-31600\/boutique\/product\/acti-selen-solution-orale\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-22T16:01:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/11\/acti-selen.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/acti-selen-solution-orale\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/acti-selen-solution-orale\\\/\",\"name\":\"Acti Selen Biove - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/acti-selen-solution-orale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/acti-selen-solution-orale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/acti-selen.webp\",\"datePublished\":\"2022-11-17T19:36:07+00:00\",\"dateModified\":\"2025-07-22T16:01:36+00:00\",\"description\":\"Suppl\u00e9ment nutritionnel de vitamine E et de s\u00e9l\u00e9nium pour bovins, ovins, caprins, porcins, volailles et lapins. Recommand\u00e9 lors des p\u00e9riodes o\u00f9 les besoins sont accrus : sevrage, phases critiques de croissance. Voie orale, dans le lait ou l'eau de boisson. \u2022 Volailles, lapins : 1 mL pour 10 kg de poids vif, soit 10 mL pour 10 litres d'eau. \u2022 Veaux nouveau-n\u00e9s laitiers : 5 mL \u00e0 la naissance ; renouveler apr\u00e8s 15 jours. \u2022 Vaches laiti\u00e8res : au tarissement : 30 mL tous les 5 jours pendant 15 jours le mois qui pr\u00e9c\u00e8de le v\u00ealage. En lactation : 30 mL par semaine. \u2022 Ovins, caprins : 1 mL pour 10 kg de poids vif. \u2022 Truies : une semaine avant la mise-bas : 15 mL par jour pendant 4 jours. Dur\u00e9e maximale d'utilisation : 10 jours.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/acti-selen-solution-orale\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/acti-selen-solution-orale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/acti-selen-solution-orale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/acti-selen.webp\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/acti-selen.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/acti-selen-solution-orale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Acti Selen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Biove\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acti Selen Biove - V\u00e9torino","description":"Suppl\u00e9ment nutritionnel de vitamine E et de s\u00e9l\u00e9nium pour bovins, ovins, caprins, porcins, volailles et lapins. Recommand\u00e9 lors des p\u00e9riodes o\u00f9 les besoins sont accrus : sevrage, phases critiques de croissance.  Voie orale, dans le lait ou l'eau de boisson.  \u2022 Volailles, lapins : 1 mL pour 10 kg de poids vif, soit 10 mL pour 10 litres d'eau.  \u2022 Veaux nouveau-n\u00e9s laitiers : 5 mL \u00e0 la naissance ; renouveler apr\u00e8s 15 jours.  \u2022 Vaches laiti\u00e8res : au tarissement : 30 mL tous les 5 jours pendant 15 jours le mois qui pr\u00e9c\u00e8de le v\u00ealage. En lactation : 30 mL par semaine.  \u2022 Ovins, caprins : 1 mL pour 10 kg de poids vif.  \u2022 Truies : une semaine avant la mise-bas : 15 mL par jour pendant 4 jours.  Dur\u00e9e maximale d'utilisation : 10 jours.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Acti Selen Biove - V\u00e9torino","og_description":"Suppl\u00e9ment nutritionnel de vitamine E et de s\u00e9l\u00e9nium pour bovins, ovins, caprins, porcins, volailles et lapins. Recommand\u00e9 lors des p\u00e9riodes o\u00f9 les besoins sont accrus : sevrage, phases critiques de croissance.  Voie orale, dans le lait ou l'eau de boisson.  \u2022 Volailles, lapins : 1 mL pour 10 kg de poids vif, soit 10 mL pour 10 litres d'eau.  \u2022 Veaux nouveau-n\u00e9s laitiers : 5 mL \u00e0 la naissance ; renouveler apr\u00e8s 15 jours.  \u2022 Vaches laiti\u00e8res : au tarissement : 30 mL tous les 5 jours pendant 15 jours le mois qui pr\u00e9c\u00e8de le v\u00ealage. En lactation : 30 mL par semaine.  \u2022 Ovins, caprins : 1 mL pour 10 kg de poids vif.  \u2022 Truies : une semaine avant la mise-bas : 15 mL par jour pendant 4 jours.  Dur\u00e9e maximale d'utilisation : 10 jours.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/muret-31600\/boutique\/product\/acti-selen-solution-orale\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2025-07-22T16:01:36+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/11\/acti-selen.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/acti-selen-solution-orale\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/acti-selen-solution-orale\/","name":"Acti Selen Biove - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/acti-selen-solution-orale\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/acti-selen-solution-orale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/11\/acti-selen.webp","datePublished":"2022-11-17T19:36:07+00:00","dateModified":"2025-07-22T16:01:36+00:00","description":"Suppl\u00e9ment nutritionnel de vitamine E et de s\u00e9l\u00e9nium pour bovins, ovins, caprins, porcins, volailles et lapins. Recommand\u00e9 lors des p\u00e9riodes o\u00f9 les besoins sont accrus : sevrage, phases critiques de croissance. Voie orale, dans le lait ou l'eau de boisson. \u2022 Volailles, lapins : 1 mL pour 10 kg de poids vif, soit 10 mL pour 10 litres d'eau. \u2022 Veaux nouveau-n\u00e9s laitiers : 5 mL \u00e0 la naissance ; renouveler apr\u00e8s 15 jours. \u2022 Vaches laiti\u00e8res : au tarissement : 30 mL tous les 5 jours pendant 15 jours le mois qui pr\u00e9c\u00e8de le v\u00ealage. En lactation : 30 mL par semaine. \u2022 Ovins, caprins : 1 mL pour 10 kg de poids vif. \u2022 Truies : une semaine avant la mise-bas : 15 mL par jour pendant 4 jours. Dur\u00e9e maximale d'utilisation : 10 jours.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/acti-selen-solution-orale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/acti-selen-solution-orale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/acti-selen-solution-orale\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/11\/acti-selen.webp","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/11\/acti-selen.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/acti-selen-solution-orale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Acti Selen"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Biove","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/muret-31600\/boutique\/wp-json\/wp\/v2\/product\/507740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/muret-31600\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/muret-31600\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/muret-31600\/boutique\/wp-json\/wp\/v2\/media\/1423976"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/muret-31600\/boutique\/wp-json\/wp\/v2\/media?parent=507740"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/muret-31600\/boutique\/wp-json\/wp\/v2\/product_cat?post=507740"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/muret-31600\/boutique\/wp-json\/wp\/v2\/product_tag?post=507740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}