{"id":507986,"date":"2022-11-17T20:45:16","date_gmt":"2022-11-17T19:45:16","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/c-for-energie\/"},"modified":"2025-07-29T10:08:41","modified_gmt":"2025-07-29T08:08:41","slug":"c-for-energie","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/muret-31600\/boutique\/product\/c-for-energie\/","title":{"rendered":"C for Energie +"},"content":{"rendered":"<p>Pour vaches laiti\u00e8res : Dans les<strong> situations de d\u00e9ficit \u00e9nerg\u00e9tique ou c\u00e9tose.<\/strong><\/p>\n<div class=\"texte_bloc\">\n<p>Il <strong>soutient le m\u00e9tabolisme \u00e9nerg\u00e9tique de l\u2019animal<\/strong> par l\u2019apport de 115 g de propionate de calcium par bolus qui est un pr\u00e9curseur de glucose permettant une <strong>compensation rapide du d\u00e9ficit \u00e9nerg\u00e9tique.<\/strong><\/p>\n<p>C for energie+<strong> stimule \u00e9galement l&#8217;activit\u00e9 de la microflore du rumen.<\/strong><\/p>\n<\/div>\n<p><em>Administrer \u00e0 l&#8217;aide d&#8217;un lance bolus universel Savetis, 1 bolus\/jour pendant 2 \u00e0 4 jours par vache.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour vaches laiti\u00e8res : Dans les<strong> situations de d\u00e9ficit \u00e9nerg\u00e9tique ou c\u00e9tose.<\/strong><\/p>\n<div class=\"texte_bloc\">\n<p>Il <strong>soutient le m\u00e9tabolisme \u00e9nerg\u00e9tique de l\u2019animal<\/strong> par l\u2019apport de 115 g de propionate de calcium par bolus qui est un pr\u00e9curseur de glucose permettant une <strong>compensation rapide du d\u00e9ficit \u00e9nerg\u00e9tique.<\/strong><\/p>\n<p>C for energie+<strong> stimule \u00e9galement l&#8217;activit\u00e9 de la microflore du rumen.<\/strong><\/p>\n<\/div>\n<p><em>Administrer \u00e0 l&#8217;aide d&#8217;un lance bolus universel Savetis, 1 bolus\/jour pendant 2 \u00e0 4 jours par vache.<\/em><\/p>\n","protected":false},"featured_media":1432082,"template":"","meta":[],"product_cat":[6864,6870],"product_tag":[],"class_list":{"0":"post-507986","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-animaux-delevage","7":"product_cat-bovins","8":"pa_marque-savetis","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>C for Energie + Savetis - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Pour vaches laiti\u00e8res : Dans les situations de d\u00e9ficit \u00e9nerg\u00e9tique ou c\u00e9tose.   Il soutient le m\u00e9tabolisme \u00e9nerg\u00e9tique de l\u2019animal par l\u2019apport de 115 g de propionate de calcium par bolus qui est un pr\u00e9curseur de glucose permettant une compensation rapide du d\u00e9ficit \u00e9nerg\u00e9tique.  C for energie+ stimule \u00e9galement l&#039;activit\u00e9 de la microflore du rumen.   Administrer \u00e0 l&#039;aide d&#039;un lance bolus universel Savetis, 1 bolus\/jour pendant 2 \u00e0 4 jours par vache.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C for Energie + Savetis - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Pour vaches laiti\u00e8res : Dans les situations de d\u00e9ficit \u00e9nerg\u00e9tique ou c\u00e9tose.   Il soutient le m\u00e9tabolisme \u00e9nerg\u00e9tique de l\u2019animal par l\u2019apport de 115 g de propionate de calcium par bolus qui est un pr\u00e9curseur de glucose permettant une compensation rapide du d\u00e9ficit \u00e9nerg\u00e9tique.  C for energie+ stimule \u00e9galement l&#039;activit\u00e9 de la microflore du rumen.   Administrer \u00e0 l&#039;aide d&#039;un lance bolus universel Savetis, 1 bolus\/jour pendant 2 \u00e0 4 jours par vache.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/muret-31600\/boutique\/product\/c-for-energie\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-29T08:08:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/11\/c-for-energie.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"522\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"60,88&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/c-for-energie\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/c-for-energie\\\/\",\"name\":\"C for Energie + Savetis - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/c-for-energie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/c-for-energie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/c-for-energie.png\",\"datePublished\":\"2022-11-17T19:45:16+00:00\",\"dateModified\":\"2025-07-29T08:08:41+00:00\",\"description\":\"Pour vaches laiti\u00e8res : Dans les situations de d\u00e9ficit \u00e9nerg\u00e9tique ou c\u00e9tose. Il soutient le m\u00e9tabolisme \u00e9nerg\u00e9tique de l\u2019animal par l\u2019apport de 115 g de propionate de calcium par bolus qui est un pr\u00e9curseur de glucose permettant une compensation rapide du d\u00e9ficit \u00e9nerg\u00e9tique. C for energie+ stimule \u00e9galement l'activit\u00e9 de la microflore du rumen. Administrer \u00e0 l'aide d'un lance bolus universel Savetis, 1 bolus\\\/jour pendant 2 \u00e0 4 jours par vache.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/c-for-energie\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/c-for-energie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/c-for-energie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/c-for-energie.png\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/c-for-energie.png\",\"width\":800,\"height\":522},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/c-for-energie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"C for Energie +\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Savetis\" \/>\n<meta property=\"product:price:amount\" content=\"60.88\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"A-1831840\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C for Energie + Savetis - V\u00e9torino","description":"Pour vaches laiti\u00e8res : Dans les situations de d\u00e9ficit \u00e9nerg\u00e9tique ou c\u00e9tose.   Il soutient le m\u00e9tabolisme \u00e9nerg\u00e9tique de l\u2019animal par l\u2019apport de 115 g de propionate de calcium par bolus qui est un pr\u00e9curseur de glucose permettant une compensation rapide du d\u00e9ficit \u00e9nerg\u00e9tique.  C for energie+ stimule \u00e9galement l'activit\u00e9 de la microflore du rumen.   Administrer \u00e0 l'aide d'un lance bolus universel Savetis, 1 bolus\/jour pendant 2 \u00e0 4 jours par vache.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"C for Energie + Savetis - V\u00e9torino","og_description":"Pour vaches laiti\u00e8res : Dans les situations de d\u00e9ficit \u00e9nerg\u00e9tique ou c\u00e9tose.   Il soutient le m\u00e9tabolisme \u00e9nerg\u00e9tique de l\u2019animal par l\u2019apport de 115 g de propionate de calcium par bolus qui est un pr\u00e9curseur de glucose permettant une compensation rapide du d\u00e9ficit \u00e9nerg\u00e9tique.  C for energie+ stimule \u00e9galement l'activit\u00e9 de la microflore du rumen.   Administrer \u00e0 l'aide d'un lance bolus universel Savetis, 1 bolus\/jour pendant 2 \u00e0 4 jours par vache.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/muret-31600\/boutique\/product\/c-for-energie\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2025-07-29T08:08:41+00:00","og_image":[{"width":800,"height":522,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/11\/c-for-energie.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"60,88&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/c-for-energie\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/c-for-energie\/","name":"C for Energie + Savetis - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/c-for-energie\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/c-for-energie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/11\/c-for-energie.png","datePublished":"2022-11-17T19:45:16+00:00","dateModified":"2025-07-29T08:08:41+00:00","description":"Pour vaches laiti\u00e8res : Dans les situations de d\u00e9ficit \u00e9nerg\u00e9tique ou c\u00e9tose. Il soutient le m\u00e9tabolisme \u00e9nerg\u00e9tique de l\u2019animal par l\u2019apport de 115 g de propionate de calcium par bolus qui est un pr\u00e9curseur de glucose permettant une compensation rapide du d\u00e9ficit \u00e9nerg\u00e9tique. C for energie+ stimule \u00e9galement l'activit\u00e9 de la microflore du rumen. Administrer \u00e0 l'aide d'un lance bolus universel Savetis, 1 bolus\/jour pendant 2 \u00e0 4 jours par vache.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/c-for-energie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/c-for-energie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/c-for-energie\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/11\/c-for-energie.png","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2022\/11\/c-for-energie.png","width":800,"height":522},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/c-for-energie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"C for Energie +"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Savetis","product_price_amount":"60.88","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"A-1831840","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/muret-31600\/boutique\/wp-json\/wp\/v2\/product\/507986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/muret-31600\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/muret-31600\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/muret-31600\/boutique\/wp-json\/wp\/v2\/media\/1432082"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/muret-31600\/boutique\/wp-json\/wp\/v2\/media?parent=507986"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/muret-31600\/boutique\/wp-json\/wp\/v2\/product_cat?post=507986"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/muret-31600\/boutique\/wp-json\/wp\/v2\/product_tag?post=507986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}