{"id":1163686,"date":"2025-01-13T12:00:00","date_gmt":"2025-01-13T11:00:00","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/?p=1163686"},"modified":"2025-01-08T08:52:58","modified_gmt":"2025-01-08T07:52:58","slug":"rappel-croquettes-salmonelle","status":"publish","type":"post","link":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/2025\/01\/13\/rappel-croquettes-salmonelle\/","title":{"rendered":"Rappel en cours de croquettes pour chat et chien [contamination aux salmonelles]"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1163686\" class=\"elementor elementor-1163686\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b4747b9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b4747b9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f0a8be6\" data-id=\"f0a8be6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77b80b4 elementor-widget elementor-widget-text-editor\" data-id=\"77b80b4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<section data-id=\"8j8qvkr\" data-element_type=\"section\">\n<div data-id=\"2u8kg9v\" data-element_type=\"column\">\n<div data-id=\"tcv8rwn\" data-element_type=\"heading.default\">\n<h2>Rappel en cours de croquettes pour chat et chien en raison d&#8217;une contamination aux salmonelles\u00a0<br \/><!-- notionvc: 5af60c17-bda6-435a-b790-601224d87c2e --><\/h2>\n<\/div>\n<\/div>\n<\/section>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86b51a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86b51a2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ca49f12\" data-id=\"ca49f12\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d92d7f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"2d92d7f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Depuis fin d\u00e9cembre, un rappel massif est en cours en France. Il concerne <strong>des croquettes pour chiens et chats pour cause de suspicion de contamination \u00e0 la salmonelle<\/strong>, un agent pathog\u00e8ne qui provoque des troubles digestifs et peut avoir de graves cons\u00e9quences sur la sant\u00e9 de nos animaux.<\/p>\n<p><!-- notionvc: f3365c80-e02e-467b-b5ae-31b62867bbca --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90b5d84 elementor-widget elementor-widget-image\" data-id=\"90b5d84\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.vetorino.com\/boutique\/marque\/royal-canin\/?s&#038;maladie=troubles-digestifs&#038;swcfpc=1\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2048\" height=\"1152\" src=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/rappel-croquettes-salmonelle-2048x1152.jpg\" class=\"attachment-2048x2048 size-2048x2048 wp-image-1164459\" alt=\"rappel croquettes salmonelle\" srcset=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/rappel-croquettes-salmonelle-2048x1152.jpg 2048w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/rappel-croquettes-salmonelle-300x169.jpg 300w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/rappel-croquettes-salmonelle-1024x576.jpg 1024w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/rappel-croquettes-salmonelle-768x432.jpg 768w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/rappel-croquettes-salmonelle-1536x864.jpg 1536w, https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/rappel-croquettes-salmonelle-555x312.jpg 555w\" sizes=\"(max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6cb33a2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6cb33a2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-89d7b48\" data-id=\"89d7b48\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e390030 elementor-widget elementor-widget-heading\" data-id=\"e390030\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Rappel croquettes : quelles sont les marques concern\u00e9es ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50e8476 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"50e8476\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Les marques de croquettes pour chats et chiens concern\u00e9es sont :<\/p>\n<ul>\n<li>Canaillou (Intermarch\u00e9)<\/li>\n<li>Cora (Carrefour)<\/li>\n<li>Companino (Carrefour)<\/li>\n<li>Orlando (Lidl)<\/li>\n<li>Pl\u00e9nima (Leclerc)<\/li>\n<li>Premier Prix (Carrefour)<\/li>\n<li>Top Budget (Intermarch\u00e9)<\/li>\n<li>Tous mes ams (Leclerc)<\/li>\n<li>Ultra Premium Direct<\/li>\n<\/ul>\n<p><!-- notionvc: b7a585a4-5655-4b43-8ae9-57a819d84d96 --><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8746fce elementor-widget elementor-widget-text-editor\" data-id=\"8746fce\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vous trouverez tous les d\u00e9tails sur les diff\u00e9rents lots concern\u00e9s sur le site national <a href=\"https:\/\/rappel.conso.gouv.fr\/categorie\/18\/1\">Rappel Conso<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c516720 elementor-widget elementor-widget-heading\" data-id=\"c516720\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Le choix de croquettes v\u00e9t\u00e9rinaire : une valeur s\u00fbre pour son animal<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4434af4 elementor-widget elementor-widget-text-editor\" data-id=\"4434af4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Cet incident souligne l\u2019importance de s\u00e9lectionner des fournisseurs et aliments de qualit\u00e9, \u00e9labor\u00e9s sous contr\u00f4le v\u00e9t\u00e9rinaire, afin de limiter au maximum les risques d\u2019intoxication ou de probl\u00e8mes de sant\u00e9. C\u2019est pourquoi chez V\u00e9torino, nous s\u00e9lectionnons uniquement des marques v\u00e9t\u00e9rinaires.<\/p>\n<p>\u2705\u00a0Les contr\u00f4les qualit\u00e9 sont nombreux et rigoureux,<\/p>\n<p>\u2705 les ingr\u00e9dients de qualit\u00e9 et les recettes adapt\u00e9s aux besoins nutritionnels de nos animaux.<\/p>\n<p>\u2705\u00a0Sans oublier la recherche et d\u00e9veloppement constants men\u00e9s pour am\u00e9liorer les aliments v\u00e9t\u00e9rinaires.<\/p>\n<p>Opter pour des croquettes v\u00e9t\u00e9rinaires, c&#8217;est faire le choix de la qualit\u00e9, de la s\u00e9curit\u00e9 et du bien-\u00eatre pour votre animal.<\/p>\n<p>Prenez soin de vos animaux, commandez chez V\u00e9torino, la boutique en ligne de votre v\u00e9t\u00e9rinaire.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f66cce elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7f66cce\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.vetorino.com\/veterinaire\/lasellesurlebied-45210\/boutique\/?s=&#038;post_type=product&#038;promotion=1\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir les promotions du moment<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Rappel en cours de croquettes pour chat et chien en raison d&#8217;une contamination aux salmonelles\u00a0 Depuis fin d\u00e9cembre, un rappel massif est en cours en France. Il concerne des croquettes pour chiens et chats pour cause de suspicion de contamination \u00e0 la salmonelle, un agent pathog\u00e8ne qui provoque des troubles digestifs et peut avoir de [&hellip;]<\/p>\n","protected":false},"author":68707,"featured_media":1164474,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_theme","format":"standard","meta":{"footnotes":""},"categories":[14089,14088,14086,14087,14095,14094],"tags":[],"class_list":["post-1163686","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentation-chat","category-alimentation-chien","category-chat","category-chien","category-sante-et-prevention-chat","category-sante-chien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rappel croquettes chat et chien : d\u00e9couvrez les marques concern\u00e9es<\/title>\n<meta name=\"description\" content=\"Depuis fin d\u00e9cembre, un rappel massif de lots de croquettes pour chien et chat est en cours. D\u00e9couvrez quelles marques sont concern\u00e9es.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rappel croquettes chat et chien : d\u00e9couvrez les marques concern\u00e9es\" \/>\n<meta property=\"og:description\" content=\"Depuis fin d\u00e9cembre, un rappel massif de lots de croquettes pour chien et chat est en cours. D\u00e9couvrez quelles marques sont concern\u00e9es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/2025\/01\/13\/rappel-croquettes-salmonelle\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-13T11:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/rappel-croquettes-animaux-contamination-salmonelle.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1905\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Clemence Sully\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Clemence Sully\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/01\\\/13\\\/rappel-croquettes-salmonelle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/01\\\/13\\\/rappel-croquettes-salmonelle\\\/\"},\"author\":{\"name\":\"Clemence Sully\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/9bd231449b5dab066d32dab7d241eb4a\"},\"headline\":\"Rappel en cours de croquettes pour chat et chien [contamination aux salmonelles]\",\"datePublished\":\"2025-01-13T11:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/01\\\/13\\\/rappel-croquettes-salmonelle\\\/\"},\"wordCount\":297,\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/01\\\/13\\\/rappel-croquettes-salmonelle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/rappel-croquettes-animaux-contamination-salmonelle.jpg\",\"articleSection\":[\"Alimentation pour chat\",\"Alimentation pour chien\",\"Chat\",\"Chien\",\"Sant\u00e9 et pr\u00e9vention pour chat\",\"Sant\u00e9 pour chien\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/01\\\/13\\\/rappel-croquettes-salmonelle\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/01\\\/13\\\/rappel-croquettes-salmonelle\\\/\",\"name\":\"Rappel croquettes chat et chien : d\u00e9couvrez les marques concern\u00e9es\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/01\\\/13\\\/rappel-croquettes-salmonelle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/01\\\/13\\\/rappel-croquettes-salmonelle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/rappel-croquettes-animaux-contamination-salmonelle.jpg\",\"datePublished\":\"2025-01-13T11:00:00+00:00\",\"description\":\"Depuis fin d\u00e9cembre, un rappel massif de lots de croquettes pour chien et chat est en cours. D\u00e9couvrez quelles marques sont concern\u00e9es.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/01\\\/13\\\/rappel-croquettes-salmonelle\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/01\\\/13\\\/rappel-croquettes-salmonelle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/01\\\/13\\\/rappel-croquettes-salmonelle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/rappel-croquettes-animaux-contamination-salmonelle.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/rappel-croquettes-animaux-contamination-salmonelle.jpg\",\"width\":1905,\"height\":450,\"caption\":\"rappel croquettes animaux contamination salmonelle\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/2025\\\/01\\\/13\\\/rappel-croquettes-salmonelle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chien\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/champs-sur-marne-77420\\\/boutique\\\/category\\\/chien\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rappel en cours de croquettes pour chat et chien [contamination aux salmonelles]\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/person\\\/9bd231449b5dab066d32dab7d241eb4a\",\"name\":\"Clemence Sully\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g\",\"caption\":\"Clemence Sully\"},\"url\":\"https:\\\/\\\/www.vetorino.com\\\/veterinaire\\\/nangy-74380\\\/boutique\\\/author\\\/clemence-sully\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rappel croquettes chat et chien : d\u00e9couvrez les marques concern\u00e9es","description":"Depuis fin d\u00e9cembre, un rappel massif de lots de croquettes pour chien et chat est en cours. D\u00e9couvrez quelles marques sont concern\u00e9es.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Rappel croquettes chat et chien : d\u00e9couvrez les marques concern\u00e9es","og_description":"Depuis fin d\u00e9cembre, un rappel massif de lots de croquettes pour chien et chat est en cours. D\u00e9couvrez quelles marques sont concern\u00e9es.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/2025\/01\/13\/rappel-croquettes-salmonelle\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_published_time":"2025-01-13T11:00:00+00:00","og_image":[{"width":1905,"height":450,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/rappel-croquettes-animaux-contamination-salmonelle.jpg","type":"image\/jpeg"}],"author":"Clemence Sully","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Clemence Sully","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vetorino.com\/boutique\/2025\/01\/13\/rappel-croquettes-salmonelle\/#article","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/01\/13\/rappel-croquettes-salmonelle\/"},"author":{"name":"Clemence Sully","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/9bd231449b5dab066d32dab7d241eb4a"},"headline":"Rappel en cours de croquettes pour chat et chien [contamination aux salmonelles]","datePublished":"2025-01-13T11:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/01\/13\/rappel-croquettes-salmonelle\/"},"wordCount":297,"publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/01\/13\/rappel-croquettes-salmonelle\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/rappel-croquettes-animaux-contamination-salmonelle.jpg","articleSection":["Alimentation pour chat","Alimentation pour chien","Chat","Chien","Sant\u00e9 et pr\u00e9vention pour chat","Sant\u00e9 pour chien"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/2025\/01\/13\/rappel-croquettes-salmonelle\/","url":"https:\/\/www.vetorino.com\/boutique\/2025\/01\/13\/rappel-croquettes-salmonelle\/","name":"Rappel croquettes chat et chien : d\u00e9couvrez les marques concern\u00e9es","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/01\/13\/rappel-croquettes-salmonelle\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/01\/13\/rappel-croquettes-salmonelle\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/rappel-croquettes-animaux-contamination-salmonelle.jpg","datePublished":"2025-01-13T11:00:00+00:00","description":"Depuis fin d\u00e9cembre, un rappel massif de lots de croquettes pour chien et chat est en cours. D\u00e9couvrez quelles marques sont concern\u00e9es.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/2025\/01\/13\/rappel-croquettes-salmonelle\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/2025\/01\/13\/rappel-croquettes-salmonelle\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/2025\/01\/13\/rappel-croquettes-salmonelle\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/rappel-croquettes-animaux-contamination-salmonelle.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2025\/01\/rappel-croquettes-animaux-contamination-salmonelle.jpg","width":1905,"height":450,"caption":"rappel croquettes animaux contamination salmonelle"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/2025\/01\/13\/rappel-croquettes-salmonelle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Chien","item":"https:\/\/www.vetorino.com\/veterinaire\/champs-sur-marne-77420\/boutique\/category\/chien\/"},{"@type":"ListItem","position":3,"name":"Rappel en cours de croquettes pour chat et chien [contamination aux salmonelles]"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]},{"@type":"Person","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/person\/9bd231449b5dab066d32dab7d241eb4a","name":"Clemence Sully","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c3d07ba2476f12a193e063eb436c57178aa9b6b609c49b221686f61773d2f29?s=96&d=mm&r=g","caption":"Clemence Sully"},"url":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/author\/clemence-sully\/"}]}},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/posts\/1163686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/users\/68707"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/comments?post=1163686"}],"version-history":[{"count":8,"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/posts\/1163686\/revisions"}],"predecessor-version":[{"id":1164472,"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/posts\/1163686\/revisions\/1164472"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/media\/1164474"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/media?parent=1163686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/categories?post=1163686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/tags?post=1163686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}