{"id":101453,"date":"2020-06-30T11:46:31","date_gmt":"2020-06-30T09:46:31","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/redplex-booster\/"},"modified":"2026-05-11T21:18:38","modified_gmt":"2026-05-11T19:18:38","slug":"redplex-booster","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/product\/redplex-booster\/","title":{"rendered":"Redplex Booster"},"content":{"rendered":"<p><strong>REDPLEX BOOSTER est con\u00e7u pour apporter aux chevaux un soutien nutritionnel adapt\u00e9 aux chevaux \u00e0 l&#8217;entra\u00eenement et en comp\u00e9tition, ainsi qu&#8217;aux chevaux ayant des baisses de performance.<\/strong><\/p>\n<p><strong><br \/>\nUtilisation :<\/strong><\/p>\n<ul>\n<li>\u00c9v\u00e9nements importants : comp\u00e9tition, courses, entra\u00eenements intenses, situations de stress.<\/li>\n<li>Chevaux \u00e0 l&#8217;entra\u00eenement et en comp\u00e9tition, ainsi que les chevaux ayant des baisses de performance<\/li>\n<\/ul>\n<p><strong>Avantages :<\/strong><\/p>\n<ul>\n<li>Apporte \u00e0 votre cheval tous les \u00e9l\u00e9ments qu\u2019il va<strong>\u00a0rapidement assimiler lors de l\u2019effort<\/strong>.<\/li>\n<li>Tr\u00e8s riche en vitamines et min\u00e9raux catalyseurs d\u2019\u00e9nergie pour donner toute sa\u00a0<strong>puissance<\/strong>\u00a0au cheval.<\/li>\n<li>Utilisez avant tous les \u00e9v\u00e8nements importants : comp\u00e9tition, courses, entra\u00eenements intenses, situations de stress.<\/li>\n<li><strong>Pratique<\/strong>\u00a0et facile \u00e0 transporter<\/li>\n<li>Ar\u00f4me\u00a0<strong>pomme<\/strong>\u00a0qui le rend tr\u00e8s\u00a0<strong>app\u00e9tent<\/strong>.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p><strong>REDPLEX BOOSTER est\u00a0con\u00e7u pour apporter aux chevaux un soutien nutritionnel adapt\u00e9 aux chevaux \u00e0 l&#8217;entra\u00eenement et en comp\u00e9tition, ainsi qu&#8217;aux chevaux ayant des baisses de performance.<\/strong><\/p>\n<p><strong>Utilisation :<\/strong><\/p>\n<ul>\n<li>\u00c9v\u00e9nements importants : comp\u00e9tition, courses, entra\u00eenements intenses, situations de stress.<\/li>\n<li>Chevaux \u00e0 l&#8217;entra\u00eenement et en comp\u00e9tition, ainsi que les chevaux ayant des baisses de performance.<\/li>\n<\/ul>\n","protected":false},"featured_media":1218273,"template":"","meta":[],"product_cat":[12757,12547,14072,12752,12566,12754],"product_tag":[],"class_list":{"0":"post-101453","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alimentation-du-cheval","7":"product_cat-cheval","8":"product_cat-dietetique-et-complements-alimentaires-du-cheval","9":"product_cat-gestion-de-leffort-du-cheval","10":"product_cat-performance-du-cheval","11":"product_cat-soins-au-quotidien-du-cheval","12":"pa_marque-audevard","14":"first","15":"instock","16":"taxable","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Redplex Booster Audevard - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"REDPLEX BOOSTER est\u00a0con\u00e7u pour apporter aux chevaux un soutien nutritionnel adapt\u00e9 aux chevaux \u00e0 l&#039;entra\u00eenement et en comp\u00e9tition, ainsi qu&#039;aux chevaux ayant des baisses de performance.  Utilisation :   \u00c9v\u00e9nements importants : comp\u00e9tition, courses, entra\u00eenements intenses, situations de stress.  Chevaux \u00e0 l&#039;entra\u00eenement et en comp\u00e9tition, ainsi que les chevaux ayant des baisses de performance.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Redplex Booster Audevard - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"REDPLEX BOOSTER est\u00a0con\u00e7u pour apporter aux chevaux un soutien nutritionnel adapt\u00e9 aux chevaux \u00e0 l&#039;entra\u00eenement et en comp\u00e9tition, ainsi qu&#039;aux chevaux ayant des baisses de performance.  Utilisation :   \u00c9v\u00e9nements importants : comp\u00e9tition, courses, entra\u00eenements intenses, situations de stress.  Chevaux \u00e0 l&#039;entra\u00eenement et en comp\u00e9tition, ainsi que les chevaux ayant des baisses de performance.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/product\/redplex-booster\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-11T19:18:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/redplex-booster-audevard.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"458\" \/>\n\t<meta property=\"og:image:height\" content=\"458\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"19,00&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/redplex-booster\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/redplex-booster\\\/\",\"name\":\"Redplex Booster Audevard - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/redplex-booster\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/redplex-booster\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/redplex-booster.webp\",\"datePublished\":\"2020-06-30T09:46:31+00:00\",\"dateModified\":\"2026-05-11T19:18:38+00:00\",\"description\":\"REDPLEX BOOSTER est\u00a0con\u00e7u pour apporter aux chevaux un soutien nutritionnel adapt\u00e9 aux chevaux \u00e0 l'entra\u00eenement et en comp\u00e9tition, ainsi qu'aux chevaux ayant des baisses de performance. Utilisation : \u00c9v\u00e9nements importants : comp\u00e9tition, courses, entra\u00eenements intenses, situations de stress. Chevaux \u00e0 l'entra\u00eenement et en comp\u00e9tition, ainsi que les chevaux ayant des baisses de performance.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/redplex-booster\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/redplex-booster\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/redplex-booster\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/redplex-booster.webp\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/redplex-booster.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/redplex-booster\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Redplex Booster\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Audevard\" \/>\n<meta property=\"product:price:amount\" content=\"19.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"C-RED009\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Redplex Booster Audevard - V\u00e9torino","description":"REDPLEX BOOSTER est\u00a0con\u00e7u pour apporter aux chevaux un soutien nutritionnel adapt\u00e9 aux chevaux \u00e0 l'entra\u00eenement et en comp\u00e9tition, ainsi qu'aux chevaux ayant des baisses de performance.  Utilisation :   \u00c9v\u00e9nements importants : comp\u00e9tition, courses, entra\u00eenements intenses, situations de stress.  Chevaux \u00e0 l'entra\u00eenement et en comp\u00e9tition, ainsi que les chevaux ayant des baisses de performance.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Redplex Booster Audevard - V\u00e9torino","og_description":"REDPLEX BOOSTER est\u00a0con\u00e7u pour apporter aux chevaux un soutien nutritionnel adapt\u00e9 aux chevaux \u00e0 l'entra\u00eenement et en comp\u00e9tition, ainsi qu'aux chevaux ayant des baisses de performance.  Utilisation :   \u00c9v\u00e9nements importants : comp\u00e9tition, courses, entra\u00eenements intenses, situations de stress.  Chevaux \u00e0 l'entra\u00eenement et en comp\u00e9tition, ainsi que les chevaux ayant des baisses de performance.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/product\/redplex-booster\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-05-11T19:18:38+00:00","og_image":[{"width":458,"height":458,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/redplex-booster-audevard.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"19,00&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/redplex-booster\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/redplex-booster\/","name":"Redplex Booster Audevard - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/redplex-booster\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/redplex-booster\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/redplex-booster.webp","datePublished":"2020-06-30T09:46:31+00:00","dateModified":"2026-05-11T19:18:38+00:00","description":"REDPLEX BOOSTER est\u00a0con\u00e7u pour apporter aux chevaux un soutien nutritionnel adapt\u00e9 aux chevaux \u00e0 l'entra\u00eenement et en comp\u00e9tition, ainsi qu'aux chevaux ayant des baisses de performance. Utilisation : \u00c9v\u00e9nements importants : comp\u00e9tition, courses, entra\u00eenements intenses, situations de stress. Chevaux \u00e0 l'entra\u00eenement et en comp\u00e9tition, ainsi que les chevaux ayant des baisses de performance.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/redplex-booster\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/redplex-booster\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/redplex-booster\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/redplex-booster.webp","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2021\/05\/redplex-booster.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/redplex-booster\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Redplex Booster"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Audevard","product_price_amount":"19.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"C-RED009","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/product\/101453","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/media\/1218273"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/media?parent=101453"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/product_cat?post=101453"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/product_tag?post=101453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}