{"id":97813,"date":"2020-06-29T22:39:03","date_gmt":"2020-06-29T20:39:03","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/housse-de-banquette-arriere-de-voiture-en-nylon\/"},"modified":"2025-05-27T09:41:31","modified_gmt":"2025-05-27T07:41:31","slug":"housse-de-banquette-arriere-de-voiture-en-nylon","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/product\/housse-de-banquette-arriere-de-voiture-en-nylon\/","title":{"rendered":"Housse de banquette arri\u00e8re Trixie en nylon"},"content":{"rendered":"<div class=\"hidden\">MATERIEL<\/div>\n<div class=\"hidden\">Chiens<\/div>\n<p>Caract\u00e9ristiques :<\/p>\n<ul>\n<li>Surface anti-d\u00e9rapante \u00e0 picots caoutchouc pour plus de maintien pour l&#8217;animal.<\/li>\n<li>C\u00f4t\u00e9s amovibles pour l&#8217;emp\u00eacher de sauter et prot\u00e9ger le garnissage.<\/li>\n<li>Avec partie repliable, lib\u00e9rant un si\u00e8ge.<\/li>\n<li>Tiges m\u00e9tal pour une forme plus stable.<\/li>\n<li>Fentes pour le passage des laisses de s\u00e9curit\u00e9.<\/li>\n<li>Nettoyage au chiffon.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Cette housse de si\u00e8ge auto pour chiens de TRIXIE prot\u00e8ge votre si\u00e8ge arri\u00e8re des poils d&#8217;animaux et des pattes boueuses.<\/p>\n","protected":false},"featured_media":625530,"template":"","meta":[],"product_cat":[12550,2698],"product_tag":[],"class_list":{"0":"post-97813","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-accessoires-du-chien","7":"product_cat-chien","8":"pa_marque-trixie","10":"first","11":"instock","12":"taxable","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Housse de banquette arri\u00e8re Trixie en nylon Trixie - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Cette housse de si\u00e8ge auto pour chiens de TRIXIE prot\u00e8ge votre si\u00e8ge arri\u00e8re des poils d&#039;animaux et des pattes boueuses.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Housse de banquette arri\u00e8re Trixie en nylon Trixie - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Cette housse de si\u00e8ge auto pour chiens de TRIXIE prot\u00e8ge votre si\u00e8ge arri\u00e8re des poils d&#039;animaux et des pattes boueuses.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/product\/housse-de-banquette-arriere-de-voiture-en-nylon\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-27T07:41:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/trixie-protection-pour-siege-de-voiture-150-x-135-cm.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1387\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Prix\" \/>\n\t<meta name=\"twitter:data1\" content=\"33,10&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data2\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/housse-de-banquette-arriere-de-voiture-en-nylon\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/housse-de-banquette-arriere-de-voiture-en-nylon\\\/\",\"name\":\"Housse de banquette arri\u00e8re Trixie en nylon Trixie - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/housse-de-banquette-arriere-de-voiture-en-nylon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/housse-de-banquette-arriere-de-voiture-en-nylon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/trixie-protection-pour-siege-de-voiture-150-x-135-cm.jpg\",\"datePublished\":\"2020-06-29T20:39:03+00:00\",\"dateModified\":\"2025-05-27T07:41:31+00:00\",\"description\":\"Cette housse de si\u00e8ge auto pour chiens de TRIXIE prot\u00e8ge votre si\u00e8ge arri\u00e8re des poils d'animaux et des pattes boueuses.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/housse-de-banquette-arriere-de-voiture-en-nylon\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/housse-de-banquette-arriere-de-voiture-en-nylon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/housse-de-banquette-arriere-de-voiture-en-nylon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/trixie-protection-pour-siege-de-voiture-150-x-135-cm.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/trixie-protection-pour-siege-de-voiture-150-x-135-cm.jpg\",\"width\":1500,\"height\":1387},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/housse-de-banquette-arriere-de-voiture-en-nylon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Housse de banquette arri\u00e8re Trixie en nylon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Trixie\" \/>\n<meta property=\"product:price:amount\" content=\"33.10\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"C-HOU709\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Housse de banquette arri\u00e8re Trixie en nylon Trixie - V\u00e9torino","description":"Cette housse de si\u00e8ge auto pour chiens de TRIXIE prot\u00e8ge votre si\u00e8ge arri\u00e8re des poils d'animaux et des pattes boueuses.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Housse de banquette arri\u00e8re Trixie en nylon Trixie - V\u00e9torino","og_description":"Cette housse de si\u00e8ge auto pour chiens de TRIXIE prot\u00e8ge votre si\u00e8ge arri\u00e8re des poils d'animaux et des pattes boueuses.","og_url":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/product\/housse-de-banquette-arriere-de-voiture-en-nylon\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2025-05-27T07:41:31+00:00","og_image":[{"width":1500,"height":1387,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/trixie-protection-pour-siege-de-voiture-150-x-135-cm.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Prix":"33,10&euro;","Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/housse-de-banquette-arriere-de-voiture-en-nylon\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/housse-de-banquette-arriere-de-voiture-en-nylon\/","name":"Housse de banquette arri\u00e8re Trixie en nylon Trixie - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/housse-de-banquette-arriere-de-voiture-en-nylon\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/housse-de-banquette-arriere-de-voiture-en-nylon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/trixie-protection-pour-siege-de-voiture-150-x-135-cm.jpg","datePublished":"2020-06-29T20:39:03+00:00","dateModified":"2025-05-27T07:41:31+00:00","description":"Cette housse de si\u00e8ge auto pour chiens de TRIXIE prot\u00e8ge votre si\u00e8ge arri\u00e8re des poils d'animaux et des pattes boueuses.","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/housse-de-banquette-arriere-de-voiture-en-nylon\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/housse-de-banquette-arriere-de-voiture-en-nylon\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/housse-de-banquette-arriere-de-voiture-en-nylon\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/trixie-protection-pour-siege-de-voiture-150-x-135-cm.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/06\/trixie-protection-pour-siege-de-voiture-150-x-135-cm.jpg","width":1500,"height":1387},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/housse-de-banquette-arriere-de-voiture-en-nylon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Housse de banquette arri\u00e8re Trixie en nylon"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Trixie","product_price_amount":"33.10","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"C-HOU709","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/product\/97813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/media\/625530"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/media?parent=97813"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/product_cat?post=97813"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/nangy-74380\/boutique\/wp-json\/wp\/v2\/product_tag?post=97813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}