{"id":96392,"date":"2020-06-29T17:41:18","date_gmt":"2020-06-29T15:41:18","guid":{"rendered":"https:\/\/www.vetorino.com\/boutique\/product\/frontline-combo-chat\/"},"modified":"2026-07-22T02:42:14","modified_gmt":"2026-07-22T00:42:14","slug":"frontline-combo-chat","status":"publish","type":"product","link":"https:\/\/www.vetorino.com\/veterinaire\/pogny-51240\/boutique\/product\/frontline-combo-chat\/","title":{"rendered":"Frontline Combo Chat"},"content":{"rendered":"<p>Frontline Combo Chat est une <strong>solution cutan\u00e9e<\/strong> cibl\u00e9e pour chats indiqu\u00e9e dans le<strong> traitement et la pr\u00e9vention des infestations de tiques<\/strong>, de <strong>puces<\/strong> et de <strong>poux<\/strong> <strong>broyeurs<\/strong>.<\/p>\n<p><strong>Caract\u00e9ristiques :\u00a0<\/strong><\/p>\n<ul>\n<li>Action insecticide contre l&#8217;apparition de puces adultes,\u00a0<strong>persiste pendant 4 semaines.<\/strong><\/li>\n<li>Action acaricide contre les tiques,\u00a0<strong>persiste jusqu&#8217;\u00e0 2 semaines.<\/strong><\/li>\n<li>Assure une protection continue gr\u00e2ce \u00e0 une double action sur les puces:\u00a0<strong>\u00e0 la fois sur les adultes et sur les larves<\/strong><\/li>\n<li>Permet de pr\u00e9server l\u2019habitat de toute infestation de puces gr\u00e2ce au S m\u00e9thopr\u00e8ne : il s\u2019agit d\u2019un r\u00e9gulateur de croissance qui va r\u00e9duire la ponte des puces, \u00e9viter l\u2019\u00e9closion des larves et la formation de cocons.<\/li>\n<\/ul>\n<p>A savoir :\u00a0Le m\u00e9dicament peut \u00eatre int\u00e9gr\u00e9 dans un programme th\u00e9rapeutique de la Dermatite Allergique par Piq\u00fbres de Puces (DAPP).<\/p>\n<p><strong>CONTRE-INDICATION: Ne pas traiter les chatons de moins de 2 mois et\/ou pesant moins de 1kg.<\/strong><\/p>\n<p><strong>Veuillez consulter votre v\u00e9t\u00e9rinaire avant utilisation.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Frontline Combo Chat est une <strong>solution cutan\u00e9e<\/strong> cibl\u00e9e pour chats indiqu\u00e9e dans le<strong> traitement et la pr\u00e9vention des infestations de tiques<\/strong>, de <strong>puces<\/strong> et de <strong>poux<\/strong> <strong>broyeurs<\/strong>.<\/p>\n<p><strong>Caract\u00e9ristiques :\u00a0<\/strong><\/p>\n<ul>\n<li>Action insecticide contre l&#8217;apparition de puces adultes,\u00a0<strong>persiste pendant 4 semaines.<\/strong><\/li>\n<li>Action acaricide contre les tiques,\u00a0<strong>persiste jusqu&#8217;\u00e0 2 semaines.<\/strong><\/li>\n<li>Assure une protection continue gr\u00e2ce \u00e0 une double action sur les puces:\u00a0<strong>\u00e0 la fois sur les adultes et sur les larves<\/strong><\/li>\n<li>Permet de pr\u00e9server l\u2019habitat de toute <strong>infestation<\/strong> de puces<\/li>\n<\/ul>\n","protected":false},"featured_media":1737534,"template":"","meta":[],"product_cat":[12553,2697,12560],"product_tag":[],"class_list":["post-96392","product","type-product","status-publish","has-post-thumbnail","product_cat-antiparasitaire-du-chat","product_cat-chat","product_cat-hygiene-du-chat","pa_marque-boehringer","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Frontline Frontline Combo Chat Boehringer - V\u00e9torino<\/title>\n<meta name=\"description\" content=\"Frontline Combo Chat est une solution cutan\u00e9e cibl\u00e9e pour chats indiqu\u00e9e dans le traitement et la pr\u00e9vention des infestations de tiques, de puces et de poux broyeurs.  Caract\u00e9ristiques :\u00a0   Action insecticide contre l&#039;apparition de puces adultes,\u00a0persiste pendant 4 semaines.  Action acaricide contre les tiques,\u00a0persiste jusqu&#039;\u00e0 2 semaines.  Assure une protection continue gr\u00e2ce \u00e0 une double action sur les puces:\u00a0\u00e0 la fois sur les adultes et sur les larves  Permet de pr\u00e9server l\u2019habitat de toute infestation de puces\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frontline Frontline Combo Chat Boehringer - V\u00e9torino\" \/>\n<meta property=\"og:description\" content=\"Frontline Combo Chat est une solution cutan\u00e9e cibl\u00e9e pour chats indiqu\u00e9e dans le traitement et la pr\u00e9vention des infestations de tiques, de puces et de poux broyeurs.  Caract\u00e9ristiques :\u00a0   Action insecticide contre l&#039;apparition de puces adultes,\u00a0persiste pendant 4 semaines.  Action acaricide contre les tiques,\u00a0persiste jusqu&#039;\u00e0 2 semaines.  Assure une protection continue gr\u00e2ce \u00e0 une double action sur les puces:\u00a0\u00e0 la fois sur les adultes et sur les larves  Permet de pr\u00e9server l\u2019habitat de toute infestation de puces\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.vetorino.com\/veterinaire\/pogny-51240\/boutique\/product\/frontline-combo-chat\/\" \/>\n<meta property=\"og:site_name\" content=\"V\u00e9torino\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Vetorino\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-22T00:42:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/frontline-combo-chat.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Disponibilit\u00e9\" \/>\n\t<meta name=\"twitter:data1\" content=\"En stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/frontline-combo-chat\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/frontline-combo-chat\\\/\",\"name\":\"Frontline Frontline Combo Chat Boehringer - V\u00e9torino\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/frontline-combo-chat\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/frontline-combo-chat\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/frontline-combo-chat.webp\",\"datePublished\":\"2020-06-29T15:41:18+00:00\",\"dateModified\":\"2026-07-22T00:42:14+00:00\",\"description\":\"Frontline Combo Chat est une solution cutan\u00e9e cibl\u00e9e pour chats indiqu\u00e9e dans le traitement et la pr\u00e9vention des infestations de tiques, de puces et de poux broyeurs. Caract\u00e9ristiques :\u00a0 Action insecticide contre l'apparition de puces adultes,\u00a0persiste pendant 4 semaines. Action acaricide contre les tiques,\u00a0persiste jusqu'\u00e0 2 semaines. Assure une protection continue gr\u00e2ce \u00e0 une double action sur les puces:\u00a0\u00e0 la fois sur les adultes et sur les larves Permet de pr\u00e9server l\u2019habitat de toute infestation de puces\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/frontline-combo-chat\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/frontline-combo-chat\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/frontline-combo-chat\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/frontline-combo-chat.webp\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/frontline-combo-chat.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/product\\\/frontline-combo-chat\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits\",\"item\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Frontline Combo Chat\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#website\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"name\":\"V\u00e9torino\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#organization\",\"name\":\"V\u00e9torino\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/logo.jpg\",\"width\":1200,\"height\":610,\"caption\":\"V\u00e9torino\"},\"image\":{\"@id\":\"https:\\\/\\\/www.vetorino.com\\\/boutique\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Vetorino\\\/\",\"https:\\\/\\\/www.instagram.com\\\/vetorino_off\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/vtorino\\\/\"]}]}<\/script>\n<meta property=\"product:brand\" content=\"Boehringer\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Frontline Frontline Combo Chat Boehringer - V\u00e9torino","description":"Frontline Combo Chat est une solution cutan\u00e9e cibl\u00e9e pour chats indiqu\u00e9e dans le traitement et la pr\u00e9vention des infestations de tiques, de puces et de poux broyeurs.  Caract\u00e9ristiques :\u00a0   Action insecticide contre l'apparition de puces adultes,\u00a0persiste pendant 4 semaines.  Action acaricide contre les tiques,\u00a0persiste jusqu'\u00e0 2 semaines.  Assure une protection continue gr\u00e2ce \u00e0 une double action sur les puces:\u00a0\u00e0 la fois sur les adultes et sur les larves  Permet de pr\u00e9server l\u2019habitat de toute infestation de puces","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"fr_FR","og_type":"article","og_title":"Frontline Frontline Combo Chat Boehringer - V\u00e9torino","og_description":"Frontline Combo Chat est une solution cutan\u00e9e cibl\u00e9e pour chats indiqu\u00e9e dans le traitement et la pr\u00e9vention des infestations de tiques, de puces et de poux broyeurs.  Caract\u00e9ristiques :\u00a0   Action insecticide contre l'apparition de puces adultes,\u00a0persiste pendant 4 semaines.  Action acaricide contre les tiques,\u00a0persiste jusqu'\u00e0 2 semaines.  Assure une protection continue gr\u00e2ce \u00e0 une double action sur les puces:\u00a0\u00e0 la fois sur les adultes et sur les larves  Permet de pr\u00e9server l\u2019habitat de toute infestation de puces","og_url":"https:\/\/www.vetorino.com\/veterinaire\/pogny-51240\/boutique\/product\/frontline-combo-chat\/","og_site_name":"V\u00e9torino","article_publisher":"https:\/\/www.facebook.com\/Vetorino\/","article_modified_time":"2026-07-22T00:42:14+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/frontline-combo-chat.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Disponibilit\u00e9":"En stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.vetorino.com\/boutique\/product\/frontline-combo-chat\/","url":"https:\/\/www.vetorino.com\/boutique\/product\/frontline-combo-chat\/","name":"Frontline Frontline Combo Chat Boehringer - V\u00e9torino","isPartOf":{"@id":"https:\/\/www.vetorino.com\/boutique\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/frontline-combo-chat\/#primaryimage"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/frontline-combo-chat\/#primaryimage"},"thumbnailUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/frontline-combo-chat.webp","datePublished":"2020-06-29T15:41:18+00:00","dateModified":"2026-07-22T00:42:14+00:00","description":"Frontline Combo Chat est une solution cutan\u00e9e cibl\u00e9e pour chats indiqu\u00e9e dans le traitement et la pr\u00e9vention des infestations de tiques, de puces et de poux broyeurs. Caract\u00e9ristiques :\u00a0 Action insecticide contre l'apparition de puces adultes,\u00a0persiste pendant 4 semaines. Action acaricide contre les tiques,\u00a0persiste jusqu'\u00e0 2 semaines. Assure une protection continue gr\u00e2ce \u00e0 une double action sur les puces:\u00a0\u00e0 la fois sur les adultes et sur les larves Permet de pr\u00e9server l\u2019habitat de toute infestation de puces","breadcrumb":{"@id":"https:\/\/www.vetorino.com\/boutique\/product\/frontline-combo-chat\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.vetorino.com\/boutique\/product\/frontline-combo-chat\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/product\/frontline-combo-chat\/#primaryimage","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/frontline-combo-chat.webp","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2020\/03\/frontline-combo-chat.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/www.vetorino.com\/boutique\/product\/frontline-combo-chat\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":2,"name":"Produits","item":"https:\/\/www.vetorino.com\/boutique\/"},{"@type":"ListItem","position":3,"name":"Frontline Combo Chat"}]},{"@type":"WebSite","@id":"https:\/\/www.vetorino.com\/boutique\/#website","url":"https:\/\/www.vetorino.com\/boutique\/","name":"V\u00e9torino","description":"","publisher":{"@id":"https:\/\/www.vetorino.com\/boutique\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.vetorino.com\/boutique\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.vetorino.com\/boutique\/#organization","name":"V\u00e9torino","url":"https:\/\/www.vetorino.com\/boutique\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/","url":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","contentUrl":"https:\/\/www.vetorino.com\/boutique\/wp-content\/uploads\/2024\/10\/logo.jpg","width":1200,"height":610,"caption":"V\u00e9torino"},"image":{"@id":"https:\/\/www.vetorino.com\/boutique\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Vetorino\/","https:\/\/www.instagram.com\/vetorino_off\/","https:\/\/www.linkedin.com\/company\/vtorino\/"]}]},"product_brand":"Boehringer","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/pogny-51240\/boutique\/wp-json\/wp\/v2\/product\/96392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/pogny-51240\/boutique\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/pogny-51240\/boutique\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/pogny-51240\/boutique\/wp-json\/wp\/v2\/media\/1737534"}],"wp:attachment":[{"href":"https:\/\/www.vetorino.com\/veterinaire\/pogny-51240\/boutique\/wp-json\/wp\/v2\/media?parent=96392"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/pogny-51240\/boutique\/wp-json\/wp\/v2\/product_cat?post=96392"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.vetorino.com\/veterinaire\/pogny-51240\/boutique\/wp-json\/wp\/v2\/product_tag?post=96392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}